{"id":8278,"date":"2019-04-04T15:49:00","date_gmt":"2019-04-04T15:49:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=8278"},"modified":"2024-11-21T15:50:35","modified_gmt":"2024-11-21T15:50:35","slug":"the-trust-for-the-americas-realiza-el-primer-encuentro-virtual-de-jovenes-de-america-latina-y-el-caribe","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/the-trust-for-the-americas-realiza-el-primer-encuentro-virtual-de-jovenes-de-america-latina-y-el-caribe\/","title":{"rendered":"The Trust for The Americas realiza el Primer Encuentro Virtual de J\u00f3venes de Am\u00e9rica Latina y el Caribe"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2019\/04\/04<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Washington, D.C. (4 de abril de 2019)<\/strong>&nbsp;<a href=\"https:\/\/www.thetrustfortheamericas.org\/\">The Trust for the Americas<\/a>&nbsp;bajo su modelo de&nbsp;<a href=\"http:\/\/fsp.trustfortheamericas.org\/es\/acerca-de-la-franquicia\">Franquicia Social POETA<\/a>, organiza el Primer Encuentro Virtual de J\u00f3venes POETA de Am\u00e9rica Latina y el Caribe el pr\u00f3ximo 07 de mayo, con el objetivo de generar un espacio para que los j\u00f3venes de diversos pa\u00edses se contacten para intercambiar ideas, logros, desaf\u00edos y soluciones sobre el aprendizaje a trav\u00e9s de las Tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n (TIC), el mundo del empleo y el emprendimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, los participantes est\u00e1n en proceso de capacitaci\u00f3n tecnol\u00f3gica en los&nbsp;Centros&nbsp;<a href=\"https:\/\/www.thetrustfortheamericas.org\/programs\/poeta\">POETA<\/a>&nbsp;y&nbsp;<a href=\"http:\/\/fsp.trustfortheamericas.org\/es\/programas-y-proyectos\/programas\/mi-llave\">Mi Llave<\/a>&nbsp;d\u00f3nde se implementa el modelo de la Franquicia Social POETA, oferta metodol\u00f3gica compuesta de recursos, servicios y beneficios para la promoci\u00f3n de la inclusi\u00f3n social y la generaci\u00f3n de oportunidades econ\u00f3micas y educativas en poblaciones vulnerables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, los j\u00f3venes propondr\u00e1n formas creativas de mapear o crear redes de comunicaci\u00f3n en sus comunidades y en otros pa\u00edses de la regi\u00f3n. En Brasil, se realizar\u00e1 un encuentro previo entre j\u00f3venes de los Centros POETA de habla portuguesa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el encuentro los participantes conversar\u00e1n sobre: a) \u00bfqu\u00e9 comparten o no los j\u00f3venes de un mismo continente? b) \u00bfcu\u00e1les son los proyectos de vida que visualizan? c) \u00bfc\u00f3mo identificar procesos que los fortalezcan? d) \u00bfc\u00f3mo crear y mantener a una Gran Comunidad de J\u00f3venes trascendiendo las fronteras? e) \u00bfpor qu\u00e9 promover la equidad de g\u00e9nero? y f) \u00bfc\u00f3mo elegir democr\u00e1ticamente?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Este encuentro virtual forma parte del impulso que da la Franquicia Social POETA a decenas de j\u00f3venes que pertenecen a las nuevas generaciones y que est\u00e1n decididos a ser los protagonistas del cambio.&nbsp;As\u00ed mismo, este espacio est\u00e1 dise\u00f1ado para ofrecer a los j\u00f3venes la oportunidad de conocer experiencias exitosas en otros pa\u00edses\u201d. C<\/em>oment\u00f3 Maite Capra, Coordinadora de Proyectos de The Trust for the Americas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los j\u00f3venes que deseen ser parte deben completar el&nbsp;<a href=\"https:\/\/es.surveymonkey.com\/r\/I_Encuentro\">formulario de inscripci\u00f3n<\/a>. El encuentro se realizar\u00e1 en las siguientes horas: 9:00 a.m. para Centroam\u00e9rica y M\u00e9xico; 10:00 a.m. para Colombia, Ecuador, Venezuela y Per\u00fa; &nbsp;11:00 a.m. para Rep\u00fablica Dominicana; y 1:00 p.m. para Argentina, Chile y Brasil. \u00a1Los esperamos!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas es una Organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados Americanos (OEA) cuya misi\u00f3n es promover alianzas para la inclusi\u00f3n econ\u00f3mica y social en las Am\u00e9ricas.&nbsp;Establecida en 1997, The Trust fue creado para la participaci\u00f3n del sector p\u00fablico, el sector privado y las iniciativas de la sociedad civil en el desarrollo social y econ\u00f3mico en Am\u00e9rica Latina y el Caribe. Las iniciativas de la organizaci\u00f3n mejoran el acceso de las comunidades a oportunidades econ\u00f3micas, mejor seguridad ciudadana y oportunidades para la expresi\u00f3n democr\u00e1tica y la gobernabilidad.&nbsp; The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas ofrece a las organizaciones locales asociadas, instrumentos de capacitaci\u00f3n, servicios, productos y asistencia t\u00e9cnica para servir mejor a las comunidades vulnerables de la regi\u00f3n.&nbsp; Visite:&nbsp;<a href=\"http:\/\/www.trustfortheamericas.org\/\">www.trustfortheamericas.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:&nbsp;<a href=\"https:\/\/www.facebook.com\/TheTrustfortheAmericas\/\">The Trust for the Americas<\/a>&nbsp; Twitter:&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/twitter.com\/Trust4Americas\">@Trust4Americas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Argentina\u00a0&#8211;\u00a0Brasil\u00a0&#8211;\u00a0Chile\u00a0&#8211;\u00a0Colombia\u00a0&#8211;\u00a0Costa Rica\u00a0&#8211;\u00a0El Salvador\u00a0&#8211;\u00a0Mexico\u00a0&#8211;\u00a0Rep\u00fablica Dominicana<\/p>","protected":false},"excerpt":{"rendered":"<p>2019\/04\/04 Washington, D.C. (4 de abril de 2019)&nbsp;The Trust for the Americas&nbsp;bajo su modelo de&nbsp;Franquicia Social POETA, organiza el Primer Encuentro Virtual de J\u00f3venes POETA de Am\u00e9rica Latina y el Caribe el pr\u00f3ximo 07 de mayo, con el objetivo de generar un espacio para que los j\u00f3venes de diversos pa\u00edses se contacten para intercambiar ideas, logros, desaf\u00edos y soluciones sobre el aprendizaje a trav\u00e9s de las Tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n (TIC), el mundo del empleo y el emprendimiento. Actualmente, los participantes est\u00e1n en proceso de capacitaci\u00f3n tecnol\u00f3gica en los&nbsp;Centros&nbsp;POETA&nbsp;y&nbsp;Mi Llave&nbsp;d\u00f3nde se implementa el modelo de la Franquicia Social POETA, oferta metodol\u00f3gica compuesta de recursos, servicios y beneficios para la promoci\u00f3n de la inclusi\u00f3n social y la generaci\u00f3n de oportunidades econ\u00f3micas y educativas en poblaciones vulnerables. Adem\u00e1s, los j\u00f3venes propondr\u00e1n formas creativas de mapear o crear redes de comunicaci\u00f3n en sus comunidades y en otros pa\u00edses de la regi\u00f3n. En Brasil, se realizar\u00e1 un encuentro previo entre j\u00f3venes de los Centros POETA de habla portuguesa. Durante el encuentro los participantes conversar\u00e1n sobre: a) \u00bfqu\u00e9 comparten o no los j\u00f3venes de un mismo continente? b) \u00bfcu\u00e1les son los proyectos de vida que visualizan? c) \u00bfc\u00f3mo identificar procesos que los fortalezcan? d) \u00bfc\u00f3mo crear y mantener a una Gran Comunidad de J\u00f3venes trascendiendo las fronteras? e) \u00bfpor qu\u00e9 promover la equidad de g\u00e9nero? y f) \u00bfc\u00f3mo elegir democr\u00e1ticamente? \u201cEste encuentro virtual forma parte del impulso que da la Franquicia Social POETA a decenas de j\u00f3venes que pertenecen a las nuevas generaciones y que est\u00e1n decididos a ser los protagonistas del cambio.&nbsp;As\u00ed mismo, este espacio est\u00e1 dise\u00f1ado para ofrecer a los j\u00f3venes la oportunidad de conocer experiencias exitosas en otros pa\u00edses\u201d. Coment\u00f3 Maite Capra, Coordinadora de Proyectos de The Trust for the Americas. Los j\u00f3venes que deseen ser parte deben completar el&nbsp;formulario de inscripci\u00f3n. El encuentro se realizar\u00e1 en las siguientes horas: 9:00 a.m. para Centroam\u00e9rica y M\u00e9xico; 10:00 a.m. para Colombia, Ecuador, Venezuela y Per\u00fa; &nbsp;11:00 a.m. para Rep\u00fablica Dominicana; y 1:00 p.m. para Argentina, Chile y Brasil. \u00a1Los esperamos! Sobre The Trust for the Americas: The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas es una Organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados Americanos (OEA) cuya misi\u00f3n es promover alianzas para la inclusi\u00f3n econ\u00f3mica y social en las Am\u00e9ricas.&nbsp;Establecida en 1997, The Trust fue creado para la participaci\u00f3n del sector p\u00fablico, el sector privado y las iniciativas de la sociedad civil en el desarrollo social y econ\u00f3mico en Am\u00e9rica Latina y el Caribe. Las iniciativas de la organizaci\u00f3n mejoran el acceso de las comunidades a oportunidades econ\u00f3micas, mejor seguridad ciudadana y oportunidades para la expresi\u00f3n democr\u00e1tica y la gobernabilidad.&nbsp; The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas ofrece a las organizaciones locales asociadas, instrumentos de capacitaci\u00f3n, servicios, productos y asistencia t\u00e9cnica para servir mejor a las comunidades vulnerables de la regi\u00f3n.&nbsp; Visite:&nbsp;www.trustfortheamericas.org Facebook:&nbsp;The Trust for the Americas&nbsp; Twitter:&nbsp;&nbsp;&nbsp;@Trust4Americas Argentina\u00a0&#8211;\u00a0Brasil\u00a0&#8211;\u00a0Chile\u00a0&#8211;\u00a0Colombia\u00a0&#8211;\u00a0Costa Rica\u00a0&#8211;\u00a0El Salvador\u00a0&#8211;\u00a0Mexico\u00a0&#8211;\u00a0Rep\u00fablica Dominicana<\/p>","protected":false},"author":37,"featured_media":8279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-8278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/8278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=8278"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/8278\/revisions"}],"predecessor-version":[{"id":8280,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/8278\/revisions\/8280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/8279"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=8278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=8278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=8278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}