{"id":8266,"date":"2019-08-27T15:44:00","date_gmt":"2019-08-27T15:44:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=8266"},"modified":"2024-11-21T15:45:19","modified_gmt":"2024-11-21T15:45:19","slug":"the-trust-for-the-americas-presenta-casos-de-exito-en-la-semana-internacional-de-datos-abiertos","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/the-trust-for-the-americas-presenta-casos-de-exito-en-la-semana-internacional-de-datos-abiertos\/","title":{"rendered":"THE TRUST FOR THE AMERICAS PRESENTA CASOS DE \u00c9XITO EN LA SEMANA INTERNACIONAL DE DATOS ABIERTOS"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2019\/08\/27<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Abrelatam y Condatos 2019 re\u00fanen a sociedad civil, sector privado, academia y gobiernos en la comunidad de datos abiertos y tecnolog\u00eda c\u00edvica.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Washington, D.C.<\/strong>&nbsp;(26 de agosto de 2019) \u2014&nbsp;The Trust for the Americas participa por segundo a\u00f1o consecutivo en la semana internacional de datos abiertos, donde concurren las m\u00e1s importantes conferencias regionales de datos abiertos, Abrelatam y Condatos del 27 al 30 de agosto de 2019. &nbsp;La agenda estar\u00e1 cargada de actividades que procuran avanzar la agenda de datos abiertos de la regi\u00f3n, empezando con una sesi\u00f3n de trabajo para definir la teor\u00eda de cambio del Programa Interamericano de Datos Abiertos&nbsp;<strong>(PIDA)<\/strong>&nbsp;en la cual participaran organizaciones l\u00edderes como&nbsp;HIVOS Latam, ILDA, Open Data Charter, CAF, Open Contracting Partnership, Open Government Partnership y Global Integrity.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o, The Trust for the Americas en alianza con el Banco Interamericano de Desarrollo (BID) y el apoyo de EDES Business School, la Universidad T\u00e9cnica Particular de Loja (UTPL) y&nbsp;CIFAL Quito\/Miami-UNITAR,&nbsp;organiza&nbsp;un taller denominado \u201cDatos Abiertos y Emprendimientos: de casos pr\u00e1cticos a una hoja de ruta\u201d el evento, se realizar\u00e1, en el Centro de Convenciones Eugenio Espejo en Quito, Ecuador el 28 de agosto de 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El taller busca, desde una perspectiva pr\u00e1ctica,&nbsp;sugerir y realizar acciones en com\u00fan entre el sector p\u00fablico, privado y social, que permita&nbsp;avanzar la agenda de datos abiertos desde el sector emprendedor. En seguimiento a la Declaraci\u00f3n de Lima y alineado con el Programa Interamericano de Datos Abiertos (PIDA), se busca potenciar el valor que el sector privado y el ecosistema emprendedor representan en el proceso de reutilizaci\u00f3n de datos p\u00fablicos, generando mayor desarrollo econ\u00f3mico y social en las comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicho espacio, contar\u00e1 con casos pr\u00e1cticos implementados en gobiernos sub-nacionales como la Ciudad de Buenos Aires&nbsp;y buscar\u00e1, fomentar el intercambio y el di\u00e1logo t\u00e9cnico entre actores relevantes como lo son organizaciones internacionales, gobiernos, sector privado, y la sociedad civil de la regi\u00f3n, con la finalidad de establecer una hoja de ruta que facilite el fortalecimiento del ecosistema emprendedor para el uso y aprovechamiento de los datos abiertos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los panelistas contaremos con&nbsp;<a href=\"https:\/\/www.linkedin.com\/in\/camilopinzonorbe\/\">Camilo Pinz\u00f3n<\/a>, decano de la EDES Business School,&nbsp;<a href=\"https:\/\/www.linkedin.com\/in\/alfonsoabdof\/\">Alfonso Abdo<\/a>, Director Ejecutivo del Programa SIN FRONTERAS,&nbsp;<a href=\"https:\/\/www.linkedin.com\/in\/auracifuentes\/\">Aura Cifuentes<\/a>, coordinadora del Equipo de Innovaci\u00f3n P\u00fablica (EiP) del Departamento Nacional de Planeaci\u00f3n de Colombia (DNP) y&nbsp;<a href=\"https:\/\/www.linkedin.com\/in\/martin-alalu-7248896b\/\">Mart\u00edn Alal\u00fa<\/a>, Gerente Operativo de Gobierno Abierto en el Gobierno de la Ciudad Aut\u00f3noma de Buenos Aires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como producto final del evento, Rodirgo Iriani, Gerente de Proyectos de The Trust for the Americas mencion\u00f3&nbsp;&#8220;se construir\u00e1 una hoja de ruta que sirva como insumo de implementaci\u00f3n piloto en alg\u00fan gobierno local de la regi\u00f3n, con la finalidad de generar aprendizajes y colaboraciones con el sector privado y emprendedor para el aprovechamiento de los datos abiertos. La idea es potenciar el uso de datos abiertos para la mejora de negocios, el desarrollo de nuevos bienes y servicios, la generaci\u00f3n de m\u00e1s emprendimientos o de acciones de responsabilidad social empresarial&#8221;.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacia el final de la semana, The Trust for the Americas estar\u00e1 participando en el panel&nbsp;<a href=\"https:\/\/sched.co\/TiHq\">\u201cEl poder de los datos a nivel local\u201d<\/a>&nbsp;presentando el caso de \u00e9xito del proyecto&nbsp;<em>&#8220;Del Gobierno Abierto al Estado Abierto en Costa Rica&#8221;&nbsp;<\/em>implementado junto con el Departamento de Gesti\u00f3n Publica Efectiva de la OEA y auspiciado por la Embajada de los Estados Unidos en Costa Rica<em>, c<\/em>ompartiendo el m\u00e9todo de trabajo de los municipios para incorporar a la sociedad civil en el proceso de co-creaci\u00f3n de las pol\u00edticas p\u00fablicas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust&nbsp;for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida&nbsp;en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno.Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo&nbsp;de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar&nbsp;los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>TheTrust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3).&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Visite:&nbsp;<a href=\"http:\/\/www.trustfortheamericas.org\/\">www.trustfortheamericas.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:&nbsp;<a href=\"https:\/\/www.facebook.com\/TheTrustfortheAmericas\/\">The Trust for the Americas<\/a>&nbsp; Twitter:&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/twitter.com\/Trust4Americas\">@Trust4Americas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Ecuador<\/p>\n\n\n\n<p class=\"has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-e208258e2160954652c1c9839d721523 wp-block-paragraph\"><a href=\"https:\/\/www.trustfortheamericas.org\/media\/press-room\/articles\/attachments\/Handout_DESARROLLO-SOCIOECONOMICO.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Handout (Only spanish)<\/a><a href=\"https:\/\/www.trustfortheamericas.org\/media\/press-room\/articles\/attachments\/Handout_DESARROLLO-SOCIOECONOMICO.pdf\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>2019\/08\/27 Abrelatam y Condatos 2019 re\u00fanen a sociedad civil, sector privado, academia y gobiernos en la comunidad de datos abiertos y tecnolog\u00eda c\u00edvica. Washington, D.C.&nbsp;(26 de agosto de 2019) \u2014&nbsp;The Trust for the Americas participa por segundo a\u00f1o consecutivo en la semana internacional de datos abiertos, donde concurren las m\u00e1s importantes conferencias regionales de datos abiertos, Abrelatam y Condatos del 27 al 30 de agosto de 2019. &nbsp;La agenda estar\u00e1 cargada de actividades que procuran avanzar la agenda de datos abiertos de la regi\u00f3n, empezando con una sesi\u00f3n de trabajo para definir la teor\u00eda de cambio del Programa Interamericano de Datos Abiertos&nbsp;(PIDA)&nbsp;en la cual participaran organizaciones l\u00edderes como&nbsp;HIVOS Latam, ILDA, Open Data Charter, CAF, Open Contracting Partnership, Open Government Partnership y Global Integrity. Este a\u00f1o, The Trust for the Americas en alianza con el Banco Interamericano de Desarrollo (BID) y el apoyo de EDES Business School, la Universidad T\u00e9cnica Particular de Loja (UTPL) y&nbsp;CIFAL Quito\/Miami-UNITAR,&nbsp;organiza&nbsp;un taller denominado \u201cDatos Abiertos y Emprendimientos: de casos pr\u00e1cticos a una hoja de ruta\u201d el evento, se realizar\u00e1, en el Centro de Convenciones Eugenio Espejo en Quito, Ecuador el 28 de agosto de 2019. El taller busca, desde una perspectiva pr\u00e1ctica,&nbsp;sugerir y realizar acciones en com\u00fan entre el sector p\u00fablico, privado y social, que permita&nbsp;avanzar la agenda de datos abiertos desde el sector emprendedor. En seguimiento a la Declaraci\u00f3n de Lima y alineado con el Programa Interamericano de Datos Abiertos (PIDA), se busca potenciar el valor que el sector privado y el ecosistema emprendedor representan en el proceso de reutilizaci\u00f3n de datos p\u00fablicos, generando mayor desarrollo econ\u00f3mico y social en las comunidades. Dicho espacio, contar\u00e1 con casos pr\u00e1cticos implementados en gobiernos sub-nacionales como la Ciudad de Buenos Aires&nbsp;y buscar\u00e1, fomentar el intercambio y el di\u00e1logo t\u00e9cnico entre actores relevantes como lo son organizaciones internacionales, gobiernos, sector privado, y la sociedad civil de la regi\u00f3n, con la finalidad de establecer una hoja de ruta que facilite el fortalecimiento del ecosistema emprendedor para el uso y aprovechamiento de los datos abiertos. Entre los panelistas contaremos con&nbsp;Camilo Pinz\u00f3n, decano de la EDES Business School,&nbsp;Alfonso Abdo, Director Ejecutivo del Programa SIN FRONTERAS,&nbsp;Aura Cifuentes, coordinadora del Equipo de Innovaci\u00f3n P\u00fablica (EiP) del Departamento Nacional de Planeaci\u00f3n de Colombia (DNP) y&nbsp;Mart\u00edn Alal\u00fa, Gerente Operativo de Gobierno Abierto en el Gobierno de la Ciudad Aut\u00f3noma de Buenos Aires. Como producto final del evento, Rodirgo Iriani, Gerente de Proyectos de The Trust for the Americas mencion\u00f3&nbsp;&#8220;se construir\u00e1 una hoja de ruta que sirva como insumo de implementaci\u00f3n piloto en alg\u00fan gobierno local de la regi\u00f3n, con la finalidad de generar aprendizajes y colaboraciones con el sector privado y emprendedor para el aprovechamiento de los datos abiertos. La idea es potenciar el uso de datos abiertos para la mejora de negocios, el desarrollo de nuevos bienes y servicios, la generaci\u00f3n de m\u00e1s emprendimientos o de acciones de responsabilidad social empresarial&#8221;.&nbsp; Hacia el final de la semana, The Trust for the Americas estar\u00e1 participando en el panel&nbsp;\u201cEl poder de los datos a nivel local\u201d&nbsp;presentando el caso de \u00e9xito del proyecto&nbsp;&#8220;Del Gobierno Abierto al Estado Abierto en Costa Rica&#8221;&nbsp;implementado junto con el Departamento de Gesti\u00f3n Publica Efectiva de la OEA y auspiciado por la Embajada de los Estados Unidos en Costa Rica, compartiendo el m\u00e9todo de trabajo de los municipios para incorporar a la sociedad civil en el proceso de co-creaci\u00f3n de las pol\u00edticas p\u00fablicas.&nbsp; Sobre The Trust for the Americas: The Trust&nbsp;for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida&nbsp;en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno.Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo&nbsp;de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar&nbsp;los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. TheTrust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3).&nbsp;&nbsp; &nbsp;Visite:&nbsp;www.trustfortheamericas.org Facebook:&nbsp;The Trust for the Americas&nbsp; Twitter:&nbsp;&nbsp;&nbsp;@Trust4Americas Ecuador Handout (Only spanish)<\/p>","protected":false},"author":37,"featured_media":8267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-8266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/8266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=8266"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/8266\/revisions"}],"predecessor-version":[{"id":8268,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/8266\/revisions\/8268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/8267"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=8266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=8266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=8266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}