{"id":8134,"date":"2021-09-20T14:29:00","date_gmt":"2021-09-20T14:29:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=8134"},"modified":"2024-11-21T14:30:31","modified_gmt":"2024-11-21T14:30:31","slug":"convocatoria-abierta-para-organizaciones-dominicanas-que-quieran-impulsar-la-innovacion-en-el-pais","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/convocatoria-abierta-para-organizaciones-dominicanas-que-quieran-impulsar-la-innovacion-en-el-pais\/","title":{"rendered":"CONVOCATORIA ABIERTA PARA ORGANIZACIONES DOMINICANAS QUE QUIERAN IMPULSAR LA INNOVACI\u00d3N EN EL PA\u00cdS"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2021\/09\/20<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rep\u00fablica&nbsp;Dominicana.<\/strong>&nbsp;&#8211;&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas,&nbsp;entidad sin fines de lucro afiliada&nbsp;a la Organizaci\u00f3n de Estados&nbsp;Americanos&nbsp;(OEA), en&nbsp;alianza con&nbsp;Citi&nbsp;Foundation,&nbsp;anuncia&nbsp;la b\u00fasqueda de un socio local para el lanzamiento del&nbsp;<strong>Laboratorio de Innovaci\u00f3n DIA en Rep\u00fablica&nbsp;Dominicana<\/strong>.&nbsp;El laboratorio&nbsp;busca&nbsp;fomentar la innovaci\u00f3n y el emprendimiento en&nbsp;la juventud&nbsp;con la finalidad de que&nbsp;desarrollen&nbsp;soluciones&nbsp;creativas&nbsp;a desaf\u00edos socioecon\u00f3micos locales, a la vez que&nbsp;adquieren&nbsp;habilidades para&nbsp;la era digital y&nbsp;para el&nbsp;empleo.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfEn qu\u00e9 consistir\u00e1 el DIA&nbsp;Lab&nbsp;Rep\u00fablica Dominicana?&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este laboratorio, al igual que todos los pertenecientes a la red de laboratorios&nbsp;del programa&nbsp;DIA&nbsp;&#8211;&nbsp;Democratizando la Innovaci\u00f3n en las Am\u00e9ricas&nbsp;&#8211;&nbsp;se enfocar\u00e1 en&nbsp;promover la innovaci\u00f3n y proporcionar a&nbsp;la juventud dominicana&nbsp;un plan de estudios personalizado centrado en la innovaci\u00f3n. De igual forma,&nbsp;se&nbsp;brindar\u00e1 acceso a tecnolog\u00eda y equipos como&nbsp;impresoras 3D y microprocesadores;&nbsp;orientaci\u00f3n por parte de agentes laborales;&nbsp;oportunidades de tutor\u00eda&nbsp;de la mano de&nbsp;profesionales en negocios;&nbsp;un&nbsp;ambiente&nbsp;de colaboraci\u00f3n;&nbsp;y&nbsp;la oportunidad de concursar por fondos semilla, que permitan consolidar los proyectos&nbsp;m\u00e1s prometedores y disruptivos, desarrollados por los participantes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 labor realizar\u00e1 el socio local?&nbsp;&nbsp;&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con una subvenci\u00f3n&nbsp;tope&nbsp;de&nbsp;US$80,000, The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;busca&nbsp;a una organizaci\u00f3n que&nbsp;tenga la capacidad t\u00e9cnica y operativa&nbsp;para implementar este proyecto de impacto social.&nbsp;Durante un a\u00f1o, y con el&nbsp;acompa\u00f1amiento&nbsp;t\u00e9cnico de&nbsp;The&nbsp;Trust,&nbsp;el socio local&nbsp;capacitar\u00e1&nbsp;a&nbsp;200&nbsp;j\u00f3venes con esp\u00edritu emprendedor,&nbsp;brindar\u00e1&nbsp;acceso&nbsp;a las instalaciones a miembros de la comunidad&nbsp;y&nbsp;desarrollar\u00e1&nbsp;actividades&nbsp;y eventos&nbsp;como competencias&nbsp;Pitch&nbsp;Tank,&nbsp;Ideathones&nbsp;y&nbsp;Hackathones.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ventajas&nbsp;para el&nbsp;socio local&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestra afiliaci\u00f3n a la Organizaci\u00f3n de Estados Americanos provee una&nbsp;plataforma&nbsp;\u00fanica de contactos a lo largo de todo el continente. Desde&nbsp;empresas del sector privado&nbsp;a oficinas e&nbsp;instituciones&nbsp;gubernamentales&nbsp;de la regi\u00f3n.&nbsp;Asimismo, obtienen&nbsp;acceso&nbsp;a contenidos curriculares DIA y red de aliados.&nbsp;Adem\u00e1s, cada socio&nbsp;local&nbsp;ha podido&nbsp;recibir&nbsp;visibilidad gracias a&nbsp;su&nbsp;presencia en nuestros canales de comunicaci\u00f3n,&nbsp;como p\u00e1gina web, redes sociales, comunicados de prensa, boletines y eventos.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCrees que tienes lo que se necesita?&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te invitamos&nbsp;a&nbsp;enviar una propuesta&nbsp;antes del 05 de noviembre&nbsp;de 2021. Como socio local no s\u00f3lo ayudar\u00e1s a&nbsp;forjar&nbsp;a los j\u00f3venes del ma\u00f1ana&nbsp;y mejorar su calidad de vida, sino que tambi\u00e9n podr\u00e1s&nbsp;impulsar tu organizaci\u00f3n&nbsp;al ser un aliado de&nbsp;una ONG internacional.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para obtener mayor informaci\u00f3n sobre el proyecto, revisar los requisitos, fechas clave y descargar el formulario, entra a&nbsp;<a href=\"https:\/\/www.trustfortheamericas.org\/programs\/dia\/dia-dominican-republic-innovation-lab\">https:\/\/www.trustfortheamericas.org\/programs\/dia\/dia-dominican-republic-innovation-lab<\/a>.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cualquier duda adicional, puedes contactar a&nbsp;Rodrigo&nbsp;Iriani, Senior&nbsp;Program&nbsp;Manager DIA, a trav\u00e9s del correo:&nbsp;<a href=\"mailto:RIriani@oas.org\" rel=\"noreferrer noopener\" target=\"_blank\">RIriani@oas.org<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;<a href=\"http:\/\/www.trustfortheamericas.org\/\">www.trustfortheamericas.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Rep\u00fablica Dominicana<\/p>","protected":false},"excerpt":{"rendered":"<p>2021\/09\/20 Rep\u00fablica&nbsp;Dominicana.&nbsp;&#8211;&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas,&nbsp;entidad sin fines de lucro afiliada&nbsp;a la Organizaci\u00f3n de Estados&nbsp;Americanos&nbsp;(OEA), en&nbsp;alianza con&nbsp;Citi&nbsp;Foundation,&nbsp;anuncia&nbsp;la b\u00fasqueda de un socio local para el lanzamiento del&nbsp;Laboratorio de Innovaci\u00f3n DIA en Rep\u00fablica&nbsp;Dominicana.&nbsp;El laboratorio&nbsp;busca&nbsp;fomentar la innovaci\u00f3n y el emprendimiento en&nbsp;la juventud&nbsp;con la finalidad de que&nbsp;desarrollen&nbsp;soluciones&nbsp;creativas&nbsp;a desaf\u00edos socioecon\u00f3micos locales, a la vez que&nbsp;adquieren&nbsp;habilidades para&nbsp;la era digital y&nbsp;para el&nbsp;empleo.&nbsp;&nbsp; \u00bfEn qu\u00e9 consistir\u00e1 el DIA&nbsp;Lab&nbsp;Rep\u00fablica Dominicana?&nbsp; Este laboratorio, al igual que todos los pertenecientes a la red de laboratorios&nbsp;del programa&nbsp;DIA&nbsp;&#8211;&nbsp;Democratizando la Innovaci\u00f3n en las Am\u00e9ricas&nbsp;&#8211;&nbsp;se enfocar\u00e1 en&nbsp;promover la innovaci\u00f3n y proporcionar a&nbsp;la juventud dominicana&nbsp;un plan de estudios personalizado centrado en la innovaci\u00f3n. De igual forma,&nbsp;se&nbsp;brindar\u00e1 acceso a tecnolog\u00eda y equipos como&nbsp;impresoras 3D y microprocesadores;&nbsp;orientaci\u00f3n por parte de agentes laborales;&nbsp;oportunidades de tutor\u00eda&nbsp;de la mano de&nbsp;profesionales en negocios;&nbsp;un&nbsp;ambiente&nbsp;de colaboraci\u00f3n;&nbsp;y&nbsp;la oportunidad de concursar por fondos semilla, que permitan consolidar los proyectos&nbsp;m\u00e1s prometedores y disruptivos, desarrollados por los participantes.&nbsp; \u00bfQu\u00e9 labor realizar\u00e1 el socio local?&nbsp;&nbsp;&nbsp;&nbsp; Con una subvenci\u00f3n&nbsp;tope&nbsp;de&nbsp;US$80,000, The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;busca&nbsp;a una organizaci\u00f3n que&nbsp;tenga la capacidad t\u00e9cnica y operativa&nbsp;para implementar este proyecto de impacto social.&nbsp;Durante un a\u00f1o, y con el&nbsp;acompa\u00f1amiento&nbsp;t\u00e9cnico de&nbsp;The&nbsp;Trust,&nbsp;el socio local&nbsp;capacitar\u00e1&nbsp;a&nbsp;200&nbsp;j\u00f3venes con esp\u00edritu emprendedor,&nbsp;brindar\u00e1&nbsp;acceso&nbsp;a las instalaciones a miembros de la comunidad&nbsp;y&nbsp;desarrollar\u00e1&nbsp;actividades&nbsp;y eventos&nbsp;como competencias&nbsp;Pitch&nbsp;Tank,&nbsp;Ideathones&nbsp;y&nbsp;Hackathones.&nbsp; Ventajas&nbsp;para el&nbsp;socio local&nbsp; Nuestra afiliaci\u00f3n a la Organizaci\u00f3n de Estados Americanos provee una&nbsp;plataforma&nbsp;\u00fanica de contactos a lo largo de todo el continente. Desde&nbsp;empresas del sector privado&nbsp;a oficinas e&nbsp;instituciones&nbsp;gubernamentales&nbsp;de la regi\u00f3n.&nbsp;Asimismo, obtienen&nbsp;acceso&nbsp;a contenidos curriculares DIA y red de aliados.&nbsp;Adem\u00e1s, cada socio&nbsp;local&nbsp;ha podido&nbsp;recibir&nbsp;visibilidad gracias a&nbsp;su&nbsp;presencia en nuestros canales de comunicaci\u00f3n,&nbsp;como p\u00e1gina web, redes sociales, comunicados de prensa, boletines y eventos.&nbsp;&nbsp; \u00bfCrees que tienes lo que se necesita?&nbsp;&nbsp; Te invitamos&nbsp;a&nbsp;enviar una propuesta&nbsp;antes del 05 de noviembre&nbsp;de 2021. Como socio local no s\u00f3lo ayudar\u00e1s a&nbsp;forjar&nbsp;a los j\u00f3venes del ma\u00f1ana&nbsp;y mejorar su calidad de vida, sino que tambi\u00e9n podr\u00e1s&nbsp;impulsar tu organizaci\u00f3n&nbsp;al ser un aliado de&nbsp;una ONG internacional.&nbsp; Para obtener mayor informaci\u00f3n sobre el proyecto, revisar los requisitos, fechas clave y descargar el formulario, entra a&nbsp;https:\/\/www.trustfortheamericas.org\/programs\/dia\/dia-dominican-republic-innovation-lab.&nbsp;&nbsp; Cualquier duda adicional, puedes contactar a&nbsp;Rodrigo&nbsp;Iriani, Senior&nbsp;Program&nbsp;Manager DIA, a trav\u00e9s del correo:&nbsp;RIriani@oas.org.&nbsp; Sobre The Trust for the Americas: The Trust for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;www.trustfortheamericas.org Rep\u00fablica Dominicana<\/p>","protected":false},"author":37,"featured_media":8135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-8134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/8134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=8134"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/8134\/revisions"}],"predecessor-version":[{"id":8136,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/8134\/revisions\/8136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/8135"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=8134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=8134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=8134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}