{"id":7967,"date":"2020-05-26T16:08:00","date_gmt":"2020-05-26T16:08:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7967"},"modified":"2024-11-20T04:09:45","modified_gmt":"2024-11-20T04:09:45","slug":"the-trust-for-the-americas-launches-youth-for-open-data-campaign-in-panama","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/the-trust-for-the-americas-launches-youth-for-open-data-campaign-in-panama\/","title":{"rendered":"The Trust for the Americas launches Youth for Open Data Campaign in Panama"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li>Youth\u00a04 Open Data\u00a0(Y4OD)\u00a0ser\u00e1 una oportunidad para que los j\u00f3venes aprendan c\u00f3mo apropiarse de los datos para beneficiar a sus comunidades\u00a0o incluso\u00a0potenciar sus negocios.\u00a0<\/li>\n\n\n\n<li>The\u00a0Trust\u00a0for\u00a0the\u00a0Americas\u00a0apoya el Gobierno Abierto y la agenda regional de gobernanza y transparencia a trav\u00e9s de\u00a0la\u00a0creaci\u00f3n\u00a0de ecosistemas de\u00a0colaboraci\u00f3n\u00a0liderados por\u00a0\u00a0todos los sectores de la sociedad.\u00a0<\/li>\n\n\n\n<li>Esta iniciativa\u00a0est\u00e1 abierta para\u00a0j\u00f3venes de todas partes\u00a0del territorio de Panam\u00e1.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Washington DC,&nbsp;26&nbsp;de mayo 2020.-<\/strong>&nbsp;En el marco del proyecto \u201cInnovaci\u00f3n a trav\u00e9s de Datos Abiertos en Panam\u00e1\u201d,&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;de la Organizaci\u00f3n de Estados Americanos (OEA)&nbsp;lanza&nbsp;una campa\u00f1a de sensibilizaci\u00f3n en datos abiertos para j\u00f3venes de distintos sectores y provincias de la Rep\u00fablica de Panam\u00e1, con la finalidad de promover la participaci\u00f3n ciudadana,&nbsp;representaci\u00f3n territorial en la tem\u00e1tica y la formaci\u00f3n de l\u00edderes en temas relacionados a Datos Abiertos, Gobierno Abierto y Periodismo de Datos.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este componente del proyecto&nbsp;es implementado&nbsp;en&nbsp;alianza con el Instituto Paname\u00f1o de Derecho y Nuevas Tecnolog\u00edas (IPANDETEC) y en&nbsp;coordinaci\u00f3n&nbsp;con&nbsp;la&nbsp;Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI),&nbsp;la Autoridad para la Innovaci\u00f3n Gubernamental (AIG)&nbsp;y&nbsp;la Direcci\u00f3n General de Contrataciones P\u00fablicas (DGCP).&nbsp;.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre la campa\u00f1a Y4OD<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se escoger\u00e1n 25 j\u00f3venes que participar\u00e1n en&nbsp;un&nbsp;<a href=\"https:\/\/www.thetrustfortheamericas.org\/media\/events\/attachments\/Programa_de_Capacitacion.pdf\" rel=\"noreferrer noopener\" target=\"_blank\">programa&nbsp;&nbsp;de cuatro m\u00f3dulos de capacitaci\u00f3n&nbsp;mediante sesiones virtuales,<\/a>&nbsp;complementados con talleres presenciales&nbsp;entre los meses de&nbsp;julio&nbsp;y septiembre. Durante este tiempo, los participantes&nbsp;desarrollar\u00e1n sus proyectos enfocados en el uso de datos.&nbsp;&nbsp;Los mejores proyectos ser\u00e1n premiados con una beca para presentar sus ideas en&nbsp;un evento de cierre en la ciudad de Panam\u00e1. Esta iniciativa sentar\u00e1 las bases del ecosistema juvenil de datos abiertos en preparaci\u00f3n para&nbsp;las Conferencias Regionales de Datos Abiertos&nbsp;AbreLatam&nbsp;y&nbsp;Condatos&nbsp;2020, a llevarse a cabo en&nbsp;el&nbsp;pa\u00eds.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rodrigo&nbsp;Iriani, Project Manager&nbsp;de&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas,&nbsp;comenta sobre el objetivo de la&nbsp;campa\u00f1a \u00a8buscamos&nbsp;proveer oportunidades concretas a j\u00f3venes estudiantes, entusiastas en tecnolog\u00eda y organizaciones juveniles de distintas regiones para desarrollar capacidades, instrumentar iniciativas innovadoras que utilicen datos abiertos para mejorar sus comunidades\u00a8.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, L\u00eda Hern\u00e1ndez,&nbsp;Directora de Instituto Paname\u00f1o de Derecho y Nuevas Tecnolog\u00edas (IPANDETEC) comenta sobre el resultado esperado: \u00a8Esta iniciativa sienta las bases de la creaci\u00f3n&nbsp;&nbsp;de un ecosistema juvenil de datos abiertos a nivel nacional, con el potencial de representaci\u00f3n en las distintas instancias ya institucionalizadas en el pa\u00eds en la tem\u00e1tica de los datos y gobierno abierto, como la Comisi\u00f3n Nacional de Gobierno Abierto. Adem\u00e1s de inculcarles&nbsp;valores que les servir\u00e1n como herramientas en sus acciones ciudadanas&nbsp;para&nbsp;generar&nbsp;cambios en sus diferentes \u00e1mbitos de acci\u00f3n\u00a8.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los datos abiertos son para todos&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta iniciativa tiene el objetivo de&nbsp;ampliar el uso de los datos a todo nivel. Durante la selecci\u00f3n de los&nbsp;25&nbsp;participantes se tomar\u00e1 en cuenta el equilibrio de g\u00e9nero y geogr\u00e1fico. Los estudiantes seleccionados tendr\u00e1n representaci\u00f3n de la Ciudad Capital y del Interior del pa\u00eds: Comarca Ng\u00e4be-Bugl\u00e9, Guna Yala, Chiriqu\u00ed, Veraguas, Herrera, Los Santos, Cocl\u00e9, Col\u00f3n, Dari\u00e9n,&nbsp;Panam\u00e1 Este&nbsp;y Oeste.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/forms.office.com\/Pages\/ResponsePage.aspx?id=thX63ibPVEyXyxaXqy3fwEisAAgMDZ5PuRL4JmDn1mlUQjIyT0pIR0E2OFFOUUoxVzZJQlQ5UUkyUS4u\" rel=\"noreferrer noopener\" target=\"_blank\">Reg\u00edstrate aqu\u00ed<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sigue nuestros HT:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#Y4ODPanama&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#OpenGovPanama&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas:&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas,&nbsp;The&nbsp;Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la sobre la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n,&nbsp;The&nbsp;Trust contin\u00faa contribuyendo a superar los desaf\u00edos promoviendo alianzas estrat\u00e9gicas que generan resultados sostenibles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una organizaci\u00f3n sin fines de lucro 501 (c) (3) de la Ciudad de Washington DC.\u202f\u202f&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visite:&nbsp;<a href=\"http:\/\/www.trustfortheamericas.org\/\" rel=\"noreferrer noopener\" target=\"_blank\">www.trustfortheamericas.org<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:&nbsp;<a href=\"https:\/\/www.facebook.com\/TheTrustfortheAmericas\/\" rel=\"noreferrer noopener\" target=\"_blank\">The Trust for the Americas<\/a>&nbsp; Twitter:&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/twitter.com\/Trust4Americas\" rel=\"noreferrer noopener\" target=\"_blank\">@Trust4Americas<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Panam\u00e1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.trustfortheamericas.org\/media\/press-room\/articles\/attachments\/Kick_Off_-_Y4OD.jpg\" target=\"_blank\" rel=\"noreferrer noopener\">Flyer Kick Off<\/a><a href=\"https:\/\/www.trustfortheamericas.org\/media\/press-room\/articles\/attachments\/Kick_Off_-_Y4OD.jpg\"><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Washington DC,&nbsp;26&nbsp;de mayo 2020.-&nbsp;En el marco del proyecto \u201cInnovaci\u00f3n a trav\u00e9s de Datos Abiertos en Panam\u00e1\u201d,&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;de la Organizaci\u00f3n de Estados Americanos (OEA)&nbsp;lanza&nbsp;una campa\u00f1a de sensibilizaci\u00f3n en datos abiertos para j\u00f3venes de distintos sectores y provincias de la Rep\u00fablica de Panam\u00e1, con la finalidad de promover la participaci\u00f3n ciudadana,&nbsp;representaci\u00f3n territorial en la tem\u00e1tica y la formaci\u00f3n de l\u00edderes en temas relacionados a Datos Abiertos, Gobierno Abierto y Periodismo de Datos.&nbsp;&nbsp; Este componente del proyecto&nbsp;es implementado&nbsp;en&nbsp;alianza con el Instituto Paname\u00f1o de Derecho y Nuevas Tecnolog\u00edas (IPANDETEC) y en&nbsp;coordinaci\u00f3n&nbsp;con&nbsp;la&nbsp;Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI),&nbsp;la Autoridad para la Innovaci\u00f3n Gubernamental (AIG)&nbsp;y&nbsp;la Direcci\u00f3n General de Contrataciones P\u00fablicas (DGCP).&nbsp;.&nbsp;&nbsp; Sobre la campa\u00f1a Y4OD Se escoger\u00e1n 25 j\u00f3venes que participar\u00e1n en&nbsp;un&nbsp;programa&nbsp;&nbsp;de cuatro m\u00f3dulos de capacitaci\u00f3n&nbsp;mediante sesiones virtuales,&nbsp;complementados con talleres presenciales&nbsp;entre los meses de&nbsp;julio&nbsp;y septiembre. Durante este tiempo, los participantes&nbsp;desarrollar\u00e1n sus proyectos enfocados en el uso de datos.&nbsp;&nbsp;Los mejores proyectos ser\u00e1n premiados con una beca para presentar sus ideas en&nbsp;un evento de cierre en la ciudad de Panam\u00e1. Esta iniciativa sentar\u00e1 las bases del ecosistema juvenil de datos abiertos en preparaci\u00f3n para&nbsp;las Conferencias Regionales de Datos Abiertos&nbsp;AbreLatam&nbsp;y&nbsp;Condatos&nbsp;2020, a llevarse a cabo en&nbsp;el&nbsp;pa\u00eds.&nbsp; Rodrigo&nbsp;Iriani, Project Manager&nbsp;de&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas,&nbsp;comenta sobre el objetivo de la&nbsp;campa\u00f1a \u00a8buscamos&nbsp;proveer oportunidades concretas a j\u00f3venes estudiantes, entusiastas en tecnolog\u00eda y organizaciones juveniles de distintas regiones para desarrollar capacidades, instrumentar iniciativas innovadoras que utilicen datos abiertos para mejorar sus comunidades\u00a8.&nbsp; Por su parte, L\u00eda Hern\u00e1ndez,&nbsp;Directora de Instituto Paname\u00f1o de Derecho y Nuevas Tecnolog\u00edas (IPANDETEC) comenta sobre el resultado esperado: \u00a8Esta iniciativa sienta las bases de la creaci\u00f3n&nbsp;&nbsp;de un ecosistema juvenil de datos abiertos a nivel nacional, con el potencial de representaci\u00f3n en las distintas instancias ya institucionalizadas en el pa\u00eds en la tem\u00e1tica de los datos y gobierno abierto, como la Comisi\u00f3n Nacional de Gobierno Abierto. Adem\u00e1s de inculcarles&nbsp;valores que les servir\u00e1n como herramientas en sus acciones ciudadanas&nbsp;para&nbsp;generar&nbsp;cambios en sus diferentes \u00e1mbitos de acci\u00f3n\u00a8.&nbsp; Los datos abiertos son para todos&nbsp; Esta iniciativa tiene el objetivo de&nbsp;ampliar el uso de los datos a todo nivel. Durante la selecci\u00f3n de los&nbsp;25&nbsp;participantes se tomar\u00e1 en cuenta el equilibrio de g\u00e9nero y geogr\u00e1fico. Los estudiantes seleccionados tendr\u00e1n representaci\u00f3n de la Ciudad Capital y del Interior del pa\u00eds: Comarca Ng\u00e4be-Bugl\u00e9, Guna Yala, Chiriqu\u00ed, Veraguas, Herrera, Los Santos, Cocl\u00e9, Col\u00f3n, Dari\u00e9n,&nbsp;Panam\u00e1 Este&nbsp;y Oeste.&nbsp; Reg\u00edstrate aqu\u00ed&nbsp; Sigue nuestros HT: #Y4ODPanama&nbsp; #OpenGovPanama&nbsp; Sobre&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas:&nbsp; The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas,&nbsp;The&nbsp;Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la sobre la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n,&nbsp;The&nbsp;Trust contin\u00faa contribuyendo a superar los desaf\u00edos promoviendo alianzas estrat\u00e9gicas que generan resultados sostenibles.&nbsp; The Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una organizaci\u00f3n sin fines de lucro 501 (c) (3) de la Ciudad de Washington DC.\u202f\u202f&nbsp;&nbsp;&nbsp;&nbsp; Visite:&nbsp;www.trustfortheamericas.org&nbsp; Facebook:&nbsp;The Trust for the Americas&nbsp; Twitter:&nbsp;&nbsp;&nbsp;@Trust4Americas&nbsp; Panam\u00e1 Flyer Kick Off<\/p>","protected":false},"author":38,"featured_media":7968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=7967"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7967\/revisions"}],"predecessor-version":[{"id":7969,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7967\/revisions\/7969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/7968"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=7967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=7967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=7967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}