{"id":7940,"date":"2020-10-30T15:50:00","date_gmt":"2020-10-30T15:50:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7940"},"modified":"2024-11-20T03:52:29","modified_gmt":"2024-11-20T03:52:29","slug":"potenciando-el-emprendimiento-innovador-conecta-2020","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/potenciando-el-emprendimiento-innovador-conecta-2020\/","title":{"rendered":"Potenciando el Emprendimiento Innovador CONECTA 2020"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>29<\/strong>&nbsp;<strong>de octubre de 2020 \/ San Juan, Puerto Rico<\/strong>&nbsp;\u2013 AES Puerto Rico, en alianza con la organizaci\u00f3n The Trust For The Americas, abri\u00f3 hoy la convocatoria del proyecto Potenciando el Emprendimiento Innovador CONECTA, con el prop\u00f3sito de fortalecer nuevas ideas de negocios o microempresas ya existentes en la isla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto, que se lleva a cabo por tercer a\u00f1o consecutivo, inici\u00f3 con la premiaci\u00f3n y reconocimiento a los 10 emprendedores que participaron en el 2018 y 2019 por la resiliencia de sus emprendimientos en tiempos de crisis y grandes desaf\u00edos. De igual forma, se inici\u00f3 el plazo para solicitar participaci\u00f3n en el pr\u00f3ximo ciclo del proyecto, que da comienzo este 29 de octubre del 2020 con la selecci\u00f3n de 20 emprendedores para recibir incentivos econ\u00f3micos y capacitaci\u00f3n. Los ganadores ser\u00e1n escogidos por un comit\u00e9 de cinco miembros que evaluar\u00e1n criterios tales como impacto social, n\u00famero de beneficiados, compromiso demostrado por los participantes, mejoras en oportunidades de empleo e innovaci\u00f3n del negocio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn AES Puerto Rico adem\u00e1s de estar comprometido con la transici\u00f3n energ\u00e9tica de Puerto Rico y tambi\u00e9n le da prioridad al desarrollo socioecon\u00f3mico de sus comunidades a trav\u00e9s de proyectos sociales que contengan el factor de sostenibilidad como una forma de generar condiciones de empleo y contribuir con el desarrollo humano en las comunidades en donde operamos\u201d, coment\u00f3 Jesus Bolinaga, presidente de AES Puerto Rico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El prop\u00f3sito del proyecto Potenciando el Emprendimiento Innovador CONECTA 2020\/2021 es fortalecer nuevas ideas de negocios o microempresas existentes con un proceso de capacitaci\u00f3n integral en metodolog\u00edas de innovaci\u00f3n, desarrollo de modelos de negocio, transformaci\u00f3n digital, habilidades empresariales y mentor\u00edas en aceleraci\u00f3n empresarial y capital semilla para los mejores emprendimientos seleccionados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte Linda Eddleman, directora ejecutiva de The Trust For the Americas, afirm\u00f3 que \u201cnuestra misi\u00f3n como The Trust For the Americas es acercar el conocimiento y las herramientas necesarias para que las comunidades generen oportunidades econ\u00f3micas, sean sostenibles y mejoren su calidad de vida, la de sus familias e impacten el crecimiento de sus comunidades. Esta alianza del The Trust For the Americas con AES Puerto Rico es parte del compromiso continuo con el futuro de la isla, para fomentar el emprendimiento como un camino claro para el desarrollo sostenible.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los microempresarios que deseen conocer los requisitos pueden acceder a la p\u00e1gina de Facebook&nbsp;<a href=\"https:\/\/www.facebook.com\/groups\/conectapuertorico\">https:\/\/www.facebook.com\/groups\/conectapuertorico<\/a>&nbsp;o solicitar ingreso al proyecto al proyecto Potenciando el Emprendimiento Innovador CONECTA 2020\/2021 deben acceder a&nbsp;<a href=\"https:\/\/n9.cl\/yzqc\">https:\/\/n9.cl\/yzqc<\/a>&nbsp;&nbsp;para m\u00e1s detalles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust For The Americas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. TheTrust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3). M\u00e1s informaci\u00f3n www.thetrustfortheamericas.org<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre AES Puerto Rico<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">AES-PR es una subsidiaria de la Corporaci\u00f3n AES (NYSE:AES), una compa\u00f1\u00eda de energ\u00eda global. La Corporaci\u00f3n AES opera un portafolio de 34,000 MW, diversificado por tipo de combustible, incluyendo m\u00e1s de 3,000 MW en proyectos solares y e\u00f3licos en operaciones o en construcci\u00f3n. AES-PR provee energ\u00eda segura, confiable y al m\u00e1s bajo costo. Actualmente, AES-PR produce aproximadamente el 25% de la electricidad de Puerto Rico. Las operaciones de AES-PR contribuyen a la econom\u00eda de la Isla a trav\u00e9s de la generaci\u00f3n de 110 empleos directos y 600 indirectos, proveyendo importantes oportunidades laborales.&nbsp; AES-PR ha diversificado la producci\u00f3n de energ\u00eda en la Isla a trav\u00e9s de AES Ilumina, una instalaci\u00f3n solar de 20 MW. AES Corp. se ha trazado una meta ambiciosa, reducir la generaci\u00f3n de carb\u00f3n de su portafolio a menos de 10% para el a\u00f1o 2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Puerto Rico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>29&nbsp;de octubre de 2020 \/ San Juan, Puerto Rico&nbsp;\u2013 AES Puerto Rico, en alianza con la organizaci\u00f3n The Trust For The Americas, abri\u00f3 hoy la convocatoria del proyecto Potenciando el Emprendimiento Innovador CONECTA, con el prop\u00f3sito de fortalecer nuevas ideas de negocios o microempresas ya existentes en la isla. El proyecto, que se lleva a cabo por tercer a\u00f1o consecutivo, inici\u00f3 con la premiaci\u00f3n y reconocimiento a los 10 emprendedores que participaron en el 2018 y 2019 por la resiliencia de sus emprendimientos en tiempos de crisis y grandes desaf\u00edos. De igual forma, se inici\u00f3 el plazo para solicitar participaci\u00f3n en el pr\u00f3ximo ciclo del proyecto, que da comienzo este 29 de octubre del 2020 con la selecci\u00f3n de 20 emprendedores para recibir incentivos econ\u00f3micos y capacitaci\u00f3n. Los ganadores ser\u00e1n escogidos por un comit\u00e9 de cinco miembros que evaluar\u00e1n criterios tales como impacto social, n\u00famero de beneficiados, compromiso demostrado por los participantes, mejoras en oportunidades de empleo e innovaci\u00f3n del negocio. \u201cEn AES Puerto Rico adem\u00e1s de estar comprometido con la transici\u00f3n energ\u00e9tica de Puerto Rico y tambi\u00e9n le da prioridad al desarrollo socioecon\u00f3mico de sus comunidades a trav\u00e9s de proyectos sociales que contengan el factor de sostenibilidad como una forma de generar condiciones de empleo y contribuir con el desarrollo humano en las comunidades en donde operamos\u201d, coment\u00f3 Jesus Bolinaga, presidente de AES Puerto Rico. El prop\u00f3sito del proyecto Potenciando el Emprendimiento Innovador CONECTA 2020\/2021 es fortalecer nuevas ideas de negocios o microempresas existentes con un proceso de capacitaci\u00f3n integral en metodolog\u00edas de innovaci\u00f3n, desarrollo de modelos de negocio, transformaci\u00f3n digital, habilidades empresariales y mentor\u00edas en aceleraci\u00f3n empresarial y capital semilla para los mejores emprendimientos seleccionados.&nbsp; Por su parte Linda Eddleman, directora ejecutiva de The Trust For the Americas, afirm\u00f3 que \u201cnuestra misi\u00f3n como The Trust For the Americas es acercar el conocimiento y las herramientas necesarias para que las comunidades generen oportunidades econ\u00f3micas, sean sostenibles y mejoren su calidad de vida, la de sus familias e impacten el crecimiento de sus comunidades. Esta alianza del The Trust For the Americas con AES Puerto Rico es parte del compromiso continuo con el futuro de la isla, para fomentar el emprendimiento como un camino claro para el desarrollo sostenible.\u201d Los microempresarios que deseen conocer los requisitos pueden acceder a la p\u00e1gina de Facebook&nbsp;https:\/\/www.facebook.com\/groups\/conectapuertorico&nbsp;o solicitar ingreso al proyecto al proyecto Potenciando el Emprendimiento Innovador CONECTA 2020\/2021 deben acceder a&nbsp;https:\/\/n9.cl\/yzqc&nbsp;&nbsp;para m\u00e1s detalles. Sobre The Trust For The Americas The Trust for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. TheTrust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3). M\u00e1s informaci\u00f3n www.thetrustfortheamericas.org Sobre AES Puerto Rico AES-PR es una subsidiaria de la Corporaci\u00f3n AES (NYSE:AES), una compa\u00f1\u00eda de energ\u00eda global. La Corporaci\u00f3n AES opera un portafolio de 34,000 MW, diversificado por tipo de combustible, incluyendo m\u00e1s de 3,000 MW en proyectos solares y e\u00f3licos en operaciones o en construcci\u00f3n. AES-PR provee energ\u00eda segura, confiable y al m\u00e1s bajo costo. Actualmente, AES-PR produce aproximadamente el 25% de la electricidad de Puerto Rico. Las operaciones de AES-PR contribuyen a la econom\u00eda de la Isla a trav\u00e9s de la generaci\u00f3n de 110 empleos directos y 600 indirectos, proveyendo importantes oportunidades laborales.&nbsp; AES-PR ha diversificado la producci\u00f3n de energ\u00eda en la Isla a trav\u00e9s de AES Ilumina, una instalaci\u00f3n solar de 20 MW. AES Corp. se ha trazado una meta ambiciosa, reducir la generaci\u00f3n de carb\u00f3n de su portafolio a menos de 10% para el a\u00f1o 2030. Puerto Rico<\/p>","protected":false},"author":38,"featured_media":7941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=7940"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7940\/revisions"}],"predecessor-version":[{"id":7942,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7940\/revisions\/7942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/7941"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=7940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=7940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=7940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}