{"id":7925,"date":"2020-12-03T15:41:00","date_gmt":"2020-12-03T15:41:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7925"},"modified":"2024-11-20T03:43:03","modified_gmt":"2024-11-20T03:43:03","slug":"foro-govtech-ofrece-espacio-de-intercambio-de-buenas-practicas-en-materia-de-gobierno-digital-en-centro-america","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/foro-govtech-ofrece-espacio-de-intercambio-de-buenas-practicas-en-materia-de-gobierno-digital-en-centro-america\/","title":{"rendered":"Foro GovTech ofrece espacio de intercambio de buenas pr\u00e1cticas en materia de gobierno digital en Centro Am\u00e9rica"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li>Siguiendo el \u00e9xito del Foro\u00a0GovTech\u00a0Latam,\u00a0presentamos la\u00a0primera edici\u00f3n del Foro\u00a0GovTech\u00a0Costa Rica 2020\u00a0<\/li>\n\n\n\n<li>Asistieron m\u00e1s de 200 personas a la\u00a0conferencia, posicion\u00e1ndose como un evento de\u00a0networking\u00a0muy relevante para el sector de la tecnolog\u00eda para mejorar servicios\u00a0de gobierno.\u00a0<\/li>\n\n\n\n<li>Se anunci\u00f3\u00a0el lanzamiento del\u00a0Fondo\u00a0Govtech\u00a0CR\u00a0que incluye recursos en capacitaci\u00f3n, plataformas de tecnolog\u00eda\u00a0c\u00edvica\u00a0y fondos semilla para el ecosistema\u00a0Govtech.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Washington DC,&nbsp;1&nbsp;de&nbsp;diciembre&nbsp;de 2020.-&nbsp;Siguiendo el \u00e9xito del Foro&nbsp;GovTech&nbsp;Latam,&nbsp;Mexico&nbsp;y Argentina,&nbsp;presentamos la&nbsp;<strong>primera edici\u00f3n del Foro&nbsp;GovTech&nbsp;Costa Rica 2020<\/strong>, organizado por OS City y&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;con el apoyo de INNOVAAP.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Foro&nbsp;GovTech&nbsp;Costa Rica&nbsp;es&nbsp;un encuentro de&nbsp;networking&nbsp;que re\u00fane a los principales actores del sector p\u00fablico, las empresas, la academia y los organismos multilaterales, con el fin de impulsar el ecosistema de tecnolog\u00eda y gobierno en Am\u00e9rica Latina.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento busca&nbsp;fortalecer los v\u00ednculos entre el sector p\u00fablico y el privado, con el fin de impulsar el uso inteligente de las nuevas tecnolog\u00edas en la mejora de los servicios p\u00fablicos y las pr\u00e1cticas democr\u00e1ticas. El Foro&nbsp;GovTech&nbsp;Costa Rica es una nueva forma de fortalecer el ecosistema regional de gobierno digital y tecnolog\u00eda c\u00edvica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lucas&nbsp;Jol\u00edas, CEO de&nbsp;OSCity&nbsp;comenta&nbsp;\u201cEste encuentro&nbsp;nace con nuestro convencimiento de que nos encontramos en un momento propicio para difundir actividades que permitan compartir ideas relacionadas con la transformaci\u00f3n digital del Estado, la transparencia y el gobierno abierto, y el ecosistema&nbsp;GovTech&nbsp;en general.\u201d&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Al finalizar el Foro GovTech Costa Rica,&nbsp;The Trust for the Americas, OSCity e Innovaap&nbsp;anunciaron el lanzamiento&nbsp;del Fondo GovTech CR.<\/strong>&nbsp;Con esta iniciativa se buscar apoyar al Gobierno de Costa Rica en su proceso de Transformaci\u00f3n&nbsp;Digital involucrando a la academia, sector p\u00fablico y privado y organismos multilaterales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rodrigo&nbsp;Iriani, Gerente del&nbsp;Programa&nbsp;DIA&nbsp;de&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;comenta sobre las&nbsp;expectativas&nbsp;de&nbsp;acceso de cara al anuncio del Fondo&nbsp;GovTech&nbsp;Costa Rica:&nbsp;\u201cEl fondo va a estar disponible para todas las entidades de gobiernos nacionales y&nbsp;subnacionales&nbsp;que quieran participar. Es un primer paso para promover la inversi\u00f3n de recursos en temas de tecnolog\u00eda para mejorar los servicios a los ciudadanos, con el objetivo de seguir sumando aliados en esta materia\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento se llev\u00f3 a cabo en la plataforma Hopin, lo cual permiti\u00f3 la<strong>&nbsp;participaci\u00f3n de m\u00e1s de&nbsp;200 personas.&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ang\u00e9lica Vega, Coordinadora del Laboratorio de innovaci\u00f3n de la Universidad de Costa Rica,&nbsp;Innovaap, comenta acerca del evento y el lanzamiento del Fondo&nbsp;GovTech&nbsp;en Costa Rica \u201cEsta iniciativa viene a&nbsp;facilitar&nbsp;un espacio de encuentro&nbsp;y de generaci\u00f3n de confianza que permite a los diversos actores tanto nacionales como territoriales potenciar&nbsp;las capacidades en&nbsp;GovTech&nbsp;con el apoyo de las buenas experiencias internacionales. Es sumamente importante, marca un inicio de acciones coordinadas, de incentivos y de espacios de discusi\u00f3n que&nbsp;abren oportunidades \u00fanicas para el ecosistema&nbsp;Govtech&nbsp;en el pa\u00eds.\u201d&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;franquicia&nbsp;del Foro&nbsp;GovTech&nbsp;se&nbsp;seguir\u00e1 promocionando en otras ciudades de&nbsp;Iberoam\u00e9rica&nbsp;para continuar&nbsp;fomentando&nbsp;los espacios de colaboraci\u00f3n y transparencia de gobiernos<strong>, siendo la pr\u00f3xima edici\u00f3n en Madrid el 10 de diciembre de 2020.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para inscripciones y mayor informaci\u00f3n visita:&nbsp;<a href=\"https:\/\/hopin.com\/events\/foro-govtech-madrid\" rel=\"noreferrer noopener\" target=\"_blank\">https:\/\/hopin.com\/events\/foro-govtech-madrid<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre&nbsp;The Trust for the Americas:&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The&nbsp;Trust\u202ffor&nbsp;the&nbsp;Americas&nbsp;es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas,&nbsp;The&nbsp;Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n,&nbsp;The&nbsp;Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TheTrust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una organizaci\u00f3n&nbsp;sin fines de lucro 501 (c) (3) de la Ciudad de Washington DC.\u202f\u202f\u202f\u202f\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visite:&nbsp;<a href=\"http:\/\/www.trustfortheamericas.org\/\" rel=\"noreferrer noopener\" target=\"_blank\">www.trustfortheamericas.org<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:&nbsp;<a href=\"https:\/\/www.facebook.com\/TheTrustfortheAmericas\/\" rel=\"noreferrer noopener\" target=\"_blank\">The Trust for the Americas<\/a>&nbsp; Twitter:&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/twitter.com\/Trust4Americas\" rel=\"noreferrer noopener\" target=\"_blank\">@Trust4Americas<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Costa Rica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Washington DC,&nbsp;1&nbsp;de&nbsp;diciembre&nbsp;de 2020.-&nbsp;Siguiendo el \u00e9xito del Foro&nbsp;GovTech&nbsp;Latam,&nbsp;Mexico&nbsp;y Argentina,&nbsp;presentamos la&nbsp;primera edici\u00f3n del Foro&nbsp;GovTech&nbsp;Costa Rica 2020, organizado por OS City y&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;con el apoyo de INNOVAAP.&nbsp; El Foro&nbsp;GovTech&nbsp;Costa Rica&nbsp;es&nbsp;un encuentro de&nbsp;networking&nbsp;que re\u00fane a los principales actores del sector p\u00fablico, las empresas, la academia y los organismos multilaterales, con el fin de impulsar el ecosistema de tecnolog\u00eda y gobierno en Am\u00e9rica Latina.&nbsp; El evento busca&nbsp;fortalecer los v\u00ednculos entre el sector p\u00fablico y el privado, con el fin de impulsar el uso inteligente de las nuevas tecnolog\u00edas en la mejora de los servicios p\u00fablicos y las pr\u00e1cticas democr\u00e1ticas. El Foro&nbsp;GovTech&nbsp;Costa Rica es una nueva forma de fortalecer el ecosistema regional de gobierno digital y tecnolog\u00eda c\u00edvica.&nbsp; Lucas&nbsp;Jol\u00edas, CEO de&nbsp;OSCity&nbsp;comenta&nbsp;\u201cEste encuentro&nbsp;nace con nuestro convencimiento de que nos encontramos en un momento propicio para difundir actividades que permitan compartir ideas relacionadas con la transformaci\u00f3n digital del Estado, la transparencia y el gobierno abierto, y el ecosistema&nbsp;GovTech&nbsp;en general.\u201d&nbsp;&nbsp; Al finalizar el Foro GovTech Costa Rica,&nbsp;The Trust for the Americas, OSCity e Innovaap&nbsp;anunciaron el lanzamiento&nbsp;del Fondo GovTech CR.&nbsp;Con esta iniciativa se buscar apoyar al Gobierno de Costa Rica en su proceso de Transformaci\u00f3n&nbsp;Digital involucrando a la academia, sector p\u00fablico y privado y organismos multilaterales.&nbsp; Rodrigo&nbsp;Iriani, Gerente del&nbsp;Programa&nbsp;DIA&nbsp;de&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;comenta sobre las&nbsp;expectativas&nbsp;de&nbsp;acceso de cara al anuncio del Fondo&nbsp;GovTech&nbsp;Costa Rica:&nbsp;\u201cEl fondo va a estar disponible para todas las entidades de gobiernos nacionales y&nbsp;subnacionales&nbsp;que quieran participar. Es un primer paso para promover la inversi\u00f3n de recursos en temas de tecnolog\u00eda para mejorar los servicios a los ciudadanos, con el objetivo de seguir sumando aliados en esta materia\u201d.&nbsp; El evento se llev\u00f3 a cabo en la plataforma Hopin, lo cual permiti\u00f3 la&nbsp;participaci\u00f3n de m\u00e1s de&nbsp;200 personas.&nbsp;&nbsp; Ang\u00e9lica Vega, Coordinadora del Laboratorio de innovaci\u00f3n de la Universidad de Costa Rica,&nbsp;Innovaap, comenta acerca del evento y el lanzamiento del Fondo&nbsp;GovTech&nbsp;en Costa Rica \u201cEsta iniciativa viene a&nbsp;facilitar&nbsp;un espacio de encuentro&nbsp;y de generaci\u00f3n de confianza que permite a los diversos actores tanto nacionales como territoriales potenciar&nbsp;las capacidades en&nbsp;GovTech&nbsp;con el apoyo de las buenas experiencias internacionales. Es sumamente importante, marca un inicio de acciones coordinadas, de incentivos y de espacios de discusi\u00f3n que&nbsp;abren oportunidades \u00fanicas para el ecosistema&nbsp;Govtech&nbsp;en el pa\u00eds.\u201d&nbsp; La&nbsp;franquicia&nbsp;del Foro&nbsp;GovTech&nbsp;se&nbsp;seguir\u00e1 promocionando en otras ciudades de&nbsp;Iberoam\u00e9rica&nbsp;para continuar&nbsp;fomentando&nbsp;los espacios de colaboraci\u00f3n y transparencia de gobiernos, siendo la pr\u00f3xima edici\u00f3n en Madrid el 10 de diciembre de 2020.&nbsp; Para inscripciones y mayor informaci\u00f3n visita:&nbsp;https:\/\/hopin.com\/events\/foro-govtech-madrid&nbsp; Sobre&nbsp;The Trust for the Americas:&nbsp; The&nbsp;Trust\u202ffor&nbsp;the&nbsp;Americas&nbsp;es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas,&nbsp;The&nbsp;Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n,&nbsp;The&nbsp;Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp; TheTrust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una organizaci\u00f3n&nbsp;sin fines de lucro 501 (c) (3) de la Ciudad de Washington DC.\u202f\u202f\u202f\u202f\u202f&nbsp; Visite:&nbsp;www.trustfortheamericas.org&nbsp; Facebook:&nbsp;The Trust for the Americas&nbsp; Twitter:&nbsp;&nbsp;&nbsp;@Trust4Americas&nbsp; Costa Rica<\/p>","protected":false},"author":38,"featured_media":7926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7925","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=7925"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7925\/revisions"}],"predecessor-version":[{"id":7927,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7925\/revisions\/7927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/7926"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=7925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=7925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=7925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}