{"id":7695,"date":"2021-05-28T17:34:00","date_gmt":"2021-05-28T17:34:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7695"},"modified":"2024-11-19T05:35:47","modified_gmt":"2024-11-19T05:35:47","slug":"eidos-global-y-the-trust-for-the-americas-impulsan-habilidades-para-el-futuro-dirigido-a-docentes-en-ecuador","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/eidos-global-y-the-trust-for-the-americas-impulsan-habilidades-para-el-futuro-dirigido-a-docentes-en-ecuador\/","title":{"rendered":"Eidos Global y The Trust for the Americas impulsan \u201cHabilidades para el Futuro\u201d dirigido a docentes en Ecuador"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Las capacitaciones est\u00e1n destinadas a docentes que buscan mejorar su conocimiento en habilidades digitales para la empleabilidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eidos Global y The Trust for the Americas, instituci\u00f3n afiliada a la Organizaci\u00f3n de Estados Americanos (OEA), con el apoyo de Microsoft impulsan el programa \u201cHabilidades para el Futuro,\u201d una iniciativa de formaci\u00f3n en destrezas digitales enfocada a potenciar el desarrollo de la empleabilidad en Latinoam\u00e9rica. La capacitaci\u00f3n impulsada por el programa se enfoca en la ense\u00f1anza conjunta de contenidos digitales y habilidades cognitivas y socioemocionales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa est\u00e1 dirigido a docentes de cualquier instituci\u00f3n, que cuenten con un nivel m\u00ednimo de alfabetizaci\u00f3n digital y quieran mejorar sus habilidades laborales a trav\u00e9s del uso de software. &nbsp;El curso est\u00e1 desarrollado en un formato adaptable y replicable, lo cual facilita su implementaci\u00f3n por parte de los gobiernos y organizaciones que lo llevan adelante.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La capacitaci\u00f3n es virtual y se combinan instancias sincr\u00f3nicas, con un formador dando clase a trav\u00e9s de la plataforma Microsoft Teams, e instancias asincr\u00f3nicas, en las que los participantes siguen las gu\u00edas &nbsp;a su propio tiempo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa se desarrolla de manera 100% virtual y sin costo. Las personas educadoras tendr\u00e1n acceso a una metodolog\u00eda creativa e innovadora para facilitar los espacios de aprendizaje virtual en habilidades digitales y sociales con las herramientas de Microsoft.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diana Andrade, coordinadora de la Franquicia Social POETA en Ecuador, coment\u00f3 que \u201cel futuro se nos presenta con grandes y nuevos desaf\u00edos, por lo tanto, las personas educadoras, docentes y facilitadores, tienen en sus manos la gran responsabilidad de seguir adquiriendo importantes destrezas para que la poblaci\u00f3n con la que trabajan pueda abrir, ampliar o mejorar sus oportunidades en el mundo laboral\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las inscripciones estar\u00e1n abiertas hasta el pr\u00f3ximo 7 de junio con cupo limitado. Las personas interesadas podr\u00e1n registrarse en http:\/\/bit.ly\/ec-habilidadesfuturo&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust for the Americas ha apoyado iniciativas en Ecuador desde 2008, en especial apoyando proyectos de capacitaci\u00f3n en tecnolog\u00eda para la generaci\u00f3n de oportunidades econ\u00f3micas para poblaci\u00f3n en situaci\u00f3n de vulnerabilidad, siempre en alianza con organizaciones locales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mayor informaci\u00f3n\u202fentra en: &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visite:\u202f&nbsp;https:\/\/www.trustfortheamericas.org\/programs\/POETA\/poeta-digispark&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:\u202fThe Trust for the Americas\u202f&nbsp;Twitter:\u202f@Trust4Americas &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre The Trust for the Americas: &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. www.trustfortheamericas.org&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Ecuador<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Las capacitaciones est\u00e1n destinadas a docentes que buscan mejorar su conocimiento en habilidades digitales para la empleabilidad.&nbsp; Eidos Global y The Trust for the Americas, instituci\u00f3n afiliada a la Organizaci\u00f3n de Estados Americanos (OEA), con el apoyo de Microsoft impulsan el programa \u201cHabilidades para el Futuro,\u201d una iniciativa de formaci\u00f3n en destrezas digitales enfocada a potenciar el desarrollo de la empleabilidad en Latinoam\u00e9rica. La capacitaci\u00f3n impulsada por el programa se enfoca en la ense\u00f1anza conjunta de contenidos digitales y habilidades cognitivas y socioemocionales.&nbsp; El programa est\u00e1 dirigido a docentes de cualquier instituci\u00f3n, que cuenten con un nivel m\u00ednimo de alfabetizaci\u00f3n digital y quieran mejorar sus habilidades laborales a trav\u00e9s del uso de software. &nbsp;El curso est\u00e1 desarrollado en un formato adaptable y replicable, lo cual facilita su implementaci\u00f3n por parte de los gobiernos y organizaciones que lo llevan adelante.&nbsp; La capacitaci\u00f3n es virtual y se combinan instancias sincr\u00f3nicas, con un formador dando clase a trav\u00e9s de la plataforma Microsoft Teams, e instancias asincr\u00f3nicas, en las que los participantes siguen las gu\u00edas &nbsp;a su propio tiempo.&nbsp; El programa se desarrolla de manera 100% virtual y sin costo. Las personas educadoras tendr\u00e1n acceso a una metodolog\u00eda creativa e innovadora para facilitar los espacios de aprendizaje virtual en habilidades digitales y sociales con las herramientas de Microsoft.&nbsp; Diana Andrade, coordinadora de la Franquicia Social POETA en Ecuador, coment\u00f3 que \u201cel futuro se nos presenta con grandes y nuevos desaf\u00edos, por lo tanto, las personas educadoras, docentes y facilitadores, tienen en sus manos la gran responsabilidad de seguir adquiriendo importantes destrezas para que la poblaci\u00f3n con la que trabajan pueda abrir, ampliar o mejorar sus oportunidades en el mundo laboral\u201d.&nbsp; Las inscripciones estar\u00e1n abiertas hasta el pr\u00f3ximo 7 de junio con cupo limitado. Las personas interesadas podr\u00e1n registrarse en http:\/\/bit.ly\/ec-habilidadesfuturo&nbsp; The Trust for the Americas ha apoyado iniciativas en Ecuador desde 2008, en especial apoyando proyectos de capacitaci\u00f3n en tecnolog\u00eda para la generaci\u00f3n de oportunidades econ\u00f3micas para poblaci\u00f3n en situaci\u00f3n de vulnerabilidad, siempre en alianza con organizaciones locales.&nbsp; Para mayor informaci\u00f3n\u202fentra en: &nbsp;&nbsp; Visite:\u202f&nbsp;https:\/\/www.trustfortheamericas.org\/programs\/POETA\/poeta-digispark&nbsp; Facebook:\u202fThe Trust for the Americas\u202f&nbsp;Twitter:\u202f@Trust4Americas &nbsp; Sobre The Trust for the Americas: &nbsp; The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. www.trustfortheamericas.org&nbsp; Ecuador<\/p>","protected":false},"author":38,"featured_media":7696,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=7695"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7695\/revisions"}],"predecessor-version":[{"id":7697,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7695\/revisions\/7697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/7696"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=7695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=7695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=7695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}