{"id":7464,"date":"2024-05-17T14:36:37","date_gmt":"2024-05-17T14:36:37","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7464"},"modified":"2024-11-14T14:37:43","modified_gmt":"2024-11-14T14:37:43","slug":"the-trust-for-the-americas-microsoft-y-parquesoft-narino-inauguran-el-centro-poeta-ia-en-colombia","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/the-trust-for-the-americas-microsoft-y-parquesoft-narino-inauguran-el-centro-poeta-ia-en-colombia\/","title":{"rendered":"The Trust for the Americas, Microsoft y ParqueSoft Nari\u00f1o inauguran el Centro POETA IA en Colombia"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2024\/05\/17<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nari\u00f1o, Colombia. 16 de mayo, 2024&nbsp;<\/strong>\u2013 Al igual que Internet, la inteligencia artificial es una tecnolog\u00eda que influye y seguir\u00e1 influyendo en diversos aspectos de la econom\u00eda, por eso, The Trust for the Americas (The Trust), Microsoft y ParqueSoft Nari\u00f1o tienen el placer de anunciar la apertura del primer&nbsp;<strong>Centro POETA de Inteligencia Artificial (IA)<\/strong>&nbsp;como un hito significativo en el fortalecimiento de la infraestructura tecnol\u00f3gica y la promoci\u00f3n de la innovaci\u00f3n en la regi\u00f3n de Nari\u00f1o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconociendo la necesidad de crear entornos propicios para el avance tecnol\u00f3gico, The Trust ha establecido los centros POETA, espacios innovadores en 22 pa\u00edses, desarrollados en colaboraci\u00f3n con organizaciones locales, donde se capacita a la comunidad en habilidades digitales. Con el apoyo de Microsoft durante dos d\u00e9cadas, The Trust for the Americas ha expandido su red desde un \u00fanico centro a casi cuatrocientos en todo el hemisferio. En esta ocasi\u00f3n, se inaugura el Centro POETA IA, dedicado exclusivamente a la formaci\u00f3n en inteligencia artificial&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La inauguraci\u00f3n tuvo lugar el jueves 16 de mayo en el Centro de Emprendimiento Digital y Tecnol\u00f3gico de Pasto. En este evento se realizaron actividades para fomentar la interacci\u00f3n y el aprendizaje en torno a la inteligencia artificial. Destacando entre estas din\u00e1micas, se estableci\u00f3 un muro interactivo sobre inteligencia artificial, donde los participantes compartieron sus ideas y perspectivas mediante una nube de palabras. Adem\u00e1s, se exhibieron pantallas que presentaban datos relevantes y una l\u00ednea de tiempo que ilustraba la evoluci\u00f3n de la IA, utilizando la realidad aumentada.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su discurso, Catalina Rengifo, directora de Filantrop\u00eda para Suram\u00e9rica Hispanoparlante de Microsoft, coment\u00f3:&nbsp;<em>\u201cEn Microsoft, creemos firmemente que la tecnolog\u00eda es un puente hacia un futuro m\u00e1s inclusivo y equitativo. A trav\u00e9s de nuestra alianza con The Trust, nos comprometemos a democratizar la tecnolog\u00eda para que nadie se quede atr\u00e1s, empoderando a todas las personas con las herramientas necesarias para prosperar en la era de la inteligencia artificial. Es imperativo que el acceso a la IA se democratice ahora m\u00e1s que nunca, para cerrar las brechas digitales y abrir un mundo de oportunidades significativas para nuestro pa\u00eds.\u201d&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En representaci\u00f3n de Linda Eddleman, CEO de The Trust for the Americas, Luz Marina Correa, Gerente de Proyectos coment\u00f3:&nbsp;<em>&#8220;Desde The Trust for the Americas, nos enorgullece inaugurar este Centro POETA IA como un testimonio de nuestro compromiso continuo con el desarrollo tecnol\u00f3gico inclusivo en la regi\u00f3n. Este centro representa un lugar donde la inteligencia artificial es una herramienta y una fuente de oportunidades econ\u00f3micas. Es un s\u00edmbolo del poder de las alianzas entre sectores, donde el potencial transformador de la IA en los emprendimientos y en la empleabilidad, se convierte en una realidad palpable para la comunidad de Nari\u00f1o.&#8221;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el transcurso del evento, se ofreci\u00f3 la descarga gratuita del Ebook &#8220;El Zumo de la Manga edici\u00f3n IA&#8221;, una obra que explora el impacto y las posibilidades de la inteligencia artificial en diversos \u00e1mbitos. Tambi\u00e9n se llev\u00f3 a cabo un Bootcamp de desaf\u00edos IA, titulado &#8220;AI4Oceans&#8221;, con el prop\u00f3sito de encontrar soluciones innovadoras para la conservaci\u00f3n y protecci\u00f3n de los oc\u00e9anos mediante el uso de la inteligencia artificial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, se organiz\u00f3 un Workshop centrado en el juego &#8220;Innovatr\u00f3n&#8221;, el cual abord\u00f3 aspectos de creatividad, imaginaci\u00f3n, tecnolog\u00eda con IA y la promoci\u00f3n de la innovaci\u00f3n a trav\u00e9s del desarrollo de ideas empresariales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ingeniero Gelber Mor\u00e1n Silva, director ejecutivo de ParqueSoft Nari\u00f1o, coment\u00f3:&nbsp;<em>\u201cJuntos, podemos aprovechar el potencial transformador de la inteligencia artificial y construir un futuro m\u00e1s innovador y pr\u00f3spero para todos.\u201d&nbsp;<\/em>Adicionalmente, destac\u00f3 el respaldo de las organizaciones del orden p\u00fablico y privado para que este Centro POETA IA mantenga un dinamismo que permita atraer oportunidades para el territorio, a trav\u00e9s de la mesa de sostenibilidad conformada por 26 organizaciones.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La apertura del Centro POETA IA marca el comienzo de una nueva era de innovaci\u00f3n y oportunidades en Colombia. M\u00e1s que simplemente un espacio f\u00edsico, este centro es un faro de oportunidades y conocimientos, dise\u00f1ado para impulsar el aprendizaje y la excelencia en el campo de la inteligencia artificial. Respaldado por la s\u00f3lida colaboraci\u00f3n entre The Trust for the Americas, Microsoft y ParqueSoft Nari\u00f1o, este centro se convertir\u00e1 en un epicentro de creatividad y descubrimiento, inspirando a la comunidad local a explorar nuevas fronteras y desatar todo el potencial transformador de la IA en la regi\u00f3n y m\u00e1s all\u00e1.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>***\u202f\u202f&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:\u202f&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3).\u202f\u202f\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Colombia<\/p>","protected":false},"excerpt":{"rendered":"<p>2024\/05\/17 Nari\u00f1o, Colombia. 16 de mayo, 2024&nbsp;\u2013 Al igual que Internet, la inteligencia artificial es una tecnolog\u00eda que influye y seguir\u00e1 influyendo en diversos aspectos de la econom\u00eda, por eso, The Trust for the Americas (The Trust), Microsoft y ParqueSoft Nari\u00f1o tienen el placer de anunciar la apertura del primer&nbsp;Centro POETA de Inteligencia Artificial (IA)&nbsp;como un hito significativo en el fortalecimiento de la infraestructura tecnol\u00f3gica y la promoci\u00f3n de la innovaci\u00f3n en la regi\u00f3n de Nari\u00f1o.&nbsp; Reconociendo la necesidad de crear entornos propicios para el avance tecnol\u00f3gico, The Trust ha establecido los centros POETA, espacios innovadores en 22 pa\u00edses, desarrollados en colaboraci\u00f3n con organizaciones locales, donde se capacita a la comunidad en habilidades digitales. Con el apoyo de Microsoft durante dos d\u00e9cadas, The Trust for the Americas ha expandido su red desde un \u00fanico centro a casi cuatrocientos en todo el hemisferio. En esta ocasi\u00f3n, se inaugura el Centro POETA IA, dedicado exclusivamente a la formaci\u00f3n en inteligencia artificial&nbsp; La inauguraci\u00f3n tuvo lugar el jueves 16 de mayo en el Centro de Emprendimiento Digital y Tecnol\u00f3gico de Pasto. En este evento se realizaron actividades para fomentar la interacci\u00f3n y el aprendizaje en torno a la inteligencia artificial. Destacando entre estas din\u00e1micas, se estableci\u00f3 un muro interactivo sobre inteligencia artificial, donde los participantes compartieron sus ideas y perspectivas mediante una nube de palabras. Adem\u00e1s, se exhibieron pantallas que presentaban datos relevantes y una l\u00ednea de tiempo que ilustraba la evoluci\u00f3n de la IA, utilizando la realidad aumentada.&nbsp; En su discurso, Catalina Rengifo, directora de Filantrop\u00eda para Suram\u00e9rica Hispanoparlante de Microsoft, coment\u00f3:&nbsp;\u201cEn Microsoft, creemos firmemente que la tecnolog\u00eda es un puente hacia un futuro m\u00e1s inclusivo y equitativo. A trav\u00e9s de nuestra alianza con The Trust, nos comprometemos a democratizar la tecnolog\u00eda para que nadie se quede atr\u00e1s, empoderando a todas las personas con las herramientas necesarias para prosperar en la era de la inteligencia artificial. Es imperativo que el acceso a la IA se democratice ahora m\u00e1s que nunca, para cerrar las brechas digitales y abrir un mundo de oportunidades significativas para nuestro pa\u00eds.\u201d&nbsp;&nbsp; En representaci\u00f3n de Linda Eddleman, CEO de The Trust for the Americas, Luz Marina Correa, Gerente de Proyectos coment\u00f3:&nbsp;&#8220;Desde The Trust for the Americas, nos enorgullece inaugurar este Centro POETA IA como un testimonio de nuestro compromiso continuo con el desarrollo tecnol\u00f3gico inclusivo en la regi\u00f3n. Este centro representa un lugar donde la inteligencia artificial es una herramienta y una fuente de oportunidades econ\u00f3micas. Es un s\u00edmbolo del poder de las alianzas entre sectores, donde el potencial transformador de la IA en los emprendimientos y en la empleabilidad, se convierte en una realidad palpable para la comunidad de Nari\u00f1o.&#8221; En el transcurso del evento, se ofreci\u00f3 la descarga gratuita del Ebook &#8220;El Zumo de la Manga edici\u00f3n IA&#8221;, una obra que explora el impacto y las posibilidades de la inteligencia artificial en diversos \u00e1mbitos. Tambi\u00e9n se llev\u00f3 a cabo un Bootcamp de desaf\u00edos IA, titulado &#8220;AI4Oceans&#8221;, con el prop\u00f3sito de encontrar soluciones innovadoras para la conservaci\u00f3n y protecci\u00f3n de los oc\u00e9anos mediante el uso de la inteligencia artificial.&nbsp; Finalmente, se organiz\u00f3 un Workshop centrado en el juego &#8220;Innovatr\u00f3n&#8221;, el cual abord\u00f3 aspectos de creatividad, imaginaci\u00f3n, tecnolog\u00eda con IA y la promoci\u00f3n de la innovaci\u00f3n a trav\u00e9s del desarrollo de ideas empresariales.&nbsp; El Ingeniero Gelber Mor\u00e1n Silva, director ejecutivo de ParqueSoft Nari\u00f1o, coment\u00f3:&nbsp;\u201cJuntos, podemos aprovechar el potencial transformador de la inteligencia artificial y construir un futuro m\u00e1s innovador y pr\u00f3spero para todos.\u201d&nbsp;Adicionalmente, destac\u00f3 el respaldo de las organizaciones del orden p\u00fablico y privado para que este Centro POETA IA mantenga un dinamismo que permita atraer oportunidades para el territorio, a trav\u00e9s de la mesa de sostenibilidad conformada por 26 organizaciones.&nbsp; La apertura del Centro POETA IA marca el comienzo de una nueva era de innovaci\u00f3n y oportunidades en Colombia. M\u00e1s que simplemente un espacio f\u00edsico, este centro es un faro de oportunidades y conocimientos, dise\u00f1ado para impulsar el aprendizaje y la excelencia en el campo de la inteligencia artificial. Respaldado por la s\u00f3lida colaboraci\u00f3n entre The Trust for the Americas, Microsoft y ParqueSoft Nari\u00f1o, este centro se convertir\u00e1 en un epicentro de creatividad y descubrimiento, inspirando a la comunidad local a explorar nuevas fronteras y desatar todo el potencial transformador de la IA en la regi\u00f3n y m\u00e1s all\u00e1.&nbsp; ***\u202f\u202f&nbsp; Sobre The Trust for the Americas:\u202f&nbsp; The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.\u202f&nbsp; The Trust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3).\u202f\u202f\u202f&nbsp; Colombia<\/p>","protected":false},"author":37,"featured_media":7465,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=7464"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7464\/revisions"}],"predecessor-version":[{"id":7466,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7464\/revisions\/7466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/7465"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=7464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=7464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=7464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}