{"id":7279,"date":"2024-11-07T19:51:28","date_gmt":"2024-11-07T19:51:28","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7279"},"modified":"2025-07-14T22:38:07","modified_gmt":"2025-07-14T22:38:07","slug":"fundacion-terra-y-the-trust-for-the-americas-anuncian-la-apertura-del-primer-centro-de-ia","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/fundacion-terra-y-the-trust-for-the-americas-anuncian-la-apertura-del-primer-centro-de-ia\/","title":{"rendered":"Fundaci\u00f3n Terra y The Trust for the Americas anuncian la apertura del primer Centro de IA"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2024\/11\/07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tegucigalpa, Honduras \u2013 07 de noviembre&nbsp;\u2013 En respuesta a la creciente demanda de habilidades digitales en el mundo actual, The Trust for the Americas y Fundaci\u00f3n Terra, con el apoyo de Microsoft, inauguran el primer Centro de Inteligencia Artificial (IA) en Honduras. Este innovador centro, ubicado en el Centro de Formaci\u00f3n Profesional San Juan Bosco, ofrecer\u00e1 a los j\u00f3venes hondure\u00f1os la oportunidad de desarrollar habilidades en IA y tecnolog\u00eda digital, promoviendo el acceso a nuevas oportunidades y empoderando a una generaci\u00f3n para enfrentar los desaf\u00edos del futuro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el Foro Econ\u00f3mico Mundial, el 23% de los empleos a nivel global experimentar\u00e1n cambios en los pr\u00f3ximos cinco a\u00f1os debido a la adopci\u00f3n de tecnolog\u00edas avanzadas como la IA. Conscientes de esta realidad, The Trust for the Americas y Fundaci\u00f3n Terra est\u00e1n comprometidos en reducir la brecha digital y asegurar que la juventud hondure\u00f1a cuente con las herramientas necesarias para prosperar en una econom\u00eda globalizada y digitalizada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNuestra misi\u00f3n es crear oportunidades donde m\u00e1s se necesitan,\u201d afirm\u00f3 Ver\u00f3nica Philippe de The Trust for the Americas. \u201cEste Centro de IA es un paso crucial para garantizar que los j\u00f3venes de Honduras puedan acceder a las habilidades y recursos que les permitir\u00e1n convertirse en l\u00edderes de cambio en sus comunidades y actores clave en la econom\u00eda digital.\u201d&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Fundaci\u00f3n Terra destac\u00f3 el valor de esta alianza estrat\u00e9gica y el impacto de llevar la tecnolog\u00eda avanzada a la comunidad local. \u201cEste Centro no solo brinda formaci\u00f3n t\u00e9cnica; promueve la creatividad, la innovaci\u00f3n y la preparaci\u00f3n de los j\u00f3venes para un mundo laboral en transformaci\u00f3n,\u201d expres\u00f3 un representante de Fundaci\u00f3n Terra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este proyecto forma parte de la iniciativa POETA DigiSpark de The Trust for the Americas, que opera en 11 pa\u00edses y est\u00e1 dise\u00f1ado para empoderar a personas mayores de 16 a\u00f1os mediante acceso a herramientas tecnol\u00f3gicas y programas educativos que fomentan la inclusi\u00f3n econ\u00f3mica y educativa en la regi\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento de inauguraci\u00f3n reuni\u00f3 a l\u00edderes de la comunidad, representantes del sector tecnol\u00f3gico y j\u00f3venes beneficiarios, quienes celebraron juntos el potencial transformador de este nuevo espacio en Honduras.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre The Trust for the Americas&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust for the Americas, una organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA), promueve la inclusi\u00f3n social y econ\u00f3mica en todo el continente americano. A trav\u00e9s de proyectos innovadores y asociaciones estrat\u00e9gicas, The Trust empodera a las personas con las habilidades y oportunidades para mejorar sus vidas y comunidades en el nuevo mundo del trabajo.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre Fundaci\u00f3n Terra:&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fundaci\u00f3n Terra es una Organizaci\u00f3n no Gubernamental de desarrollo con amplia trayectoria en implementaci\u00f3n de programas y proyectos en Honduras, Guatemala, El Salvador y Nicaragua. Su accionar social se concentra en objetivos que buscan mejorar la calidad de vida, el bienestar socioecon\u00f3mico y el medioambiente de nuestras comunidades mediante 4 ejes de acci\u00f3n: educaci\u00f3n de calidad, Infraestructura social, emprendimiento y ambiente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre Microsoft:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La misi\u00f3n de Microsoft es \u201cempoderar a cada persona y organizaci\u00f3n en el planeta para lograr m\u00e1s\u201d&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contacto de prensa:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carlos Escalante, Gerente de Comunicaci\u00f3n&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">+1 202 370 9865&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"mailto:cescalante@20.9.190.97\" target=\"_blank\" rel=\"noreferrer noopener\">cescalante@20.9.190.97<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Honduras<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>2024\/11\/07 Tegucigalpa, Honduras \u2013 07 de noviembre&nbsp;\u2013 En respuesta a la creciente demanda de habilidades digitales en el mundo actual, The Trust for the Americas y Fundaci\u00f3n Terra, con el apoyo de Microsoft, inauguran el primer Centro de Inteligencia Artificial (IA) en Honduras. Este innovador centro, ubicado en el Centro de Formaci\u00f3n Profesional San Juan Bosco, ofrecer\u00e1 a los j\u00f3venes hondure\u00f1os la oportunidad de desarrollar habilidades en IA y tecnolog\u00eda digital, promoviendo el acceso a nuevas oportunidades y empoderando a una generaci\u00f3n para enfrentar los desaf\u00edos del futuro.&nbsp; De acuerdo con el Foro Econ\u00f3mico Mundial, el 23% de los empleos a nivel global experimentar\u00e1n cambios en los pr\u00f3ximos cinco a\u00f1os debido a la adopci\u00f3n de tecnolog\u00edas avanzadas como la IA. Conscientes de esta realidad, The Trust for the Americas y Fundaci\u00f3n Terra est\u00e1n comprometidos en reducir la brecha digital y asegurar que la juventud hondure\u00f1a cuente con las herramientas necesarias para prosperar en una econom\u00eda globalizada y digitalizada. \u201cNuestra misi\u00f3n es crear oportunidades donde m\u00e1s se necesitan,\u201d afirm\u00f3 Ver\u00f3nica Philippe de The Trust for the Americas. \u201cEste Centro de IA es un paso crucial para garantizar que los j\u00f3venes de Honduras puedan acceder a las habilidades y recursos que les permitir\u00e1n convertirse en l\u00edderes de cambio en sus comunidades y actores clave en la econom\u00eda digital.\u201d&nbsp; Por su parte, Fundaci\u00f3n Terra destac\u00f3 el valor de esta alianza estrat\u00e9gica y el impacto de llevar la tecnolog\u00eda avanzada a la comunidad local. \u201cEste Centro no solo brinda formaci\u00f3n t\u00e9cnica; promueve la creatividad, la innovaci\u00f3n y la preparaci\u00f3n de los j\u00f3venes para un mundo laboral en transformaci\u00f3n,\u201d expres\u00f3 un representante de Fundaci\u00f3n Terra.&nbsp; Este proyecto forma parte de la iniciativa POETA DigiSpark de The Trust for the Americas, que opera en 11 pa\u00edses y est\u00e1 dise\u00f1ado para empoderar a personas mayores de 16 a\u00f1os mediante acceso a herramientas tecnol\u00f3gicas y programas educativos que fomentan la inclusi\u00f3n econ\u00f3mica y educativa en la regi\u00f3n.&nbsp; El evento de inauguraci\u00f3n reuni\u00f3 a l\u00edderes de la comunidad, representantes del sector tecnol\u00f3gico y j\u00f3venes beneficiarios, quienes celebraron juntos el potencial transformador de este nuevo espacio en Honduras.&nbsp; Sobre The Trust for the Americas&nbsp; The Trust for the Americas, una organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA), promueve la inclusi\u00f3n social y econ\u00f3mica en todo el continente americano. A trav\u00e9s de proyectos innovadores y asociaciones estrat\u00e9gicas, The Trust empodera a las personas con las habilidades y oportunidades para mejorar sus vidas y comunidades en el nuevo mundo del trabajo.&nbsp;&nbsp; Sobre Fundaci\u00f3n Terra:&nbsp;&nbsp; Fundaci\u00f3n Terra es una Organizaci\u00f3n no Gubernamental de desarrollo con amplia trayectoria en implementaci\u00f3n de programas y proyectos en Honduras, Guatemala, El Salvador y Nicaragua. Su accionar social se concentra en objetivos que buscan mejorar la calidad de vida, el bienestar socioecon\u00f3mico y el medioambiente de nuestras comunidades mediante 4 ejes de acci\u00f3n: educaci\u00f3n de calidad, Infraestructura social, emprendimiento y ambiente.&nbsp; Sobre Microsoft:&nbsp; La misi\u00f3n de Microsoft es \u201cempoderar a cada persona y organizaci\u00f3n en el planeta para lograr m\u00e1s\u201d&nbsp;&nbsp; Contacto de prensa:&nbsp; Carlos Escalante, Gerente de Comunicaci\u00f3n&nbsp;&nbsp; +1 202 370 9865&nbsp;&nbsp; cescalante@20.9.190.97&nbsp; Honduras<\/p>","protected":false},"author":40,"featured_media":12780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=7279"}],"version-history":[{"count":4,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7279\/revisions"}],"predecessor-version":[{"id":7451,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/7279\/revisions\/7451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/12780"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=7279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=7279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=7279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}