{"id":622,"date":"2019-08-20T15:28:28","date_gmt":"2019-08-20T19:28:28","guid":{"rendered":"http:\/\/40.117.174.162\/gobiernos-locales-de-costa-rica-un-paso-mas-cerca-del-estado-abierto\/"},"modified":"2019-08-20T15:28:28","modified_gmt":"2019-08-20T19:28:28","slug":"gobiernos-locales-de-costa-rica-un-paso-mas-cerca-del-estado-abierto","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/gobiernos-locales-de-costa-rica-un-paso-mas-cerca-del-estado-abierto\/","title":{"rendered":"Gobiernos locales de Costa Rica: un paso m\u00e1s cerca del Estado Abierto"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Los gobiernos locales son la instancia m\u00e1s cercana a la ciudadan\u00eda y, por\nlo tanto, son claves para alcanzar un Estado Abierto. En esto coinciden las 104\npersonas de Municipalidades, organizaciones, academia y gobierno que\nparticiparon en el Encuentro Nacional de Municipios Abiertos, el 30 y 31 de\njulio en San Jos\u00e9, Costa Rica.<\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\" size-large\\\"><img src=\"\\\"https:><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Encuentro forma parte del proyecto \u201cDel Gobierno Abierto al Estado Abierto: innovaci\u00f3n y colaboraci\u00f3n sectorial para mejorar servicios de gobierno a nivel municipal en Costa Rica\u201d de The Trust for the Americas con financiamiento de la Embajada de los Estados Unidos. Adem\u00e1s, el Encuentro se realiz\u00f3 en conjunto con el programa de Gobierno Abierto de la Presidencia de la Rep\u00fablica de Costa Rica, el Centro de Investigaci\u00f3n y Capacitaci\u00f3n en Administraci\u00f3n P\u00fablica de la Universidad de Costa Rica y la Escuela de Gobierno de la Organizaci\u00f3n de Estados Americanos.<\/p>\n\n\n\n<ul class=\"\\&quot;wp-block-gallery wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\" columns-3 is-cropped\\\"><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Estos gobiernos locales reciben acompa\u00f1amiento directo de The Trust for the Americas. <\/p>\n\n\n\n<blockquote class=\"\\&quot;wp-block-quote\\&quot; is-layout-flow wp-block-quote-is-layout-flow\"><p>Jorge Uma\u00f1a, Coordinador Regional de The Trust, explica que durante 2019, las municipalidades, se formaron en participaci\u00f3n ciudadana, acceso a informaci\u00f3n y datos abiertos. El encuentro permiti\u00f3 intercambiar experiencias, casos de \u00e9xito y herramientas para mejorar la ruta de estas Municipalidades hacia la apertura.<\/p><\/blockquote>\n\n\n\n<figure class=\"\\\"wp-block-image\" size-large\\\"><img src=\"\\\"https:><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gobiernos locales m\u00e1s presentes, comunidades m\u00e1s activas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos esfuerzos han permitido que, por ejemplo, la Municipalidad de Esparza\nahora cuente con un inventario de datos con responsables asignados, una Comisi\u00f3n\nde Datos Abiertos, un portal de datos abiertos y una iniciativa para permitir\nel acceso de personas ciegas del cant\u00f3n a estos recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La articulaci\u00f3n con organizaciones de sociedad civil tambi\u00e9n ha dado frutos. En San Mateo de Alajuela, el Centro de Desarrollo Gerencial de la Universidad Nacional desarroll\u00f3 un modelo metodol\u00f3gico para identificar y priorizar problem\u00e1ticas y soluciones. El proyecto apoyado por The Trust for the Americas, cre\u00f3 equipos en las localidades del cant\u00f3n y les capacit\u00f3 para abordar problem\u00e1ticas desde la innovaci\u00f3n social. La metodolog\u00eda seguir\u00e1 siendo aplicada por la Municipalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para las personas participantes del Encuentro, los beneficios de\nimplementar el Gobierno Abierto son muchos. La iniciativa les ha permitido generar\nespacios de innovaci\u00f3n con la comunidad; mejorar el flujo de informaci\u00f3n dentro\nde las Municipalidades y hacia la ciudadan\u00eda; crear insumos dirigidos a los\nproblemas que los habitantes consideran prioritarios; y m\u00e1s participaci\u00f3n\nciudadana en la b\u00fasqueda de soluciones.<\/p>\n\n\n\n<ul class=\"\\&quot;wp-block-gallery wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\" columns-3 is-cropped\\\"><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto ahora estar\u00e1 dirigido a la<strong> \u201cRuta Munis Abiertas\u201d.<\/strong> En esta fase, The Trust acompa\u00f1ar\u00e1 a cada una de las Municipalidades en la construcci\u00f3n de planes de acci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Encuentro Nacional de Municipios Abiertos cont\u00f3 con participantes de las Municipalidad de Hojancha, Abangares, Osa, Quepos, Orotina, Esparza, Grecia, Jim\u00e9nez, Turrialba, Pococ\u00ed, Gu\u00e1cimo, La Uni\u00f3n, San Jos\u00e9, Santa Ana, Curridabat, Cartago, Heredia. Asistieron como autoridades locales: Luis Fernando Le\u00f3n, Alcalde de Turrialba; Minor Molina Murillo, Alcalde de Grecia; Rolando Rodr\u00edguez Brenes, Alcalde de Cartago; \u00c9dgar Villarreal, Vicealcalde de Pococ\u00ed; Alicia Borja, Alcaldesa de Curridabat; Flor Valer\u00edn, Vicealcaldesa de Gu\u00e1cimo; Erick Cordero, Vicealcalde de Quepos; y Luis Mario Portuguez Solano, Vicealcalde de Jim\u00e9nez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas<\/strong><\/p>\n\n\n\n<div class=\"\\\"wp-block-group\\\"\"><div class=\"\\&quot;wp-block-group__inner-container\\&quot; is-layout-flow wp-block-group-is-layout-flow\">\n<pre class=\"\\\"wp-block-preformatted\\\"\">The Trust&nbsp;for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida&nbsp;en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo&nbsp;de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar&nbsp;los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. <em>TheTrust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3).<\/em><\/pre>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Los gobiernos locales son la instancia m\u00e1s cercana a la ciudadan\u00eda y, por lo tanto, son claves para alcanzar un Estado Abierto. En esto coinciden las 104 personas de Municipalidades, organizaciones, academia y gobierno que participaron en el Encuentro Nacional de Municipios Abiertos, el 30 y 31 de julio en San Jos\u00e9, Costa Rica. El Encuentro forma parte del proyecto \u201cDel Gobierno Abierto al Estado Abierto: innovaci\u00f3n y colaboraci\u00f3n sectorial para mejorar servicios de gobierno a nivel municipal en Costa Rica\u201d de The Trust for the Americas con financiamiento de la Embajada de los Estados Unidos. Adem\u00e1s, el Encuentro se realiz\u00f3 en conjunto con el programa de Gobierno Abierto de la Presidencia de la Rep\u00fablica de Costa Rica, el Centro de Investigaci\u00f3n y Capacitaci\u00f3n en Administraci\u00f3n P\u00fablica de la Universidad de Costa Rica y la Escuela de Gobierno de la Organizaci\u00f3n de Estados Americanos. Estos gobiernos locales reciben acompa\u00f1amiento directo de The Trust for the Americas. Jorge Uma\u00f1a, Coordinador Regional de The Trust, explica que durante 2019, las municipalidades, se formaron en participaci\u00f3n ciudadana, acceso a informaci\u00f3n y datos abiertos. El encuentro permiti\u00f3 intercambiar experiencias, casos de \u00e9xito y herramientas para mejorar la ruta de estas Municipalidades hacia la apertura. Gobiernos locales m\u00e1s presentes, comunidades m\u00e1s activas Estos esfuerzos han permitido que, por ejemplo, la Municipalidad de Esparza ahora cuente con un inventario de datos con responsables asignados, una Comisi\u00f3n de Datos Abiertos, un portal de datos abiertos y una iniciativa para permitir el acceso de personas ciegas del cant\u00f3n a estos recursos. La articulaci\u00f3n con organizaciones de sociedad civil tambi\u00e9n ha dado frutos. En San Mateo de Alajuela, el Centro de Desarrollo Gerencial de la Universidad Nacional desarroll\u00f3 un modelo metodol\u00f3gico para identificar y priorizar problem\u00e1ticas y soluciones. El proyecto apoyado por The Trust for the Americas, cre\u00f3 equipos en las localidades del cant\u00f3n y les capacit\u00f3 para abordar problem\u00e1ticas desde la innovaci\u00f3n social. La metodolog\u00eda seguir\u00e1 siendo aplicada por la Municipalidad. Para las personas participantes del Encuentro, los beneficios de implementar el Gobierno Abierto son muchos. La iniciativa les ha permitido generar espacios de innovaci\u00f3n con la comunidad; mejorar el flujo de informaci\u00f3n dentro de las Municipalidades y hacia la ciudadan\u00eda; crear insumos dirigidos a los problemas que los habitantes consideran prioritarios; y m\u00e1s participaci\u00f3n ciudadana en la b\u00fasqueda de soluciones. El proyecto ahora estar\u00e1 dirigido a la \u201cRuta Munis Abiertas\u201d. En esta fase, The Trust acompa\u00f1ar\u00e1 a cada una de las Municipalidades en la construcci\u00f3n de planes de acci\u00f3n. El Encuentro Nacional de Municipios Abiertos cont\u00f3 con participantes de las Municipalidad de Hojancha, Abangares, Osa, Quepos, Orotina, Esparza, Grecia, Jim\u00e9nez, Turrialba, Pococ\u00ed, Gu\u00e1cimo, La Uni\u00f3n, San Jos\u00e9, Santa Ana, Curridabat, Cartago, Heredia. Asistieron como autoridades locales: Luis Fernando Le\u00f3n, Alcalde de Turrialba; Minor Molina Murillo, Alcalde de Grecia; Rolando Rodr\u00edguez Brenes, Alcalde de Cartago; \u00c9dgar Villarreal, Vicealcalde de Pococ\u00ed; Alicia Borja, Alcaldesa de Curridabat; Flor Valer\u00edn, Vicealcaldesa de Gu\u00e1cimo; Erick Cordero, Vicealcalde de Quepos; y Luis Mario Portuguez Solano, Vicealcalde de Jim\u00e9nez. Sobre The Trust for the Americas The Trust&nbsp;for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida&nbsp;en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo&nbsp;de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar&nbsp;los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. TheTrust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3).<\/p>","protected":false},"author":4,"featured_media":641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-622","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=622"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/622\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/641"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}