{"id":548,"date":"2019-08-14T13:50:20","date_gmt":"2019-08-14T17:50:20","guid":{"rendered":"http:\/\/40.117.174.162\/lenovo-le-apuesta-a-la-inclusion-digital-en-colombia\/"},"modified":"2019-08-14T13:50:20","modified_gmt":"2019-08-14T17:50:20","slug":"lenovo-le-apuesta-a-la-inclusion-digital-en-colombia","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/lenovo-le-apuesta-a-la-inclusion-digital-en-colombia\/","title":{"rendered":"Lenovo le apuesta a la Inclusi\u00f3n Digital en Colombia"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Lenovo don\u00f3 800 computadores a m\u00e1s de 20 organizaciones a nivel nacional, por una cifra cercana a los 600 millones de pesos, con la cual busca contribuir a generar mayores oportunidades para que personas de escasos recursos puedan acceder a mayor informaci\u00f3n, m\u00e1s conocimiento y mejor educaci\u00f3n. Los j\u00f3venes, ni\u00f1os y ni\u00f1as, ser\u00e1n los mayores beneficiados. <\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\" size-large\\\"><img src=\"\\\"https:><figcaption>En la fotograf\u00eda: Paola Pe\u00f1a, oficial de comunicaciones de Laudes Infantis y Luz Marina Correa, Gerente de Proyectos de The Trust for the Americas. <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Lenovo don\u00f3 a The Trust for the Americas, organizaci\u00f3n afiliada la Organizaci\u00f3n de Estados Americanos (OEA),<strong> 150 computadores <\/strong>para seguir promoviendo oportunidades educativas y econ\u00f3micas en Colombia. Los computadores se donar\u00e1n a Socios Locales Miembros, que tengan un Centro POETA o Centro Mi Llave, centros de tecnolog\u00eda que promueven la inclusi\u00f3n econ\u00f3mica y social y proporcionan herramientas y conocimiento a j\u00f3venes en condici\u00f3n de vulnerabilidad. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/pt\/\"https:>Luz Marina Correa<\/a>, Gerente de Proyectos de Trust for the Americas, lidera  los procesos de fortalecimiento y equipamiento a los Centros Poeta y Mi Llave m\u00e1s destacados en colombia; para generar mayor impacto en el cierre de la brecha digital y los procesos de apropiaci\u00f3n con las TIC en aquellas zonas que m\u00e1s lo necesitan. Agradecemos a Microsoft Colombia por facilitar y vincular a Lenovo en el Impacto de nuestros Programas Sociales en el pa\u00eds.<\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\" size-large\\\"><img src=\"\\\"https:><\/figure>\n\n\n\n<blockquote class=\"\\&quot;wp-block-quote\\&quot; is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cQueremos agradecer a LENOVO por su gran contribuci\u00f3n a los Programas sociales que The Trust for the Americas- OEA implementa en Colombia. Estos equipos de c\u00f3mputo permitir\u00e1n que por lo menos <strong>dos mil mujeres y j\u00f3venes<\/strong> en condici\u00f3n de vulnerabilidad puedan acceder y apropiarse de la tecnolog\u00eda, mediante procesos de capacitaci\u00f3n acorde a las necesidades de las diferentes regiones&nbsp; del pa\u00eds y as\u00ed, generar nuevas y mejores oportunidades econ\u00f3micas y fomentar su desarrollo profesional y personal\u201d Linda Eddleman, Directora Ejecutiva de The Trust for the Americas.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Con este prop\u00f3sito, Lenovo espera que cada dispositivo contribuya de manera significativa a que la mayor\u00eda de las personas se acerquen a la tecnolog\u00eda&nbsp; y sean parte de quienes gozan de acceso al mundo digital en Colombia, sobre todo en la poblaci\u00f3n estudiantil, que seg\u00fan cifras del Ministerio TIC entre el a\u00f1o 2010 y 2018, pas\u00f3 de tener un computador para 24 estudiantes a uno para cada 4, lo cual es un avance significativo que necesita de todo el apoyo posible para seguir creciendo.<\/p>\n\n\n\n<blockquote class=\"\\&quot;wp-block-quote\\&quot; is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEstamos comprometidos en contribuir para que la mayor cantidad de personas tengan oportunidad de cumplir sus sue\u00f1os y sabemos que la tecnolog\u00eda es una herramiento importante para lograrlo\u201d,&nbsp; afirm\u00f3 Santiago Holgu\u00edn, gerente general de Lenovo Colombia.<\/p><\/blockquote>\n\n\n\n<figure class=\"\\\"wp-block-image\" size-large\\\"><img src=\"\\\"https:><figcaption> <br> <br> De izq a derecha: Bibiana Castrill\u00f3n, Coordinadora de Desarrollo Social; Mar\u00eda M\u00f3nica L\u00f3pez, Auxiliar T\u00e9cnica;  Martha Paez, Coordinadora Comunitaria de Usme;  Almudena Rivas, Directora de Desarrollo Social y Productivo y Brigith Galindo, Auxiliar Administrativa de la Fundaci\u00f3n Laudes Infantis.  <\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Lenovo don\u00f3 800 computadores a m\u00e1s de 20 organizaciones a nivel nacional, por una cifra cercana a los 600 millones de pesos, con la cual busca contribuir a generar mayores oportunidades para que personas de escasos recursos puedan acceder a mayor informaci\u00f3n, m\u00e1s conocimiento y mejor educaci\u00f3n. Los j\u00f3venes, ni\u00f1os y ni\u00f1as, ser\u00e1n los mayores beneficiados. Por su parte, Lenovo don\u00f3 a The Trust for the Americas, organizaci\u00f3n afiliada la Organizaci\u00f3n de Estados Americanos (OEA), 150 computadores para seguir promoviendo oportunidades educativas y econ\u00f3micas en Colombia. Los computadores se donar\u00e1n a Socios Locales Miembros, que tengan un Centro POETA o Centro Mi Llave, centros de tecnolog\u00eda que promueven la inclusi\u00f3n econ\u00f3mica y social y proporcionan herramientas y conocimiento a j\u00f3venes en condici\u00f3n de vulnerabilidad. Luz Marina Correa, Gerente de Proyectos de Trust for the Americas, lidera los procesos de fortalecimiento y equipamiento a los Centros Poeta y Mi Llave m\u00e1s destacados en colombia; para generar mayor impacto en el cierre de la brecha digital y los procesos de apropiaci\u00f3n con las TIC en aquellas zonas que m\u00e1s lo necesitan. Agradecemos a Microsoft Colombia por facilitar y vincular a Lenovo en el Impacto de nuestros Programas Sociales en el pa\u00eds. \u201cQueremos agradecer a LENOVO por su gran contribuci\u00f3n a los Programas sociales que The Trust for the Americas- OEA implementa en Colombia. Estos equipos de c\u00f3mputo permitir\u00e1n que por lo menos dos mil mujeres y j\u00f3venes en condici\u00f3n de vulnerabilidad puedan acceder y apropiarse de la tecnolog\u00eda, mediante procesos de capacitaci\u00f3n acorde a las necesidades de las diferentes regiones&nbsp; del pa\u00eds y as\u00ed, generar nuevas y mejores oportunidades econ\u00f3micas y fomentar su desarrollo profesional y personal\u201d Linda Eddleman, Directora Ejecutiva de The Trust for the Americas. Con este prop\u00f3sito, Lenovo espera que cada dispositivo contribuya de manera significativa a que la mayor\u00eda de las personas se acerquen a la tecnolog\u00eda&nbsp; y sean parte de quienes gozan de acceso al mundo digital en Colombia, sobre todo en la poblaci\u00f3n estudiantil, que seg\u00fan cifras del Ministerio TIC entre el a\u00f1o 2010 y 2018, pas\u00f3 de tener un computador para 24 estudiantes a uno para cada 4, lo cual es un avance significativo que necesita de todo el apoyo posible para seguir creciendo. \u201cEstamos comprometidos en contribuir para que la mayor cantidad de personas tengan oportunidad de cumplir sus sue\u00f1os y sabemos que la tecnolog\u00eda es una herramiento importante para lograrlo\u201d,&nbsp; afirm\u00f3 Santiago Holgu\u00edn, gerente general de Lenovo Colombia.<\/p>","protected":false},"author":6,"featured_media":617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=548"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/617"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}