{"id":502,"date":"2019-06-28T11:44:21","date_gmt":"2019-06-28T15:44:21","guid":{"rendered":"http:\/\/40.117.174.162\/ciclo-de-seminarios-en-gobierno-abierto-para-sociedad-civil-sector-privado-y-jovenes-de-panama\/"},"modified":"2019-06-28T11:44:21","modified_gmt":"2019-06-28T15:44:21","slug":"ciclo-de-seminarios-en-gobierno-abierto-para-sociedad-civil-sector-privado-y-jovenes-de-panama","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/ciclo-de-seminarios-en-gobierno-abierto-para-sociedad-civil-sector-privado-y-jovenes-de-panama\/","title":{"rendered":"CICLO DE SEMINARIOS EN GOBIERNO ABIERTO PARA SOCIEDAD CIVIL, SECTOR PRIVADO, Y J\u00d3VENES DE PANAM\u00c1."},"content":{"rendered":"<p class=\"wp-block-paragraph\">El Departamento para la Gesti\u00f3n P\u00fablica Efectiva de la Organizaci\u00f3n de los Estados Americanos y The Trust for the Americas, en coordinaci\u00f3n con la Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI) y la Autoridad Nacional para la Innovaci\u00f3n Gubernamental (AIG), imparten un ciclo de capacitaciones a participantes de organizaciones de sociedad civil, el sector privado, y j\u00f3venes de Panam\u00e1, en el marco del proyecto \u201cInnovaci\u00f3n p\u00fablica a trav\u00e9s de los Datos Abiertos\u201d con el apoyo de la Embajada<br> de los Estados Unidos de Am\u00e9rica en Panam\u00e1. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los objetivos centrales de este proyecto est\u00e1n dise\u00f1ados para aumentar la apropiaci\u00f3n y asegurar la colaboraci\u00f3n continua entre la sociedad civil, el sector privado, los gobiernos nacionales y sub-nacionales bajo el concepto de gobierno abierto. En el proceso, este proyecto imparte un ciclo de seminarios, los cuales buscan ofrecer mayor claridad y comprensi\u00f3n acerca de \u00e1reas complementarias de la administraci\u00f3n p\u00fablica que tienden a entrelazarse, como lo son gobierno abierto, gobierno digital y datos abiertos. El ciclo de<br> seminarios se imparte en modalidad virtual y\/o presencial (semi-presencial), tendientes a elevar el nivel de conocimiento, capacidades, y pericia pr\u00e1ctica de los interesados en las materias citadas.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al final de estas capacitaciones, los participantes tendr\u00e1n un amplio conocimiento con el cual podr\u00e1n aportar a un continuo y mejor envolvimiento de actores no-gubernamentales en procesos de gobierno. Asimismo, las organizaciones de sociedad civil aumentar\u00e1n su involucramiento en procesos de co-creaci\u00f3n, tales como la construcci\u00f3n de planes de acci\u00f3n de gobierno abierto, generando confianza, y abriendo mecanismos de consulta, lo cual se convierte en la base de una gobernanza democr\u00e1tica mejorada. <\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\\\"\"><img src=\"\\\"https:><\/figure>\n\n\n\n<figure class=\"\\\"wp-block-image\\\"\"><img src=\"\\\"https:><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>GENERALIDADES: ASISTENCIA, REGISTRO,<br> CERTIFICACI\u00d3N Y PRODUCTO FINAL<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Las capacitaciones ser\u00e1n facilitadas sincr\u00f3nicamente por la OEA desde Washington DC como seminario virtual, bajo la coordinaci\u00f3n local del Trust en Panam\u00e1 por parte del Gerente de Proyecto en localidades espec\u00edficas que ser\u00e1n anunciadas con antelaci\u00f3n para aquellas personas que deseen o se les facilite participar presencialmente. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada sesi\u00f3n ser\u00e1 impartida por expertos de Am\u00e9rica Latina con reconocida trayectoria en las tem\u00e1ticas. Las sesiones ser\u00e1n documentadas y grabadas como recurso permanente a cualquier actor de sociedad civil, de sector privado, o j\u00f3venes de Panam\u00e1 en general. Los participantes interesados deber\u00e1n registrarse al ciclo de capacitaciones. Solo aquellos participantes que completen m\u00e1s de un 80% de asistencia recibir\u00e1n una certificaci\u00f3n de participaci\u00f3n por parte del proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los seminarios son gratuitos y se les entregar\u00e1 un certificado de participaci\u00f3n a los participantes que atiendan por lo menos un 80% de seminarios del ciclo. Sin embargo, para recibir el certificado, los participantes deber\u00e1n entregar como resultado de su participaci\u00f3n un producto informativo acerca de c\u00f3mo considera que puede aplicar el conocimiento adquirido en su entorno. Los participantes recibir\u00e1n al inicio de su participaci\u00f3n en el ciclo de seminarios una plantilla modelo, que podr\u00e1n completar para estos efectos y deber\u00e1n incluir recursos audiovisuales como videos, presentaciones y\/o fotograf\u00edas que sustenten su producto informativo propuesto.<\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\\\"\"><img src=\"\\\"https:><\/figure>\n\n\n\n<figure class=\"\\\"wp-block-image\\\"\"><img src=\"\\\"https:><\/figure>","protected":false},"excerpt":{"rendered":"<p>El Departamento para la Gesti\u00f3n P\u00fablica Efectiva de la Organizaci\u00f3n de los Estados Americanos y The Trust for the Americas, en coordinaci\u00f3n con la Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI) y la Autoridad Nacional para la Innovaci\u00f3n Gubernamental (AIG), imparten un ciclo de capacitaciones a participantes de organizaciones de sociedad civil, el sector privado, y j\u00f3venes de Panam\u00e1, en el marco del proyecto \u201cInnovaci\u00f3n p\u00fablica a trav\u00e9s de los Datos Abiertos\u201d con el apoyo de la Embajada de los Estados Unidos de Am\u00e9rica en Panam\u00e1. Los objetivos centrales de este proyecto est\u00e1n dise\u00f1ados para aumentar la apropiaci\u00f3n y asegurar la colaboraci\u00f3n continua entre la sociedad civil, el sector privado, los gobiernos nacionales y sub-nacionales bajo el concepto de gobierno abierto. En el proceso, este proyecto imparte un ciclo de seminarios, los cuales buscan ofrecer mayor claridad y comprensi\u00f3n acerca de \u00e1reas complementarias de la administraci\u00f3n p\u00fablica que tienden a entrelazarse, como lo son gobierno abierto, gobierno digital y datos abiertos. El ciclo de seminarios se imparte en modalidad virtual y\/o presencial (semi-presencial), tendientes a elevar el nivel de conocimiento, capacidades, y pericia pr\u00e1ctica de los interesados en las materias citadas. Al final de estas capacitaciones, los participantes tendr\u00e1n un amplio conocimiento con el cual podr\u00e1n aportar a un continuo y mejor envolvimiento de actores no-gubernamentales en procesos de gobierno. Asimismo, las organizaciones de sociedad civil aumentar\u00e1n su involucramiento en procesos de co-creaci\u00f3n, tales como la construcci\u00f3n de planes de acci\u00f3n de gobierno abierto, generando confianza, y abriendo mecanismos de consulta, lo cual se convierte en la base de una gobernanza democr\u00e1tica mejorada. GENERALIDADES: ASISTENCIA, REGISTRO, CERTIFICACI\u00d3N Y PRODUCTO FINAL Las capacitaciones ser\u00e1n facilitadas sincr\u00f3nicamente por la OEA desde Washington DC como seminario virtual, bajo la coordinaci\u00f3n local del Trust en Panam\u00e1 por parte del Gerente de Proyecto en localidades espec\u00edficas que ser\u00e1n anunciadas con antelaci\u00f3n para aquellas personas que deseen o se les facilite participar presencialmente. Cada sesi\u00f3n ser\u00e1 impartida por expertos de Am\u00e9rica Latina con reconocida trayectoria en las tem\u00e1ticas. Las sesiones ser\u00e1n documentadas y grabadas como recurso permanente a cualquier actor de sociedad civil, de sector privado, o j\u00f3venes de Panam\u00e1 en general. Los participantes interesados deber\u00e1n registrarse al ciclo de capacitaciones. Solo aquellos participantes que completen m\u00e1s de un 80% de asistencia recibir\u00e1n una certificaci\u00f3n de participaci\u00f3n por parte del proyecto. Los seminarios son gratuitos y se les entregar\u00e1 un certificado de participaci\u00f3n a los participantes que atiendan por lo menos un 80% de seminarios del ciclo. Sin embargo, para recibir el certificado, los participantes deber\u00e1n entregar como resultado de su participaci\u00f3n un producto informativo acerca de c\u00f3mo considera que puede aplicar el conocimiento adquirido en su entorno. Los participantes recibir\u00e1n al inicio de su participaci\u00f3n en el ciclo de seminarios una plantilla modelo, que podr\u00e1n completar para estos efectos y deber\u00e1n incluir recursos audiovisuales como videos, presentaciones y\/o fotograf\u00edas que sustenten su producto informativo propuesto.<\/p>","protected":false},"author":6,"featured_media":503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=502"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/503"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}