{"id":2863,"date":"2024-05-02T11:52:34","date_gmt":"2024-05-02T15:52:34","guid":{"rendered":"http:\/\/40.117.174.162\/celebrando-el-empoderamiento-digital-de-las-ninas-en-la-republica-dominicana\/"},"modified":"2025-06-03T21:12:44","modified_gmt":"2025-06-03T21:12:44","slug":"celebrando-el-empoderamiento-digital-de-las-ninas-en-la-republica-dominicana","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/celebrando-el-empoderamiento-digital-de-las-ninas-en-la-republica-dominicana\/","title":{"rendered":"\u00a1Celebrando el Empoderamiento Digital de las Ni\u00f1as en la Rep\u00fablica Dominicana!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Cada a\u00f1o, nuestro apreciado Socio Local CTC Rep\u00fablica Dominicana llena de entusiasmo el calendario con la conmemoraci\u00f3n del \\&#8221;D\u00eda de las Ni\u00f1as en las TIC\\&#8221;. Como el socio local con m\u00e1s Centros POETA en nuestra red, su compromiso con el empoderamiento digital es palpable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado 4 de abril, en muchos de los 108 Centros POETA, se llev\u00f3 a cabo un emocionante encuentro donde chicas desde los 8 a\u00f1os en adelante se congregaron para expresar su determinaci\u00f3n en cerrar la brecha digital y su anhelo por aprender m\u00e1s sobre tecnolog\u00edas digitales d\u00eda a d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante este inspirador evento, nuestra colega Maite Capra ofreci\u00f3 una charla y taller enfocado en las Redes Sociales. En este espacio, se destac\u00f3 el potencial de las redes sociales y se se\u00f1alaron las malas pr\u00e1cticas que es necesario evitar. La sesi\u00f3n fue un rotundo \u00e9xito, con la participaci\u00f3n activa de m\u00e1s de 300 chicas, quienes se empoderaron con este tema y muchos otros m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El compromiso de CTC Rep\u00fablica Dominicana con el desarrollo digital de las ni\u00f1as es un ejemplo inspirador de c\u00f3mo la educaci\u00f3n y el acceso equitativo a la tecnolog\u00eda pueden transformar vidas. Estamos emocionados de seguir colaborando con ellos en esta importante misi\u00f3n de empoderamiento digital.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cada a\u00f1o, nuestro apreciado Socio Local CTC Rep\u00fablica Dominicana llena de entusiasmo el calendario con la conmemoraci\u00f3n del \\&#8221;D\u00eda de las Ni\u00f1as en las TIC\\&#8221;. Como el socio local con m\u00e1s Centros POETA en nuestra red, su compromiso con el empoderamiento digital es palpable. El pasado 4 de abril, en muchos de los 108 Centros POETA, se llev\u00f3 a cabo un emocionante encuentro donde chicas desde los 8 a\u00f1os en adelante se congregaron para expresar su determinaci\u00f3n en cerrar la brecha digital y su anhelo por aprender m\u00e1s sobre tecnolog\u00edas digitales d\u00eda a d\u00eda. Durante este inspirador evento, nuestra colega Maite Capra ofreci\u00f3 una charla y taller enfocado en las Redes Sociales. En este espacio, se destac\u00f3 el potencial de las redes sociales y se se\u00f1alaron las malas pr\u00e1cticas que es necesario evitar. La sesi\u00f3n fue un rotundo \u00e9xito, con la participaci\u00f3n activa de m\u00e1s de 300 chicas, quienes se empoderaron con este tema y muchos otros m\u00e1s. El compromiso de CTC Rep\u00fablica Dominicana con el desarrollo digital de las ni\u00f1as es un ejemplo inspirador de c\u00f3mo la educaci\u00f3n y el acceso equitativo a la tecnolog\u00eda pueden transformar vidas. Estamos emocionados de seguir colaborando con ellos en esta importante misi\u00f3n de empoderamiento digital.<\/p>","protected":false},"author":29,"featured_media":11836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=2863"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2863\/revisions"}],"predecessor-version":[{"id":11837,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2863\/revisions\/11837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/11836"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=2863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=2863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=2863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}