{"id":2850,"date":"2024-04-30T12:25:15","date_gmt":"2024-04-30T16:25:15","guid":{"rendered":"http:\/\/40.117.174.162\/exito-en-guatemala-el-benemerito-comite-pro-ciegos-y-sordos-culmina-con-exito-la-implementacion-del-proyecto-poeta-digispark-2023\/"},"modified":"2025-06-03T21:31:24","modified_gmt":"2025-06-03T21:31:24","slug":"exito-en-guatemala-el-benemerito-comite-pro-ciegos-y-sordos-culmina-con-exito-la-implementacion-del-proyecto-poeta-digispark-2023","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/exito-en-guatemala-el-benemerito-comite-pro-ciegos-y-sordos-culmina-con-exito-la-implementacion-del-proyecto-poeta-digispark-2023\/","title":{"rendered":"\u00a1\u00c9xito en Guatemala! El Benem\u00e9rito Comit\u00e9 pro Ciegos y Sordos culmina con \u00e9xito la implementaci\u00f3n del Proyecto POETA DigiSpark 2023"},"content":{"rendered":"<p class=\"wp-block-paragraph\">\u00a1El Benem\u00e9rito Comit\u00e9 pro Ciegos y Sordos de Guatemala celebra un gran logro! Durante el mes de marzo, concluy\u00f3 con \u00e9xito la implementaci\u00f3n del Proyecto POETA DigiSpark 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde su uni\u00f3n al Proyecto POETA DigiSpark (PDS)en junio del a\u00f1o pasado, el Benem\u00e9rito Comit\u00e9 ha demostrado un compromiso inquebrantable y ha contado con un equipo excepcional que ha superado con creces las metas establecidas. En Guatemala, se unieron a PDS con tres centros: Ciudad de Guatemala, Quetzaltenango y Carch\u00e1. Desde estos lugares, se impartieron cursos de la Academia Trust con el apoyo de tecnolog\u00eda y lectores de pantalla para personas con discapacidad visual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los resultados obtenidos hablan por s\u00ed solos: Total de personas capacitadas directamente: 359.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante este proceso, el Comit\u00e9 capacit\u00f3 a 276 personas adultas, 83 docentes y se proporcionaron 197 Oportunidades Econ\u00f3micas (OE), logrando un cumplimiento. Adem\u00e1s de estos impresionantes n\u00fameros, queremos compartir una historia inspiradora de \u00e9xito. Marlyn Quino, una joven que perdi\u00f3 la visi\u00f3n durante la infancia, ha encontrado una nueva oportunidad gracias a los esfuerzos conjuntos del Benem\u00e9rito y PDS. Ahora, Marlyn tiene la posibilidad de mejorar su calidad de vida y perseguir sus sue\u00f1os de convertirse en abogada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Benem\u00e9rito Comit\u00e9 pro Ciegos y Sordos de Guatemala contin\u00faa marcando la diferencia y transformando vidas a trav\u00e9s de la implementaci\u00f3n de programas como POETA DigiSpark. Estamos emocionados por ver m\u00e1s historias de \u00e9xito como la de Marlyn y por seguir avanzando juntos hacia un futuro m\u00e1s inclusivo y lleno de oportunidades para todos.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1El Benem\u00e9rito Comit\u00e9 pro Ciegos y Sordos de Guatemala celebra un gran logro! Durante el mes de marzo, concluy\u00f3 con \u00e9xito la implementaci\u00f3n del Proyecto POETA DigiSpark 2023. Desde su uni\u00f3n al Proyecto POETA DigiSpark (PDS)en junio del a\u00f1o pasado, el Benem\u00e9rito Comit\u00e9 ha demostrado un compromiso inquebrantable y ha contado con un equipo excepcional que ha superado con creces las metas establecidas. En Guatemala, se unieron a PDS con tres centros: Ciudad de Guatemala, Quetzaltenango y Carch\u00e1. Desde estos lugares, se impartieron cursos de la Academia Trust con el apoyo de tecnolog\u00eda y lectores de pantalla para personas con discapacidad visual. Los resultados obtenidos hablan por s\u00ed solos: Total de personas capacitadas directamente: 359. Durante este proceso, el Comit\u00e9 capacit\u00f3 a 276 personas adultas, 83 docentes y se proporcionaron 197 Oportunidades Econ\u00f3micas (OE), logrando un cumplimiento. Adem\u00e1s de estos impresionantes n\u00fameros, queremos compartir una historia inspiradora de \u00e9xito. Marlyn Quino, una joven que perdi\u00f3 la visi\u00f3n durante la infancia, ha encontrado una nueva oportunidad gracias a los esfuerzos conjuntos del Benem\u00e9rito y PDS. Ahora, Marlyn tiene la posibilidad de mejorar su calidad de vida y perseguir sus sue\u00f1os de convertirse en abogada. El Benem\u00e9rito Comit\u00e9 pro Ciegos y Sordos de Guatemala contin\u00faa marcando la diferencia y transformando vidas a trav\u00e9s de la implementaci\u00f3n de programas como POETA DigiSpark. Estamos emocionados por ver m\u00e1s historias de \u00e9xito como la de Marlyn y por seguir avanzando juntos hacia un futuro m\u00e1s inclusivo y lleno de oportunidades para todos.<\/p>","protected":false},"author":29,"featured_media":11858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=2850"}],"version-history":[{"count":2,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2850\/revisions"}],"predecessor-version":[{"id":11860,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2850\/revisions\/11860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/11858"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=2850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=2850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=2850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}