{"id":2813,"date":"2024-02-26T21:00:55","date_gmt":"2024-02-27T02:00:55","guid":{"rendered":"http:\/\/40.117.174.162\/empoderamiento-en-accion-jcc-celebra-graduacion-del-proyecto-cima-en-la-ciudad-de-mexico\/"},"modified":"2025-06-03T21:38:00","modified_gmt":"2025-06-03T21:38:00","slug":"empoderamiento-en-accion-jcc-celebra-graduacion-del-proyecto-cima-en-la-ciudad-de-mexico","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/empoderamiento-en-accion-jcc-celebra-graduacion-del-proyecto-cima-en-la-ciudad-de-mexico\/","title":{"rendered":"Empoderamiento en Acci\u00f3n: JCC celebra graduaci\u00f3n del Proyecto CIMA en la Ciudad de M\u00e9xico"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El 15 de febrero fue un d\u00eda especial y lleno de significado, ya que tuve el honor de ser la madrina en la graduaci\u00f3n de 65 participantes del Proyecto CIMA, una iniciativa impulsada por J\u00f3venes Constructores de la Comunidad AC (JCC), nuestro socio local en la vibrante Ciudad de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta jornada de celebraci\u00f3n, dirig\u00ed unas palabras sencillas pero profundas a las graduadas, inst\u00e1ndolas a seguir con determinaci\u00f3n en su camino, a aprovechar cada oportunidad que se les presente y alzar su voz para expresar sus deseos de aprendizaje y crecimiento continuo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante mi discurso, quise resaltar el poder transformador de las alianzas y c\u00f3mo, al unir esfuerzos, podemos convertir ideas en acciones tangibles, contribuyendo as\u00ed a forjar un futuro m\u00e1s pr\u00f3spero para toda la sociedad. La visita no solo fue un momento para celebrar los logros individuales de las participantes, sino tambi\u00e9n para reflexionar sobre el impacto duradero que el Proyecto CIMA tiene en sus vidas y en la comunidad en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiero expresar mi m\u00e1s profundo agradecimiento al dedicado equipo de J\u00f3venes Constructores de la Comunidad por su incansable trabajo y compromiso con el \u00e9xito de las mujeres en la Ciudad de M\u00e9xico. Su labor ha sido fundamental para la implementaci\u00f3n exitosa del Proyecto CIMA durante los \u00faltimos dos a\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2024\/02\/image-1.png\" alt=\"\" class=\"wp-image-11870\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2024\/02\/image-1.png 576w, https:\/\/trust-oea.org\/wp-content\/uploads\/2024\/02\/image-1-169x300.png 169w, https:\/\/trust-oea.org\/wp-content\/uploads\/2024\/02\/image-1-7x12.png 7w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Esta experiencia reafirma mi convicci\u00f3n en el poder de las iniciativas que empoderan a las mujeres y transforman comunidades. Estoy emocionada por el futuro que aguarda a estas mujeres valientes y orgullosa de haber sido parte de su viaje hacia un empoderamiento significativo. Sigamos trabajando juntas para construir un mundo donde todas las mujeres tengan la oportunidad de alcanzar su m\u00e1ximo potencial.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2024\/02\/image-2.png\" alt=\"\" class=\"wp-image-11871\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2024\/02\/image-2.png 1024w, https:\/\/trust-oea.org\/wp-content\/uploads\/2024\/02\/image-2-300x169.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2024\/02\/image-2-768x432.png 768w, https:\/\/trust-oea.org\/wp-content\/uploads\/2024\/02\/image-2-18x10.png 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>","protected":false},"excerpt":{"rendered":"<p>El 15 de febrero fue un d\u00eda especial y lleno de significado, ya que tuve el honor de ser la madrina en la graduaci\u00f3n de 65 participantes del Proyecto CIMA, una iniciativa impulsada por J\u00f3venes Constructores de la Comunidad AC (JCC), nuestro socio local en la vibrante Ciudad de M\u00e9xico. En esta jornada de celebraci\u00f3n, dirig\u00ed unas palabras sencillas pero profundas a las graduadas, inst\u00e1ndolas a seguir con determinaci\u00f3n en su camino, a aprovechar cada oportunidad que se les presente y alzar su voz para expresar sus deseos de aprendizaje y crecimiento continuo. Durante mi discurso, quise resaltar el poder transformador de las alianzas y c\u00f3mo, al unir esfuerzos, podemos convertir ideas en acciones tangibles, contribuyendo as\u00ed a forjar un futuro m\u00e1s pr\u00f3spero para toda la sociedad. La visita no solo fue un momento para celebrar los logros individuales de las participantes, sino tambi\u00e9n para reflexionar sobre el impacto duradero que el Proyecto CIMA tiene en sus vidas y en la comunidad en general. Quiero expresar mi m\u00e1s profundo agradecimiento al dedicado equipo de J\u00f3venes Constructores de la Comunidad por su incansable trabajo y compromiso con el \u00e9xito de las mujeres en la Ciudad de M\u00e9xico. Su labor ha sido fundamental para la implementaci\u00f3n exitosa del Proyecto CIMA durante los \u00faltimos dos a\u00f1os. Esta experiencia reafirma mi convicci\u00f3n en el poder de las iniciativas que empoderan a las mujeres y transforman comunidades. Estoy emocionada por el futuro que aguarda a estas mujeres valientes y orgullosa de haber sido parte de su viaje hacia un empoderamiento significativo. Sigamos trabajando juntas para construir un mundo donde todas las mujeres tengan la oportunidad de alcanzar su m\u00e1ximo potencial.<\/p>","protected":false},"author":36,"featured_media":11872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=2813"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2813\/revisions"}],"predecessor-version":[{"id":11873,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2813\/revisions\/11873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/11872"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=2813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=2813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=2813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}