{"id":2611,"date":"2023-06-28T15:10:57","date_gmt":"2023-06-28T19:10:57","guid":{"rendered":"http:\/\/40.117.174.162\/the-trust-for-the-americas-lanza-su-nuevo-programa-skills-for-sustainability-s4s\/"},"modified":"2025-06-03T22:24:57","modified_gmt":"2025-06-03T22:24:57","slug":"the-trust-for-the-americas-lanza-su-nuevo-programa-skills-for-sustainability-s4s","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/the-trust-for-the-americas-lanza-su-nuevo-programa-skills-for-sustainability-s4s\/","title":{"rendered":"The Trust for the Americas lanza su nuevo programa Skills for Sustainability \u2013 S4S"},"content":{"rendered":"<p class=\"wp-block-paragraph\">The Trust for the Americas lanz\u00f3 este mayo 2023 su primer programa enfocado en capacitaci\u00f3n de fuerza laboral verde. Apalanc\u00e1ndose en la exitosa experiencia de POETA, S4S brindar\u00e1 capacitaci\u00f3n y vinculaci\u00f3n laboral a poblaciones vulnerables y de bajos ingresos para puestos en el sector de gesti\u00f3n de agua y aguas residuales en El Paso, Texas, Estados Unidos, y Ciudad Ju\u00e1rez, Chihuahua, M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este programa busca brindar a poblaciones vulnerables de ambos lados de la frontera EEUU\/M\u00e9xico las habilidades que requieren los empleadores, cerrando la brecha entre las personas que desean una carrera estable, y el sector del agua y las empresas que hacen un uso intensivo de este escaso recurso; las cuales, a su vez, necesitan urgentemente una fuerza laboral calificada para operar sus instalaciones.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"568\" height=\"426\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2023\/06\/image-1.png\" alt=\"\" class=\"wp-image-11938\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2023\/06\/image-1.png 568w, https:\/\/trust-oea.org\/wp-content\/uploads\/2023\/06\/image-1-300x225.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2023\/06\/image-1-16x12.png 16w\" sizes=\"(max-width: 568px) 100vw, 568px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de dos visitas a El Paso y Ciudad Ju\u00e1rez por parte de Jorge M\u00e1rquez Gaspar, Especialista de Desarrollo de Negocios, y Christopher Barton, consultor del proyecto, este programa cuenta con el apoyo financiero del Banco de Desarrollo de America del Norte \u2013 NADBank, Microsoft, y otras empresas privadas, incluyendo Water House Group. Adem\u00e1s, se logr\u00f3 establecer alianzas estrat\u00e9gicas con la Junta Municipal de Aguas y Saneamiento de Ju\u00e1rez, El Paso Water, la C\u00e1mara Nacional de Comercio de Ju\u00e1rez, El Paso Chamber of Commerce, entre otras organizaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de dos meses de reclutamiento de potenciales participantes, este pr\u00f3ximo agosto comenzar\u00e1 la capacitaci\u00f3n de la primera cohorte de 70 beneficiarios del programa junto a J\u00f3venes Constructores de la Comunidad (JCC), nuestro socio local de Ciudad Ju\u00e1rez, y Success Through Technology Education Foundation (STTE) y Western Tech, nuestros socios locales en El Paso.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"768\" height=\"431\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2023\/06\/image.png\" alt=\"\" class=\"wp-image-11937\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2023\/06\/image.png 768w, https:\/\/trust-oea.org\/wp-content\/uploads\/2023\/06\/image-300x168.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2023\/06\/image-18x10.png 18w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00f3ximamente traeremos m\u00e1s noticias sobre este programa que busca promover el desarrollo sostenible de esta regi\u00f3n binacional.<\/p>","protected":false},"excerpt":{"rendered":"<p>The Trust for the Americas lanz\u00f3 este mayo 2023 su primer programa enfocado en capacitaci\u00f3n de fuerza laboral verde. Apalanc\u00e1ndose en la exitosa experiencia de POETA, S4S brindar\u00e1 capacitaci\u00f3n y vinculaci\u00f3n laboral a poblaciones vulnerables y de bajos ingresos para puestos en el sector de gesti\u00f3n de agua y aguas residuales en El Paso, Texas, Estados Unidos, y Ciudad Ju\u00e1rez, Chihuahua, M\u00e9xico. Este programa busca brindar a poblaciones vulnerables de ambos lados de la frontera EEUU\/M\u00e9xico las habilidades que requieren los empleadores, cerrando la brecha entre las personas que desean una carrera estable, y el sector del agua y las empresas que hacen un uso intensivo de este escaso recurso; las cuales, a su vez, necesitan urgentemente una fuerza laboral calificada para operar sus instalaciones. Luego de dos visitas a El Paso y Ciudad Ju\u00e1rez por parte de Jorge M\u00e1rquez Gaspar, Especialista de Desarrollo de Negocios, y Christopher Barton, consultor del proyecto, este programa cuenta con el apoyo financiero del Banco de Desarrollo de America del Norte \u2013 NADBank, Microsoft, y otras empresas privadas, incluyendo Water House Group. Adem\u00e1s, se logr\u00f3 establecer alianzas estrat\u00e9gicas con la Junta Municipal de Aguas y Saneamiento de Ju\u00e1rez, El Paso Water, la C\u00e1mara Nacional de Comercio de Ju\u00e1rez, El Paso Chamber of Commerce, entre otras organizaciones. Luego de dos meses de reclutamiento de potenciales participantes, este pr\u00f3ximo agosto comenzar\u00e1 la capacitaci\u00f3n de la primera cohorte de 70 beneficiarios del programa junto a J\u00f3venes Constructores de la Comunidad (JCC), nuestro socio local de Ciudad Ju\u00e1rez, y Success Through Technology Education Foundation (STTE) y Western Tech, nuestros socios locales en El Paso. Pr\u00f3ximamente traeremos m\u00e1s noticias sobre este programa que busca promover el desarrollo sostenible de esta regi\u00f3n binacional.<\/p>","protected":false},"author":34,"featured_media":11940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=2611"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2611\/revisions"}],"predecessor-version":[{"id":11941,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2611\/revisions\/11941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/11940"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=2611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=2611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=2611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}