{"id":2282,"date":"2022-08-31T12:31:43","date_gmt":"2022-08-31T16:31:43","guid":{"rendered":"http:\/\/40.117.174.162\/fundacion-laudes-infantis-celebro-graduacion-de-70-personas-de-poeta-digispark-en-colombia\/"},"modified":"2022-08-31T12:31:43","modified_gmt":"2022-08-31T16:31:43","slug":"fundacion-laudes-infantis-celebro-graduacion-de-70-personas-de-poeta-digispark-en-colombia","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/fundacion-laudes-infantis-celebro-graduacion-de-70-personas-de-poeta-digispark-en-colombia\/","title":{"rendered":"<strong>Fundaci\u00f3n Laudes Infantis celebr\u00f3 graduaci\u00f3n de 70 personas de <\/strong><strong>DigiSpark <\/strong><strong>en Colombia<\/strong>&nbsp;"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La Fundaci\u00f3n Laudes Infantis, Socio Local POETA DigiSpark en Colombia, celebr\u00f3 la graduaci\u00f3n de 70 personas en la Ciudad de Bogot\u00e1. Con el apoyo de Microsoft Filantrop\u00edas y The Trust for the Americas, estas personas se capacitaron en temas de tecnolog\u00eda y emprendimiento para impulsar sus habilidades y lograr el acceso a mejores oportunidades de empleabilidad.\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se realiz\u00f3 la \u201cMuestra Empresarial\u201d donde 4 emprendedoras y representantes de la Organizaci\u00f3n \u201cPuntos Verdes\u201d mostraron sus productos y servicio, adem\u00e1s de y explicar c\u00f3mo sus conocimientos les ayudar\u00e1n a incrementar sus ventas para mejorar su calidad de vida.\u00a0\u00a0<\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\" aligncenter size-large is-resized\\\"><img src=\"\\\"https:><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el marco de dicha celebraci\u00f3n, Luz Marina Correa, Coordinadora de POETA DigiSpark coment\u00f3 que \u201cpara The Trust for the Americas, es un honor saber que este proyecto es posible gracias a las personas que se capacitan, aprovechan las actividades y los recursos.\u201d Adem\u00e1s, recalc\u00f3 que lo m\u00e1s satisfactorio es reencontrarse despu\u00e9s de varios a\u00f1os, con personas que se han capacitado y evidenciar c\u00f3mo esto ha generado un impacto en su vida, a trav\u00e9s de la obtenci\u00f3n de un empleo, el inicio o continuaci\u00f3n de sus estudios o la puesta en marcha de un negocio; lo cual Luz Marina afirma nos impulsa a continuar con la labor.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sesi\u00f3n fue llevada a cabo en el centro de Laudes Infantis en el Barrio Arrayanes, ubicado en la localidad de Usme en el sur de la ciudad; una zona caracterizada por una alta concentraci\u00f3n de personas en situaci\u00f3n de vulnerabilidad. Durante esta visita, los asistentes tuvieron la oportunidad de conocer el Centro y presentar sus distintas propuestas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Catalina Rengifo, Gerente de proyectos para las Am\u00e9ricas en Microsoft, destac\u00f3 las habilidades y esfuerzos que cada persona hizo para obtener su certificaci\u00f3n \u201cprincipalmente quiero felicitar a cada una de las personas que hoy se grad\u00faan; los que dieron ese extra, los que trabajaron fuerte, los que vieron la oportunidad em ese conocimiento que estaban adquiriendo, los que encontraron la importancia de trabajar y fortalecer habilidades digitales&#8230; a todos ustedes los felicito, son la inspiraci\u00f3n de muchas personas, a m\u00ed me inspira cada uno de ustedes\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la visita, la Organizaci\u00f3n \u201cPuntos Verdes\u201d, especializada en apoyar a emprendedores en sus iniciativas relacionadas con sostenibilidad ambiental, presentaron el programa de reciclaje de dispositivos electr\u00f3nicos, lo que beneficiar\u00e1 a distintas causas sociales y ambientales, a la comunidad que se encuentra en los barrios Arrayanes y Bella Flor y tambi\u00e9n, por supuesto a Laudes Infantis, quienes esperan poder ser un Punto Verde y un centro de recolecci\u00f3n de estos residuos electr\u00f3nicos, para contribuir con el correcto reciclaje de los mismos.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el evento, se present\u00f3 el caso exitoso de Martha Blanco, fundadora de la revista Olympia, donde se tratan temas de inter\u00e9s para las mujeres.&nbsp; Martha explic\u00f3 como logr\u00f3 consolidar la venta de su revista en la localidad y c\u00f3mo ha logrado generar ingreso gracias a las pautas publicitarias.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yessica Pinz\u00f3n, quien fue la mentora de Martha durante este proceso, explic\u00f3 c\u00f3mo se centraron en generar habilidades en marketing, contabilidad, creaci\u00f3n de plantillas, producci\u00f3n de contenidos y pautas publicitarias, las cuales fueron fundamentales para llevar un modelo de negocio exitoso.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al finalizar el evento, Beatriz Rojas, una joven beneficiaria de POETA DigiSpark, quien utiliza los cursos formativos del programa para planear la creaci\u00f3n de su propio emprendimiento: una papeler\u00eda (miscel\u00e1nea)explic\u00f3 c\u00f3mo Laudes Infantis le brind\u00f3 la posibilidad de adquirir m\u00e1s conocimientos acerca del \\&#8221;mundo digital y el emprendimiento, para hacer crecer nuestro negocio\u201d, y los cursos de Excel, Word y PowerPoint, que pondr\u00e1 en pr\u00e1ctica en su negocio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, Almudena Rivas, resalt\u00f3 la importancia de la generaci\u00f3n de habilidades como herramienta para salir de la pobreza, su alegr\u00eda de retomar los eventos y certificaciones presenciales. Agradeci\u00f3 la oportunidad de reunirse y poder celebrar, con las personas que han apostado no solo por la organizaci\u00f3n, sino tambi\u00e9n por el proyecto DigiSpark. Destac\u00f3 que las personas seguir\u00e1n tomando capacitaciones y avanzando en los procesos que brindar\u00e1n en el segundo semestre del a\u00f1o.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este evento cont\u00f3 con la participaci\u00f3n de: Catalina Rengifo, de Microsoft Filantrop\u00eda, quien estuvo de manera virtual, Luz Marina Correa, Gerente de Proyectos en The Trust for The Americas, Almudena Rivas, Directora de Desarrollo Social y Productivo de Fundaci\u00f3n Laudes Infantis, Juan David Fern\u00e1ndez, de la Fundaci\u00f3n Puntos Verdes, Mar\u00eda Camila Guerra, Oficial de Proyectos de The Trust for the Americas y Yessica Pinz\u00f3n, formadora de Laudes Infantis&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mayor informaci\u00f3n:&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visite:\u202f https:\/\/www.trustfortheamericas.org\/programs\/POETA\/poeta-digispark&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:\u202fThe Trust for the Americas\u202fTwitter:\u202f@Trust4Americas&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n Laudes Infantis, Socio Local POETA DigiSpark en Colombia, celebr\u00f3 la graduaci\u00f3n de 70 personas en la Ciudad de Bogot\u00e1. Con el apoyo de Microsoft Filantrop\u00edas y The Trust for the Americas, estas personas se capacitaron en temas de tecnolog\u00eda y emprendimiento para impulsar sus habilidades y lograr el acceso a mejores oportunidades de empleabilidad.\u00a0\u00a0\u00a0 Adem\u00e1s, se realiz\u00f3 la \u201cMuestra Empresarial\u201d donde 4 emprendedoras y representantes de la Organizaci\u00f3n \u201cPuntos Verdes\u201d mostraron sus productos y servicio, adem\u00e1s de y explicar c\u00f3mo sus conocimientos les ayudar\u00e1n a incrementar sus ventas para mejorar su calidad de vida.\u00a0\u00a0 En el marco de dicha celebraci\u00f3n, Luz Marina Correa, Coordinadora de POETA DigiSpark coment\u00f3 que \u201cpara The Trust for the Americas, es un honor saber que este proyecto es posible gracias a las personas que se capacitan, aprovechan las actividades y los recursos.\u201d Adem\u00e1s, recalc\u00f3 que lo m\u00e1s satisfactorio es reencontrarse despu\u00e9s de varios a\u00f1os, con personas que se han capacitado y evidenciar c\u00f3mo esto ha generado un impacto en su vida, a trav\u00e9s de la obtenci\u00f3n de un empleo, el inicio o continuaci\u00f3n de sus estudios o la puesta en marcha de un negocio; lo cual Luz Marina afirma nos impulsa a continuar con la labor.\u00a0 La sesi\u00f3n fue llevada a cabo en el centro de Laudes Infantis en el Barrio Arrayanes, ubicado en la localidad de Usme en el sur de la ciudad; una zona caracterizada por una alta concentraci\u00f3n de personas en situaci\u00f3n de vulnerabilidad. Durante esta visita, los asistentes tuvieron la oportunidad de conocer el Centro y presentar sus distintas propuestas.&nbsp;&nbsp; Catalina Rengifo, Gerente de proyectos para las Am\u00e9ricas en Microsoft, destac\u00f3 las habilidades y esfuerzos que cada persona hizo para obtener su certificaci\u00f3n \u201cprincipalmente quiero felicitar a cada una de las personas que hoy se grad\u00faan; los que dieron ese extra, los que trabajaron fuerte, los que vieron la oportunidad em ese conocimiento que estaban adquiriendo, los que encontraron la importancia de trabajar y fortalecer habilidades digitales&#8230; a todos ustedes los felicito, son la inspiraci\u00f3n de muchas personas, a m\u00ed me inspira cada uno de ustedes\u201d.&nbsp; Durante la visita, la Organizaci\u00f3n \u201cPuntos Verdes\u201d, especializada en apoyar a emprendedores en sus iniciativas relacionadas con sostenibilidad ambiental, presentaron el programa de reciclaje de dispositivos electr\u00f3nicos, lo que beneficiar\u00e1 a distintas causas sociales y ambientales, a la comunidad que se encuentra en los barrios Arrayanes y Bella Flor y tambi\u00e9n, por supuesto a Laudes Infantis, quienes esperan poder ser un Punto Verde y un centro de recolecci\u00f3n de estos residuos electr\u00f3nicos, para contribuir con el correcto reciclaje de los mismos.&nbsp;&nbsp; En el evento, se present\u00f3 el caso exitoso de Martha Blanco, fundadora de la revista Olympia, donde se tratan temas de inter\u00e9s para las mujeres.&nbsp; Martha explic\u00f3 como logr\u00f3 consolidar la venta de su revista en la localidad y c\u00f3mo ha logrado generar ingreso gracias a las pautas publicitarias.&nbsp;&nbsp; Yessica Pinz\u00f3n, quien fue la mentora de Martha durante este proceso, explic\u00f3 c\u00f3mo se centraron en generar habilidades en marketing, contabilidad, creaci\u00f3n de plantillas, producci\u00f3n de contenidos y pautas publicitarias, las cuales fueron fundamentales para llevar un modelo de negocio exitoso.&nbsp;&nbsp; Al finalizar el evento, Beatriz Rojas, una joven beneficiaria de POETA DigiSpark, quien utiliza los cursos formativos del programa para planear la creaci\u00f3n de su propio emprendimiento: una papeler\u00eda (miscel\u00e1nea)explic\u00f3 c\u00f3mo Laudes Infantis le brind\u00f3 la posibilidad de adquirir m\u00e1s conocimientos acerca del \\&#8221;mundo digital y el emprendimiento, para hacer crecer nuestro negocio\u201d, y los cursos de Excel, Word y PowerPoint, que pondr\u00e1 en pr\u00e1ctica en su negocio.&nbsp; Por \u00faltimo, Almudena Rivas, resalt\u00f3 la importancia de la generaci\u00f3n de habilidades como herramienta para salir de la pobreza, su alegr\u00eda de retomar los eventos y certificaciones presenciales. Agradeci\u00f3 la oportunidad de reunirse y poder celebrar, con las personas que han apostado no solo por la organizaci\u00f3n, sino tambi\u00e9n por el proyecto DigiSpark. Destac\u00f3 que las personas seguir\u00e1n tomando capacitaciones y avanzando en los procesos que brindar\u00e1n en el segundo semestre del a\u00f1o.&nbsp;&nbsp; Este evento cont\u00f3 con la participaci\u00f3n de: Catalina Rengifo, de Microsoft Filantrop\u00eda, quien estuvo de manera virtual, Luz Marina Correa, Gerente de Proyectos en The Trust for The Americas, Almudena Rivas, Directora de Desarrollo Social y Productivo de Fundaci\u00f3n Laudes Infantis, Juan David Fern\u00e1ndez, de la Fundaci\u00f3n Puntos Verdes, Mar\u00eda Camila Guerra, Oficial de Proyectos de The Trust for the Americas y Yessica Pinz\u00f3n, formadora de Laudes Infantis&nbsp; Para mayor informaci\u00f3n:&nbsp;&nbsp;&nbsp; Visite:\u202f https:\/\/www.trustfortheamericas.org\/programs\/POETA\/poeta-digispark&nbsp; Facebook:\u202fThe Trust for the Americas\u202fTwitter:\u202f@Trust4Americas&nbsp;&nbsp; Sobre The Trust for the Americas:&nbsp;&nbsp; The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles&nbsp;<\/p>","protected":false},"author":5,"featured_media":2287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=2282"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/2287"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=2282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=2282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=2282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}