{"id":2161,"date":"2022-05-03T18:32:42","date_gmt":"2022-05-03T22:32:42","guid":{"rendered":"http:\/\/40.117.174.162\/los-datos-abiertos-como-herramienta-para-combatir-la-corrupcion-en-las-americas\/"},"modified":"2022-05-03T18:32:42","modified_gmt":"2022-05-03T22:32:42","slug":"los-datos-abiertos-como-herramienta-para-combatir-la-corrupcion-en-las-americas","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/los-datos-abiertos-como-herramienta-para-combatir-la-corrupcion-en-las-americas\/","title":{"rendered":"Los Datos Abiertos como herramienta para combatir la corrupci\u00f3n en las Am\u00e9ricas\u00a0"},"content":{"rendered":"<p class=\"wp-block-paragraph\">En abril de 2018, se celebr\u00f3 en Lima, Per\u00fa, la VIII Cumbre de las Am\u00e9ricas. En este encuentro, jefes de Estado y Gobierno del hemisferio se reunieron una vez m\u00e1s para debatir sobre temas pol\u00edticos comunes y comprometerse a acciones clave para hacer frente a los principales desaf\u00edos que enfrentan las Am\u00e9ricas. En esa ocasi\u00f3n, El <em>Compromiso de Lima<\/em> se enfoc\u00f3 principalmente en acciones en pos de la <strong>gobernabilidad democr\u00e1tica frente a la corrupci\u00f3n.<\/strong>\u00a0<\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\" size-large\\\"><img src=\"\\\"https:><figcaption>VII Cumbre de las Am\u00e9ricas. Lima, Per\u00fa (2018). <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que un tema tan vital para el desarrollo de la regi\u00f3n es reconocido por los jefes de Estado y de Gobierno y, adem\u00e1s, se establece como prioridad, se empiezan a llevar a cabo una serie de discusiones que buscan plantear herramientas y mecanismos para combatir la corrupci\u00f3n. Es as\u00ed como en el <a rel=\"\\\"noreferrer\" noopener\\\" href=\"\/pt\/\"http:><em>Compromiso de Lima<\/em><\/a> se defini\u00f3 que cualquier actividad a implementarse debe tratarse de un esfuerzo colaborativo. Los compromisos 14, 17 y 20, mencionan el mandato de promover pol\u00edticas de gobierno abierto, datos abiertos, y uso de las tecnolog\u00edas digitales para impulsar la transparencia, la rendici\u00f3n de cuentas, la interacci\u00f3n con los ciudadanos, la reducci\u00f3n de la burocracia y la simplificaci\u00f3n de tr\u00e1mites, la apertura de la informaci\u00f3n y el fortalecimiento de la cooperaci\u00f3n e intercambio de buenas pr\u00e1cticas para el desarrollo y aplicaci\u00f3n de dichas tecnolog\u00edas.\u00a0<\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\" size-large is-resized\\\"><img src=\"\\\"https:><figcaption>Compromiso de Lima<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En el contexto pol\u00edtico actual en las Am\u00e9ricas, la corrupci\u00f3n se ha presentado como un elemento casi sistem\u00e1tico, ejercido en muchos casos no solo por el Estado, sino tambi\u00e9n por empresas y otros sectores; afectando en mayor medida a la ciudadan\u00eda. Para combatir un desaf\u00edo generalizado, se debe encontrar una soluci\u00f3n transversal que provenga de todos los actores de la sociedad. Es as\u00ed como la VIII Cumbre propuso un acercamiento a los Datos Abiertos como herramienta para combatir la corrupci\u00f3n, ya que funciona como un mecanismo de <strong>rendici\u00f3n de cuentas y de empoderamiento ciudadano.<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Datos Abiertos son un componente efectivo para garantizar la <strong>transparencia activa<\/strong>, que hace referencia a c\u00f3mo las instituciones del Estado publican informaci\u00f3n, incluso antes de que la ciudadan\u00eda realice solicitudes de acceso a la misma.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando hablamos de Datos Abiertos (Open Data en ingl\u00e9s) tambi\u00e9n nos referimos a la garant\u00eda del derecho de acceso a la informaci\u00f3n, lo que propicia un entorno con mayor conocimiento sobre asuntos p\u00fablicos y, por lo tanto, mayor <strong>participaci\u00f3n ciudadana<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Para avanzar hacia gobiernos m\u00e1s abiertos y fortalecer la buena gobernanza en la regi\u00f3n, The Trust for the Americas, a trav\u00e9s de su programa Democratizando la Innovaci\u00f3n en las Am\u00e9ricas (DIA), se ha comprometido a brindar apoyo en la implementaci\u00f3n del <strong>Programa Interamericano de Datos Abiertos para Prevenir y Combatir la Corrupci\u00f3n (PIDA) en Panam\u00e1<\/strong>.\u00a0<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Para empoderar a la ciudadan\u00eda y generar nuevos canales de combate a la corrupci\u00f3n a trav\u00e9s de los Datos Abiertos, <a rel=\"\\\"noreferrer\" noopener\\\" href=\"\/pt\/\"https:>The Trust for the Americas<\/a>, en alianza con la <a rel=\"\\\"noreferrer\" noopener\\\" href=\"\/pt\/\"https:>CAF -Banco de Desarrollo de Am\u00e9rica Latina<\/a>, <a rel=\"\\\"noreferrer\" noopener\\\" href=\"\/pt\/\"https:>Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI)<\/a>, y la <a rel=\"\\\"noreferrer\" noopener\\\" href=\"\/pt\/\"https:>Autoridad Nacional para la Innovaci\u00f3n Gubernamental (AIG) en Panam\u00e1,<\/a> buscar\u00e1:\u00a0<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Desarrollar y reforzar las capacidades t\u00e9cnicas en datos abiertos de las instituciones p\u00fablicas paname\u00f1as.&nbsp;<\/li><\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"\\\"2\\\"\"><li>Realizar actividades basadas en Datos Abiertos como capacitaciones, actividades de sensibilizaci\u00f3n, acci\u00f3n e incubaci\u00f3n de proyectos de empoderamiento ciudadano.&nbsp;<\/li><\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"\\\"3\\\"\"><li>Posicionar la innovaci\u00f3n y el aprovechamiento de las tecnolog\u00edas digitales como factores clave en esta lucha.&nbsp;<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Esta clase de proyectos representa una buena forma de brindar seguimiento y darle continuidad a la serie de estrategias e implementaciones que han nacido y se est\u00e1n ejecutando desde hace mucho, las cuales posicionan a los Datos Abiertos como herramienta clave para combatir la corrupci\u00f3n.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque, innegablemente todav\u00eda queda mucho por hacer, un primer paso en este largo camino es que los ciudadanos empecemos a informarnos m\u00e1s para tomar un papel protag\u00f3nico en esta lucha. Te invitamos a estar atento a nuestros canales de comunicaci\u00f3n, en los que difundiremos contenido relevante sobre c\u00f3mo combatir la corrupci\u00f3n en las Am\u00e9ricas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conoce m\u00e1s de c\u00f3mo The Trust, mediante el Programa DIA, apoya a Panam\u00e1 en la implementaci\u00f3n del PIDA, haciendo click <strong><a rel=\"\\\"noreferrer\" noopener\\\" href=\"\/pt\/\"https:>aqu\u00ed.<\/a>\u00a0<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>En abril de 2018, se celebr\u00f3 en Lima, Per\u00fa, la VIII Cumbre de las Am\u00e9ricas. En este encuentro, jefes de Estado y Gobierno del hemisferio se reunieron una vez m\u00e1s para debatir sobre temas pol\u00edticos comunes y comprometerse a acciones clave para hacer frente a los principales desaf\u00edos que enfrentan las Am\u00e9ricas. En esa ocasi\u00f3n, El Compromiso de Lima se enfoc\u00f3 principalmente en acciones en pos de la gobernabilidad democr\u00e1tica frente a la corrupci\u00f3n.\u00a0 Una vez que un tema tan vital para el desarrollo de la regi\u00f3n es reconocido por los jefes de Estado y de Gobierno y, adem\u00e1s, se establece como prioridad, se empiezan a llevar a cabo una serie de discusiones que buscan plantear herramientas y mecanismos para combatir la corrupci\u00f3n. Es as\u00ed como en el Compromiso de Lima se defini\u00f3 que cualquier actividad a implementarse debe tratarse de un esfuerzo colaborativo. Los compromisos 14, 17 y 20, mencionan el mandato de promover pol\u00edticas de gobierno abierto, datos abiertos, y uso de las tecnolog\u00edas digitales para impulsar la transparencia, la rendici\u00f3n de cuentas, la interacci\u00f3n con los ciudadanos, la reducci\u00f3n de la burocracia y la simplificaci\u00f3n de tr\u00e1mites, la apertura de la informaci\u00f3n y el fortalecimiento de la cooperaci\u00f3n e intercambio de buenas pr\u00e1cticas para el desarrollo y aplicaci\u00f3n de dichas tecnolog\u00edas.\u00a0 En el contexto pol\u00edtico actual en las Am\u00e9ricas, la corrupci\u00f3n se ha presentado como un elemento casi sistem\u00e1tico, ejercido en muchos casos no solo por el Estado, sino tambi\u00e9n por empresas y otros sectores; afectando en mayor medida a la ciudadan\u00eda. Para combatir un desaf\u00edo generalizado, se debe encontrar una soluci\u00f3n transversal que provenga de todos los actores de la sociedad. Es as\u00ed como la VIII Cumbre propuso un acercamiento a los Datos Abiertos como herramienta para combatir la corrupci\u00f3n, ya que funciona como un mecanismo de rendici\u00f3n de cuentas y de empoderamiento ciudadano.&nbsp; Los Datos Abiertos son un componente efectivo para garantizar la transparencia activa, que hace referencia a c\u00f3mo las instituciones del Estado publican informaci\u00f3n, incluso antes de que la ciudadan\u00eda realice solicitudes de acceso a la misma.&nbsp;&nbsp; Cuando hablamos de Datos Abiertos (Open Data en ingl\u00e9s) tambi\u00e9n nos referimos a la garant\u00eda del derecho de acceso a la informaci\u00f3n, lo que propicia un entorno con mayor conocimiento sobre asuntos p\u00fablicos y, por lo tanto, mayor participaci\u00f3n ciudadana.&nbsp;&nbsp; Para avanzar hacia gobiernos m\u00e1s abiertos y fortalecer la buena gobernanza en la regi\u00f3n, The Trust for the Americas, a trav\u00e9s de su programa Democratizando la Innovaci\u00f3n en las Am\u00e9ricas (DIA), se ha comprometido a brindar apoyo en la implementaci\u00f3n del Programa Interamericano de Datos Abiertos para Prevenir y Combatir la Corrupci\u00f3n (PIDA) en Panam\u00e1.\u00a0 Para empoderar a la ciudadan\u00eda y generar nuevos canales de combate a la corrupci\u00f3n a trav\u00e9s de los Datos Abiertos, The Trust for the Americas, en alianza con la CAF -Banco de Desarrollo de Am\u00e9rica Latina, la Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI), y la Autoridad Nacional para la Innovaci\u00f3n Gubernamental (AIG) en Panam\u00e1, buscar\u00e1:\u00a0 Desarrollar y reforzar las capacidades t\u00e9cnicas en datos abiertos de las instituciones p\u00fablicas paname\u00f1as.&nbsp; Realizar actividades basadas en Datos Abiertos como capacitaciones, actividades de sensibilizaci\u00f3n, acci\u00f3n e incubaci\u00f3n de proyectos de empoderamiento ciudadano.&nbsp; Posicionar la innovaci\u00f3n y el aprovechamiento de las tecnolog\u00edas digitales como factores clave en esta lucha.&nbsp; Esta clase de proyectos representa una buena forma de brindar seguimiento y darle continuidad a la serie de estrategias e implementaciones que han nacido y se est\u00e1n ejecutando desde hace mucho, las cuales posicionan a los Datos Abiertos como herramienta clave para combatir la corrupci\u00f3n.&nbsp;&nbsp; Aunque, innegablemente todav\u00eda queda mucho por hacer, un primer paso en este largo camino es que los ciudadanos empecemos a informarnos m\u00e1s para tomar un papel protag\u00f3nico en esta lucha. Te invitamos a estar atento a nuestros canales de comunicaci\u00f3n, en los que difundiremos contenido relevante sobre c\u00f3mo combatir la corrupci\u00f3n en las Am\u00e9ricas.\u00a0 Conoce m\u00e1s de c\u00f3mo The Trust, mediante el Programa DIA, apoya a Panam\u00e1 en la implementaci\u00f3n del PIDA, haciendo click aqu\u00ed.\u00a0<\/p>","protected":false},"author":32,"featured_media":2171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=2161"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/2171"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=2161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=2161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=2161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}