{"id":2054,"date":"2022-02-24T20:50:07","date_gmt":"2022-02-25T01:50:07","guid":{"rendered":"http:\/\/40.117.174.162\/proyecto-poeta-digispark-prepara-a-las-personas-para-asegurar-oportunidades-laborales-en-la-region\/"},"modified":"2022-02-24T20:50:07","modified_gmt":"2022-02-25T01:50:07","slug":"proyecto-poeta-digispark-prepara-a-las-personas-para-asegurar-oportunidades-laborales-en-la-region","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/proyecto-poeta-digispark-prepara-a-las-personas-para-asegurar-oportunidades-laborales-en-la-region\/","title":{"rendered":"Proyecto POETA DigiSpark prepara a las personas para asegurar oportunidades laborales en la regi\u00f3n\u00a0"},"content":{"rendered":"<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">Luego de enfrentar diferentes retos mundiales, la nueva normalidad nos invita a impulsar acciones que permitan sumar al empoderamiento de personas que viven alguna condici\u00f3n de vulnerabilidad. En ese sentido, The Trust for the Americas y Microsoft, impulsan Proyecto POETA DigiSpark 2022.&nbsp;<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">En la <em>Sesi\u00f3n de<\/em> <em>Bienvenida POETA DigiSpark 2022<\/em>, Jorge Cella, Director Regional de Filantrop\u00eda &#8211; Microsoft Am\u00e9ricas, reconoci\u00f3 a The Trust for the Americas y a sus socios locales por su alance e impacto al haber brindado capacitaciones a m\u00e1s de 15 mil personas en 2021 en Argentina, Brasil, Chile, Colombia, M\u00e9xico y Per\u00fa.&nbsp;&nbsp;<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">Cella record\u00f3 que los \u00faltimos a\u00f1os fueron tiempos complicados, y que, aunque el mundo vuelve a la normalidad, la realidad es que el mundo del trabajo cambi\u00f3 para siempre y eso ha creado una enorme cantidad de oportunidades laborales. En referencia a la brecha de habilidades en LATAM, Cella mencion\u00f3 que \u201cHoy, el hacer real el potencial que tienen todas las personas en la regi\u00f3n, nunca ha sido tan f\u00e1cil, pero al mismo tiempo tan dif\u00edcil; ya que no estamos preparados para asegurar esas oportunidades laborales.\u201d&nbsp;<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">En ese sentido, Jorge Cella explic\u00f3 que el objetivo del Proyecto POETA DigiSpark es preparar a las personas, principalmente a las que viven en condici\u00f3n de vulnerabilidad, para fortalecer sus habilidades digitales, t\u00e9cnicas y para la vida con el fin de que accedan a esas distintas oportunidades educacionales y laborales. \u201cEsa es nuestra tarea principal &#8211; preparar a la gente para que esas oportunidades no se nos vayan de largo y se conviertan en una realidad\u201d, recalc\u00f3.&nbsp;<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">En 2021, el Proyecto POETA DigiSpark logr\u00f3 impactar a 15,115 personas adultas a trav\u00e9s de acceso a capacitaciones en persona y virtuales, webinars de microaprendizajes, bootcamps y contenido asincr\u00f3nico. Como uno de los objetivos del proyecto, casi dos tercios (63%) de las capacitadas fueron mujeres viviendo en alguna condici\u00f3n de vulnerabilidad. Adem\u00e1s, en alianza con Eidos, se lograron capacitar a m\u00e1s de cuatro mil 800 docentes y facilitadores, mismos que replicaron los contenidos de <em>reskilling <\/em>entre sus estudiantes.\u00a0<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">Ver\u00f3nica Philippe, Gerente de Proyectos del Trust for the Americas, destac\u00f3 la importancia de sumar esfuerzos a trav\u00e9s de alianzas con cada una de las instituciones pertenecientes al proyecto, pues \u201cgracias al trabajo que cada uno de ustedes (Socios Locales) hace, logramos capacitar a esas personas, pero tambi\u00e9n logramos generar seis mil 695 oportunidades econ\u00f3micas y educativas; de las cuales, el 33% est\u00e1n relacionadas en Ciencias de la Computaci\u00f3n.\u201d&nbsp;<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">Este a\u00f1o, Proyecto POETA DigiSpark suma a Fundaci\u00f3n A Ganar en Uruguay, Centro para Puerto Rico en Puerto Rico y, Universidad Tecnolog\u00eda de Quer\u00e9taro (UTEQ) y Centro Laboral M\u00e9xico (CELAMEX) en M\u00e9xico. Adem\u00e1s, continua en alianza con: Fundaci\u00f3n SES y CILSA en Argentina; UNILEHU, ITI, Casa dos Sete, OSJC e IDEAR en Brasil; CDI Chile, Innovacien\u202fy Lace\u202fEducaci\u00f3n en Chile; Polit\u00e9cnico de Occidente, Laudes Infantis, Microempresas\u202fde Colombia y ParqueSoft\u202fNari\u00f1o en Colombia; Universidad Tecnol\u00f3gica de Santa Catarina en M\u00e9xico y Fundades en Per\u00fa.\u00a0<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para conocer m\u00e1s de POETA DigiSpark visitar:&nbsp; <a href=\"\/pt\/\"https:>https:\/\/www.thetrustfortheamericas.org\/programs\/POETA\/poeta-digispark <\/a>&nbsp; <\/p>","protected":false},"excerpt":{"rendered":"<p>Luego de enfrentar diferentes retos mundiales, la nueva normalidad nos invita a impulsar acciones que permitan sumar al empoderamiento de personas que viven alguna condici\u00f3n de vulnerabilidad. En ese sentido, The Trust for the Americas y Microsoft, impulsan Proyecto POETA DigiSpark 2022.&nbsp; En la Sesi\u00f3n de Bienvenida POETA DigiSpark 2022, Jorge Cella, Director Regional de Filantrop\u00eda &#8211; Microsoft Am\u00e9ricas, reconoci\u00f3 a The Trust for the Americas y a sus socios locales por su alance e impacto al haber brindado capacitaciones a m\u00e1s de 15 mil personas en 2021 en Argentina, Brasil, Chile, Colombia, M\u00e9xico y Per\u00fa.&nbsp;&nbsp; Cella record\u00f3 que los \u00faltimos a\u00f1os fueron tiempos complicados, y que, aunque el mundo vuelve a la normalidad, la realidad es que el mundo del trabajo cambi\u00f3 para siempre y eso ha creado una enorme cantidad de oportunidades laborales. En referencia a la brecha de habilidades en LATAM, Cella mencion\u00f3 que \u201cHoy, el hacer real el potencial que tienen todas las personas en la regi\u00f3n, nunca ha sido tan f\u00e1cil, pero al mismo tiempo tan dif\u00edcil; ya que no estamos preparados para asegurar esas oportunidades laborales.\u201d&nbsp; En ese sentido, Jorge Cella explic\u00f3 que el objetivo del Proyecto POETA DigiSpark es preparar a las personas, principalmente a las que viven en condici\u00f3n de vulnerabilidad, para fortalecer sus habilidades digitales, t\u00e9cnicas y para la vida con el fin de que accedan a esas distintas oportunidades educacionales y laborales. \u201cEsa es nuestra tarea principal &#8211; preparar a la gente para que esas oportunidades no se nos vayan de largo y se conviertan en una realidad\u201d, recalc\u00f3.&nbsp; En 2021, el Proyecto POETA DigiSpark logr\u00f3 impactar a 15,115 personas adultas a trav\u00e9s de acceso a capacitaciones en persona y virtuales, webinars de microaprendizajes, bootcamps y contenido asincr\u00f3nico. Como uno de los objetivos del proyecto, casi dos tercios (63%) de las capacitadas fueron mujeres viviendo en alguna condici\u00f3n de vulnerabilidad. Adem\u00e1s, en alianza con Eidos, se lograron capacitar a m\u00e1s de cuatro mil 800 docentes y facilitadores, mismos que replicaron los contenidos de reskilling entre sus estudiantes.\u00a0 Ver\u00f3nica Philippe, Gerente de Proyectos del Trust for the Americas, destac\u00f3 la importancia de sumar esfuerzos a trav\u00e9s de alianzas con cada una de las instituciones pertenecientes al proyecto, pues \u201cgracias al trabajo que cada uno de ustedes (Socios Locales) hace, logramos capacitar a esas personas, pero tambi\u00e9n logramos generar seis mil 695 oportunidades econ\u00f3micas y educativas; de las cuales, el 33% est\u00e1n relacionadas en Ciencias de la Computaci\u00f3n.\u201d&nbsp; Este a\u00f1o, Proyecto POETA DigiSpark suma a Fundaci\u00f3n A Ganar en Uruguay, Centro para Puerto Rico en Puerto Rico y, Universidad Tecnolog\u00eda de Quer\u00e9taro (UTEQ) y Centro Laboral M\u00e9xico (CELAMEX) en M\u00e9xico. Adem\u00e1s, continua en alianza con: Fundaci\u00f3n SES y CILSA en Argentina; UNILEHU, ITI, Casa dos Sete, OSJC e IDEAR en Brasil; CDI Chile, Innovacien\u202fy Lace\u202fEducaci\u00f3n en Chile; Polit\u00e9cnico de Occidente, Laudes Infantis, Microempresas\u202fde Colombia y ParqueSoft\u202fNari\u00f1o en Colombia; Universidad Tecnol\u00f3gica de Santa Catarina en M\u00e9xico y Fundades en Per\u00fa.\u00a0 Para conocer m\u00e1s de POETA DigiSpark visitar:&nbsp; https:\/\/www.thetrustfortheamericas.org\/programs\/POETA\/poeta-digispark &nbsp;<\/p>","protected":false},"author":5,"featured_media":1854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=2054"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/2054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/1854"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=2054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=2054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=2054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}