{"id":1903,"date":"2021-10-26T10:26:58","date_gmt":"2021-10-26T14:26:58","guid":{"rendered":"http:\/\/40.117.174.162\/oea-reconocio-labor-de-the-trust-for-the-americas-para-capacitar-a-mujeres-migrantes\/"},"modified":"2021-10-26T10:26:58","modified_gmt":"2021-10-26T14:26:58","slug":"oea-reconocio-labor-de-the-trust-for-the-americas-para-capacitar-a-mujeres-migrantes","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/oea-reconocio-labor-de-the-trust-for-the-americas-para-capacitar-a-mujeres-migrantes\/","title":{"rendered":"OEA reconoci\u00f3 labor de The Trust for the Americas para capacitar a mujeres migrantes"},"content":{"rendered":"<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">En el marco del Proyecto \u201cFortaleciendo las Capacidades del Gobierno de Costa Rica y de las comunidades de acogida para la recepci\u00f3n de migrantes y refugiados\u201d la Organizaci\u00f3n de Estados Americanos (OEA) reconoci\u00f3 el trabajo realizado por The Trust for the Americas en capacitar a mujeres nicarag\u00fcenses refugiadas en Costa Rica.<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large is-resized\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">Durante la presentaci\u00f3n de resultados de la primera fase del proyecto, Maricarmen Plata, Secretaria de Acceso a Derechos y Equidad de la OEA, agradeci\u00f3 a \u201cThe Trust for the Americas, socio a nivel de terrero\u201d, por su rol importante en la capacitaci\u00f3n de emprendedoras migrantes de Nicaragua, para desarrollar sus habilidades empresariales y digitales.<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">Maricarmen Plata reiter\u00f3 que \u201cla OEA pone a disposici\u00f3n las herramientas para seguir contribuyendo a mejorar las condiciones de vida de las personas migrantes, refugiadas y solicitantes de asilo, y de sus comunidades de acogida. As\u00ed como abrir nuevos espacios para la cooperaci\u00f3n nacional.\u201d<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">Maite Capra, Coordinadora Regional en The Trust for the Americas, trabaj\u00f3 durante siete meses en la capacitaci\u00f3n de las mujeres nicarag\u00fcenses:\u202f\u201cestablecimos una comunicaci\u00f3n fluida que se refleja en la\u202fnumerosa\u202fcantidad de\u202fintercambios\u202frelacionados con sus emprendimientos, sus dificultades, sue\u00f1os y dosis de realidad\u201d, explic\u00f3. \u202f<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large is-resized\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">Maite record\u00f3 que \u201ceste grupo de 12 mujeres, han trabajado analizando videos que en The Trust for the Americas se han creado para empoderar a otras mujeres en condiciones similares. Tuvimos el atrevimiento de reunirnos presencialmente una \u00fanica vez, para desarrollar un taller sobre CANVAS, respetando protocolos de distanciamiento, herramientas de protecci\u00f3n, en un espacio f\u00edsico-abierto, lleno de plantas y vida. Ese d\u00eda nos conocimos cara a cara y se conform\u00f3 una RED SORORA que se mantiene hasta el d\u00eda de hoy. Estamos en una etapa muy significativa, ellas han creado sus CANVAS y con apoyo de una experta en el tema, los hemos revisado minuciosamente con el fin de retroalimentar y potenciar cada uno, para una pronta implementaci\u00f3n.\u201d<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">Al final de las capacitaciones nueve mujeres no solo recibieron un subsidio de mil d\u00f3lares, sino que crearon su plan de inversi\u00f3n adherido a los conocimientos construidos sobre emprender de forma segura y con calidad, que han ayudado a mejorar notablemente su emprendimiento.<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-left\\&quot; wp-block-paragraph\">La implementaci\u00f3n del Proyecto estuvo a cargo del Departamento de Inclusi\u00f3n Social de la Secretar\u00eda de Acceso a Derechos y Equidad de la OEA, en estrecha colaboraci\u00f3n con el Gobierno de Costa Rica, con el apoyo de los Gobiernos de Espa\u00f1a y Corea del Sur.<\/p>","protected":false},"excerpt":{"rendered":"<p>En el marco del Proyecto \u201cFortaleciendo las Capacidades del Gobierno de Costa Rica y de las comunidades de acogida para la recepci\u00f3n de migrantes y refugiados\u201d la Organizaci\u00f3n de Estados Americanos (OEA) reconoci\u00f3 el trabajo realizado por The Trust for the Americas en capacitar a mujeres nicarag\u00fcenses refugiadas en Costa Rica. Durante la presentaci\u00f3n de resultados de la primera fase del proyecto, Maricarmen Plata, Secretaria de Acceso a Derechos y Equidad de la OEA, agradeci\u00f3 a \u201cThe Trust for the Americas, socio a nivel de terrero\u201d, por su rol importante en la capacitaci\u00f3n de emprendedoras migrantes de Nicaragua, para desarrollar sus habilidades empresariales y digitales. Maricarmen Plata reiter\u00f3 que \u201cla OEA pone a disposici\u00f3n las herramientas para seguir contribuyendo a mejorar las condiciones de vida de las personas migrantes, refugiadas y solicitantes de asilo, y de sus comunidades de acogida. As\u00ed como abrir nuevos espacios para la cooperaci\u00f3n nacional.\u201d Maite Capra, Coordinadora Regional en The Trust for the Americas, trabaj\u00f3 durante siete meses en la capacitaci\u00f3n de las mujeres nicarag\u00fcenses:\u202f\u201cestablecimos una comunicaci\u00f3n fluida que se refleja en la\u202fnumerosa\u202fcantidad de\u202fintercambios\u202frelacionados con sus emprendimientos, sus dificultades, sue\u00f1os y dosis de realidad\u201d, explic\u00f3. \u202f Maite record\u00f3 que \u201ceste grupo de 12 mujeres, han trabajado analizando videos que en The Trust for the Americas se han creado para empoderar a otras mujeres en condiciones similares. Tuvimos el atrevimiento de reunirnos presencialmente una \u00fanica vez, para desarrollar un taller sobre CANVAS, respetando protocolos de distanciamiento, herramientas de protecci\u00f3n, en un espacio f\u00edsico-abierto, lleno de plantas y vida. Ese d\u00eda nos conocimos cara a cara y se conform\u00f3 una RED SORORA que se mantiene hasta el d\u00eda de hoy. Estamos en una etapa muy significativa, ellas han creado sus CANVAS y con apoyo de una experta en el tema, los hemos revisado minuciosamente con el fin de retroalimentar y potenciar cada uno, para una pronta implementaci\u00f3n.\u201d Al final de las capacitaciones nueve mujeres no solo recibieron un subsidio de mil d\u00f3lares, sino que crearon su plan de inversi\u00f3n adherido a los conocimientos construidos sobre emprender de forma segura y con calidad, que han ayudado a mejorar notablemente su emprendimiento. La implementaci\u00f3n del Proyecto estuvo a cargo del Departamento de Inclusi\u00f3n Social de la Secretar\u00eda de Acceso a Derechos y Equidad de la OEA, en estrecha colaboraci\u00f3n con el Gobierno de Costa Rica, con el apoyo de los Gobiernos de Espa\u00f1a y Corea del Sur.<\/p>","protected":false},"author":5,"featured_media":1909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=1903"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/1909"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=1903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=1903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=1903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}