{"id":1865,"date":"2021-09-30T13:25:52","date_gmt":"2021-09-30T17:25:52","guid":{"rendered":"http:\/\/40.117.174.162\/compartir-para-crecer-objetivo-de-iti\/"},"modified":"2021-09-30T13:25:52","modified_gmt":"2021-09-30T17:25:52","slug":"compartir-para-crecer-objetivo-de-iti","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/compartir-para-crecer-objetivo-de-iti\/","title":{"rendered":"Compartir para\u00a0Crecer, objetivo de ITI"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El objetivo del&nbsp;ITI &#8211; Instituto Tecnol\u00f3gico&nbsp;Inova\u00e7\u00e3o&nbsp;es promover la investigaci\u00f3n y la promoci\u00f3n de tecnolog\u00edas para el desarrollo de las \u00e1reas econ\u00f3mica, cient\u00edfica y social, proporcionando inclusi\u00f3n digital, social y educativa, as\u00ed como estimulando la preservaci\u00f3n del medio ambiente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de la Franquicia Social POETA desde 2018 y con dos Centros POETA en la ciudad de S\u00e3o Paulo,&nbsp;Brasil,&nbsp;ITI es tambi\u00e9n una de las organizaciones participantes en el proyecto POETA&nbsp;DigiSpark&nbsp;2021.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un enfoque humanizado, guiado por metodolog\u00edas activas, escuchando atenta a las demandas de sus beneficiarios y enfoc\u00e1ndose en la expansi\u00f3n de&nbsp;la rede de alianzas,&nbsp;el Centro POETA ITI ha impartido diferentes cursos en&nbsp;habilidades&nbsp;digitales, inform\u00e1tica, rob\u00f3tica y emprendimiento para personas con y sin discapacidad, adolescentes, j\u00f3venes, ancianos, mujeres, docentes y trabajadores, repartidos por todo el pa\u00eds, que han tomado conciencia del impacto de las TIC en su vida personal, profesional y social.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Centro POETA ITI, en el marco del Proyecto POETA&nbsp;DIgiSpark, ha venido desarrollando diferentes e innovadoras iniciativas a trav\u00e9s de cursos, talleres y&nbsp;webinars, buscando siempre atender la transversalidad de su p\u00fablico objetivo. Entre ellos, destacamos el \u201cBora&nbsp;Inovar\u201d &#8211; un curso de rob\u00f3tica, con una metodolog\u00eda l\u00fadica y experiencias pr\u00e1cticas, que brinda el manejo de herramientas tecnol\u00f3gicas a trav\u00e9s de la realizaci\u00f3n de prototipos integrando las cuatro disciplinas STEM (Ciencia, Tecnolog\u00eda, Ingenier\u00eda, Matem\u00e1ticas). En sus \u00faltimas ediciones cont\u00f3 con la participaci\u00f3n activa de j\u00f3venes estudiantes, con y sin discapacidad, provenientes de escuelas p\u00fablicas y en alianza con organizaciones no gubernamentales.&nbsp;<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large\\\"><img src=\"\\\"https:><figcaption><em>Actividades \u201cBora&nbsp;Inovar\u201d &#8211; curso de rob\u00f3tica \/ STEM (ciencia, tecnolog\u00eda, ingenier\u00eda, matem\u00e1ticas)<\/em>&nbsp;<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa \u201cHora do C\u00f3digo\u201d ha sido un gran \u00e9xito para la formaci\u00f3n de docentes en Habilidades Digitales e Introducci\u00f3n a la Programaci\u00f3n,&nbsp;trayendo el refuerzo del razonamiento l\u00f3gico a trav\u00e9s del concepto de pensamiento computacional, talleres pr\u00e1cticos y una colecci\u00f3n de ejercicios para replicar a los estudiantes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como impacto de estas iniciativas, destacamos las actividades pr\u00e1cticas y l\u00fadicas con testimonios de estudiantes que relatan la forma f\u00e1cil y divertida de aprender, adem\u00e1s de la oportunidad de ampliar alianzas con organizaciones p\u00fablicas y privadas.&nbsp;<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large\\\"><img src=\"\\\"https:><figcaption><em>Hora del C\u00f3digo: formaci\u00f3n de profesores en Habilidades Digitales e Introducci\u00f3n a la Programaci\u00f3n<\/em>&nbsp;<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente, ITI firm\u00f3 dos nuevas e importantes alianzas para aumentar el n\u00famero de personas que se benefician de la capacitaci\u00f3n y las iniciativas del Proyecto POETA&nbsp;DigiSpark. Con la Municipalidad de S\u00e3o Caetano do Sul, en la regi\u00f3n&nbsp;del&nbsp;ABC Paulista, ITI firm\u00f3 un Convenio de Cooperaci\u00f3n T\u00e9cnica para ofrecer cursos de capacitaci\u00f3n tecnol\u00f3gica a la poblaci\u00f3n local. Con la IVG&nbsp;Academy, un programa del Instituto&nbsp;Vasselo&nbsp;Goldoni, la alianza tiene como objetivo contribuir al desarrollo de las personas para que puedan lograr resultados y oportunidades profesionales, a trav\u00e9s del acceso a contenidos creados por reconocidos especialistas. Adem\u00e1s de los cursos de POETA&nbsp;DIgiSpark, los participantes tendr\u00e1n acceso a podcasts, libros electr\u00f3nicos, art\u00edculos,&nbsp;videoclases&nbsp;sobre diversos temas, como Diversidad e Inclusi\u00f3n, Emprendimiento y Negocios, Tecnolog\u00eda e Innovaci\u00f3n, Empoderamiento Femenino y Hermandad de mujeres, entre otros.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marcelo\u00a0Pascios, CEO de ITI, durante el evento con la Academia IVG: \u201cNuestra alianza viene a sumarse y con esto nos volvemos cada vez m\u00e1s activos, no solo para llevar la educaci\u00f3n y la tecnolog\u00eda al alcance de todos,\u00a0sino principalmente porque el conocimiento debe ser compartido con otros, para que puedan compartirlo con\u00a0otros ma\u00f1ana, y as\u00ed sucesivamente. \u00a1De esta manera crece la cadena del bien al \u00e9xito!\\&#8221;\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">POETA DigiSpark es financiado por Microsoft e implementado por The Trust for the Americas en: Argentina, Brasil, Chile, Colombia, M\u00e9xico, Per\u00fa y Rep\u00fablica Dominicana a trav\u00e9s de 18 socios locales. Desde la implementaci\u00f3n del proyecto en 2013, POETA DigiSpark ha logrado beneficiar a m\u00e1s de 42 mil participantes a trav\u00e9s de capacitaciones. Adem\u00e1s, ha facilitado cerca de 16,700\u00a0 oportunidades econ\u00f3micas y educativas en LATAM y el Caribe.<\/p>","protected":false},"excerpt":{"rendered":"<p>El objetivo del&nbsp;ITI &#8211; Instituto Tecnol\u00f3gico&nbsp;Inova\u00e7\u00e3o&nbsp;es promover la investigaci\u00f3n y la promoci\u00f3n de tecnolog\u00edas para el desarrollo de las \u00e1reas econ\u00f3mica, cient\u00edfica y social, proporcionando inclusi\u00f3n digital, social y educativa, as\u00ed como estimulando la preservaci\u00f3n del medio ambiente.&nbsp; Como parte de la Franquicia Social POETA desde 2018 y con dos Centros POETA en la ciudad de S\u00e3o Paulo,&nbsp;Brasil,&nbsp;ITI es tambi\u00e9n una de las organizaciones participantes en el proyecto POETA&nbsp;DigiSpark&nbsp;2021.&nbsp; A trav\u00e9s de un enfoque humanizado, guiado por metodolog\u00edas activas, escuchando atenta a las demandas de sus beneficiarios y enfoc\u00e1ndose en la expansi\u00f3n de&nbsp;la rede de alianzas,&nbsp;el Centro POETA ITI ha impartido diferentes cursos en&nbsp;habilidades&nbsp;digitales, inform\u00e1tica, rob\u00f3tica y emprendimiento para personas con y sin discapacidad, adolescentes, j\u00f3venes, ancianos, mujeres, docentes y trabajadores, repartidos por todo el pa\u00eds, que han tomado conciencia del impacto de las TIC en su vida personal, profesional y social.&nbsp; El Centro POETA ITI, en el marco del Proyecto POETA&nbsp;DIgiSpark, ha venido desarrollando diferentes e innovadoras iniciativas a trav\u00e9s de cursos, talleres y&nbsp;webinars, buscando siempre atender la transversalidad de su p\u00fablico objetivo. Entre ellos, destacamos el \u201cBora&nbsp;Inovar\u201d &#8211; un curso de rob\u00f3tica, con una metodolog\u00eda l\u00fadica y experiencias pr\u00e1cticas, que brinda el manejo de herramientas tecnol\u00f3gicas a trav\u00e9s de la realizaci\u00f3n de prototipos integrando las cuatro disciplinas STEM (Ciencia, Tecnolog\u00eda, Ingenier\u00eda, Matem\u00e1ticas). En sus \u00faltimas ediciones cont\u00f3 con la participaci\u00f3n activa de j\u00f3venes estudiantes, con y sin discapacidad, provenientes de escuelas p\u00fablicas y en alianza con organizaciones no gubernamentales.&nbsp; La iniciativa \u201cHora do C\u00f3digo\u201d ha sido un gran \u00e9xito para la formaci\u00f3n de docentes en Habilidades Digitales e Introducci\u00f3n a la Programaci\u00f3n,&nbsp;trayendo el refuerzo del razonamiento l\u00f3gico a trav\u00e9s del concepto de pensamiento computacional, talleres pr\u00e1cticos y una colecci\u00f3n de ejercicios para replicar a los estudiantes.&nbsp; Como impacto de estas iniciativas, destacamos las actividades pr\u00e1cticas y l\u00fadicas con testimonios de estudiantes que relatan la forma f\u00e1cil y divertida de aprender, adem\u00e1s de la oportunidad de ampliar alianzas con organizaciones p\u00fablicas y privadas.&nbsp; Recientemente, ITI firm\u00f3 dos nuevas e importantes alianzas para aumentar el n\u00famero de personas que se benefician de la capacitaci\u00f3n y las iniciativas del Proyecto POETA&nbsp;DigiSpark. Con la Municipalidad de S\u00e3o Caetano do Sul, en la regi\u00f3n&nbsp;del&nbsp;ABC Paulista, ITI firm\u00f3 un Convenio de Cooperaci\u00f3n T\u00e9cnica para ofrecer cursos de capacitaci\u00f3n tecnol\u00f3gica a la poblaci\u00f3n local. Con la IVG&nbsp;Academy, un programa del Instituto&nbsp;Vasselo&nbsp;Goldoni, la alianza tiene como objetivo contribuir al desarrollo de las personas para que puedan lograr resultados y oportunidades profesionales, a trav\u00e9s del acceso a contenidos creados por reconocidos especialistas. Adem\u00e1s de los cursos de POETA&nbsp;DIgiSpark, los participantes tendr\u00e1n acceso a podcasts, libros electr\u00f3nicos, art\u00edculos,&nbsp;videoclases&nbsp;sobre diversos temas, como Diversidad e Inclusi\u00f3n, Emprendimiento y Negocios, Tecnolog\u00eda e Innovaci\u00f3n, Empoderamiento Femenino y Hermandad de mujeres, entre otros.&nbsp; Marcelo\u00a0Pascios, CEO de ITI, durante el evento con la Academia IVG: \u201cNuestra alianza viene a sumarse y con esto nos volvemos cada vez m\u00e1s activos, no solo para llevar la educaci\u00f3n y la tecnolog\u00eda al alcance de todos,\u00a0sino principalmente porque el conocimiento debe ser compartido con otros, para que puedan compartirlo con\u00a0otros ma\u00f1ana, y as\u00ed sucesivamente. \u00a1De esta manera crece la cadena del bien al \u00e9xito!\\&#8221;\u00a0 POETA DigiSpark es financiado por Microsoft e implementado por The Trust for the Americas en: Argentina, Brasil, Chile, Colombia, M\u00e9xico, Per\u00fa y Rep\u00fablica Dominicana a trav\u00e9s de 18 socios locales. Desde la implementaci\u00f3n del proyecto en 2013, POETA DigiSpark ha logrado beneficiar a m\u00e1s de 42 mil participantes a trav\u00e9s de capacitaciones. Adem\u00e1s, ha facilitado cerca de 16,700\u00a0 oportunidades econ\u00f3micas y educativas en LATAM y el Caribe.<\/p>","protected":false},"author":4,"featured_media":1848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1865","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=1865"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1865\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/1848"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=1865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=1865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=1865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}