{"id":1793,"date":"2021-08-23T18:01:23","date_gmt":"2021-08-23T22:01:23","guid":{"rendered":"http:\/\/40.117.174.162\/the-trust-for-the-americas-a-traves-de-poeta-realizo-el-curso-empoderamiento-en-derechos-para-personas-con-discapacidad\/"},"modified":"2021-08-23T18:01:23","modified_gmt":"2021-08-23T22:01:23","slug":"the-trust-for-the-americas-a-traves-de-poeta-realizo-el-curso-empoderamiento-en-derechos-para-personas-con-discapacidad","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/the-trust-for-the-americas-a-traves-de-poeta-realizo-el-curso-empoderamiento-en-derechos-para-personas-con-discapacidad\/","title":{"rendered":"The Trust for the Americas, a trav\u00e9s de POETA, realiz\u00f3 el curso: Empoderamiento en Derechos para Personas con Discapacidad"},"content":{"rendered":"<p class=\"\\&quot;has-text-align-justify\\&quot; wp-block-paragraph\">En el Marco de la Semana de la Inclusi\u00f3n&nbsp;Trust,&nbsp;del 26 y 30 de Julio 2021, se&nbsp;llev\u00f3 a cabo&nbsp;el curso virtual&nbsp;<strong>\u201cEmpoderamiento en Derechos de las Personas con Discapacidad\u201d. <\/strong>Este curso estuvo dirigido a personas interesadas en el tema, p\u00fablico en general y profesionales que trabajan en la promoci\u00f3n de&nbsp;derechos,&nbsp;inclusi\u00f3n y accesibilidad de&nbsp;PcD,&nbsp;en \u00e1mbitos&nbsp;laborales, educativos y culturales.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-justify\\&quot; wp-block-paragraph\">El curso cont\u00f3&nbsp;con la participaci\u00f3n de 200 personas de 16 pa\u00edses, quienes&nbsp;se capacitaron&nbsp;en forma aut\u00f3noma a trav\u00e9s del Aula Virtual Trust. Adem\u00e1s,&nbsp;recibieron&nbsp;apoyo de un equipo t\u00e9cnico que acompa\u00f1\u00f3 este proceso. Felicitamos&nbsp;a quienes formaron parte de&nbsp;este&nbsp;curso:&nbsp;por su dedicaci\u00f3n y&nbsp;esfuerzo por mejorar cada d\u00eda sus acciones en busca de una sociedad m\u00e1s igualitaria e inclusiva.&nbsp;<\/p>\n\n\n\n<p class=\"\\&quot;has-text-align-justify\\&quot; wp-block-paragraph\">A&nbsp;continuaci\u00f3n,&nbsp;compartimos la experiencia&nbsp;de una de nuestras participantes:&nbsp;Selma Pav\u00f3n,&nbsp;Coordinadora del programa de inclusi\u00f3n laboral de la Fundaci\u00f3n Telet\u00f3n&nbsp;en&nbsp;Honduras.&nbsp;<\/p>\n\n\n\n<blockquote class=\"\\&quot;wp-block-quote\\&quot; is-layout-flow wp-block-quote-is-layout-flow\"><p><em>\u201cHa sido una experiencia de aprendizaje extraordinaria muy enriquecedora, reflexiva,&nbsp;al pensar&nbsp;c\u00f3mo&nbsp;nos&nbsp;hemos construido como personas, como facilitadores,&nbsp;y&nbsp;como sociedad para contar con la participaci\u00f3n completa y directa de las Personas con discapacidad.&nbsp;La experiencia de&nbsp;interacci\u00f3n con otros participantes&nbsp;al compartir&nbsp;historias de vida que nos&nbsp;motivan a ser mejores cada d\u00eda.&nbsp;Definitivamente el aprendizaje alcanzado es \u00fatil para mi trabajo porque puedo ayudar, transmitir conocimiento, generar cambios,&nbsp;procesos de independencia y autonom\u00eda&nbsp;en las personas con&nbsp;discapacidad&nbsp;y&nbsp;&nbsp;tambi\u00e9n&nbsp;en la vida del familiar o cuidador primario.\\&#8221;<\/em>&nbsp;<\/p><\/blockquote>\n\n\n\n<p class=\"\\&quot;has-text-align-justify\\&quot; wp-block-paragraph\">Selma cont\u00f3 que aprendi\u00f3 que \\&#8221;la <em>Vida Independiente<\/em> no significa tener al autonom\u00eda para hacer todo sin ninguna ayuda extrema, sino contar con apoyos necesarios para posibilitar la integraci\u00f3n social, la participaci\u00f3n activa, y la capacidad de tomar decisiones. Adem\u00e1s, tenemos una gran responsabilidad como coordinadores, facilitadores,&nbsp;madres y&nbsp;padres de familia, al&nbsp;ense\u00f1ar a la sociedad&nbsp;el&nbsp;significado&nbsp;correcto de&nbsp;la&nbsp;discapacidad.\\&#8221;&nbsp;<\/p>\n\n\n\n<blockquote class=\"\\&quot;wp-block-quote\\&quot; is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Las TIC&nbsp;ayudan&nbsp;a promover la igualdad de oportunidades y la inclusi\u00f3n de las personas con discapacidad en la educaci\u00f3n y otras \u00e1reas de la vida.&nbsp;Aun hace falta contar con equipos adaptados que respondan a los retos de las personas con discapacidad.<\/em>&nbsp;<\/p><\/blockquote>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large is-resized\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<blockquote class=\"\\&quot;wp-block-quote\\&quot; is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Finalmente, nunca olvidar&nbsp;que,&nbsp;en el caso de las personas con discapacidad,&nbsp;su derecho se traduce en acciones reales como:&nbsp;\u00a1NADA PARA NOSOTROS SIN NOSOTROS!<\/em>&nbsp;<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Desde la Franquicia&nbsp;Social&nbsp;POETA&nbsp;felicitamos a todas las personas egresadas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para conocer m\u00e1s del curso y los temas abordados durante la Semana de la Inclusi\u00f3n Trust, les invitamos a visitar <a rel=\"\\\"noreferrer\" noopener\\\" href=\"\/pt\/\"https:>https:\/\/bit.ly\/3xSb0Es<\/a>&nbsp;&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>En el Marco de la Semana de la Inclusi\u00f3n&nbsp;Trust,&nbsp;del 26 y 30 de Julio 2021, se&nbsp;llev\u00f3 a cabo&nbsp;el curso virtual&nbsp;\u201cEmpoderamiento en Derechos de las Personas con Discapacidad\u201d. Este curso estuvo dirigido a personas interesadas en el tema, p\u00fablico en general y profesionales que trabajan en la promoci\u00f3n de&nbsp;derechos,&nbsp;inclusi\u00f3n y accesibilidad de&nbsp;PcD,&nbsp;en \u00e1mbitos&nbsp;laborales, educativos y culturales.&nbsp;&nbsp; El curso cont\u00f3&nbsp;con la participaci\u00f3n de 200 personas de 16 pa\u00edses, quienes&nbsp;se capacitaron&nbsp;en forma aut\u00f3noma a trav\u00e9s del Aula Virtual Trust. Adem\u00e1s,&nbsp;recibieron&nbsp;apoyo de un equipo t\u00e9cnico que acompa\u00f1\u00f3 este proceso. Felicitamos&nbsp;a quienes formaron parte de&nbsp;este&nbsp;curso:&nbsp;por su dedicaci\u00f3n y&nbsp;esfuerzo por mejorar cada d\u00eda sus acciones en busca de una sociedad m\u00e1s igualitaria e inclusiva.&nbsp; A&nbsp;continuaci\u00f3n,&nbsp;compartimos la experiencia&nbsp;de una de nuestras participantes:&nbsp;Selma Pav\u00f3n,&nbsp;Coordinadora del programa de inclusi\u00f3n laboral de la Fundaci\u00f3n Telet\u00f3n&nbsp;en&nbsp;Honduras.&nbsp; \u201cHa sido una experiencia de aprendizaje extraordinaria muy enriquecedora, reflexiva,&nbsp;al pensar&nbsp;c\u00f3mo&nbsp;nos&nbsp;hemos construido como personas, como facilitadores,&nbsp;y&nbsp;como sociedad para contar con la participaci\u00f3n completa y directa de las Personas con discapacidad.&nbsp;La experiencia de&nbsp;interacci\u00f3n con otros participantes&nbsp;al compartir&nbsp;historias de vida que nos&nbsp;motivan a ser mejores cada d\u00eda.&nbsp;Definitivamente el aprendizaje alcanzado es \u00fatil para mi trabajo porque puedo ayudar, transmitir conocimiento, generar cambios,&nbsp;procesos de independencia y autonom\u00eda&nbsp;en las personas con&nbsp;discapacidad&nbsp;y&nbsp;&nbsp;tambi\u00e9n&nbsp;en la vida del familiar o cuidador primario.\\&#8221;&nbsp; Selma cont\u00f3 que aprendi\u00f3 que \\&#8221;la Vida Independiente no significa tener al autonom\u00eda para hacer todo sin ninguna ayuda extrema, sino contar con apoyos necesarios para posibilitar la integraci\u00f3n social, la participaci\u00f3n activa, y la capacidad de tomar decisiones. Adem\u00e1s, tenemos una gran responsabilidad como coordinadores, facilitadores,&nbsp;madres y&nbsp;padres de familia, al&nbsp;ense\u00f1ar a la sociedad&nbsp;el&nbsp;significado&nbsp;correcto de&nbsp;la&nbsp;discapacidad.\\&#8221;&nbsp; Las TIC&nbsp;ayudan&nbsp;a promover la igualdad de oportunidades y la inclusi\u00f3n de las personas con discapacidad en la educaci\u00f3n y otras \u00e1reas de la vida.&nbsp;Aun hace falta contar con equipos adaptados que respondan a los retos de las personas con discapacidad.&nbsp; Finalmente, nunca olvidar&nbsp;que,&nbsp;en el caso de las personas con discapacidad,&nbsp;su derecho se traduce en acciones reales como:&nbsp;\u00a1NADA PARA NOSOTROS SIN NOSOTROS!&nbsp; Desde la Franquicia&nbsp;Social&nbsp;POETA&nbsp;felicitamos a todas las personas egresadas.&nbsp;&nbsp; Para conocer m\u00e1s del curso y los temas abordados durante la Semana de la Inclusi\u00f3n Trust, les invitamos a visitar https:\/\/bit.ly\/3xSb0Es&nbsp;&nbsp;<\/p>","protected":false},"author":31,"featured_media":1800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=1793"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/1800"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=1793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=1793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=1793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}