{"id":1673,"date":"2021-03-15T16:48:30","date_gmt":"2021-03-15T20:48:30","guid":{"rendered":"http:\/\/40.117.174.162\/a-un-ano-del-inicio-de-la-pandemia\/"},"modified":"2025-06-04T00:19:59","modified_gmt":"2025-06-04T00:19:59","slug":"a-un-ano-del-inicio-de-la-pandemia","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/a-un-ano-del-inicio-de-la-pandemia\/","title":{"rendered":"A UN A\u00d1O DEL INICIO DE LA PANDEMIA"},"content":{"rendered":"<p class=\"wp-block-paragraph\">\u00bfMarzo otra vez?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Wao! Es la \u00fanica palabra que viene a mi mente al saber que ya ha pasado un a\u00f1o de aquel 13 de marzo del 2020; \u00faltimo d\u00eda de lo que conoc\u00eda como normalidad y donde empez\u00f3 el temor a un virus desconocido que hasta entonces, solo sab\u00eda que ven\u00eda del otro lado del mundo, que hab\u00eda personas muriendo, ya hab\u00eda algunos casos en Estados Unidos y hac\u00eda dos d\u00edas hab\u00eda sido decretada como una pandemia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aquel d\u00eda al final de la tarde, luego de la reuni\u00f3n de staff, la cual fue con distancia social, nos informaron que a partir del lunes trabajar\u00edamos desde casa hasta nuevo aviso. Recog\u00ed de mi puesto de trabajo cuadernos, lapiceros, su\u00e9teres y art\u00edculos personales que usaba en mi d\u00eda a d\u00eda. Sal\u00ed de la oficina con una compa\u00f1era la cual estaba un poco asombrada de mi caja -hoy me siento toda una visionaria-. Algo dentro de m\u00ed me dec\u00eda que aquello llamado COVID-19 durar\u00eda m\u00e1s de dos semanas o 40 d\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras camin\u00e1bamos por las desoladas calles de DC y con una sensaci\u00f3n de incertidumbre, pasamos por mi casa a dejar mi caja y nos fuimos a recorrer un supermercado que ya estaba con la mayor\u00eda de sus anaqueles vac\u00edos, situaci\u00f3n que me dej\u00f3 preocupada y con un mal recuerdo de revivir momentos del pasado en mi pa\u00eds natal,Venezuela. No lograba entender en esa oportunidad todo lo que est\u00e1bamos empezando a vivir, solo pensaba en lo vulnerables que somos los seres humanos y c\u00f3mo algo que ni podemos ver, puede cambiar el mundo de manera tan radical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante estos doce meses he desarrollado muchas habilidades nuevas, como tambi\u00e9n he atravesado por varios sentimientos. Algunos que nunca hab\u00eda experimentado como el miedo a salir de mi casa y contagiarme de una enfermedad mortal solo por tocar un bot\u00f3n de un ascensor. Lo cotidiano se volvi\u00f3 extraordinario, actividades como ir al supermercado, comprar por internet o conseguir papel higi\u00e9nico eran tareas que se volvieron imposible de realizar y que demandaban mucho tiempo y esfuerzo para lograrlas debido a la alta demanda de alimentos y productos de limpieza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pasaban los meses y mi mente fue adapt\u00e1ndose a la nueva normalidad y aprend\u00ed a cuidarme y a cuidar a los dem\u00e1s a mi alrededor.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2021\/03\/image-1024x768.png\" alt=\"\" class=\"wp-image-12110\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-1024x768.png 1024w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-300x225.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-768x576.png 768w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-16x12.png 16w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image.png 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2021\/03\/image-1.png\" alt=\"\" class=\"wp-image-12111\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-1.png 768w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-1-225x300.png 225w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-1-9x12.png 9w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2021\/03\/image-2.png\" alt=\"\" class=\"wp-image-12112\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-2.png 1024w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-2-300x225.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-2-768x576.png 768w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-2-16x12.png 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2021\/03\/image-3-768x1024.png\" alt=\"\" class=\"wp-image-12113\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-3-768x1024.png 768w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-3-225x300.png 225w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-3-1152x1536.png 1152w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-3-9x12.png 9w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/03\/image-3.png 1200w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">He enfocado mi tiempo en establecerme metas, rutinas y horarios, a realizar actividades que me gustan y me relajan como colorear, leer, ir al parque, ver series de Netflix, tomar fotos y hacer yoga en casa. Organizar mi tiempo entre mis horarios de trabajo, horario de entretenimiento y quehaceres del hogar me ha permitido aprovechar este tiempo en casa para aprender \u00e1reas nuevas, como mercadeo, que enriquecen mi perfil profesional. Reforzar t\u00e9rminos y aprender nuevos temas en mi \u00e1rea de trabajo, que ha sido posible gracias a varios cursos en l\u00ednea gratuitos como los de LinkedIn. Que vaya que es una cosa muy buena que nos ha dejado la pandemia y que tambi\u00e9n he valorado el saber que no estamos solos y que a un solo clic podemos conectarnos con nuestros seres queridos, esos que nos suben el \u00e1nimo cuando lo necesitamos y saben qu\u00e9 decirnos para apoyarnos y seguir adelante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He descubierto nuevos hobbies y  rescat\u00e9 algunos que ten\u00eda olvidados, como la fotograf\u00eda. Con las clases en l\u00ednea, he tenido la oportunidad de salir a practicar lo aprendido, as\u00ed he podido tambi\u00e9n distraer a mi mente de la infinita rutina y obligarme a sacar el espacio para hacer algo que me apasiona. Gracias a la pandemia ahora me considero una persona m\u00e1s consciente de mis actos, que se atreve a salirse de su zona de confort, como escribir en un blog, estando enfocada en mis objetivos personales y profesionales, que disfruta el tiempo con los dem\u00e1s y agradece tener esos espacios. Mi mensaje final ser\u00eda que debemos enfocarnos en soluciones y ver siempre el lado positivo a las situaciones y c\u00f3mo podemos enfrentarlas con los recursos que tenemos a nuestra disposici\u00f3n. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00bfMarzo otra vez? \u00a1Wao! Es la \u00fanica palabra que viene a mi mente al saber que ya ha pasado un a\u00f1o de aquel 13 de marzo del 2020; \u00faltimo d\u00eda de lo que conoc\u00eda como normalidad y donde empez\u00f3 el temor a un virus desconocido que hasta entonces, solo sab\u00eda que ven\u00eda del otro lado del mundo, que hab\u00eda personas muriendo, ya hab\u00eda algunos casos en Estados Unidos y hac\u00eda dos d\u00edas hab\u00eda sido decretada como una pandemia. Aquel d\u00eda al final de la tarde, luego de la reuni\u00f3n de staff, la cual fue con distancia social, nos informaron que a partir del lunes trabajar\u00edamos desde casa hasta nuevo aviso. Recog\u00ed de mi puesto de trabajo cuadernos, lapiceros, su\u00e9teres y art\u00edculos personales que usaba en mi d\u00eda a d\u00eda. Sal\u00ed de la oficina con una compa\u00f1era la cual estaba un poco asombrada de mi caja -hoy me siento toda una visionaria-. Algo dentro de m\u00ed me dec\u00eda que aquello llamado COVID-19 durar\u00eda m\u00e1s de dos semanas o 40 d\u00edas. Mientras camin\u00e1bamos por las desoladas calles de DC y con una sensaci\u00f3n de incertidumbre, pasamos por mi casa a dejar mi caja y nos fuimos a recorrer un supermercado que ya estaba con la mayor\u00eda de sus anaqueles vac\u00edos, situaci\u00f3n que me dej\u00f3 preocupada y con un mal recuerdo de revivir momentos del pasado en mi pa\u00eds natal,Venezuela. No lograba entender en esa oportunidad todo lo que est\u00e1bamos empezando a vivir, solo pensaba en lo vulnerables que somos los seres humanos y c\u00f3mo algo que ni podemos ver, puede cambiar el mundo de manera tan radical. Durante estos doce meses he desarrollado muchas habilidades nuevas, como tambi\u00e9n he atravesado por varios sentimientos. Algunos que nunca hab\u00eda experimentado como el miedo a salir de mi casa y contagiarme de una enfermedad mortal solo por tocar un bot\u00f3n de un ascensor. Lo cotidiano se volvi\u00f3 extraordinario, actividades como ir al supermercado, comprar por internet o conseguir papel higi\u00e9nico eran tareas que se volvieron imposible de realizar y que demandaban mucho tiempo y esfuerzo para lograrlas debido a la alta demanda de alimentos y productos de limpieza. Pasaban los meses y mi mente fue adapt\u00e1ndose a la nueva normalidad y aprend\u00ed a cuidarme y a cuidar a los dem\u00e1s a mi alrededor. He enfocado mi tiempo en establecerme metas, rutinas y horarios, a realizar actividades que me gustan y me relajan como colorear, leer, ir al parque, ver series de Netflix, tomar fotos y hacer yoga en casa. Organizar mi tiempo entre mis horarios de trabajo, horario de entretenimiento y quehaceres del hogar me ha permitido aprovechar este tiempo en casa para aprender \u00e1reas nuevas, como mercadeo, que enriquecen mi perfil profesional. Reforzar t\u00e9rminos y aprender nuevos temas en mi \u00e1rea de trabajo, que ha sido posible gracias a varios cursos en l\u00ednea gratuitos como los de LinkedIn. Que vaya que es una cosa muy buena que nos ha dejado la pandemia y que tambi\u00e9n he valorado el saber que no estamos solos y que a un solo clic podemos conectarnos con nuestros seres queridos, esos que nos suben el \u00e1nimo cuando lo necesitamos y saben qu\u00e9 decirnos para apoyarnos y seguir adelante. He descubierto nuevos hobbies y rescat\u00e9 algunos que ten\u00eda olvidados, como la fotograf\u00eda. Con las clases en l\u00ednea, he tenido la oportunidad de salir a practicar lo aprendido, as\u00ed he podido tambi\u00e9n distraer a mi mente de la infinita rutina y obligarme a sacar el espacio para hacer algo que me apasiona. Gracias a la pandemia ahora me considero una persona m\u00e1s consciente de mis actos, que se atreve a salirse de su zona de confort, como escribir en un blog, estando enfocada en mis objetivos personales y profesionales, que disfruta el tiempo con los dem\u00e1s y agradece tener esos espacios. Mi mensaje final ser\u00eda que debemos enfocarnos en soluciones y ver siempre el lado positivo a las situaciones y c\u00f3mo podemos enfrentarlas con los recursos que tenemos a nuestra disposici\u00f3n. &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>","protected":false},"author":27,"featured_media":12109,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=1673"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1673\/revisions"}],"predecessor-version":[{"id":12114,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1673\/revisions\/12114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/12109"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=1673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=1673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=1673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}