{"id":1528,"date":"2020-08-13T11:03:54","date_gmt":"2020-08-13T15:03:54","guid":{"rendered":"http:\/\/40.117.174.162\/proyecto-vive-y-ambientes-de-paz-y-desarrollo-colaboran-en-el-empoderamiento-de-las-mujeres-toluquenas\/"},"modified":"2020-08-13T11:03:54","modified_gmt":"2020-08-13T15:03:54","slug":"proyecto-vive-y-ambientes-de-paz-y-desarrollo-colaboran-en-el-empoderamiento-de-las-mujeres-toluquenas","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/proyecto-vive-y-ambientes-de-paz-y-desarrollo-colaboran-en-el-empoderamiento-de-las-mujeres-toluquenas\/","title":{"rendered":"Proyecto VIVE y Ambientes de Paz y Desarrollo colaboran en el empoderamiento de las mujeres Toluque\u00f1as"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><img width=\"\\\"179\\\"\" height=\"\\\"238\\\"\" src=\"\\\"\\\"\"><img width=\"\\\"177\\\"\" height=\"\\\"236\\\"\" src=\"\\\"\\\"\">The Trust for the Americas y el Municipio de Toluca, a trav\u00e9s de su programa \u201cAmbientes de Paz y Desarrollo\u201d ampliaron su compromiso de colaboraci\u00f3n hasta octubre del presente a\u00f1o con el objetivo de fomentar el empoderamiento econ\u00f3mico de las mujeres y as\u00ed, prevenir la violencia contra las mujeres y las ni\u00f1as.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Rodolfo S\u00e1nchez G\u00f3mez, Presidente Municipal de la capital del Estado de M\u00e9xico, y Ma. Fernanda Sierra Perea, Gerente de Proyecto VIVE, firmaron esta semana el documento que confirma el compromiso por parte del Trust for the Americas de capacitar a m\u00e1s mujeres toluque\u00f1as.&nbsp; Los cursos se basan en un esquema innovador que incorpora el uso de herramientas digitales, redes sociales y sesiones de acompa\u00f1amiento que permiten el desarrollo de habilidades que les permitan acceder a un empleo, transformar sus emprendimientos a plataformas digitales, e identificar y prevenir la violencia contra las mujeres.<\/p>\n\n\n\n<figure class=\"\\&quot;wp-block-gallery wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\" columns-2 is-cropped\\\"><ul class=\"\\\"blocks-gallery-grid\\\"\"><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><\/ul><figcaption class=\"\\\"blocks-gallery-caption\\\"\">Foto: Mar\u00eda Fernanda Sierra Perea, Gerente de Proyecto VIVE en The Trust for the Americas y Juan Rodolfo S\u00e1nchez G\u00f3mez, Presidente Municipal de Toluca.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La colaboraci\u00f3n entre Proyecto VIVE y Ambientes de Paz y Desarrollo inici\u00f3 a principios de 2020, con la capacitaci\u00f3n presencial de m\u00e1s de 50 mujeres que desarrollaron habilidades para la empleabilidad y el emprendimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicha capacitaci\u00f3n culmin\u00f3 en la implementaci\u00f3n de un magno evento de Entrega de Diplomas y <a href=\"\/pt\/\"https:>Bazar de Emprendedoras<\/a> que se llev\u00f3 a cabo el pasado 5 de marzo en la Plaza de la Constituci\u00f3n de la ciudad de Toluca. Ah\u00ed, todas las egresadas de tuvieron la oportunidad de presentar sus emprendimientos y vender sus productos a la poblaci\u00f3n en general. Durante el evento, se cont\u00f3 con la presencia de la Mtra. Norma Alicia Soto Aceves, Coordinadora de programa Municipal De Ambientes de Paz; la Dra.&nbsp; Mar\u00eda de Lourdes Medina Ortega, Directora General del Instituto Municipal de la Mujer; el Dr. Fernando Galindo Cruz, Director de Prevenci\u00f3n Comunitaria, la Lic. M\u00f3nica Luc\u00eda Arellano Aguilar, Jefa de Departamento de Polic\u00eda Comunitaria, y Klaudia Gonz\u00e1lez, Coordinadora nacional de Proyecto VIVE. En su mensaje a las egresadas, Klaudia enfatiz\u00f3 que la independencia econ\u00f3mica de las mujeres es un factor clave para reducir la vulnerabilidad y prevenir la violencia de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Proyecto VIVE es implementado en M\u00e9xico por The Trust for the Americas desde el 2016 gracias al apoyo&nbsp; de Walmart Foundation. El Proyecto tiene como objetivo ofrecer herramientas que permitan el desarrollo econ\u00f3mico de las mujeres y darles alternativas que mejoren su condici\u00f3n econ\u00f3mica y la de su familia. Entre 2016 y 2019 capacit\u00f3 a m\u00e1s de 60 mil personas a nivel nacional. Del total de personas capacitadas, m\u00e1s de 55 \u202fmil son mujeres (40% de las cuales son jefas de familia). Asimismo, cerca de 7 mil personas fueron vinculadas a oportunidades econ\u00f3micas (86% mujeres, 60% fueron vinculadas a un trabajo de tiempo completo y el 21% se auto-emplearon o iniciaron proyectos de emprendimiento).<\/p>","protected":false},"excerpt":{"rendered":"<p>The Trust for the Americas y el Municipio de Toluca, a trav\u00e9s de su programa \u201cAmbientes de Paz y Desarrollo\u201d ampliaron su compromiso de colaboraci\u00f3n hasta octubre del presente a\u00f1o con el objetivo de fomentar el empoderamiento econ\u00f3mico de las mujeres y as\u00ed, prevenir la violencia contra las mujeres y las ni\u00f1as. Juan Rodolfo S\u00e1nchez G\u00f3mez, Presidente Municipal de la capital del Estado de M\u00e9xico, y Ma. Fernanda Sierra Perea, Gerente de Proyecto VIVE, firmaron esta semana el documento que confirma el compromiso por parte del Trust for the Americas de capacitar a m\u00e1s mujeres toluque\u00f1as.&nbsp; Los cursos se basan en un esquema innovador que incorpora el uso de herramientas digitales, redes sociales y sesiones de acompa\u00f1amiento que permiten el desarrollo de habilidades que les permitan acceder a un empleo, transformar sus emprendimientos a plataformas digitales, e identificar y prevenir la violencia contra las mujeres. La colaboraci\u00f3n entre Proyecto VIVE y Ambientes de Paz y Desarrollo inici\u00f3 a principios de 2020, con la capacitaci\u00f3n presencial de m\u00e1s de 50 mujeres que desarrollaron habilidades para la empleabilidad y el emprendimiento. Dicha capacitaci\u00f3n culmin\u00f3 en la implementaci\u00f3n de un magno evento de Entrega de Diplomas y Bazar de Emprendedoras que se llev\u00f3 a cabo el pasado 5 de marzo en la Plaza de la Constituci\u00f3n de la ciudad de Toluca. Ah\u00ed, todas las egresadas de tuvieron la oportunidad de presentar sus emprendimientos y vender sus productos a la poblaci\u00f3n en general. Durante el evento, se cont\u00f3 con la presencia de la Mtra. Norma Alicia Soto Aceves, Coordinadora de programa Municipal De Ambientes de Paz; la Dra.&nbsp; Mar\u00eda de Lourdes Medina Ortega, Directora General del Instituto Municipal de la Mujer; el Dr. Fernando Galindo Cruz, Director de Prevenci\u00f3n Comunitaria, la Lic. M\u00f3nica Luc\u00eda Arellano Aguilar, Jefa de Departamento de Polic\u00eda Comunitaria, y Klaudia Gonz\u00e1lez, Coordinadora nacional de Proyecto VIVE. En su mensaje a las egresadas, Klaudia enfatiz\u00f3 que la independencia econ\u00f3mica de las mujeres es un factor clave para reducir la vulnerabilidad y prevenir la violencia de g\u00e9nero. El Proyecto VIVE es implementado en M\u00e9xico por The Trust for the Americas desde el 2016 gracias al apoyo&nbsp; de Walmart Foundation. El Proyecto tiene como objetivo ofrecer herramientas que permitan el desarrollo econ\u00f3mico de las mujeres y darles alternativas que mejoren su condici\u00f3n econ\u00f3mica y la de su familia. Entre 2016 y 2019 capacit\u00f3 a m\u00e1s de 60 mil personas a nivel nacional. Del total de personas capacitadas, m\u00e1s de 55 \u202fmil son mujeres (40% de las cuales son jefas de familia). Asimismo, cerca de 7 mil personas fueron vinculadas a oportunidades econ\u00f3micas (86% mujeres, 60% fueron vinculadas a un trabajo de tiempo completo y el 21% se auto-emplearon o iniciaron proyectos de emprendimiento).<\/p>","protected":false},"author":11,"featured_media":1539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=1528"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/1539"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=1528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=1528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=1528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}