{"id":1235,"date":"2020-05-08T19:55:28","date_gmt":"2020-05-08T23:55:28","guid":{"rendered":"http:\/\/40.117.174.162\/para-participar-es-importante-leer-la-convocatoria-para-el-tianguis-virtual-vive\/"},"modified":"2025-06-04T01:18:06","modified_gmt":"2025-06-04T01:18:06","slug":"para-participar-es-importante-leer-la-convocatoria-para-el-tianguis-virtual-vive","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/para-participar-es-importante-leer-la-convocatoria-para-el-tianguis-virtual-vive\/","title":{"rendered":"Para participar, es importante leer la Convocatoria para el \\&#8221;Tianguis Virtual VIVE\\&#8221;"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><p class=\"\\\"has-text-align-center\\\"\" style=\"\\\"font-size:24px;\\\"\"><strong>\u00a1Participa en la edici\u00f3n <strong>\u201cNacional\u201d del 18 de septiembre de 2020!<\/strong><\/strong><\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La contingencia mundial ocasionada por el COVID-19 nos ha llevado a buscar la virtualidad como una herramienta para continuar y crecer nuestros proyectos. En este marco, el Trust&nbsp;for&nbsp;the&nbsp;Americas,&nbsp;a trav\u00e9s del Proyecto VIVE, busca visibilizar los emprendimientos de sus egresadas para&nbsp;reconocer sus esfuerzos y acercarles con potenciales clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;A continuaci\u00f3n, los requisitos para sumarse a la d\u00e9cima edici\u00f3n \u201cNacional\u201d del 18 de septiembre de 2020.<\/p>\n\n\n\n<p class=\"\\ wp-block-paragraph\"has-text-align-center\"><strong>Requisitos de participaci\u00f3n a cumplir como m\u00e1ximo el<\/strong> <strong>18 de septiembre de 2020<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Que tu emprendimiento se encuentre en la Rep\u00fablica Mexicana<\/li>\n\n\n\n<li>Llenar y enviar el cuestionario de registro a <a href=\"\/pt\/\"mailto:vcelaya@20.9.190.97\\\"\">vcelaya@20.9.190.97.<\/a><\/li>\n\n\n\n<li>Enviar un gui\u00f3 escrito para un v\u00eddeo de tres minutos presentando su emprendimiento y sus estrategias ante la contingencia.<\/li>\n\n\n\n<li>Enviar una fotograf\u00eda tuya y de tus productos que pueda utilizarse para la publicidad virtual del Tianguis.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><p style=\"\\\"font-size:18px;\\\"\">&nbsp;<strong><u>Fecha l\u00edmite de env\u00edo:<\/u><\/strong> jueves 10 de Septiembre a mas tardar a las 5 PM (Hora CDMX).<\/p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ser parte de la <a href=\"\/pt\/\"https:>Comunidad de Egresadas VIVE<\/a> en Facebook<\/li>\n\n\n\n<li>Registrar su emprendimiento en el Directorio de Emprendedoras VIVE<\/li>\n\n\n\n<li>Contar con plataformas de distribuci\u00f3n que permitan proporcionar el servicio a distancia o enviar el producto.<\/li>\n\n\n\n<li>Contar con una p\u00e1gina de Facebook* para su emprendimiento en la cual puedas estar conectadas durante la transimisi\u00f3n en VIVO el <strong>viernes 18 de septiembre<\/strong> y durante la media hora posterior (el horario de transmisi\u00f3n se informar\u00e1 a las participantes seleccionadas)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">*Si no tienes p\u00e1gina de Facebook para tu emprendimiento, revisa el Video tutorial al respecto que se encuentra en la Comunidad de Egresadas. Puedes consultar con las administradoras cualquier duda*<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A m\u00e1s tardar el <strong><u><strong><strong>viernes 11 de Septiembre<\/strong><\/strong><\/u><\/strong> se contactar\u00e1 a las personas seleccionadas para la transmisi\u00f3n en VIVO. En caso de aplicar y no ser seleccionada, se le dar\u00e1 seguimiento al caso para poder incluirlo en futuras ediciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p style=\"\\\"font-size:30px;\\\"\"><strong>Cuestionario de registro<\/strong><\/p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nombre completo de la emprendedora:<\/li>\n\n\n\n<li>Nombre del emprendimiento:<\/li>\n\n\n\n<li>Celular de contacto:<\/li>\n\n\n\n<li>Ciudad:<\/li>\n\n\n\n<li>A\u00f1o en el que curs\u00f3 VIVE:<\/li>\n\n\n\n<li>CURP:<\/li>\n\n\n\n<li>E-mail:<\/li>\n\n\n\n<li>Nombre de Perfil en Facebook Personal:<\/li>\n\n\n\n<li>Nombre de Perfil en Facebook Empresarial (si lo hay):<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><p style=\"\\\"font-size:30px;\\\"\"><strong>Preguntas a responder en el v\u00eddeo<\/strong><\/p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Presentaci\u00f3n en general tuya y de tu emprendimiento (pitch de elevador)\n<ol start=\"NaN\" class=\"wp-block-list\">\n<li>\u00bfC\u00f3mo te llamas? \u00bfC\u00f3mo se llama tu emprendimiento?<\/li>\n\n\n\n<li>\u00bfCu\u00e1l es tu giro, productos?<\/li>\n\n\n\n<li>\u00bfQu\u00e9 lo hace diferente?<\/li>\n<\/ol>\n<\/li>\n\n\n\n<li>\u00bfC\u00f3mo se ha adaptado a la contingencia por el Covid-19?\n<ol start=\"NaN\" class=\"wp-block-list\">\n<li>\u00bfCu\u00e1l ha sido el principal reto que enfrentaste?<\/li>\n\n\n\n<li>\u00bfHaz hecho alg\u00fan cambio relevante? \u00bfCu\u00e1l?<\/li>\n\n\n\n<li>\u00bfHaz utilizado plataformas virtuales para expandir tu negocio?<\/li>\n\n\n\n<li>\u00bfEst\u00e1n tomando medidas de sanidad especiales? (en caso de aplicar)<\/li>\n\n\n\n<li>\u00bfCon qu\u00e9 frecuencia est\u00e1n sanitizando los productos y el \u00e1rea de trabajo? (en caso de aplicar)<\/li>\n<\/ol>\n<\/li>\n\n\n\n<li>Recomendaciones y mensaje a la comunidad\n<ol start=\"NaN\" class=\"wp-block-list\">\n<li>\u00bfQu\u00e9 les recomiendas a otras emprendedoras para solventar la crisis?<\/li>\n\n\n\n<li>\u00bfTienes alg\u00fan mensaje para ellas? (de generaci\u00f3n de comunidad o redes de apoyo, por ejemplo)<\/li>\n<\/ol>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Fernanda Barrag\u00e1n, Facilitadora de Proyecto VIVE, les apoyar\u00e1 en la creaci\u00f3n del gui\u00f3n para su v\u00eddeo.<br>Contacto:<em> <a href=\"\/pt\/\"mailto:vcelaya@20.9.190.97\\\"\">vcelaya@20.9.190.97<\/a><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a1Participa en la edici\u00f3n \u201cNacional\u201d del 18 de septiembre de 2020! La contingencia mundial ocasionada por el COVID-19 nos ha llevado a buscar la virtualidad como una herramienta para continuar y crecer nuestros proyectos. En este marco, el Trust&nbsp;for&nbsp;the&nbsp;Americas,&nbsp;a trav\u00e9s del Proyecto VIVE, busca visibilizar los emprendimientos de sus egresadas para&nbsp;reconocer sus esfuerzos y acercarles con potenciales clientes. &nbsp;A continuaci\u00f3n, los requisitos para sumarse a la d\u00e9cima edici\u00f3n \u201cNacional\u201d del 18 de septiembre de 2020.<\/p>","protected":false},"author":11,"featured_media":12170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=1235"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1235\/revisions"}],"predecessor-version":[{"id":12171,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1235\/revisions\/12171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/12170"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=1235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=1235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=1235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}