{"id":1114,"date":"2020-04-08T16:18:22","date_gmt":"2020-04-08T20:18:22","guid":{"rendered":"http:\/\/40.117.174.162\/el-proyecto-vive-genero-estrategia-de-capacitacion-y-oportunidades-economicas-en-el-contexto-del-covid-19\/"},"modified":"2025-06-04T01:27:27","modified_gmt":"2025-06-04T01:27:27","slug":"el-proyecto-vive-genero-estrategia-de-capacitacion-y-oportunidades-economicas-en-el-contexto-del-covid-19","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/pt\/el-proyecto-vive-genero-estrategia-de-capacitacion-y-oportunidades-economicas-en-el-contexto-del-covid-19\/","title":{"rendered":"El Proyecto VIVE gener\u00f3 estrategia de Capacitaci\u00f3n y Oportunidades Econ\u00f3micas en el Contexto del COVID-19"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Escrito en coautor\u00eda con Mar\u00eda Fernanda Sierra, Gerente del Proyecto VIVE en The Trust for the Americas.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"820\" height=\"312\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2020\/04\/image-1.png\" alt=\"\" class=\"wp-image-12182\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-1.png 820w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-1-300x114.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-1-768x292.png 768w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-1-18x7.png 18w\" sizes=\"(max-width: 820px) 100vw, 820px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En The Trust for the Americas nos sentimos honradas de contribuir, a trav\u00e9s del Proyecto VIVE, con oportunidades de aprendizaje y una red de apoyo para mujeres, durante la contingencia por el COVID-19. Asimismo, estamos agradecidas de contar con el apoyo de <a href=\"\/pt\/\"https:>Walmart Foundation<\/a> para estos esfuerzos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A finales del mes de marzo lanzado una exitosa estrategia digital para ofrecer capacitaci\u00f3n y contenidos de calidad para mujeres egresadas del Proyecto VIVE y nuevas participantes. Esta estrategia est\u00e1 basada en conto puntos fundamentales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1.- <strong>Sesiones virtuales en l\u00ednea: <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A finales del mes de marzo, <\/strong>Proyecto VIVE lanz\u00f3 una serie de cursos virtuales para que las mujeres aprendan desde casa. Esta serie se suma al \u00e9xito que tuvo el piloto del Componente Digital desarrollado a finales del 2019. Las sesiones responden a las recomendaciones de la Organizaci\u00f3n Mundial de la Salud (OMS) sobre el distanciamiento social y de la crisis actual por el COVID-19, con medidas virtuales e innovadoras para continuar implementando nuestra oferta de capacitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.- <strong>Contenido Exclusivo para Egresadas:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dise\u00f1amos contenido exclusivo para mujeres que son egresadas del Proyecto VIVE, estos insumos se han compartido a trav\u00e9s de Facebook, espec\u00edficamente en el grupo privado de Facebook \u201c<em>Comunidad de Egresadas de Proyecto VIVE\u201d<\/em>. Estos contenidos son: <strong>V\u00eddeo-tutoriales (microemprendimientos) sobre c\u00f3mo utilizar herramientas digitales para ventas, creaci\u00f3n de dise\u00f1os y manejo de plataformas digitales, entre otros. <\/strong>La duraci\u00f3n de estos v\u00eddeos es entre 5 y 10 minutos en los cuales se explica paso a paso c\u00f3mo utilizar distintas herramientas. El contenido est\u00e1 dise\u00f1ado para egresadas con poca o casi nula alfabetizaci\u00f3n digital. Los temas incluyen: \u00bfC\u00f3mo hacer la p\u00e1gina de Facebook de mi emprendimiento? \u00bfC\u00f3mo registrar mi negocio en el Directorio de Emprendedoras VIVE? \u00bfC\u00f3mo utilizar Microsoft Office para dise\u00f1ar las publicaciones sobre mi emprendimiento?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contenido con recomendaciones sobre c\u00f3mo promocionar sus emprendimientos durante la contingencia del COVID-19:<\/strong> destinado a egresadas con una avanzada alfabetizaci\u00f3n digital.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"656\" height=\"369\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2020\/04\/image-2.png\" alt=\"\" class=\"wp-image-12184\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-2.png 656w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-2-300x169.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-2-18x10.png 18w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"656\" height=\"368\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2020\/04\/image-3.png\" alt=\"\" class=\"wp-image-12185\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-3.png 656w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-3-300x168.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-3-18x10.png 18w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"656\" height=\"368\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2020\/04\/image-4.png\" alt=\"\" class=\"wp-image-12186\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-4.png 656w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-4-300x168.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-4-18x10.png 18w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"656\" height=\"368\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2020\/04\/image-5.png\" alt=\"\" class=\"wp-image-12187\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-5.png 656w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-5-300x168.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-5-18x10.png 18w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"656\" height=\"368\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2020\/04\/image-6.png\" alt=\"\" class=\"wp-image-12188\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-6.png 656w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-6-300x168.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-6-18x10.png 18w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Recomendaciones sobre sesiones de capacitaci\u00f3n relevantes para ayudar a sus emprendimientos a sobrellevar la contingencia.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"656\" height=\"369\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2020\/04\/image-7.png\" alt=\"\" class=\"wp-image-12189\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-7.png 656w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-7-300x169.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-7-18x10.png 18w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A finales del a\u00f1o 2019 creamos un directorio de emprendedoras, en el cual las egresadas del Proyecto VIVE pueden registrar la informaci\u00f3n b\u00e1sica de sus emprendimientos y darles difusi\u00f3n. Nos encargamos de divulgar el directorio mediante nuestra comunidad en l\u00ednea y con nuestros aliados estrat\u00e9gicos. Para m\u00e1s informaci\u00f3n, aqu\u00ed las ligas para consultar el <a href=\"\/pt\/\"https:>blog<\/a> e <a href=\"\/pt\/\"https:>directorio<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.- <strong>Promover el registro y uso del Directorio de Emprendedoras VIVE:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vamos a fortalecer nuestro esfuerzo en la promoci\u00f3n del directorio de la siguiente manera:\n<ul class=\"wp-block-list\">\n<li>Dise\u00f1ar una estrategia para volver al Directorio m\u00e1s visible ante potenciales compradores.<\/li>\n\n\n\n<li>Expandir el alcance del Directorio para incluir a otros proyectos de TheTrust for the Americas, como los que se est\u00e1n implementando en Puerto Rico y Rep\u00fablica Dominicana y as\u00ed, vincularlo a una iniciativa regional.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full \\\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"530\" height=\"548\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2020\/04\/directorio.jpg\" alt=\"\" class=\"wp-image-12190\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/directorio.jpg 530w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/directorio-290x300.jpg 290w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/directorio-12x12.jpg 12w\" sizes=\"(max-width: 530px) 100vw, 530px\" \/><figcaption class=\"wp-element-caption\">Directorio de Egresadas VIVE: https:\/\/nuevo.sit.trustfortheamericas.org\/es\/directorio-vive\/listado-directorio-vive<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">4.- <strong>Lanzamiento del Banco de Talento para promover entre nuestros socios potenciales: <\/strong>considerando que a pesar de nuestros esfuerzos el sector empresarial se ver\u00e1 altamente lastimado durante la contingencia, buscamos fortalecer nuestro componente de empleabilidad mediante la creaci\u00f3n de un Banco de Talento que podremos compartir con nuestros aliados en el sector privado y proporcionales una lista de empleadas potenciales que cumplen con sus criterios de selecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5.- <strong>\u201cLavado de Manos\u201d <a href=\"\/pt\/\"https:>Jingle<\/a>:<\/strong> En 2018 tuvimos un concurso entre las egresadas para seleccionar el mejor \u201c<em>jingle\u201d<\/em> del Proyecto. Raquel Pedroza, egresada en Ciudad de M\u00e9xico, cre\u00f3 la canci\u00f3n ganadora. Retomamos este jingle y lo convertimos en un video corto para promover el correcto lavado de manos (<a href=\"\/pt\/\"https:>liga al video<\/a>). Raquel es una participante activa de nuestra comunidad de egresadas y particip\u00f3 en la <em>Serie de Concursos de Pitch de CDMX <\/em>en 2019<em>.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"368\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2020\/04\/image-8.png\" alt=\"\" class=\"wp-image-12191\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-8.png 378w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-8-300x292.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2020\/04\/image-8-12x12.png 12w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre el Proyecto VIVE<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Proyecto VIVE: ven, insp\u00edrate y vende, se implement\u00f3 en M\u00e9xico por The Trust for the Americas en alianza con Fundaci\u00f3n ManpowerGroup y con el apoyo de Walmart Foundation de Estados Unidos. En 2016, Proyecto VIVE inici\u00f3 con el objetivo de impulsar el empoderamiento econ\u00f3mico de las mujeres mexicanas a trav\u00e9s de la capacitaci\u00f3n en habilidades t\u00e9cnicas: ventas, promotor\u00eda, atenci\u00f3n al cliente y habilidades para la vida como: emprendimiento, comunicaci\u00f3n efectiva y liderazgo. La capacitaci\u00f3n esta dirigida a mujeres mayores de 15 a\u00f1os que se encuentren en una situaci\u00f3n de vulnerabilidad. VIVE ha tenido presencia en 184 municipios, en 28 estados de M\u00e9xico. Durante 2018, The Trust for the Americas sum\u00f3 al curriculum de VIVE el curso de prevenci\u00f3n de violencia hacia las ni\u00f1as y las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre Walmart Foundation:&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juntos Walmart y Walmart Foundation generalmente proporcionan m\u00e1s de $1 bill\u00f3n en efectivo y en especie para apoyar programas que se alinean con sus prioridades filantr\u00f3picas.&nbsp;Walmart Foundation se enfoca en \u00e1reas donde pueden hacer el bien \u2013 combinando las fortalezas \u00fanicas del negocio junto con la filantrop\u00eda.&nbsp;Walmart Foundation ofrecer un mayor impacto social.&nbsp;Hoy, Walmart.org, a trav\u00e9s de los esfuerzos filantr\u00f3picos combinados de Walmart y la Walmart Foundation crea oportunidades para que las personas vivan mejor cada d\u00eda.<\/p>","protected":false},"excerpt":{"rendered":"<p>Escrito en coautor\u00eda con Mar\u00eda Fernanda Sierra, Gerente del Proyecto VIVE en The Trust for the Americas. En The Trust for the Americas nos sentimos honradas de contribuir, a trav\u00e9s del Proyecto VIVE, con oportunidades de aprendizaje y una red de apoyo para mujeres, durante la contingencia por el COVID-19. Asimismo, estamos agradecidas de contar con el apoyo de Walmart Foundation para estos esfuerzos. A finales del mes de marzo lanzado una exitosa estrategia digital para ofrecer capacitaci\u00f3n y contenidos de calidad para mujeres egresadas del Proyecto VIVE y nuevas participantes. Esta estrategia est\u00e1 basada en conto puntos fundamentales 1.- Sesiones virtuales en l\u00ednea: A finales del mes de marzo, Proyecto VIVE lanz\u00f3 una serie de cursos virtuales para que las mujeres aprendan desde casa. Esta serie se suma al \u00e9xito que tuvo el piloto del Componente Digital desarrollado a finales del 2019. Las sesiones responden a las recomendaciones de la Organizaci\u00f3n Mundial de la Salud (OMS) sobre el distanciamiento social y de la crisis actual por el COVID-19, con medidas virtuales e innovadoras para continuar implementando nuestra oferta de capacitaci\u00f3n. 2.- Contenido Exclusivo para Egresadas: Dise\u00f1amos contenido exclusivo para mujeres que son egresadas del Proyecto VIVE, estos insumos se han compartido a trav\u00e9s de Facebook, espec\u00edficamente en el grupo privado de Facebook \u201cComunidad de Egresadas de Proyecto VIVE\u201d. Estos contenidos son: V\u00eddeo-tutoriales (microemprendimientos) sobre c\u00f3mo utilizar herramientas digitales para ventas, creaci\u00f3n de dise\u00f1os y manejo de plataformas digitales, entre otros. La duraci\u00f3n de estos v\u00eddeos es entre 5 y 10 minutos en los cuales se explica paso a paso c\u00f3mo utilizar distintas herramientas. El contenido est\u00e1 dise\u00f1ado para egresadas con poca o casi nula alfabetizaci\u00f3n digital. Los temas incluyen: \u00bfC\u00f3mo hacer la p\u00e1gina de Facebook de mi emprendimiento? \u00bfC\u00f3mo registrar mi negocio en el Directorio de Emprendedoras VIVE? \u00bfC\u00f3mo utilizar Microsoft Office para dise\u00f1ar las publicaciones sobre mi emprendimiento? Contenido con recomendaciones sobre c\u00f3mo promocionar sus emprendimientos durante la contingencia del COVID-19: destinado a egresadas con una avanzada alfabetizaci\u00f3n digital. Recomendaciones sobre sesiones de capacitaci\u00f3n relevantes para ayudar a sus emprendimientos a sobrellevar la contingencia. A finales del a\u00f1o 2019 creamos un directorio de emprendedoras, en el cual las egresadas del Proyecto VIVE pueden registrar la informaci\u00f3n b\u00e1sica de sus emprendimientos y darles difusi\u00f3n. Nos encargamos de divulgar el directorio mediante nuestra comunidad en l\u00ednea y con nuestros aliados estrat\u00e9gicos. Para m\u00e1s informaci\u00f3n, aqu\u00ed las ligas para consultar el blog y el directorio. 3.- Promover el registro y uso del Directorio de Emprendedoras VIVE: 4.- Lanzamiento del Banco de Talento para promover entre nuestros socios potenciales: considerando que a pesar de nuestros esfuerzos el sector empresarial se ver\u00e1 altamente lastimado durante la contingencia, buscamos fortalecer nuestro componente de empleabilidad mediante la creaci\u00f3n de un Banco de Talento que podremos compartir con nuestros aliados en el sector privado y proporcionales una lista de empleadas potenciales que cumplen con sus criterios de selecci\u00f3n. 5.- \u201cLavado de Manos\u201d Jingle: En 2018 tuvimos un concurso entre las egresadas para seleccionar el mejor \u201cjingle\u201d del Proyecto. Raquel Pedroza, egresada en Ciudad de M\u00e9xico, cre\u00f3 la canci\u00f3n ganadora. Retomamos este jingle y lo convertimos en un video corto para promover el correcto lavado de manos (liga al video). Raquel es una participante activa de nuestra comunidad de egresadas y particip\u00f3 en la Serie de Concursos de Pitch de CDMX en 2019. Sobre el Proyecto VIVE El Proyecto VIVE: ven, insp\u00edrate y vende, se implement\u00f3 en M\u00e9xico por The Trust for the Americas en alianza con Fundaci\u00f3n ManpowerGroup y con el apoyo de Walmart Foundation de Estados Unidos. En 2016, Proyecto VIVE inici\u00f3 con el objetivo de impulsar el empoderamiento econ\u00f3mico de las mujeres mexicanas a trav\u00e9s de la capacitaci\u00f3n en habilidades t\u00e9cnicas: ventas, promotor\u00eda, atenci\u00f3n al cliente y habilidades para la vida como: emprendimiento, comunicaci\u00f3n efectiva y liderazgo. La capacitaci\u00f3n esta dirigida a mujeres mayores de 15 a\u00f1os que se encuentren en una situaci\u00f3n de vulnerabilidad. VIVE ha tenido presencia en 184 municipios, en 28 estados de M\u00e9xico. Durante 2018, The Trust for the Americas sum\u00f3 al curriculum de VIVE el curso de prevenci\u00f3n de violencia hacia las ni\u00f1as y las mujeres. Sobre Walmart Foundation:&nbsp;&nbsp; Juntos Walmart y Walmart Foundation generalmente proporcionan m\u00e1s de $1 bill\u00f3n en efectivo y en especie para apoyar programas que se alinean con sus prioridades filantr\u00f3picas.&nbsp;Walmart Foundation se enfoca en \u00e1reas donde pueden hacer el bien \u2013 combinando las fortalezas \u00fanicas del negocio junto con la filantrop\u00eda.&nbsp;Walmart Foundation ofrecer un mayor impacto social.&nbsp;Hoy, Walmart.org, a trav\u00e9s de los esfuerzos filantr\u00f3picos combinados de Walmart y la Walmart Foundation crea oportunidades para que las personas vivan mejor cada d\u00eda.<\/p>","protected":false},"author":11,"featured_media":12181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/comments?post=1114"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1114\/revisions"}],"predecessor-version":[{"id":12192,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/posts\/1114\/revisions\/12192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media\/12181"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/media?parent=1114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/categories?post=1114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/pt\/wp-json\/wp\/v2\/tags?post=1114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}