{"id":856,"date":"2019-11-22T15:12:55","date_gmt":"2019-11-22T20:12:55","guid":{"rendered":"http:\/\/40.117.174.162\/emprendimientos-por-el-bien-comun-mujeres-egresadas-del-proyecto-vive-concursaron-en-mi-pitch-mi-negocio-en-guerrero\/"},"modified":"2019-11-22T15:12:55","modified_gmt":"2019-11-22T20:12:55","slug":"emprendimientos-por-el-bien-comun-mujeres-egresadas-del-proyecto-vive-concursaron-en-mi-pitch-mi-negocio-en-guerrero","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/emprendimientos-por-el-bien-comun-mujeres-egresadas-del-proyecto-vive-concursaron-en-mi-pitch-mi-negocio-en-guerrero\/","title":{"rendered":"Emprendimientos por el bien com\u00fan: mujeres egresadas del Proyecto VIVE concursaron en \u201cMi Pitch de Negocio\u201d en Guerrero."},"content":{"rendered":"<p class=\"wp-block-paragraph\">El pasado 31 de octubre, 8 emprendedoras egresadas del programa \u201cMujeres descubriendo su potencial\u201d, del Proyecto VIVE y de Crea Emprendedoras Sociales AC, participaron en el concurso \u201cMi Pitch de Negocio\u201d en Chilpancingo, Guerrero.<\/p>\n\n\n\n<figure class=\"\\&quot;wp-block-gallery wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\" columns-1 is-cropped\\\"><ul class=\"\\\"blocks-gallery-grid\\\"\"><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><figcaption class=\"\\\"blocks-gallery-item__caption\\\"\">Emprendedoras participantes de \\&#8221;Mi pitch de negocio\\&#8221;<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En un ambiente de sororidad y mucha emoci\u00f3n,\nlas participantes dieron la bienvenida al jurado e invitadas con mesas de\npresentaci\u00f3n de sus productos y servicios; un centro de salud para el\ndesarrollo integral, servicios de cuidado a domicilio para adultos mayores, una\nred de construcci\u00f3n de mujeres, mezcales saborizados con frutos de la regi\u00f3n,\nuna loncher\u00eda de comida saludable y responsable con el medio ambiente, entre\notros muy interesantes. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, cada una de las participantes\npresent\u00f3 su Pitch en 3 minutos y busc\u00f3 transmitir de manera clara su idea de\nnegocio al jurado compuesto por; Ivette Montero, Fundadora del Centro Mexicano\nPro Bono; Rosario Nieves, Directora de operaciones de CREA;&nbsp; Edita Nava S\u00e1nchez, Licenciada en\nCosmetolog\u00eda &nbsp;y Tania Fuentes Presidenta\nde la Comisi\u00f3n de Sectores Vulnerables de Chilpancingo. <\/p>\n\n\n\n<figure class=\"\\&quot;wp-block-gallery wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\" aligncenter columns-1 is-cropped\\\"><ul class=\"\\\"blocks-gallery-grid\\\"\"><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><figcaption class=\"\\\"blocks-gallery-item__caption\\\"\">Leonor  con su emprendimiento \\&#8221;Frijoles Do\u00f1a Leonor\\&#8221;<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las ganadoras del primer y segundo lugar fueron\nacreedoras a un incentivo econ\u00f3mico de mil d\u00f3lares para impulsar sus negocios,\nadem\u00e1s de participar en mentor\u00edas especializadas. Ellas fueron: Leonor con su\nemprendimiento \u201cFrijoles Do\u00f1a Leonor\u201d y Giovanna con su emprendimiento\n\u201cLoncher\u00eda Verde\u201d, ambas ganadoras enfatizaron que el Proyecto VIVE ha tenido\nun impacto muy importante en el fortalecimiento de sus negocios, incluso,\nLeonor coment\u00f3 que su emprendimiento naci\u00f3 como resultado de su vinculaci\u00f3n con\nVIVE. <\/p>\n\n\n\n<figure class=\"\\&quot;wp-block-gallery wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\" columns-1 is-cropped\\\"><ul class=\"\\\"blocks-gallery-grid\\\"\"><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><figcaption class=\"\\\"blocks-gallery-item__caption\\\"\">Giovanna con su emprendimieto \\&#8221;Loncher\u00eda Verde\\&#8221;<\/figcaption><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En general, los emprendimientos se destacaron por tener un factor de diferenciaci\u00f3n vinculado a la responsabilidad social y el bienestar com\u00fan. Esta situaci\u00f3n invita a reflexionar \u00bfPor qu\u00e9 es tan importante promover la inclusi\u00f3n de las mujeres en el mercado laboral con igualdad sustantiva?<\/p>\n\n\n\n<figure class=\"\\&quot;wp-block-gallery wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\" columns-1 is-cropped\\\"><ul class=\"\\\"blocks-gallery-grid\\\"\"><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La respuesta pudo verse ejemplificada en las\nideas de negocios de estas mujeres; los emprendimientos participantes tienen un\nfuerte compromiso con objetivos de desarrollo y bienestar com\u00fan. Si cada uno de\nestos emprendimientos tiene el potencial de brindar independencia econ\u00f3mica a\nsus creadoras, pero adem\u00e1s, tienen el potencial de generar empleo para grupos\nvulnerables, promover el cuidado del medio ambiente, incentivar el cuidado de\nla salud y promover el consumo a productores locales, son en definitiva\nproyectos que tienen un doble valor agregado y adem\u00e1s tienen el respaldo de\nmujeres comprometidas y apasionadas para llevarlos al \u00e9xito.&nbsp; <\/p>","protected":false},"excerpt":{"rendered":"<p>El pasado 31 de octubre, 8 emprendedoras egresadas del programa \u201cMujeres descubriendo su potencial\u201d, del Proyecto VIVE y de Crea Emprendedoras Sociales AC, participaron en el concurso \u201cMi Pitch de Negocio\u201d en Chilpancingo, Guerrero. En un ambiente de sororidad y mucha emoci\u00f3n, las participantes dieron la bienvenida al jurado e invitadas con mesas de presentaci\u00f3n de sus productos y servicios; un centro de salud para el desarrollo integral, servicios de cuidado a domicilio para adultos mayores, una red de construcci\u00f3n de mujeres, mezcales saborizados con frutos de la regi\u00f3n, una loncher\u00eda de comida saludable y responsable con el medio ambiente, entre otros muy interesantes. Posteriormente, cada una de las participantes present\u00f3 su Pitch en 3 minutos y busc\u00f3 transmitir de manera clara su idea de negocio al jurado compuesto por; Ivette Montero, Fundadora del Centro Mexicano Pro Bono; Rosario Nieves, Directora de operaciones de CREA;&nbsp; Edita Nava S\u00e1nchez, Licenciada en Cosmetolog\u00eda &nbsp;y Tania Fuentes Presidenta de la Comisi\u00f3n de Sectores Vulnerables de Chilpancingo. Las ganadoras del primer y segundo lugar fueron acreedoras a un incentivo econ\u00f3mico de mil d\u00f3lares para impulsar sus negocios, adem\u00e1s de participar en mentor\u00edas especializadas. Ellas fueron: Leonor con su emprendimiento \u201cFrijoles Do\u00f1a Leonor\u201d y Giovanna con su emprendimiento \u201cLoncher\u00eda Verde\u201d, ambas ganadoras enfatizaron que el Proyecto VIVE ha tenido un impacto muy importante en el fortalecimiento de sus negocios, incluso, Leonor coment\u00f3 que su emprendimiento naci\u00f3 como resultado de su vinculaci\u00f3n con VIVE. En general, los emprendimientos se destacaron por tener un factor de diferenciaci\u00f3n vinculado a la responsabilidad social y el bienestar com\u00fan. Esta situaci\u00f3n invita a reflexionar \u00bfPor qu\u00e9 es tan importante promover la inclusi\u00f3n de las mujeres en el mercado laboral con igualdad sustantiva? La respuesta pudo verse ejemplificada en las ideas de negocios de estas mujeres; los emprendimientos participantes tienen un fuerte compromiso con objetivos de desarrollo y bienestar com\u00fan. Si cada uno de estos emprendimientos tiene el potencial de brindar independencia econ\u00f3mica a sus creadoras, pero adem\u00e1s, tienen el potencial de generar empleo para grupos vulnerables, promover el cuidado del medio ambiente, incentivar el cuidado de la salud y promover el consumo a productores locales, son en definitiva proyectos que tienen un doble valor agregado y adem\u00e1s tienen el respaldo de mujeres comprometidas y apasionadas para llevarlos al \u00e9xito.&nbsp;<\/p>","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-856","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=856"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/856\/revisions"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}