{"id":8299,"date":"2019-03-12T15:57:00","date_gmt":"2019-03-12T15:57:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=8299"},"modified":"2024-11-21T15:58:23","modified_gmt":"2024-11-21T15:58:23","slug":"the-trust-for-the-americas-y-la-organizacion-de-estados-americanos-oea-impulsan-la-agenda-de-gobierno-abierto-de-panama","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/the-trust-for-the-americas-y-la-organizacion-de-estados-americanos-oea-impulsan-la-agenda-de-gobierno-abierto-de-panama\/","title":{"rendered":"The Trust for the Americas y la Organizaci\u00f3n de Estados Americanos \u2013OEA, impulsan la agenda de Gobierno Abierto de Panam\u00e1"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2019\/03\/12<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Washington, D.C.<\/strong>&nbsp;(12 de marzo de 2019) \u2014 The Trust for the Americas y el&nbsp;<a href=\"http:\/\/www.oas.org\/es\/sap\/dgpe\/default.asp\">departamento para la Gesti\u00f3n P\u00fablica Efectiva de la Organizaci\u00f3n de Estados Americanos (OEA)<\/a>&nbsp;presentar\u00e1n su nueva iniciativa de innovaci\u00f3n y datos abiertos durante la Open Government Week, en la que l\u00edderes y practicantes de gobierno abierto de todo el mundo se reunir\u00e1n para compartir ideas, discutir soluciones y comprometerse con nuevos niveles de participaci\u00f3n ciudadana en el gobierno. Este lanzamiento se realizar\u00e1 el 14 de marzo en Panam\u00e1 durante el evento \u201cPanam\u00e1 Abierto\u201d organizado junto con la&nbsp;<a href=\"http:\/\/www.antai.gob.pa\/\">Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI)<\/a>&nbsp;y la Autoridad Nacional para la Innovaci\u00f3n Gubernamental (AIG) de Panam\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto denominado \u201cInnovaci\u00f3n p\u00fablica a trav\u00e9s de los Datos Abiertos en Panam\u00e1\u201d se desarroll\u00f3 para incentivar a los gobiernos&nbsp; y a la sociedad civil de Panam\u00e1 a que, de manera colaborativa, generen espacios de discusi\u00f3n, colaboraci\u00f3n, deliberaci\u00f3n de pol\u00edticas p\u00fablicas, y proyectos mediante el uso de datos abiertos. El proyecto es financiado por la Embajada de los Estados Unidos en Panam\u00e1 y se implementa en tres fases: formaci\u00f3n t\u00e9cnica para servidores p\u00fablicos, sociedad civil, academia, medios de comunicaci\u00f3n y el sector privado; creaci\u00f3n de espacios de di\u00e1logo e intercambio de ideas para fomentar la inclusi\u00f3n de todos los sectores en la b\u00fasqueda de soluciones; y, por \u00faltimo, el financiamiento de iniciativas sociales innovadoras que promuevan el uso de datos para mejorar problemas de las comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto del programa,&nbsp;<a href=\"http:\/\/www.thetrustfortheamericas.org\/about-us\/rodrigo-iriani\">Rodrigo Iriani, Gerente de proyectos del Trust<\/a>&nbsp;for the Americas coment\u00f3: \u201cLas iniciativas de Gobierno Abierto de The Trust for the Americas fomentan la colaboraci\u00f3n entre diversos sectores de sociedad civil, el sector privado y los gobiernos para promover proyectos de innovaci\u00f3n c\u00edvica que mejoren la calidad de vida de los ciudadanos de la regi\u00f3n. Durante la semana de eventos trabajaremos junto con entusiastas del gobierno abierto de todo el mundo para intercambiar experiencias y comprometernos a alcanzar mayor y mejor participaci\u00f3n de todos los sectores de la sociedad\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, A\u00edda Mart\u00ednez M\u00f3rtola de la ANTAI coment\u00f3: \u201cEl proyecto&nbsp;<em>Public Innovation through Open Data in Panama&nbsp;<\/em>nos ayudar\u00e1 a fortalecer la agenda de Gobierno Abierto en nuestro pa\u00eds, mediante la participaci\u00f3n de nuevos sectores para llevar adelante nuevas pol\u00edticas p\u00fablicas y proyectos, que fomentar\u00e1n una mejor prestaci\u00f3n de los servicios p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las actividades en las que participar\u00e1 The Trust for the Americas junto con la OEA, ANTAI y AIG, est\u00e1n alineadas con el desarrollo del Programa Interamericano de Datos Abiertos (PIDA) y se enfocar\u00e1n en compartir los avances del gobierno de Panam\u00e1 en materia de Gobierno Abierto y Datos Abiertos, as\u00ed como la incorporaci\u00f3n de los j\u00f3venes como nuevos actores dentro de las mesas de discusi\u00f3n. La semana cerrar\u00e1 con mesas de di\u00e1logo para elaborar una gu\u00eda de implementaci\u00f3n de la Pol\u00edtica P\u00fablica de Transparencia de Datos Abiertos, y la presentaci\u00f3n del Grupo de Trabajo de Datos Abiertos de Panam\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas es una Organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados Americanos (OEA) cuya misi\u00f3n es promover alianzas para la inclusi\u00f3n econ\u00f3mica y social en las Am\u00e9ricas.&nbsp;Establecida en 1997, The Trust fue creado para la participaci\u00f3n del sector p\u00fablico, el sector privado y las iniciativas de la sociedad civil en el desarrollo social y econ\u00f3mico en Am\u00e9rica Latina y el Caribe. Las iniciativas de la organizaci\u00f3n mejoran el acceso de las comunidades a oportunidades econ\u00f3micas, mejor seguridad ciudadana y oportunidades para la expresi\u00f3n democr\u00e1tica y la gobernabilidad.&nbsp; The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas ofrece a las organizaciones locales asociadas, instrumentos de capacitaci\u00f3n, servicios, productos y asistencia t\u00e9cnica para servir mejor a las comunidades vulnerables de la regi\u00f3n.&nbsp; Visite:&nbsp;<a href=\"http:\/\/www.trustfortheamericas.org\/\">www.trustfortheamericas.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:&nbsp;<a href=\"https:\/\/www.facebook.com\/TheTrustfortheAmericas\/\">The Trust for the Americas<\/a>&nbsp; Twitter:&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/twitter.com\/Trust4Americas\">@Trust4Americas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Panama<\/p>","protected":false},"excerpt":{"rendered":"<p>2019\/03\/12 Washington, D.C.&nbsp;(12 de marzo de 2019) \u2014 The Trust for the Americas y el&nbsp;departamento para la Gesti\u00f3n P\u00fablica Efectiva de la Organizaci\u00f3n de Estados Americanos (OEA)&nbsp;presentar\u00e1n su nueva iniciativa de innovaci\u00f3n y datos abiertos durante la Open Government Week, en la que l\u00edderes y practicantes de gobierno abierto de todo el mundo se reunir\u00e1n para compartir ideas, discutir soluciones y comprometerse con nuevos niveles de participaci\u00f3n ciudadana en el gobierno. Este lanzamiento se realizar\u00e1 el 14 de marzo en Panam\u00e1 durante el evento \u201cPanam\u00e1 Abierto\u201d organizado junto con la&nbsp;Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI)&nbsp;y la Autoridad Nacional para la Innovaci\u00f3n Gubernamental (AIG) de Panam\u00e1. El proyecto denominado \u201cInnovaci\u00f3n p\u00fablica a trav\u00e9s de los Datos Abiertos en Panam\u00e1\u201d se desarroll\u00f3 para incentivar a los gobiernos&nbsp; y a la sociedad civil de Panam\u00e1 a que, de manera colaborativa, generen espacios de discusi\u00f3n, colaboraci\u00f3n, deliberaci\u00f3n de pol\u00edticas p\u00fablicas, y proyectos mediante el uso de datos abiertos. El proyecto es financiado por la Embajada de los Estados Unidos en Panam\u00e1 y se implementa en tres fases: formaci\u00f3n t\u00e9cnica para servidores p\u00fablicos, sociedad civil, academia, medios de comunicaci\u00f3n y el sector privado; creaci\u00f3n de espacios de di\u00e1logo e intercambio de ideas para fomentar la inclusi\u00f3n de todos los sectores en la b\u00fasqueda de soluciones; y, por \u00faltimo, el financiamiento de iniciativas sociales innovadoras que promuevan el uso de datos para mejorar problemas de las comunidades. Al respecto del programa,&nbsp;Rodrigo Iriani, Gerente de proyectos del Trust&nbsp;for the Americas coment\u00f3: \u201cLas iniciativas de Gobierno Abierto de The Trust for the Americas fomentan la colaboraci\u00f3n entre diversos sectores de sociedad civil, el sector privado y los gobiernos para promover proyectos de innovaci\u00f3n c\u00edvica que mejoren la calidad de vida de los ciudadanos de la regi\u00f3n. Durante la semana de eventos trabajaremos junto con entusiastas del gobierno abierto de todo el mundo para intercambiar experiencias y comprometernos a alcanzar mayor y mejor participaci\u00f3n de todos los sectores de la sociedad\u201d Por su parte, A\u00edda Mart\u00ednez M\u00f3rtola de la ANTAI coment\u00f3: \u201cEl proyecto&nbsp;Innovaci\u00f3n p\u00fablica a trav\u00e9s de los datos abiertos en Panam\u00e1&nbsp;nos ayudar\u00e1 a fortalecer la agenda de Gobierno Abierto en nuestro pa\u00eds, mediante la participaci\u00f3n de nuevos sectores para llevar adelante nuevas pol\u00edticas p\u00fablicas y proyectos, que fomentar\u00e1n una mejor prestaci\u00f3n de los servicios p\u00fablicos. Las actividades en las que participar\u00e1 The Trust for the Americas junto con la OEA, ANTAI y AIG, est\u00e1n alineadas con el desarrollo del Programa Interamericano de Datos Abiertos (PIDA) y se enfocar\u00e1n en compartir los avances del gobierno de Panam\u00e1 en materia de Gobierno Abierto y Datos Abiertos, as\u00ed como la incorporaci\u00f3n de los j\u00f3venes como nuevos actores dentro de las mesas de discusi\u00f3n. La semana cerrar\u00e1 con mesas de di\u00e1logo para elaborar una gu\u00eda de implementaci\u00f3n de la Pol\u00edtica P\u00fablica de Transparencia de Datos Abiertos, y la presentaci\u00f3n del Grupo de Trabajo de Datos Abiertos de Panam\u00e1. Sobre The Trust for the Americas: The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas es una Organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados Americanos (OEA) cuya misi\u00f3n es promover alianzas para la inclusi\u00f3n econ\u00f3mica y social en las Am\u00e9ricas.&nbsp;Establecida en 1997, The Trust fue creado para la participaci\u00f3n del sector p\u00fablico, el sector privado y las iniciativas de la sociedad civil en el desarrollo social y econ\u00f3mico en Am\u00e9rica Latina y el Caribe. Las iniciativas de la organizaci\u00f3n mejoran el acceso de las comunidades a oportunidades econ\u00f3micas, mejor seguridad ciudadana y oportunidades para la expresi\u00f3n democr\u00e1tica y la gobernabilidad.&nbsp; The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas ofrece a las organizaciones locales asociadas, instrumentos de capacitaci\u00f3n, servicios, productos y asistencia t\u00e9cnica para servir mejor a las comunidades vulnerables de la regi\u00f3n.&nbsp; Visite:&nbsp;www.trustfortheamericas.org Facebook:&nbsp;The Trust for the Americas&nbsp; Twitter:&nbsp;&nbsp;&nbsp;@Trust4Americas Panam\u00e1<\/p>","protected":false},"author":37,"featured_media":8300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-8299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=8299"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8299\/revisions"}],"predecessor-version":[{"id":8301,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8299\/revisions\/8301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/8300"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=8299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=8299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=8299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}