{"id":8216,"date":"2020-04-08T15:09:00","date_gmt":"2020-04-08T15:09:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=8216"},"modified":"2024-11-21T15:10:06","modified_gmt":"2024-11-21T15:10:06","slug":"proyecto-vive-genero-estrategia-de-capacitacion-y-oportunidades-economicas-en-el-contexto-del-covid-19","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/proyecto-vive-genero-estrategia-de-capacitacion-y-oportunidades-economicas-en-el-contexto-del-covid-19\/","title":{"rendered":"Proyecto VIVE gener\u00f3 estrategia de Capacitaci\u00f3n y Oportunidades Econ\u00f3micas en el Contexto del COVID-19"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2020\/04\/08<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Originalmente publicado en el blog de The Trust for the Americas por Elizabeth Laredo y Maria Fernanda Sierra.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agradecemos a&nbsp;<a href=\"https:\/\/walmart.org\/\">Walmart<\/a>&nbsp;Foundation&nbsp;por contar con su apoyo para estos esfuerzos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A finales del mes de marzo lanzamos&nbsp;una exitosa estrategia digital para ofrecer capacitaci\u00f3n y contenidos de calidad para mujeres egresadas del Proyecto VIVE y nuevas participantes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Sesiones virtuales en l\u00ednea:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Las sesiones responden a las recomendaciones de la Organizaci\u00f3n Mundial de la Salud (OMS) sobre el distanciamiento social y de la crisis actual por el COVID-19, con medidas virtuales e innovadoras para continuar implementando nuestra oferta de capacitaci\u00f3n.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Dise\u00f1amos\u00a0<strong>9 Seminarios digitales que ser\u00e1n impartidos entre el 25 de marzo y el 30 de abril<\/strong>, los martes y jueves a las 7:00 p.m. hora de CDMX. Estas sesiones se imparten v\u00eda Facebook LIVE, lo cual fomenta la interacci\u00f3n din\u00e1mica y creaci\u00f3n de comunidad entre los y las participantes. Algunas sesiones se complementan mediante podcasts.<\/li>\n\n\n\n<li>Hasta el 8 de abril hemos impartido exitosamente\u00a0<strong>4 cursos virtuales en<\/strong>\u00a0dos semanas, alcanzando a un total de\u00a0<strong>473 participantes<\/strong>\u00a0(+80% mujeres), m\u00e1s de cuatro mil reproducciones y m\u00e1s de ocho mil personas alcanzadas en Facebook (@ProyectoVIVEmx).<\/li>\n\n\n\n<li><strong>Continuamos con la difusi\u00f3n de \u201cVIVE En L\u00ednea\u201d en el\u00a0<\/strong><a href=\"https:\/\/aulavirtual.trustfortheamericas.org\/\"><strong>Aula Virtual<\/strong><\/a><strong>\u00a0del Trust:<\/strong>\u00a0Este contenido est\u00e1 alineado a tres est\u00e1ndares de certificaci\u00f3n que ofrece el Consejo Nacional de Normalizaci\u00f3n y Certificaci\u00f3n de Competencias Laborales (CONOCER), organismo afiliado a la Secretar\u00eda de Educaci\u00f3n P\u00fablica en M\u00e9xico. El curso est\u00e1 abierto al p\u00fablico en general.<\/li>\n<\/ul>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>Contenido Exclusivo para Egresadas:<\/strong><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Dise\u00f1amos contenido exclusivo para mujeres que son egresadas del Proyecto VIVE, estos insumos son compartidos a trav\u00e9s de Facebook, espec\u00edficamente en el grupo privado de Facebook \u201c<em>Comunidad de Egresadas de Proyecto VIVE\u201d<\/em>. Estos contenidos son:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\n<ol class=\"wp-block-list\">\n<li><strong>Tutoriales breves sobre c\u00f3mo utilizar herramientas digitales para ventas:<\/strong>\u00a0la duraci\u00f3n de estos videos est\u00e1 entre 5 y 10 minutos en los cuales se explica paso a paso c\u00f3mo utilizar las herramientas de venta en l\u00ednea gratuitas m\u00e1s comunes. El contenido est\u00e1 dise\u00f1ado para egresadas con poca o casi nula alfabetizaci\u00f3n digital. Los temas incluyen: \u00bfC\u00f3mo hacer la p\u00e1gina de Facebook de mi emprendimiento? \u00bfC\u00f3mo registrar mi negocio en el Directorio de Emprendedoras VIVE? \u00bfC\u00f3mo utilizar Microsoft Office para dise\u00f1ar las publicaciones sobre mi emprendimiento?<\/li>\n\n\n\n<li><strong>Contenido con recomendaciones sobre c\u00f3mo promocionar sus emprendimientos durante la contingencia del COVID-19:<\/strong>\u00a0destinado a egresadas con una avanzada alfabetizaci\u00f3n digital.<\/li>\n\n\n\n<li><strong>Recomendaciones sobre sesiones de capacitaci\u00f3n relevantes para ayudar a sus emprendimientos a sobrellevar la contingencia.\u00a0<\/strong><strong>Promover el registro y uso del Directorio de Emprendedoras VIVE:<\/strong><\/li>\n<\/ol>\n<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>3. Promover el registro y uso del Directorio de Emprendedoras VIVE:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A finales del a\u00f1o 2019 creamos un directorio de emprendedoras, en el cual las egresadas del Proyecto VIVE pueden registrar la informaci\u00f3n b\u00e1sica de sus emprendimientos y darles difusi\u00f3n. Nos encargamos de divulgar el directorio mediante nuestra comunidad en l\u00ednea y con nuestros aliados estrat\u00e9gicos. Para m\u00e1s informaci\u00f3n, aqu\u00ed las ligas para consultar el&nbsp;<a href=\"https:\/\/tfaoea.wordpress.com\/2020\/01\/09\/directorio-de-emprendedoras-vive-una-opcion-para-encontrar-los-productos-que-buscas\/\">blog<\/a>&nbsp;and the&nbsp;<a href=\"https:\/\/nuevo.sit.trustfortheamericas.org\/es\/directorio-vive\/listado-directorio-vive\">directorio<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vamos a fortalecer nuestro esfuerzo en la promoci\u00f3n del directorio de la siguiente manera:\n<ol class=\"wp-block-list\">\n<li>\n<ol class=\"wp-block-list\">\n<li>Dise\u00f1ar una estrategia para volver al Directorio m\u00e1s visible ante potenciales compradores.<\/li>\n\n\n\n<li>Expandir el alcance del Directorio para incluir a otros proyectos de TheTrust for the Americas, como los que se est\u00e1n implementando en Puerto Rico y Rep\u00fablica Dominicana y as\u00ed, vincularlo a una iniciativa regional.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<\/li>\n<\/ul>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li><strong>Crear un Banco de Talento para promover entre nuestros socios potenciales:\u00a0<\/strong>considerando que a pesar de nuestros esfuerzos el sector empresarial se ver\u00e1 altamente lastimado durante la contingencia, buscamos fortalecer nuestro componente de empleabilidad mediante la creaci\u00f3n de un Banco de Talento que podamos compartir con nuestros aliados en el sector privado y proporcionales una lista de empleadas potenciales que cumplen con sus criterios de selecci\u00f3n.<\/li>\n\n\n\n<li><strong>\u201cLavado de Manos\u201d\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/ProyectoVIVEmx\/videos\/724054778341506\/\"><strong>Jingle<\/strong><\/a><strong>:<\/strong>\u00a0En 2018 tuvimos un concurso entre las egresadas para seleccionar el mejor \u201c<em>jingle\u201d<\/em>\u00a0del Proyecto. Raquel Pedroza, egresada en Ciudad de M\u00e9xico, cre\u00f3 la canci\u00f3n ganadora. Retomamos este jingle y lo convertimos en un video corto para promover el correcto lavado de manos (<a href=\"https:\/\/www.facebook.com\/watch\/?v=724054778341506\">liga al video<\/a>). Raquel es una participante activa de nuestra comunidad de egresadas y particip\u00f3 en la\u00a0<em>Serie de Concursos de Pitch de CDMX\u00a0<\/em>en 2019<em>.<\/em><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Mexico<\/p>","protected":false},"excerpt":{"rendered":"<p>2020\/04\/08 Originalmente publicado en el blog de The Trust for the Americas por Elizabeth Laredo y Maria Fernanda Sierra. Agradecemos a&nbsp;Walmart&nbsp;Foundation&nbsp;por contar con su apoyo para estos esfuerzos. A finales del mes de marzo lanzamos&nbsp;una exitosa estrategia digital para ofrecer capacitaci\u00f3n y contenidos de calidad para mujeres egresadas del Proyecto VIVE y nuevas participantes: Las sesiones responden a las recomendaciones de la Organizaci\u00f3n Mundial de la Salud (OMS) sobre el distanciamiento social y de la crisis actual por el COVID-19, con medidas virtuales e innovadoras para continuar implementando nuestra oferta de capacitaci\u00f3n. Dise\u00f1amos contenido exclusivo para mujeres que son egresadas del Proyecto VIVE, estos insumos son compartidos a trav\u00e9s de Facebook, espec\u00edficamente en el grupo privado de Facebook \u201cComunidad de Egresadas de Proyecto VIVE\u201d. Estos contenidos son: 3. Promover el registro y uso del Directorio de Emprendedoras VIVE: A finales del a\u00f1o 2019 creamos un directorio de emprendedoras, en el cual las egresadas del Proyecto VIVE pueden registrar la informaci\u00f3n b\u00e1sica de sus emprendimientos y darles difusi\u00f3n. Nos encargamos de divulgar el directorio mediante nuestra comunidad en l\u00ednea y con nuestros aliados estrat\u00e9gicos. Para m\u00e1s informaci\u00f3n, aqu\u00ed las ligas para consultar el&nbsp;blog&nbsp;y el&nbsp;directorio. Mexico<\/p>","protected":false},"author":37,"featured_media":8217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-8216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=8216"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8216\/revisions"}],"predecessor-version":[{"id":8218,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8216\/revisions\/8218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/8217"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=8216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=8216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=8216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}