{"id":8161,"date":"2021-03-06T14:41:00","date_gmt":"2021-03-06T14:41:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=8161"},"modified":"2024-11-21T14:42:09","modified_gmt":"2024-11-21T14:42:09","slug":"the-trust-for-the-americas-firma-convenio-de-colaboracion-para-beneficiar-a-mujeres-en-el-municipio-de-los-cabos-en-mexico","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/the-trust-for-the-americas-firma-convenio-de-colaboracion-para-beneficiar-a-mujeres-en-el-municipio-de-los-cabos-en-mexico\/","title":{"rendered":"The Trust for the Americas firma Convenio de Colaboraci\u00f3n para beneficiar a mujeres en el Municipio de Los Cabos en M\u00e9xico"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2021\/03\/06<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e9xico 5 de marzo de 2021\u2013 En el marco del D\u00eda Internacional de la Mujer, The Trust for the Am\u00e9ricas, el Instituto de las Mujeres del Municipio de Los Cabos y Manpower Group, firmaron un convenio de colaboraci\u00f3n para ejecutar el programa denominado \u201cFRANQUICIA SOCIAL POETA Y PROYECTO VIVE EN AULA VIRTUAL\u201d, para fortalecer la econom\u00eda de las mujeres en el municipio de Los Cabos en Baja California Sur, M\u00e9xico, a trav\u00e9s del Proyecto VIVE: Ven, insp\u00edrate y vende.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siguiendo las recomendaciones de distanciamiento social por el COVID-19, la firma se realiz\u00f3 de forma virtual, Lorena Cort\u00e9s Torralbo, Directora General del Instituto de las Mujeres del Municipio de Los Cabos, explic\u00f3 que con esta alianza, las mujeres podr\u00e1n acceder a herramientas digitales para el emprendimiento y empleabilidad, con lo que se pretende reforzar sus habilidades y sumar a su empoderamiento econ\u00f3mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta alianza nos permite cumplir con las exigencias que nos est\u00e1 pidiendo la ciudadan\u00eda, en espec\u00edfico las mujeres. Vivir una situaci\u00f3n de violencia no es conveniente para nadie. En M\u00e9xico, estamos enfrentando una realidad y hay que implementar una estrategia a nivel nacional para poder prevenir y atender estas violencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sumarnos a la Franquicia Social Poeta es significa un gran avance porque vamos a dar respuesta a esta situaci\u00f3n de prevenci\u00f3n y tambi\u00e9n vamos a dar estas herramientas para su empoderamiento econ\u00f3mico\u201d, afirm\u00f3 Cortes Torralbo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido Eduardo Almanza, Gerente Regional de Capacitaci\u00f3n y Empleabilidad de Manpower Group M\u00e9xico, reiter\u00f3 que \u201cestamos muy contentos porque vamos a continuar impartiendo capacitaci\u00f3n y desarrollo, creemos que para prevenir la violencia hacia las mujeres y las ni\u00f1as es necesario impulsar la educaci\u00f3n. Esta alianza para ser parte de la franquicia, es un gran logro, porque haber migrado a la virtualidad es un gran avance, es importante recordar que el mundo que conoc\u00edamos no va a regresar. Tenemos amplias expectativas porque este modelo significa ampliar oportunidades para las mujeres que tomen VIVE\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Klaudia Gonz\u00e1lez, Coordinadora Nacional del Proyecto VIVE en M\u00e9xico, record\u00f3 que en cuatro a\u00f1os \u201clogramos capacitar a m\u00e1s de 72 mil personas. Con proyecto VIVE tuvimos grandes resultados, que estoy segura, se repetir\u00e1n en la Franquicia. Esta alianza es un ejemplo vivo que no solo se firman papeles, sino que se hace trabajo en favor de las mujeres. En el marco del D\u00eda Internacional de la Mujer, reconocemos que hay mucho camino por recorrer, muchas cosas por hacer, la erradicaci\u00f3n de la violencia hacia las mujeres tiene que ser una realidad, tiene que ser una prioridad. Estoy segura que con alianzas como esta, lo vamos a lograr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Proyecto VIVE es implementado en M\u00e9xico por The Trust for the Americas desde el 2016 gracias al apoyo&nbsp; de Walmart Foundation. El Proyecto tiene como objetivo ofrecer herramientas que permitan el desarrollo econ\u00f3mico de las mujeres y darles alternativas que mejoren su condici\u00f3n econ\u00f3mica y la de su familia. Entre 2016 y 2020 capacit\u00f3 a m\u00e1s de 72 mil personas a nivel nacional. Del total de personas capacitadas, m\u00e1s de 53 mil son mujeres (40% de las cuales son jefas de familia). Asimismo, cerca de 11 mil personas fueron vinculadas a oportunidades econ\u00f3micas (86% mujeres, 60% fueron vinculadas a un trabajo de tiempo completo y el 21% se auto emplearon o iniciaron proyectos de emprendimiento).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mayor informaci\u00f3n\u202fentra en:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visite:\u202fwww.trust-oea.org\/vive<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:\u202fThe Trust for the Americas\u202f<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twitter:\u202f\u202f\u202f@Trust4Americas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Proyecto VIVE: @ProyectoVIVEMx<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Mexico<\/p>","protected":false},"excerpt":{"rendered":"<p>2021\/03\/06 M\u00e9xico 5 de marzo de 2021\u2013 En el marco del D\u00eda Internacional de la Mujer, The Trust for the Am\u00e9ricas, el Instituto de las Mujeres del Municipio de Los Cabos y Manpower Group, firmaron un convenio de colaboraci\u00f3n para ejecutar el programa denominado \u201cFRANQUICIA SOCIAL POETA Y PROYECTO VIVE EN AULA VIRTUAL\u201d, para fortalecer la econom\u00eda de las mujeres en el municipio de Los Cabos en Baja California Sur, M\u00e9xico, a trav\u00e9s del Proyecto VIVE: Ven, insp\u00edrate y vende. Siguiendo las recomendaciones de distanciamiento social por el COVID-19, la firma se realiz\u00f3 de forma virtual, Lorena Cort\u00e9s Torralbo, Directora General del Instituto de las Mujeres del Municipio de Los Cabos, explic\u00f3 que con esta alianza, las mujeres podr\u00e1n acceder a herramientas digitales para el emprendimiento y empleabilidad, con lo que se pretende reforzar sus habilidades y sumar a su empoderamiento econ\u00f3mico. \u201cEsta alianza nos permite cumplir con las exigencias que nos est\u00e1 pidiendo la ciudadan\u00eda, en espec\u00edfico las mujeres. Vivir una situaci\u00f3n de violencia no es conveniente para nadie. En M\u00e9xico, estamos enfrentando una realidad y hay que implementar una estrategia a nivel nacional para poder prevenir y atender estas violencias. Sumarnos a la Franquicia Social Poeta es significa un gran avance porque vamos a dar respuesta a esta situaci\u00f3n de prevenci\u00f3n y tambi\u00e9n vamos a dar estas herramientas para su empoderamiento econ\u00f3mico\u201d, afirm\u00f3 Cortes Torralbo. En ese sentido Eduardo Almanza, Gerente Regional de Capacitaci\u00f3n y Empleabilidad de Manpower Group M\u00e9xico, reiter\u00f3 que \u201cestamos muy contentos porque vamos a continuar impartiendo capacitaci\u00f3n y desarrollo, creemos que para prevenir la violencia hacia las mujeres y las ni\u00f1as es necesario impulsar la educaci\u00f3n. Esta alianza para ser parte de la franquicia, es un gran logro, porque haber migrado a la virtualidad es un gran avance, es importante recordar que el mundo que conoc\u00edamos no va a regresar. Tenemos amplias expectativas porque este modelo significa ampliar oportunidades para las mujeres que tomen VIVE\u201d. Klaudia Gonz\u00e1lez, Coordinadora Nacional del Proyecto VIVE en M\u00e9xico, record\u00f3 que en cuatro a\u00f1os \u201clogramos capacitar a m\u00e1s de 72 mil personas. Con proyecto VIVE tuvimos grandes resultados, que estoy segura, se repetir\u00e1n en la Franquicia. Esta alianza es un ejemplo vivo que no solo se firman papeles, sino que se hace trabajo en favor de las mujeres. En el marco del D\u00eda Internacional de la Mujer, reconocemos que hay mucho camino por recorrer, muchas cosas por hacer, la erradicaci\u00f3n de la violencia hacia las mujeres tiene que ser una realidad, tiene que ser una prioridad. Estoy segura que con alianzas como esta, lo vamos a lograr. El Proyecto VIVE es implementado en M\u00e9xico por The Trust for the Americas desde el 2016 gracias al apoyo&nbsp; de Walmart Foundation. El Proyecto tiene como objetivo ofrecer herramientas que permitan el desarrollo econ\u00f3mico de las mujeres y darles alternativas que mejoren su condici\u00f3n econ\u00f3mica y la de su familia. Entre 2016 y 2020 capacit\u00f3 a m\u00e1s de 72 mil personas a nivel nacional. Del total de personas capacitadas, m\u00e1s de 53 mil son mujeres (40% de las cuales son jefas de familia). Asimismo, cerca de 11 mil personas fueron vinculadas a oportunidades econ\u00f3micas (86% mujeres, 60% fueron vinculadas a un trabajo de tiempo completo y el 21% se auto emplearon o iniciaron proyectos de emprendimiento). Para mayor informaci\u00f3n\u202fentra en:&nbsp; Visite:\u202fwww.trust-oea.org\/vive Facebook:\u202fThe Trust for the Americas\u202f Twitter:\u202f\u202f\u202f@Trust4Americas Proyecto VIVE: @ProyectoVIVEMx Sobre The Trust for the Americas: The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. Mexico<\/p>","protected":false},"author":37,"featured_media":8162,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-8161","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=8161"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8161\/revisions"}],"predecessor-version":[{"id":8163,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8161\/revisions\/8163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/8162"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=8161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=8161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=8161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}