{"id":8037,"date":"2019-03-04T17:01:00","date_gmt":"2019-03-04T17:01:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=8037"},"modified":"2024-11-20T05:02:48","modified_gmt":"2024-11-20T05:02:48","slug":"maria-juliana-ruiz-primera-dama-de-la-nacion-colombiana-visito-el-centro-mi-llave-laudes-infantis-en-la-localidad-de-ciudad-bolivar-al-sur-de-bogota","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/maria-juliana-ruiz-primera-dama-de-la-nacion-colombiana-visito-el-centro-mi-llave-laudes-infantis-en-la-localidad-de-ciudad-bolivar-al-sur-de-bogota\/","title":{"rendered":"Mar\u00eda Juliana Ruiz, Primera Dama de la Naci\u00f3n Colombiana visit\u00f3 el Centro Mi Llave Laudes Infantis, en la localidad de Ciudad Bol\u00edvar, al sur de Bogot\u00e1"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Bogot\u00e1, D.C.<\/strong>&nbsp;(28 de febrero de 2019) \u2014 Mar\u00eda Juliana Ruiz, Primera Dama de la Naci\u00f3n Colombiana, visit\u00f3 el Centro Mi Llave Laudes Infantis, ubicado en Ciudad Bol\u00edvar una de las localidades m\u00e1s vulnerables de la capital colombiana. La visita fue guiada por Linda Eddleman, Directora Ejecutiva de The Trust for the Americas y Jaqueline Moreno, Directora de la Fundaci\u00f3n Laudes Infantis, socio local de The Trust for the Americas hace m\u00e1s de ocho a\u00f1os. &nbsp;Adem\u00e1s acompa\u00f1aron la visita Andr\u00e9s Uma\u00f1a, Director de Asuntos Corporativos de Microsoft Colombia y Natalia Serrano, representante de Microsoft Filantrop\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Centro Mi Llave Bella Flor fue inaugurado en julio de 2011 gracias a la alianza entre la Fundaci\u00f3n Laudes Infantis y The Trust for the Americas, con el objetivo de promover oportunidades educativas y econ\u00f3micas, especialmente para mujeres j\u00f3venes y adultas que habitan las localidades de Ciudad Bol\u00edvar, Usme y San Crist\u00f3bal, al sur de Bogot\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el a\u00f1o 2011, el Centro Mi Llave ha impactado la vida de m\u00e1s de&nbsp;<strong>14.477 j\u00f3venes<\/strong>&nbsp;y ha generado m\u00e1s de&nbsp;<strong>143 Oportunidades Econ\u00f3micas<\/strong>&nbsp;de las cuales el&nbsp;<strong>70%<\/strong>&nbsp;son mujeres entre los 16 y 35 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias al modelo de intervenci\u00f3n a traves de la metodolog\u00eda del trueque, la Fundaci\u00f3n Laudes Infantis logr\u00f3 que la poblaci\u00f3n acceda a servicios comunitarios y formativos a cambio de aportes no econ\u00f3micos para mejorar la situacion de las mujeres y sus familias. &nbsp;Con \u00e9sta modalidad, el servicio que se ofrece al miembro de la comunidad se brinda a cambio de esfuerzos personales como el compromiso de modificar alguna conducta o h\u00e1bito, acudir a atenci\u00f3n en orientaci\u00f3n y conciliaci\u00f3n o a alguna capacitaci\u00f3n que le permita adquirir herramientas para enfrentar mejorar su realidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la visita, la Primera Dama recorri\u00f3 el Centro Tecnol\u00f3gico, convers\u00f3 con las participantes y habl\u00f3 de poder determinar posibles caminos de trabajo articulado que permitan seguir generando oportunidades de colaboraci\u00f3n para fomentar el desarrollo de habilidades, capacidades y talentos, al igual que la inclusi\u00f3n social y econ\u00f3mica de los j\u00f3venes en Colombia, a trav\u00e9s de la estrategia nacional \u201cSac\u00fadete\u201d, liderada por la Consejer\u00eda Presidencial para la Juventud-Colombia Joven. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Linda Eddleman, CEO de The Trust for the Americas, agradeci\u00f3 a Mar\u00eda Juliana Ruiz y a Microsoft por haber aceptado la invitaci\u00f3n y buscar caminos de colaboraci\u00f3n conjunta para apoyar las iniciativas del Gobierno Colombiano generando m\u00e1s derechos para m\u00e1s personas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n agradeci\u00f3 a Jaqueline Moreno, Directora de la Fundaci\u00f3n Laudes Infantis por convertirse en aliado de The Trust for the Americas y trabajar conjuntamente con las iniciativas de la instituci\u00f3n y su modelo de Franquicia Social POETA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la jornada, tambi\u00e9n particip\u00f3 la Directora Ejecutiva de The Trust for the Americas en Colombia; Myriam Stella Romero, la Directora de Programas; Mar\u00eda Liliana Mor, la Gerente de Proyectos; Luz Marina Correa y el Coordinador de Comunicaciones; Manuel Matiz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas es una Organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados Americanos (OEA) cuya misi\u00f3n es promover alianzas para la inclusi\u00f3n econ\u00f3mica y social en las Am\u00e9ricas.&nbsp;Establecida en 1997, The Trust fue creado para la participaci\u00f3n del sector p\u00fablico, el sector privado y las iniciativas de la sociedad civil en el desarrollo social y econ\u00f3mico en Am\u00e9rica Latina y el Caribe. Las iniciativas de la organizaci\u00f3n mejoran el acceso de las comunidades a oportunidades econ\u00f3micas, mejor seguridad ciudadana y oportunidades para la expresi\u00f3n democr\u00e1tica y la gobernabilidad.&nbsp; The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas ofrece a las organizaciones locales asociadas, instrumentos de capacitaci\u00f3n, servicios, productos y asistencia t\u00e9cnica para servir mejor a las comunidades vulnerables de la regi\u00f3n.&nbsp; Visite:&nbsp;<a href=\"http:\/\/www.trustfortheamericas.org\/\">www.trustfortheamericas.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:&nbsp;<a href=\"https:\/\/www.facebook.com\/TheTrustfortheAmericas\/\">The Trust for the Americas<\/a>&nbsp; Twitter:&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/twitter.com\/Trust4Americas\">@Trust4Americas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Colombia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Bogot\u00e1, D.C.&nbsp;(28 de febrero de 2019) \u2014 Mar\u00eda Juliana Ruiz, Primera Dama de la Naci\u00f3n Colombiana, visit\u00f3 el Centro Mi Llave Laudes Infantis, ubicado en Ciudad Bol\u00edvar una de las localidades m\u00e1s vulnerables de la capital colombiana. La visita fue guiada por Linda Eddleman, Directora Ejecutiva de The Trust for the Americas y Jaqueline Moreno, Directora de la Fundaci\u00f3n Laudes Infantis, socio local de The Trust for the Americas hace m\u00e1s de ocho a\u00f1os. &nbsp;Adem\u00e1s acompa\u00f1aron la visita Andr\u00e9s Uma\u00f1a, Director de Asuntos Corporativos de Microsoft Colombia y Natalia Serrano, representante de Microsoft Filantrop\u00eda. El Centro Mi Llave Bella Flor fue inaugurado en julio de 2011 gracias a la alianza entre la Fundaci\u00f3n Laudes Infantis y The Trust for the Americas, con el objetivo de promover oportunidades educativas y econ\u00f3micas, especialmente para mujeres j\u00f3venes y adultas que habitan las localidades de Ciudad Bol\u00edvar, Usme y San Crist\u00f3bal, al sur de Bogot\u00e1. Desde el a\u00f1o 2011, el Centro Mi Llave ha impactado la vida de m\u00e1s de&nbsp;14.477 j\u00f3venes&nbsp;y ha generado m\u00e1s de&nbsp;143 Oportunidades Econ\u00f3micas&nbsp;de las cuales el&nbsp;70%&nbsp;son mujeres entre los 16 y 35 a\u00f1os. Gracias al modelo de intervenci\u00f3n a traves de la metodolog\u00eda del trueque, la Fundaci\u00f3n Laudes Infantis logr\u00f3 que la poblaci\u00f3n acceda a servicios comunitarios y formativos a cambio de aportes no econ\u00f3micos para mejorar la situacion de las mujeres y sus familias. &nbsp;Con \u00e9sta modalidad, el servicio que se ofrece al miembro de la comunidad se brinda a cambio de esfuerzos personales como el compromiso de modificar alguna conducta o h\u00e1bito, acudir a atenci\u00f3n en orientaci\u00f3n y conciliaci\u00f3n o a alguna capacitaci\u00f3n que le permita adquirir herramientas para enfrentar mejorar su realidad. Durante la visita, la Primera Dama recorri\u00f3 el Centro Tecnol\u00f3gico, convers\u00f3 con las participantes y habl\u00f3 de poder determinar posibles caminos de trabajo articulado que permitan seguir generando oportunidades de colaboraci\u00f3n para fomentar el desarrollo de habilidades, capacidades y talentos, al igual que la inclusi\u00f3n social y econ\u00f3mica de los j\u00f3venes en Colombia, a trav\u00e9s de la estrategia nacional \u201cSac\u00fadete\u201d, liderada por la Consejer\u00eda Presidencial para la Juventud-Colombia Joven. &nbsp; Por su parte, Linda Eddleman, CEO de The Trust for the Americas, agradeci\u00f3 a Mar\u00eda Juliana Ruiz y a Microsoft por haber aceptado la invitaci\u00f3n y buscar caminos de colaboraci\u00f3n conjunta para apoyar las iniciativas del Gobierno Colombiano generando m\u00e1s derechos para m\u00e1s personas.&nbsp; Tambi\u00e9n agradeci\u00f3 a Jaqueline Moreno, Directora de la Fundaci\u00f3n Laudes Infantis por convertirse en aliado de The Trust for the Americas y trabajar conjuntamente con las iniciativas de la instituci\u00f3n y su modelo de Franquicia Social POETA. Durante la jornada, tambi\u00e9n particip\u00f3 la Directora Ejecutiva de The Trust for the Americas en Colombia; Myriam Stella Romero, la Directora de Programas; Mar\u00eda Liliana Mor, la Gerente de Proyectos; Luz Marina Correa y el Coordinador de Comunicaciones; Manuel Matiz. Sobre The Trust for the Americas: The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas es una Organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados Americanos (OEA) cuya misi\u00f3n es promover alianzas para la inclusi\u00f3n econ\u00f3mica y social en las Am\u00e9ricas.&nbsp;Establecida en 1997, The Trust fue creado para la participaci\u00f3n del sector p\u00fablico, el sector privado y las iniciativas de la sociedad civil en el desarrollo social y econ\u00f3mico en Am\u00e9rica Latina y el Caribe. Las iniciativas de la organizaci\u00f3n mejoran el acceso de las comunidades a oportunidades econ\u00f3micas, mejor seguridad ciudadana y oportunidades para la expresi\u00f3n democr\u00e1tica y la gobernabilidad.&nbsp; The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas ofrece a las organizaciones locales asociadas, instrumentos de capacitaci\u00f3n, servicios, productos y asistencia t\u00e9cnica para servir mejor a las comunidades vulnerables de la regi\u00f3n.&nbsp; Visite:&nbsp;www.trustfortheamericas.org Facebook:&nbsp;The Trust for the Americas&nbsp; Twitter:&nbsp;&nbsp;&nbsp;@Trust4Americas Colombia<\/p>","protected":false},"author":38,"featured_media":8038,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-8037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=8037"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8037\/revisions"}],"predecessor-version":[{"id":8039,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/8037\/revisions\/8039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/8038"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=8037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=8037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=8037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}