{"id":7916,"date":"2020-12-17T15:33:00","date_gmt":"2020-12-17T15:33:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7916"},"modified":"2024-11-20T03:36:01","modified_gmt":"2024-11-20T03:36:01","slug":"closing-event-innovation-through-open-data-in-panama","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/closing-event-innovation-through-open-data-in-panama\/","title":{"rendered":"Closing Event Innovation through Open Data in Panama"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Washington, D.C. 17 de diciembre de 2020.- Despu\u00e9s de dos a\u00f1os de exitosa implementaci\u00f3n, The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;de la Organizaci\u00f3n de Estados Americanos (OEA) presenta resultados&nbsp;para marcar la culminaci\u00f3n &nbsp;del Proyecto&nbsp;\u201cInnovaci\u00f3n a trav\u00e9s de Datos Abiertos en Panam\u00e1\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto denominado \u201cInnovaci\u00f3n p\u00fablica a trav\u00e9s de los Datos Abiertos en Panam\u00e1\u201d se desarroll\u00f3 para incentivar a los gobiernos&nbsp; y a la sociedad civil de Panam\u00e1 a que, de manera colaborativa, generen espacios de discusi\u00f3n, colaboraci\u00f3n, deliberaci\u00f3n de pol\u00edticas p\u00fablicas, y proyectos mediante el uso de datos abiertos. El proyecto fue&nbsp;financiado por la Embajada de los Estados Unidos en Panam\u00e1 y se implement\u00f3&nbsp;en tres fases: formaci\u00f3n t\u00e9cnica para servidores p\u00fablicos, sociedad civil, academia, medios de comunicaci\u00f3n y el sector privado; creaci\u00f3n de espacios de di\u00e1logo e intercambio de ideas para fomentar la inclusi\u00f3n de todos los sectores en la b\u00fasqueda de soluciones; y, por \u00faltimo, el financiamiento de iniciativas sociales innovadoras que promuevan el uso de datos para mejorar problemas de las comunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente, este proyecto&nbsp;form\u00f3 exitosas&nbsp;alianzas con distintos sectores de la sociedad incluyendo, sector privado, gobierno, academia y sociedad civil. Durante el evento de cierre se presentaron los hitos del proyecto que se construyeron de la mano de organizaciones como&nbsp;el Instituto Paname\u00f1o de Derecho y Nuevas Tecnolog\u00edas (IPANDETEC),&nbsp;la&nbsp;Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI),&nbsp;la Autoridad para la Innovaci\u00f3n Gubernamental (AIG)&nbsp;y&nbsp;la Direcci\u00f3n General de Contrataciones P\u00fablicas (DGCP).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La agenda de presentaci\u00f3n de resultados queda reflejada a continuaci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Presentaci\u00f3n de Resultados<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Proyecto \u201cInnovaci\u00f3n a trav\u00e9s de los Datos Abiertos en Panam\u00e1\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">17 de diciembre de 2020 \u2013 2 pm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.00pm. Palabras de Bienvenida y Presentaci\u00f3n del Proyecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elsa Fern\u00e1ndez, Directora General ANTAI y Rodrigo Iriani, Gerente de Programa Senior, The Trust for the Americas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.10pm. Resultados componente Capacitaci\u00f3n a Funcionarios y Sociedad Civil<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juan Pablo Rodr\u00edguez, ANTAI y Hamzah Haji, The Trust for the Americas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.30pm. Y4OD \u2013 J\u00f3venes en Datos Abiertos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jorge Uma\u00f1a, The Trust for the Americas y Lia Hern\u00e1ndez, IPANDETEC<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.40pm. Proyectos Y4OD<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Modera Ariaxna V\u00e1zquez, IPANDETEC<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2.55pm. Proyectos Financiados<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Sistema de Transparencia Presupuestaria<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Portal Caja del Seguro Social<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; Becas Educativas en la Comarca<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Modera Hamzah Haji, Coordinador Local del Proyecto, The Trust for the Americas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3.10pm. Anuncio Plataforma Seguimiento 4to Plan de Acci\u00f3n OGP y cierre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elsa Fern\u00e1ndez, Directora General ANTAI y Rodrigo Iriani, Gerente de Programa Senior, The Trust for the Americas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sigue nuestros HT para mayor informaci\u00f3n de las actividades:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#Y4ODPanama&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#OpenGovPanama&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas:&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas,&nbsp;The&nbsp;Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la sobre la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n,&nbsp;The&nbsp;Trust contin\u00faa contribuyendo a superar los desaf\u00edos promoviendo alianzas estrat\u00e9gicas que generan resultados sostenibles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una organizaci\u00f3n sin fines de lucro 501 (c) (3) de la Ciudad de Washington DC.\u202f\u202f&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visite:&nbsp;<a href=\"http:\/\/www.trustfortheamericas.org\/\" rel=\"noreferrer noopener\" target=\"_blank\">www.trustfortheamericas.org<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:&nbsp;<a href=\"https:\/\/www.facebook.com\/TheTrustfortheAmericas\/\" rel=\"noreferrer noopener\" target=\"_blank\">The Trust for the Americas<\/a>&nbsp; Twitter:&nbsp;&nbsp;&nbsp;<a href=\"https:\/\/twitter.com\/Trust4Americas\" rel=\"noreferrer noopener\" target=\"_blank\">@Trust4Americas<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Panama<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Washington, D.C. 17 de diciembre de 2020.- Despu\u00e9s de dos a\u00f1os de exitosa implementaci\u00f3n, The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;de la Organizaci\u00f3n de Estados Americanos (OEA) presenta resultados&nbsp;para marcar la culminaci\u00f3n &nbsp;del Proyecto&nbsp;\u201cInnovaci\u00f3n a trav\u00e9s de Datos Abiertos en Panam\u00e1\u201d. El proyecto denominado \u201cInnovaci\u00f3n p\u00fablica a trav\u00e9s de los Datos Abiertos en Panam\u00e1\u201d se desarroll\u00f3 para incentivar a los gobiernos&nbsp; y a la sociedad civil de Panam\u00e1 a que, de manera colaborativa, generen espacios de discusi\u00f3n, colaboraci\u00f3n, deliberaci\u00f3n de pol\u00edticas p\u00fablicas, y proyectos mediante el uso de datos abiertos. El proyecto fue&nbsp;financiado por la Embajada de los Estados Unidos en Panam\u00e1 y se implement\u00f3&nbsp;en tres fases: formaci\u00f3n t\u00e9cnica para servidores p\u00fablicos, sociedad civil, academia, medios de comunicaci\u00f3n y el sector privado; creaci\u00f3n de espacios de di\u00e1logo e intercambio de ideas para fomentar la inclusi\u00f3n de todos los sectores en la b\u00fasqueda de soluciones; y, por \u00faltimo, el financiamiento de iniciativas sociales innovadoras que promuevan el uso de datos para mejorar problemas de las comunidades. Adicionalmente, este proyecto&nbsp;form\u00f3 exitosas&nbsp;alianzas con distintos sectores de la sociedad incluyendo, sector privado, gobierno, academia y sociedad civil. Durante el evento de cierre se presentaron los hitos del proyecto que se construyeron de la mano de organizaciones como&nbsp;el Instituto Paname\u00f1o de Derecho y Nuevas Tecnolog\u00edas (IPANDETEC),&nbsp;la&nbsp;Autoridad Nacional de Transparencia y Acceso a la Informaci\u00f3n (ANTAI),&nbsp;la Autoridad para la Innovaci\u00f3n Gubernamental (AIG)&nbsp;y&nbsp;la Direcci\u00f3n General de Contrataciones P\u00fablicas (DGCP).&nbsp; La agenda de presentaci\u00f3n de resultados queda reflejada a continuaci\u00f3n: Presentaci\u00f3n de Resultados Proyecto \u201cInnovaci\u00f3n a trav\u00e9s de los Datos Abiertos en Panam\u00e1\u201d 17 de diciembre de 2020 \u2013 2 pm. 2.00pm. Palabras de Bienvenida y Presentaci\u00f3n del Proyecto. Elsa Fern\u00e1ndez, Directora General ANTAI y Rodrigo Iriani, Gerente de Programa Senior, The Trust for the Americas 2.10pm. Resultados componente Capacitaci\u00f3n a Funcionarios y Sociedad Civil Juan Pablo Rodr\u00edguez, ANTAI y Hamzah Haji, The Trust for the Americas 2.30pm. Y4OD \u2013 J\u00f3venes en Datos Abiertos Jorge Uma\u00f1a, The Trust for the Americas y Lia Hern\u00e1ndez, IPANDETEC 2.40pm. Proyectos Y4OD Modera Ariaxna V\u00e1zquez, IPANDETEC 2.55pm. Proyectos Financiados &#8211; Sistema de Transparencia Presupuestaria &#8211; Portal Caja del Seguro Social &#8211; Becas Educativas en la Comarca Modera Hamzah Haji, Coordinador Local del Proyecto, The Trust for the Americas 3.10pm. Anuncio Plataforma Seguimiento 4to Plan de Acci\u00f3n OGP y cierre. Elsa Fern\u00e1ndez, Directora General ANTAI y Rodrigo Iriani, Gerente de Programa Senior, The Trust for the Americas. Sigue nuestros HT para mayor informaci\u00f3n de las actividades: #Y4ODPanama&nbsp; #OpenGovPanama&nbsp; Sobre&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas:&nbsp; The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas,&nbsp;The&nbsp;Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la sobre la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n,&nbsp;The&nbsp;Trust contin\u00faa contribuyendo a superar los desaf\u00edos promoviendo alianzas estrat\u00e9gicas que generan resultados sostenibles.&nbsp; The Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;es una organizaci\u00f3n sin fines de lucro 501 (c) (3) de la Ciudad de Washington DC.\u202f\u202f&nbsp;&nbsp;&nbsp;&nbsp; Visite:&nbsp;www.trustfortheamericas.org&nbsp; Facebook:&nbsp;The Trust for the Americas&nbsp; Twitter:&nbsp;&nbsp;&nbsp;@Trust4Americas&nbsp; Panam\u00e1<\/p>","protected":false},"author":38,"featured_media":7917,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=7916"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7916\/revisions"}],"predecessor-version":[{"id":7918,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7916\/revisions\/7918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/7917"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=7916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=7916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=7916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}