{"id":7692,"date":"2021-05-20T05:31:00","date_gmt":"2021-05-20T05:31:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7692"},"modified":"2024-11-19T05:33:31","modified_gmt":"2024-11-19T05:33:31","slug":"eidos-global-y-the-trust-for-the-americas-suman-esfuerzos-para-empoderar-a-personas-en-peru-a-traves-de-habilidades-para-el-futuro","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/eidos-global-y-the-trust-for-the-americas-suman-esfuerzos-para-empoderar-a-personas-en-peru-a-traves-de-habilidades-para-el-futuro\/","title":{"rendered":"Eidos Global y The Trust for the Americas suman esfuerzos para empoderar a personas en Per\u00fa a trav\u00e9s de \u201cHabilidades para el Futuro\u201d"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Eidos&nbsp;Always&nbsp;Learning&nbsp;y&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;convocan a educadores, docentes y facilitadores de Am\u00e9rica Latina a participar en el programa&nbsp;Habilidades para el Futuro, una iniciativa que tiene como finalidad dotar a los profesionales de la educaci\u00f3n de las habilidades digitales necesarias para potenciar el desarrollo de la empleabilidad en Latinoam\u00e9rica. El programa cuenta con el apoyo de Microsoft.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;programa est\u00e1 destinado a docentes de cualquier instituci\u00f3n, que cuenten con un nivel m\u00ednimo de alfabetizaci\u00f3n digital y quieran mejorar sus habilidades laborales a trav\u00e9s del uso de software.&nbsp; El curso est\u00e1 desarrollado en un formato adaptable y replicable, lo cual facilita su implementaci\u00f3n por parte de los gobiernos y organizaciones que lo llevan adelante.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La capacitaci\u00f3n se enfoca&nbsp;principalmente&nbsp;en la ense\u00f1anza conjunta de contenidos digitales y habilidades cognitivas y socioemocionales a fin de que los participantes&nbsp;se&nbsp;apropien&nbsp;de aprendizajes y&nbsp;puedan&nbsp;aplicarlos en contextos m\u00faltiples de su vida laboral y otros \u00e1mbitos en donde se desarrollen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el curso&nbsp;que se desarrolla de manera&nbsp;virtual y&nbsp;es gratuito, los&nbsp;educadores&nbsp;tendr\u00e1n acceso a una metodolog\u00eda creativa e innovadora para facilitar los espacios de aprendizaje virtual en habilidades digitales y sociales con las herramientas de Microsoft.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A esta alianza se suma&nbsp;Fundades, organizaci\u00f3n que tiene por objetivo contribuir a mejorar la calidad de vida de personas en situaci\u00f3n de vulnerabilidad, especialmente de personas con discapacidad, a trav\u00e9s de la promoci\u00f3n y ejecuci\u00f3n de actividades y proyectos sociales relacionados con la salud, la ni\u00f1ez en&nbsp;situaci\u00f3n de vulnerabilidad, la educaci\u00f3n, el trabajo, el deporte y el medio ambiente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diana Andrade, coordinadora&nbsp;DigiSpark&nbsp;en Per\u00fa, coment\u00f3 que \u201cel futuro se nos presenta con grandes y nuevos desaf\u00edos, por lo tanto,&nbsp;los educadores,&nbsp;docentes&nbsp;y&nbsp;facilitadores, tienen en sus manos la gran responsabilidad de seguir adquiriendo destrezas para que la poblaci\u00f3n con la que trabajan&nbsp;pueda&nbsp;abrir, ampliar o mejorar sus oportunidades en el mundo laboral.\u201d&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las inscripciones estar\u00e1n abiertas hasta el pr\u00f3ximo 21 de mayo y tendremos cupo limitado. Las personas interesadas podr\u00e1n registrarse en&nbsp;<a href=\"http:\/\/bit.ly\/registrohf\" rel=\"noreferrer noopener\" target=\"_blank\">http:\/\/bit.ly\/registrohf<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">POETA&nbsp;DigiSpark&nbsp;es financiado por Microsoft e implementado por&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;en&nbsp;Argentina, Brasil, Chile, Colombia, M\u00e9xico, Per\u00fa y Rep\u00fablica Dominicana&nbsp;a trav\u00e9s de 19&nbsp;socios locales.&nbsp;Desde la implementaci\u00f3n del proyecto en 2012, POETA&nbsp;DigiSpark&nbsp;ha logrado beneficiar a&nbsp;m\u00e1s de&nbsp;34 mil&nbsp;participantes a trav\u00e9s de acceso a centros tecnol\u00f3gicos y ha logrado empoderar a cerca de 40&nbsp;mil&nbsp;participantes a trav\u00e9s de&nbsp;diversas&nbsp;capacitaciones. Adem\u00e1s, ha facilitado cerca de 20 mil&nbsp;oportunidades econ\u00f3micas y educativas en la regi\u00f3n.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mayor informaci\u00f3n:&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visite:\u202f&nbsp;https:\/\/www.trustfortheamericas.org\/programs\/POETA\/poeta-digispark&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:\u202fThe Trust for the Americas&nbsp;&#8211;&nbsp;Twitter:\u202f@Trust4Americas&nbsp;\u2013 Instagram: @Trust4Americas \u2013 LinkedIn: The Trust for the Americas&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre&nbsp;The&nbsp;Trust for the Americas:&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The&nbsp;Trust\u202ffor&nbsp;the&nbsp;Americas&nbsp;es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas,&nbsp;The&nbsp;Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n,&nbsp;The&nbsp;Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Peru<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Eidos&nbsp;Always&nbsp;Learning&nbsp;y&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;convocan a educadores, docentes y facilitadores de Am\u00e9rica Latina a participar en el programa&nbsp;Habilidades para el Futuro, una iniciativa que tiene como finalidad dotar a los profesionales de la educaci\u00f3n de las habilidades digitales necesarias para potenciar el desarrollo de la empleabilidad en Latinoam\u00e9rica. El programa cuenta con el apoyo de Microsoft.&nbsp; El&nbsp;programa est\u00e1 destinado a docentes de cualquier instituci\u00f3n, que cuenten con un nivel m\u00ednimo de alfabetizaci\u00f3n digital y quieran mejorar sus habilidades laborales a trav\u00e9s del uso de software.&nbsp; El curso est\u00e1 desarrollado en un formato adaptable y replicable, lo cual facilita su implementaci\u00f3n por parte de los gobiernos y organizaciones que lo llevan adelante.&nbsp; La capacitaci\u00f3n se enfoca&nbsp;principalmente&nbsp;en la ense\u00f1anza conjunta de contenidos digitales y habilidades cognitivas y socioemocionales a fin de que los participantes&nbsp;se&nbsp;apropien&nbsp;de aprendizajes y&nbsp;puedan&nbsp;aplicarlos en contextos m\u00faltiples de su vida laboral y otros \u00e1mbitos en donde se desarrollen.&nbsp; Durante el curso&nbsp;que se desarrolla de manera&nbsp;virtual y&nbsp;es gratuito, los&nbsp;educadores&nbsp;tendr\u00e1n acceso a una metodolog\u00eda creativa e innovadora para facilitar los espacios de aprendizaje virtual en habilidades digitales y sociales con las herramientas de Microsoft.&nbsp; A esta alianza se suma&nbsp;Fundades, organizaci\u00f3n que tiene por objetivo contribuir a mejorar la calidad de vida de personas en situaci\u00f3n de vulnerabilidad, especialmente de personas con discapacidad, a trav\u00e9s de la promoci\u00f3n y ejecuci\u00f3n de actividades y proyectos sociales relacionados con la salud, la ni\u00f1ez en&nbsp;situaci\u00f3n de vulnerabilidad, la educaci\u00f3n, el trabajo, el deporte y el medio ambiente.&nbsp; Diana Andrade, coordinadora&nbsp;DigiSpark&nbsp;en Per\u00fa, coment\u00f3 que \u201cel futuro se nos presenta con grandes y nuevos desaf\u00edos, por lo tanto,&nbsp;los educadores,&nbsp;docentes&nbsp;y&nbsp;facilitadores, tienen en sus manos la gran responsabilidad de seguir adquiriendo destrezas para que la poblaci\u00f3n con la que trabajan&nbsp;pueda&nbsp;abrir, ampliar o mejorar sus oportunidades en el mundo laboral.\u201d&nbsp; Las inscripciones estar\u00e1n abiertas hasta el pr\u00f3ximo 21 de mayo y tendremos cupo limitado. Las personas interesadas podr\u00e1n registrarse en&nbsp;http:\/\/bit.ly\/registrohf&nbsp; POETA&nbsp;DigiSpark&nbsp;es financiado por Microsoft e implementado por&nbsp;The&nbsp;Trust&nbsp;for&nbsp;the&nbsp;Americas&nbsp;en&nbsp;Argentina, Brasil, Chile, Colombia, M\u00e9xico, Per\u00fa y Rep\u00fablica Dominicana&nbsp;a trav\u00e9s de 19&nbsp;socios locales.&nbsp;Desde la implementaci\u00f3n del proyecto en 2012, POETA&nbsp;DigiSpark&nbsp;ha logrado beneficiar a&nbsp;m\u00e1s de&nbsp;34 mil&nbsp;participantes a trav\u00e9s de acceso a centros tecnol\u00f3gicos y ha logrado empoderar a cerca de 40&nbsp;mil&nbsp;participantes a trav\u00e9s de&nbsp;diversas&nbsp;capacitaciones. Adem\u00e1s, ha facilitado cerca de 20 mil&nbsp;oportunidades econ\u00f3micas y educativas en la regi\u00f3n.&nbsp;&nbsp; Para mayor informaci\u00f3n:&nbsp;&nbsp;&nbsp; Visite:\u202f&nbsp;https:\/\/www.trustfortheamericas.org\/programs\/POETA\/poeta-digispark&nbsp; Facebook:\u202fThe Trust for the Americas&nbsp;&#8211;&nbsp;Twitter:\u202f@Trust4Americas&nbsp;\u2013 Instagram: @Trust4Americas \u2013 LinkedIn: The Trust for the Americas&nbsp; Sobre&nbsp;The&nbsp;Trust for the Americas:&nbsp;&nbsp; The&nbsp;Trust\u202ffor&nbsp;the&nbsp;Americas&nbsp;es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas,&nbsp;The&nbsp;Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n,&nbsp;The&nbsp;Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;&nbsp; Per\u00fa<\/p>","protected":false},"author":38,"featured_media":7693,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=7692"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7692\/revisions"}],"predecessor-version":[{"id":7694,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7692\/revisions\/7694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/7693"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=7692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=7692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=7692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}