{"id":7689,"date":"2021-07-05T17:29:00","date_gmt":"2021-07-05T17:29:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7689"},"modified":"2024-11-19T05:31:27","modified_gmt":"2024-11-19T05:31:27","slug":"the-trust-for-the-americas-a-traves-del-programa-poeta-lanza-su-bootcamp-de-emprendimiento-una-iniciativa-internacional-y-gratuita","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/the-trust-for-the-americas-a-traves-del-programa-poeta-lanza-su-bootcamp-de-emprendimiento-una-iniciativa-internacional-y-gratuita\/","title":{"rendered":"The Trust for the Americas, a trav\u00e9s del Programa POETA, lanza su Bootcamp de Emprendimiento, una iniciativa internacional y gratuita"},"content":{"rendered":"<p class=\"wp-block-paragraph\">La situaci\u00f3n actual, nos ha mostrado que el emprendimiento representa cada vez m\u00e1s una oportunidad para alcanzar la independencia econ\u00f3mica. &nbsp;Tras la llegada de la pandemia por el Covid 19, la Organizaci\u00f3n de Naciones Unidas alert\u00f3 que \u201c114.4 millones de personas se sumaron a la condici\u00f3n de pobreza extrema, 57.8 millones de ellas son mujeres y ni\u00f1as. Esta situaci\u00f3n apunta un duro golpe a los esfuerzos de reducci\u00f3n de la pobreza en todo el mundo\u201d&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante este escenario, The Trust for the Americas, organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados Americanos (OEA), lanza la iniciativa \u201cBootcamp &#8211; Potencializando su Negocio\u201d en Brasil y simult\u00e1neamente en Am\u00e9rica Latina, con el objetivo de desarrollar el emprendimiento. y fortalecer la mentalidad emprendedora de las personas interesadas en iniciar y \/ o fortalecer sus negocios, sobre la base de una experiencia de aprendizaje din\u00e1mica y desafiante.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valentina Coley, facilitadora, CEO y Co-fundadora de Cubo Social, explic\u00f3 que \u201cel Bootcamp de Emprendimiento es un espacio diferenciado que creamos a partir de las expectativas y necesidades de personas emprendedoras, el nivel de madurez de sus emprendimientos, los actuales retos sociales y las principales tendencias en habilidades t\u00e9cnicas y esenciales asociadas a la mentalidad emprendedora\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La convocatoria contar\u00e1 con espacios limitados para mujeres y hombres entre 18 y 60 a\u00f1os. Las sesiones ser\u00e1n sincr\u00f3nicas y asincr\u00f3nicas donde los y las participantes ser\u00e1n desafiadas a comprender el emprendimiento como un medio para la construcci\u00f3n de proyectos de vida y como posibilidad de autonom\u00eda financiera.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer evento, que tuvo lugar el 30 de junio, fue una sesi\u00f3n informativa donde los participantes tuvieron la oportunidad de conocer, en detalle, esta interesante experiencia de capacitaci\u00f3n e implementaci\u00f3n de nuevas herramientas en su propio negocio. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 aprender\u00e1n las y los participantes? Comunicaci\u00f3n asertiva, Liderazgo, Inteligencia emocional, resoluci\u00f3n de problemas, Actitud de ventas, propuesta de valor, Marketing digital y Neurofinanzas en el emprendimiento, entre otro temas. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al finalizar el Bootcamp, 50 personas emprendedoras podr\u00e1n acceder a mentorias especializadas, se realizar\u00e1 proceso de selecci\u00f3n de los participantes de acuerdo al cumplimiento y compromiso con las actividades.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al finalizar el Bootcamp, 50 emprendedores tendr\u00e1n acceso a mentoras especializadas, siendo seleccionados en funci\u00f3n de su compromiso y cumplimiento de actividades a lo largo de la iniciativa que tendr\u00e1 una duraci\u00f3n de 8 semanas, a partir del 12 de julio.&nbsp;Las inscripciones est\u00e1n abiertas hasta el 7 de julio y se pueden realizar en este enlace:&nbsp;<a href=\"https:\/\/bit.ly\/3jatwmN%C2%A0\">https:\/\/bit.ly\/3jatwmN&nbsp;<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para mayor informaci\u00f3n\u202fentra en: &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visite:\u202f&nbsp;https:\/\/www.trustfortheamericas.org\/programs\/POETA\/poeta-digispark&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:\u202fThe Trust for the Americas\u202f&nbsp;Twitter:\u202f@Trust4Americas &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre The Trust for the Americas: &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. www.trustfortheamericas.org&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Argentina\u00a0&#8211;\u00a0Brasil\u00a0&#8211;\u00a0Chile\u00a0&#8211;\u00a0Colombia\u00a0&#8211;\u00a0Costa Rica\u00a0&#8211;\u00a0Ecuador\u00a0&#8211;\u00a0El Salvador\u00a0&#8211;\u00a0Guatemala\u00a0&#8211;\u00a0Honduras\u00a0&#8211;\u00a0Mexico\u00a0&#8211;\u00a0Nicaragua\u00a0&#8211;\u00a0Panam\u00e1\u00a0&#8211;\u00a0Per\u00fa\u00a0&#8211;\u00a0Rep\u00fablica Dominicana\u00a0&#8211;\u00a0Venezuela<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>La situaci\u00f3n actual, nos ha mostrado que el emprendimiento representa cada vez m\u00e1s una oportunidad para alcanzar la independencia econ\u00f3mica. &nbsp;Tras la llegada de la pandemia por el Covid 19, la Organizaci\u00f3n de Naciones Unidas alert\u00f3 que \u201c114.4 millones de personas se sumaron a la condici\u00f3n de pobreza extrema, 57.8 millones de ellas son mujeres y ni\u00f1as. Esta situaci\u00f3n apunta un duro golpe a los esfuerzos de reducci\u00f3n de la pobreza en todo el mundo\u201d&nbsp; Ante este escenario, The Trust for the Americas, organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados Americanos (OEA), lanza la iniciativa \u201cBootcamp &#8211; Potencializando su Negocio\u201d en Brasil y simult\u00e1neamente en Am\u00e9rica Latina, con el objetivo de desarrollar el emprendimiento. y fortalecer la mentalidad emprendedora de las personas interesadas en iniciar y \/ o fortalecer sus negocios, sobre la base de una experiencia de aprendizaje din\u00e1mica y desafiante.&nbsp; Valentina Coley, facilitadora, CEO y Co-fundadora de Cubo Social, explic\u00f3 que \u201cel Bootcamp de Emprendimiento es un espacio diferenciado que creamos a partir de las expectativas y necesidades de personas emprendedoras, el nivel de madurez de sus emprendimientos, los actuales retos sociales y las principales tendencias en habilidades t\u00e9cnicas y esenciales asociadas a la mentalidad emprendedora\u201d.&nbsp; La convocatoria contar\u00e1 con espacios limitados para mujeres y hombres entre 18 y 60 a\u00f1os. Las sesiones ser\u00e1n sincr\u00f3nicas y asincr\u00f3nicas donde los y las participantes ser\u00e1n desafiadas a comprender el emprendimiento como un medio para la construcci\u00f3n de proyectos de vida y como posibilidad de autonom\u00eda financiera.&nbsp; El primer evento, que tuvo lugar el 30 de junio, fue una sesi\u00f3n informativa donde los participantes tuvieron la oportunidad de conocer, en detalle, esta interesante experiencia de capacitaci\u00f3n e implementaci\u00f3n de nuevas herramientas en su propio negocio. &nbsp; \u00bfQu\u00e9 aprender\u00e1n las y los participantes? Comunicaci\u00f3n asertiva, Liderazgo, Inteligencia emocional, resoluci\u00f3n de problemas, Actitud de ventas, propuesta de valor, Marketing digital y Neurofinanzas en el emprendimiento, entre otro temas. &nbsp; Al finalizar el Bootcamp, 50 personas emprendedoras podr\u00e1n acceder a mentorias especializadas, se realizar\u00e1 proceso de selecci\u00f3n de los participantes de acuerdo al cumplimiento y compromiso con las actividades.&nbsp; Al finalizar el Bootcamp, 50 emprendedores tendr\u00e1n acceso a mentoras especializadas, siendo seleccionados en funci\u00f3n de su compromiso y cumplimiento de actividades a lo largo de la iniciativa que tendr\u00e1 una duraci\u00f3n de 8 semanas, a partir del 12 de julio.&nbsp;Las inscripciones est\u00e1n abiertas hasta el 7 de julio y se pueden realizar en este enlace:&nbsp;https:\/\/bit.ly\/3jatwmN&nbsp; Para mayor informaci\u00f3n\u202fentra en: &nbsp;&nbsp; Visite:\u202f&nbsp;https:\/\/www.trustfortheamericas.org\/programs\/POETA\/poeta-digispark&nbsp; Facebook:\u202fThe Trust for the Americas\u202f&nbsp;Twitter:\u202f@Trust4Americas &nbsp; Sobre The Trust for the Americas: &nbsp; The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles. www.trustfortheamericas.org&nbsp; Argentina\u00a0&#8211;\u00a0Brasil\u00a0&#8211;\u00a0Chile\u00a0&#8211;\u00a0Colombia\u00a0&#8211;\u00a0Costa Rica\u00a0&#8211;\u00a0Ecuador\u00a0&#8211;\u00a0El Salvador\u00a0&#8211;\u00a0Guatemala\u00a0&#8211;\u00a0Honduras\u00a0&#8211;\u00a0Mexico\u00a0&#8211;\u00a0Nicaragua\u00a0&#8211;\u00a0Panam\u00e1\u00a0&#8211;\u00a0Per\u00fa\u00a0&#8211;\u00a0Rep\u00fablica Dominicana\u00a0&#8211;\u00a0Venezuela<\/p>","protected":false},"author":38,"featured_media":7690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=7689"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7689\/revisions"}],"predecessor-version":[{"id":7691,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7689\/revisions\/7691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/7690"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=7689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=7689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=7689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}