{"id":7665,"date":"2022-02-18T16:52:00","date_gmt":"2022-02-18T16:52:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7665"},"modified":"2024-11-19T04:55:06","modified_gmt":"2024-11-19T04:55:06","slug":"emprendedores-colombianos-y-venezolanos-vulnerables-fortalecen-sus-habilidades-digitales-gracias-a-un-acuerdo-entre-la-fundacion-microfinanzas-bbva-y-the-trust-for-the-americas","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/emprendedores-colombianos-y-venezolanos-vulnerables-fortalecen-sus-habilidades-digitales-gracias-a-un-acuerdo-entre-la-fundacion-microfinanzas-bbva-y-the-trust-for-the-americas\/","title":{"rendered":"Emprendedores colombianos y venezolanos vulnerables fortalecen sus habilidades digitales, gracias a un acuerdo entre la Fundaci\u00f3n Microfinanzas BBVA y The Trust for the Americas"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Bogot\u00e1, febrero 17 de 2022<\/strong>Para Mar\u00eda Elizabeth Romero vivir en el municipio de San Vicente del Cagu\u00e1n, uno de los lugares m\u00e1s afectados por el conflicto en Colombia, con acceso limitado a internet y pocos conocimientos en el uso de la tecnolog\u00eda, no ha sido un impedimento para ingresar al programa Empropaz. A trav\u00e9s de la formaci\u00f3n en l\u00ednea potenci\u00f3 su idea de negocio y pas\u00f3 de vender pan de yuca en las calles a tener un local de comida r\u00e1pida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Mar\u00eda Elizabeth hoy puede usar herramientas de tecnolog\u00eda para llevar adelante su negocio. Dise\u00f1\u00f3 su logo, est\u00e1 construyendo su cat\u00e1logo de productos y en pocas semanas se encontrar\u00e1 lista para abrir su cuenta empresarial en redes sociales. Sobre el programa que le ayud\u00f3 a potenciar su emprendimiento, coment\u00f3: \u201caunque tengo que comprar un pin para cargar el celular y muchas veces buscar un lugar donde coja se\u00f1al, me doy a la tarea de hacer mis clases.\u201d Esta emprendedora, madre de cuatro hijos, tiene 38 a\u00f1os y fue desplazada por el conflicto armado. Ella accedi\u00f3 a un Cr\u00e9dito Semilla con Bancam\u00eda, y lo utiliz\u00f3 para darle un mejor imagen a su negocio, adecuar la cocina, poner un punto de agua y comprar un congelador. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Por mujeres como ella, que viven en zonas afectadas por la violencia y la pobreza en Colombia, Bancam\u00eda, entidad de la FMBBVA, en alianza con la Agencia de los Estados Unidos para el desarrollo, USAID, junto a la Corporaci\u00f3n Mundial de la Mujer Colombia y la Corporaci\u00f3n Mundial de la Mujer Medell\u00edn, crearon en 2018 el programa Empropaz, con el objetivo de acompa\u00f1ar, con formaci\u00f3n especializada e inclusi\u00f3n financiera, a los emprendedores en el desarrollo de sus ideas de negocio, y a los microempresarios con su fortalecimiento empresarial: colombianos y venezolanos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Para ampliar este impacto, la Fundaci\u00f3n Microfinanzas BBVA y The Trust for the Americas, convencidos de que la educaci\u00f3n, junto con el emprendimiento, son factores que influyen en el desarrollo y progreso de las personas y sociedades, recientemente firmaron un acuerdo para llevar a cabo acciones conjuntas, orientadas a promover la cooperaci\u00f3n, con miras a fomentar el desarrollo econ\u00f3mico, social, sostenible e inclusivo de personas vulnerables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Como primer compromiso, lanzaron un piloto en Colombia con beneficiarios del programa Empropaz, donde se busca brindar formaci\u00f3n en habilidades ofim\u00e1ticas y marketing digital, a m\u00e1s de 140 emprendedores y microempresarios, con el prop\u00f3sito de incrementar sus conocimientos en materia de uso y apropiaci\u00f3n de nuevas tecnolog\u00edas, a fin de potenciar y desarrollar sus emprendimientos, a trav\u00e9s de la digitalizaci\u00f3n, as\u00ed como la venta de productos y servicios en l\u00ednea.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Durante la firma del acuerdo, Javier M. Flores, director general de la FMBBVA, afirm\u00f3 que \u201clas poblaciones vulnerables a las que se dirigen las cinco entidades microfinancieras de la FMBBVA en Am\u00e9rica Latina sufren de la existente brecha digital en un entorno en el que cada vez m\u00e1s, la formaci\u00f3n es virtual y resulta esencial el acceso a internet para la adquisici\u00f3n de habilidades digitales. Por eso, nos hemos aliado con el Trust for the Am\u00e9ricas, una instituci\u00f3n con una amplia trayectoria, porque nosotros creemos mucho en las alianzas, en las que cada cual aporta sus conocimientos para conseguir un fin com\u00fan. Tambi\u00e9n creo que son fundamentales para conseguir alcanzar impactos positivos, duraderos y sostenibles.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los beneficiarios del piloto se suman a los m\u00e1s de medio mill\u00f3n de emprendedores, a trav\u00e9s de las entidades de la FMBBVA, que ya han recibido alg\u00fan tipo de formaci\u00f3n, principalmente educaci\u00f3n financiera, pero tambi\u00e9n en otras materias como la gesti\u00f3n del negocio o las &nbsp;habilidades digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Por su parte, Linda Eddleman, Directora Ejecutiva de The Trust for the Americas a\u00f1adi\u00f3: \u201cColaborar con la Fundaci\u00f3n Microfinanzas BBVA es un hecho muy importante ya que empezamos a trabajar en Colombia hace m\u00e1s de 15 a\u00f1os. Y en esos a\u00f1os hemos impactado la vida de m\u00e1s de un mill\u00f3n de colombianas y colombianas. Estamos convencidos que este proyecto ya est\u00e1 teniendo un impacto muy grande en la historia de vida de emprendedores del pa\u00eds, y ahora ya estamos celebrando los frutos de esta alianza y esta capacitaci\u00f3n.\u201d&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>En este programa se destaca, tambi\u00e9n, la atenci\u00f3n a emprendedores migrantes venezolanos como Ana Mar\u00eda Almao, quien lleg\u00f3 a Colombia desde Barquisimeto. Cre\u00f3 \u2018Antojitos Anita\u2019, un negocio de panader\u00eda y pasteler\u00eda al sur de Bogot\u00e1 que gracias a la formaci\u00f3n impartida, avanz\u00f3 en su proceso de digitalizaci\u00f3n y hoy tiene m\u00e1s de 2.300 seguidores en sus redes sociales.<br>En la actualidad la iniciativa beneficia a hombres y mujeres emprendedores, j\u00f3venes, migrantes, desplazados y v\u00edctimas del conflicto en 14 departamentos del pa\u00eds.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acerca de FMBBVA<\/strong><br>La Fundaci\u00f3n Microfinanzas BBVA (FMBBVA) es una entidad espa\u00f1ola sin \u00e1nimo de lucro cuyo prop\u00f3sito es fomentar el desarrollo sostenible de personas en vulnerabilidad que cuentan con actividades productivas en Am\u00e9rica Latina a trav\u00e9s de las Finanzas Productivas, modelo de servicios financieros, capacitaci\u00f3n y acompa\u00f1amiento para que personas en situaci\u00f3n de vulnerabilidad progresen a trav\u00e9s de los excedentes generados por su actividad productiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acerca de The Trust for the Americas<\/strong><br>The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Colombia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Bogot\u00e1, febrero 17 de 2022Para Mar\u00eda Elizabeth Romero vivir en el municipio de San Vicente del Cagu\u00e1n, uno de los lugares m\u00e1s afectados por el conflicto en Colombia, con acceso limitado a internet y pocos conocimientos en el uso de la tecnolog\u00eda, no ha sido un impedimento para ingresar al programa Empropaz. A trav\u00e9s de la formaci\u00f3n en l\u00ednea potenci\u00f3 su idea de negocio y pas\u00f3 de vender pan de yuca en las calles a tener un local de comida r\u00e1pida.&nbsp; Mar\u00eda Elizabeth hoy puede usar herramientas de tecnolog\u00eda para llevar adelante su negocio. Dise\u00f1\u00f3 su logo, est\u00e1 construyendo su cat\u00e1logo de productos y en pocas semanas se encontrar\u00e1 lista para abrir su cuenta empresarial en redes sociales. Sobre el programa que le ayud\u00f3 a potenciar su emprendimiento, coment\u00f3: \u201caunque tengo que comprar un pin para cargar el celular y muchas veces buscar un lugar donde coja se\u00f1al, me doy a la tarea de hacer mis clases.\u201d Esta emprendedora, madre de cuatro hijos, tiene 38 a\u00f1os y fue desplazada por el conflicto armado. Ella accedi\u00f3 a un Cr\u00e9dito Semilla con Bancam\u00eda, y lo utiliz\u00f3 para darle un mejor imagen a su negocio, adecuar la cocina, poner un punto de agua y comprar un congelador. &nbsp; Por mujeres como ella, que viven en zonas afectadas por la violencia y la pobreza en Colombia, Bancam\u00eda, entidad de la FMBBVA, en alianza con la Agencia de los Estados Unidos para el desarrollo, USAID, junto a la Corporaci\u00f3n Mundial de la Mujer Colombia y la Corporaci\u00f3n Mundial de la Mujer Medell\u00edn, crearon en 2018 el programa Empropaz, con el objetivo de acompa\u00f1ar, con formaci\u00f3n especializada e inclusi\u00f3n financiera, a los emprendedores en el desarrollo de sus ideas de negocio, y a los microempresarios con su fortalecimiento empresarial: colombianos y venezolanos.&nbsp; Para ampliar este impacto, la Fundaci\u00f3n Microfinanzas BBVA y The Trust for the Americas, convencidos de que la educaci\u00f3n, junto con el emprendimiento, son factores que influyen en el desarrollo y progreso de las personas y sociedades, recientemente firmaron un acuerdo para llevar a cabo acciones conjuntas, orientadas a promover la cooperaci\u00f3n, con miras a fomentar el desarrollo econ\u00f3mico, social, sostenible e inclusivo de personas vulnerables. Como primer compromiso, lanzaron un piloto en Colombia con beneficiarios del programa Empropaz, donde se busca brindar formaci\u00f3n en habilidades ofim\u00e1ticas y marketing digital, a m\u00e1s de 140 emprendedores y microempresarios, con el prop\u00f3sito de incrementar sus conocimientos en materia de uso y apropiaci\u00f3n de nuevas tecnolog\u00edas, a fin de potenciar y desarrollar sus emprendimientos, a trav\u00e9s de la digitalizaci\u00f3n, as\u00ed como la venta de productos y servicios en l\u00ednea.&nbsp; Durante la firma del acuerdo, Javier M. Flores, director general de la FMBBVA, afirm\u00f3 que \u201clas poblaciones vulnerables a las que se dirigen las cinco entidades microfinancieras de la FMBBVA en Am\u00e9rica Latina sufren de la existente brecha digital en un entorno en el que cada vez m\u00e1s, la formaci\u00f3n es virtual y resulta esencial el acceso a internet para la adquisici\u00f3n de habilidades digitales. Por eso, nos hemos aliado con el Trust for the Am\u00e9ricas, una instituci\u00f3n con una amplia trayectoria, porque nosotros creemos mucho en las alianzas, en las que cada cual aporta sus conocimientos para conseguir un fin com\u00fan. Tambi\u00e9n creo que son fundamentales para conseguir alcanzar impactos positivos, duraderos y sostenibles.\u201d Los beneficiarios del piloto se suman a los m\u00e1s de medio mill\u00f3n de emprendedores, a trav\u00e9s de las entidades de la FMBBVA, que ya han recibido alg\u00fan tipo de formaci\u00f3n, principalmente educaci\u00f3n financiera, pero tambi\u00e9n en otras materias como la gesti\u00f3n del negocio o las &nbsp;habilidades digitales. Por su parte, Linda Eddleman, Directora Ejecutiva de The Trust for the Americas a\u00f1adi\u00f3: \u201cColaborar con la Fundaci\u00f3n Microfinanzas BBVA es un hecho muy importante ya que empezamos a trabajar en Colombia hace m\u00e1s de 15 a\u00f1os. Y en esos a\u00f1os hemos impactado la vida de m\u00e1s de un mill\u00f3n de colombianas y colombianas. Estamos convencidos que este proyecto ya est\u00e1 teniendo un impacto muy grande en la historia de vida de emprendedores del pa\u00eds, y ahora ya estamos celebrando los frutos de esta alianza y esta capacitaci\u00f3n.\u201d&nbsp; En este programa se destaca, tambi\u00e9n, la atenci\u00f3n a emprendedores migrantes venezolanos como Ana Mar\u00eda Almao, quien lleg\u00f3 a Colombia desde Barquisimeto. Cre\u00f3 \u2018Antojitos Anita\u2019, un negocio de panader\u00eda y pasteler\u00eda al sur de Bogot\u00e1 que gracias a la formaci\u00f3n impartida, avanz\u00f3 en su proceso de digitalizaci\u00f3n y hoy tiene m\u00e1s de 2.300 seguidores en sus redes sociales.En la actualidad la iniciativa beneficia a hombres y mujeres emprendedores, j\u00f3venes, migrantes, desplazados y v\u00edctimas del conflicto en 14 departamentos del pa\u00eds.&nbsp; &#8212; Acerca de FMBBVALa Fundaci\u00f3n Microfinanzas BBVA (FMBBVA) es una entidad espa\u00f1ola sin \u00e1nimo de lucro cuyo prop\u00f3sito es fomentar el desarrollo sostenible de personas en vulnerabilidad que cuentan con actividades productivas en Am\u00e9rica Latina a trav\u00e9s de las Finanzas Productivas, modelo de servicios financieros, capacitaci\u00f3n y acompa\u00f1amiento para que personas en situaci\u00f3n de vulnerabilidad progresen a trav\u00e9s de los excedentes generados por su actividad productiva. Acerca de The Trust for the AmericasThe Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp; Colombia<\/p>","protected":false},"author":38,"featured_media":7666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=7665"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7665\/revisions"}],"predecessor-version":[{"id":7667,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7665\/revisions\/7667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/7666"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=7665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=7665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=7665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}