{"id":7572,"date":"2022-05-01T01:20:00","date_gmt":"2022-05-01T01:20:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7572"},"modified":"2024-11-18T01:23:27","modified_gmt":"2024-11-18T01:23:27","slug":"the-trust-for-the-americas-visito-la-sala-tic-de-las-mujeres-de-itagui","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/the-trust-for-the-americas-visito-la-sala-tic-de-las-mujeres-de-itagui\/","title":{"rendered":"The Trust for the Americas visit\u00f3 la Sala TIC de las Mujeres de Itag\u00fci"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2022\/05\/31<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>The Trust for the Americas don\u00f3 15 computadoras con licencias de Microsoft para equipar la sala TIC de las mujeres.\u00a0<\/li>\n\n\n\n<li>Las mujeres recibir\u00e1n capacitaciones en temas de tecnolog\u00eda, emprendimiento y prevenci\u00f3n de violencia, entre otras.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Medell\u00edn, Colombia \u2013 25 de mayo de 2022. El Centro POETA Itag\u00fc\u00ed- Sala TICS de las Mujeres recibi\u00f3 de The Trust for the Americas y Lenovo, 15 computadoras port\u00e1tiles con licencias de Microsoft para equipar la Sala TIC de las Mujeres de Itag\u00fc\u00ed. Desde octubre 2021, este centro ha beneficiado a m\u00e1s de 100 mujeres a trav\u00e9s de capacitaci\u00f3n en ofim\u00e1tica b\u00e1sica e iniciaci\u00f3n digital.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la Alcald\u00eda de Itag\u00fc\u00ed se suma a los 11 socios locales de la Franquicia Social POETA que trabajan en diferentes localidades de Colombia. En estos centros se implementa el Programa de Oportunidades Econ\u00f3micas a trav\u00e9s de la Tecnolog\u00eda en las Am\u00e9ricas (POETA), cuyo objetivo es impulsar el desarrollo integral de las personas a trav\u00e9s de la tecnolog\u00eda por medio de la capacitaci\u00f3n en comunidades vulnerables a fin de facilitar su acceso a oportunidades econ\u00f3micas que contribuyan a mejorar su calidad de vida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Linda Eddleman, Directora Ejecutiva de The Trust for the Americas destac\u00f3 que \u201cdurante 25 a\u00f1os, desde The Trust for the Americas hemos trabajado en pro de la igualdad y la equidad para las mujeres. Me emociona saber que a trav\u00e9s de la Franquicia Social POETA, la Municipalidad de Itag\u00fc\u00ed continuar\u00e1 apoyando a m\u00e1s mujeres colombianas\u201d.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de este nuevo Centro POETA, muchas mujeres de la localidad se han capacitado en nuevas tecnolog\u00edas de la informaci\u00f3n y las comunicaciones, emprendimiento, administraci\u00f3n, contabilidad, mercadeo, prevenci\u00f3n y atenci\u00f3n de violencias, para que puedan acceder a m\u00e1s y mejores oportunidades econ\u00f3micas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ufffcJos\u00e9 Fernando Escobar, alcalde de Itag\u00fc\u00ed coment\u00f3 que \u201cen nuestra ciudad estamos empoderando a las mujeres a trav\u00e9s de la oferta institucional con enfoque en formaci\u00f3n y emprendimiento, de ah\u00ed la importancia de la articulaci\u00f3n institucional con organizaciones internacionales que fortalezcan nuestra estrategia, a trav\u00e9s de su experiencia en otras ciudades de Latinoam\u00e9rica\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Luz Marina Correa, Gerente de Proyectos POETA en The Trust for the Americas, particip\u00f3 en la visita donde pudo conocer a beneficiarias de la Sala TIC de las Mujeres de Itag\u00fc\u00ed. Para ella, \u201ctener el programa POETA en el municipio de Itag\u00fc\u00ed posibilita que m\u00e1s mujeres se acerquen a la tecnolog\u00eda para mejorar sus habilidades y competencias digitales y as\u00ed est\u00e9n mejor preparadas para el mundo laboral de hoy, lo cual tiene un impacto positivo en el desarrollo social del municipio.\u201d&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sala TIC de las mujeres atender\u00e1, anualmente, a 100 mujeres del municipio. En el evento estuvieron presentes Johana Casta\u00f1o, Secretaria de la Familia; Gustavo Vel\u00e1squez, Director TIC; Ana Catalina Rendon, Subsecretaria de las Mujeres; as\u00ed como mujeres que ya se han beneficiado de esta sala y Catalina Rengifo, Gerente de Microsoft Filantrop\u00eda.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.trustfortheamericas.org\/programs\/POETA\">https:\/\/www.trustfortheamericas.org\/programs\/POETA<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:\u202fThe Trust for the Americas\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Twitter:\u202f@Trust4Americas&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre The Trust for the Americas:&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Colombia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>2022\/05\/31 Medell\u00edn, Colombia \u2013 25 de mayo de 2022. El Centro POETA Itag\u00fc\u00ed- Sala TICS de las Mujeres recibi\u00f3 de The Trust for the Americas y Lenovo, 15 computadoras port\u00e1tiles con licencias de Microsoft para equipar la Sala TIC de las Mujeres de Itag\u00fc\u00ed. Desde octubre 2021, este centro ha beneficiado a m\u00e1s de 100 mujeres a trav\u00e9s de capacitaci\u00f3n en ofim\u00e1tica b\u00e1sica e iniciaci\u00f3n digital.&nbsp; Adem\u00e1s, la Alcald\u00eda de Itag\u00fc\u00ed se suma a los 11 socios locales de la Franquicia Social POETA que trabajan en diferentes localidades de Colombia. En estos centros se implementa el Programa de Oportunidades Econ\u00f3micas a trav\u00e9s de la Tecnolog\u00eda en las Am\u00e9ricas (POETA), cuyo objetivo es impulsar el desarrollo integral de las personas a trav\u00e9s de la tecnolog\u00eda por medio de la capacitaci\u00f3n en comunidades vulnerables a fin de facilitar su acceso a oportunidades econ\u00f3micas que contribuyan a mejorar su calidad de vida.&nbsp; Linda Eddleman, Directora Ejecutiva de The Trust for the Americas destac\u00f3 que \u201cdurante 25 a\u00f1os, desde The Trust for the Americas hemos trabajado en pro de la igualdad y la equidad para las mujeres. Me emociona saber que a trav\u00e9s de la Franquicia Social POETA, la Municipalidad de Itag\u00fc\u00ed continuar\u00e1 apoyando a m\u00e1s mujeres colombianas\u201d.&nbsp;&nbsp; A trav\u00e9s de este nuevo Centro POETA, muchas mujeres de la localidad se han capacitado en nuevas tecnolog\u00edas de la informaci\u00f3n y las comunicaciones, emprendimiento, administraci\u00f3n, contabilidad, mercadeo, prevenci\u00f3n y atenci\u00f3n de violencias, para que puedan acceder a m\u00e1s y mejores oportunidades econ\u00f3micas.&nbsp;&nbsp; \ufffcJos\u00e9 Fernando Escobar, alcalde de Itag\u00fc\u00ed coment\u00f3 que \u201cen nuestra ciudad estamos empoderando a las mujeres a trav\u00e9s de la oferta institucional con enfoque en formaci\u00f3n y emprendimiento, de ah\u00ed la importancia de la articulaci\u00f3n institucional con organizaciones internacionales que fortalezcan nuestra estrategia, a trav\u00e9s de su experiencia en otras ciudades de Latinoam\u00e9rica\u201d.&nbsp; Por su parte, Luz Marina Correa, Gerente de Proyectos POETA en The Trust for the Americas, particip\u00f3 en la visita donde pudo conocer a beneficiarias de la Sala TIC de las Mujeres de Itag\u00fc\u00ed. Para ella, \u201ctener el programa POETA en el municipio de Itag\u00fc\u00ed posibilita que m\u00e1s mujeres se acerquen a la tecnolog\u00eda para mejorar sus habilidades y competencias digitales y as\u00ed est\u00e9n mejor preparadas para el mundo laboral de hoy, lo cual tiene un impacto positivo en el desarrollo social del municipio.\u201d&nbsp; La sala TIC de las mujeres atender\u00e1, anualmente, a 100 mujeres del municipio. En el evento estuvieron presentes Johana Casta\u00f1o, Secretaria de la Familia; Gustavo Vel\u00e1squez, Director TIC; Ana Catalina Rendon, Subsecretaria de las Mujeres; as\u00ed como mujeres que ya se han beneficiado de esta sala y Catalina Rengifo, Gerente de Microsoft Filantrop\u00eda.&nbsp; https:\/\/www.trustfortheamericas.org\/programs\/POETA Facebook:\u202fThe Trust for the Americas\u202f&nbsp; Twitter:\u202f@Trust4Americas&nbsp;&nbsp; Sobre The Trust for the Americas:&nbsp;&nbsp; The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras\u202finiciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;&nbsp; Colombia<\/p>","protected":false},"author":37,"featured_media":7573,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=7572"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7572\/revisions"}],"predecessor-version":[{"id":7574,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7572\/revisions\/7574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/7573"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=7572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=7572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=7572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}