{"id":7547,"date":"2022-10-04T15:53:00","date_gmt":"2022-10-04T15:53:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7547"},"modified":"2024-11-17T15:55:19","modified_gmt":"2024-11-17T15:55:19","slug":"jovenes-emprendedores-reciben-fondos-semilla-de-la-fundacion-citi-para-proyectos-innovadores-de-los-dia-labs-en-republica-dominicana","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/jovenes-emprendedores-reciben-fondos-semilla-de-la-fundacion-citi-para-proyectos-innovadores-de-los-dia-labs-en-republica-dominicana\/","title":{"rendered":"J\u00f3venes emprendedores reciben fondos semilla de la Fundaci\u00f3n Citi para Proyectos Innovadores de los DIA Labs en Rep\u00fablica Dominicana"},"content":{"rendered":"<p class=\"wp-block-paragraph\">2022\/10\/04<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ban\u00ed, Rep\u00fablica Dominicana \u2013 27 de septiembre, 2022&nbsp;<\/strong>&#8211;&nbsp;<strong>The Trust for the Americas<\/strong>, junto a su socio local&nbsp;<strong>ADASEC<\/strong>&nbsp;y con el apoyo financiero de&nbsp;<strong>Citi Foundation<\/strong>, celebraron la primera<strong>&nbsp;Competencia Pitch de Proyectos Innovadores<\/strong>&nbsp;de los&nbsp;<strong>DIA Labs en Rep\u00fablica Dominicana<\/strong>. En este encuentro presencial, 14 proyectos se presentaron ante un jurado multidisciplinario, compitiendo as\u00ed por la posibilidad de ganar fondos semilla con el objetivo de fortalecer e impulsar sus emprendimientos, los cuales buscan dar soluciones a problem\u00e1ticas locales en torno al desempleo, seguridad ciudadana y cambio clim\u00e1tico. Siete de estas iniciativas resultaron ganadoras, por su potencial y factibilidad de implementaci\u00f3n en sus comunidades.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los j\u00f3venes participaron en grupo o de manera individual luego de haber preparado y desarrollado sus propuestas de emprendimiento a lo largo de semanas previas de capacitaci\u00f3n y pr\u00e1ctica. En&nbsp;el evento, los jueces&nbsp;seleccionaron a los siguientes equipos ganadores:&nbsp;&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u2018SEAVERSE\u2019<\/strong>: Proyecto que busca establecer una red de concientizaci\u00f3n, limpieza y tratamiento del sargazo que contribuya en la mitigaci\u00f3n de su propagaci\u00f3n y se produzcan derivados para usos agr\u00edcolas.\u00a0<\/li>\n\n\n\n<li><strong>\u2018Las arroceras\u2019<\/strong>: iniciativa que busca combatir la quema del rastrojo del arroz como pr\u00e1ctica comunitaria, a trav\u00e9s de la concientizaci\u00f3n del impacto al medio ambiente y a la salud p\u00fablica, y su procesamiento como insumo para abono natural.\u00a0<\/li>\n\n\n\n<li><strong>\u2018Bota el golpe en la presa de Rinc\u00f3n\u2019<\/strong>: Propuestas comerciales que promuevan el ecoturismo sustentable, atendiendo las necesidades de la comunidad local y la protecci\u00f3n de la fauna y la flora local.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u2018Helados Boutique\u2019<\/strong>: Desarrollo de una l\u00ednea de helados artesanales, basada en el empleo comunitario y el impulso la marca comunitaria establecida alrededor del producto de mayor exportaci\u00f3n de la regi\u00f3n: el mango.\u00a0<\/li>\n\n\n\n<li><strong>\u2018Yampol Food Service\u2019<\/strong>: Oferta de alimentos vegetarianos con el objetivo de ofrecer una alternativa alimenticia saludable ante los altos \u00edndices de diabetes, obesidad y gastritis en la comunidad.\u00a0<\/li>\n\n\n\n<li><strong>\u2018Tamo Ready\u2019<\/strong>: Proyecto de manejo y segmentaci\u00f3n de residuos. Posteriormente a la segmentaci\u00f3n de los residuos, a trav\u00e9s de una herramienta digital, el contenedor de residuos equipado con sensores notifica a los recolectores para el recojo del mismo.\u00a0\u00a0<\/li>\n\n\n\n<li><strong>\u2018Banco de Semillas Terra Alta\u2019<\/strong>: Emprendimiento que busca disminuir el nivel de desnutrici\u00f3n en la comunidad de Constanza, a trav\u00e9s de la administraci\u00f3n comunaria de bancos de reservas de semillas, la gesti\u00f3n de cultivos coordinada y posterior siembra.\u00a0\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el encuentro, Gabriella Hache \u2013 Relaciones Publicas para el Caribe y en representaci\u00f3n de la Fundaci\u00f3n Citi, resalt\u00f3:&nbsp;<em>\u201cHoy nos encontramos impulsando y motivando a nuestra juventud para continuar en su ruta de aprendizaje y crecimiento y as\u00ed hacerles frente a los desaf\u00edos de un escenario laboral en constante transformaci\u00f3n. A trav\u00e9s de los DIA Labs, buscamos proveerle las oportunidades que los fortalezcan y generen las condiciones necesarias para mejorar sus vidas y las de sus comunidades.\u201d&nbsp;&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, el Ing. Rafael Lorenzo, presidente de ADASEC, afirm\u00f3 el impacto que est\u00e1s iniciativas tienen en la vida de los participantes:&nbsp;<em>\u201cEs para ADASEC Rep\u00fablica Dominicana una gran satisfacci\u00f3n ser parte de los sue\u00f1os de los j\u00f3venes que inician su viaje de emprendimiento a trav\u00e9s de los Laboratorios DIA de Innovaci\u00f3n y emprendimiento de The&nbsp;Trust&nbsp;for the&nbsp;Americas&nbsp;y el apoyo de Citi Foundation. Es un antes y un despu\u00e9s para la vida de todos los participantes, ya que han adquirido un nivel de conocimiento invaluable, que les servir\u00e1 para toda su vida. Los proyectos seleccionados dar\u00e1n testimonio de este aprendizaje y contribuir\u00e1n a mejorar el entorno socio econ\u00f3mico de sus comunidades.\u201d&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de un ecosistema \u00fanico que fomenta la innovaci\u00f3n y el emprendimiento, los&nbsp;<strong>DIA Labs en Rep\u00fablica Dominicana<\/strong>&nbsp;brindan oportunidades de desarrollo a j\u00f3venes de las comunidades de Ban\u00ed, La Vega y Bonao. A trav\u00e9s de acceso a tecnolog\u00eda, espacios colaborativos, entrenamiento y fondos semillas concursables, la juventud obtiene las herramientas para desarrollar sus ideas de negocios o impulsar proyectos sociales orientados a resolver desaf\u00edos locales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido, Rodrigo Iriani, Gerente Senior del Programa DIA de The Trust for the Americas, le asegur\u00f3&nbsp;a los jovenes que&nbsp;<em>\u201clas competencias Pitch organizadas por el Programa DIA, son una celebraci\u00f3n del esfuerzo y el compromiso de la juventud en ser parte de la soluci\u00f3n con respecto a los desaf\u00edos locales. Continuar adquiriendo habilidades y aprovechando estas oportunidades marcar\u00e1n la diferencia para el desarrollo individual y colectivo.\u201d&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Competencia Pitch de Proyectos Innovadores&nbsp;<\/strong>de los&nbsp;<strong>DIA Labs en Rep\u00fablica Dominicana<\/strong>, son s\u00f3lo el primer paso en su andadura empresarial, que busca mejorar la calidad de vida de los participantes, retribuir a la comunidad y marcar la diferencia en la vida de su gente.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>***&nbsp;&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u202fFacebook:&nbsp;<a href=\"https:\/\/www.facebook.com\/TheTrustfortheAmericas\/\" rel=\"noreferrer noopener\" target=\"_blank\">The Trust for the Americas<\/a>&nbsp; | Twitter:&nbsp;<a href=\"https:\/\/twitter.com\/Trust4Americas\" rel=\"noreferrer noopener\" target=\"_blank\">@Trust4Americas<\/a>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre el Programa Programa Democratizando la Innovaci\u00f3n en las Am\u00e9ricas (DIA):&nbsp;&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DIA es una iniciativa regional que promueve el fortalecimiento de los procesos democr\u00e1ticos en la regi\u00f3n y el empoderamiento de nuevas generaciones a trav\u00e9s del acceso a capacitaci\u00f3n en tecnolog\u00eda, curr\u00edcula especializada, espacios de colaboraci\u00f3n, mentor\u00edas y apoyos financieros para el desarrollo de emprendimientos sociales y econ\u00f3micos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre Citi:&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Citi, el banco l\u00edder global, tiene aproximadamente 200 millones de cuentas de clientes y realiza negocios en m\u00e1s de 160 pa\u00edses y jurisdicciones. Citi ofrece a personas, corporaciones, gobiernos e instituciones una amplia gama de productos y servicios financieros, incluyendo servicios bancarios y de cr\u00e9dito al consumidor, servicios bancarios corporativos y de inversi\u00f3n, corretaje de valores, servicios de transacci\u00f3n y administraci\u00f3n patrimonial. Informaci\u00f3n adicional:&nbsp;<a href=\"http:\/\/www.citigroup.com\/\" rel=\"noreferrer noopener\" target=\"_blank\">www.citigroup.com<\/a>&nbsp;| Twitter: @Citi | YouTube:&nbsp;<a href=\"http:\/\/www.youtube.com\/citi\" rel=\"noreferrer noopener\" target=\"_blank\">www.youtube.com\/citi<\/a>&nbsp;| Blog:&nbsp;<a href=\"http:\/\/blog.citigroup.com\/\" rel=\"noreferrer noopener\" target=\"_blank\">http:\/\/blog.citigroup.com<\/a>&nbsp;| Facebook:&nbsp;<a href=\"http:\/\/www.facebook.com\/citi\" rel=\"noreferrer noopener\" target=\"_blank\">www.facebook.com\/citi<\/a>&nbsp;| LinkedIn:&nbsp;<a href=\"http:\/\/www.linkedin.com\/company\/citi\" rel=\"noreferrer noopener\" target=\"_blank\">www.linkedin.com\/company\/citi<\/a>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre la Fundaci\u00f3n Citi:&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3n Citi trabaja para promover el progreso econ\u00f3mico y mejorar la vida de las personas en comunidades de bajos ingresos en todo el mundo. Invertimos en esfuerzos que aumentan la inclusi\u00f3n financiera, catalizan oportunidades laborales para los j\u00f3venes y reinventan enfoques para construir comunidades econ\u00f3micamente din\u00e1micas. El enfoque \u201cM\u00e1s que Filantrop\u00eda\u201d de la Fundaci\u00f3n Citi despliega la enorme especializaci\u00f3n de Citi y su gente para cumplir nuestra misi\u00f3n e impulsar el liderazgo de ideas y la innovaci\u00f3n. Para ver m\u00e1s informaci\u00f3n, visite&nbsp;<a href=\"http:\/\/www.citifoundation.com\/\" rel=\"noreferrer noopener\" target=\"_blank\">www.citifoundation.com<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Republica Dominicana<\/p>","protected":false},"excerpt":{"rendered":"<p>2022\/10\/04 Ban\u00ed, Rep\u00fablica Dominicana \u2013 27 de septiembre, 2022&nbsp;&#8211;&nbsp;The Trust for the Americas, junto a su socio local&nbsp;ADASEC&nbsp;y con el apoyo financiero de&nbsp;Citi Foundation, celebraron la primera&nbsp;Competencia Pitch de Proyectos Innovadores&nbsp;de los&nbsp;DIA Labs en Rep\u00fablica Dominicana. En este encuentro presencial, 14 proyectos se presentaron ante un jurado multidisciplinario, compitiendo as\u00ed por la posibilidad de ganar fondos semilla con el objetivo de fortalecer e impulsar sus emprendimientos, los cuales buscan dar soluciones a problem\u00e1ticas locales en torno al desempleo, seguridad ciudadana y cambio clim\u00e1tico. Siete de estas iniciativas resultaron ganadoras, por su potencial y factibilidad de implementaci\u00f3n en sus comunidades.&nbsp;&nbsp; Los j\u00f3venes participaron en grupo o de manera individual luego de haber preparado y desarrollado sus propuestas de emprendimiento a lo largo de semanas previas de capacitaci\u00f3n y pr\u00e1ctica. En&nbsp;el evento, los jueces&nbsp;seleccionaron a los siguientes equipos ganadores:&nbsp;&nbsp; Durante el encuentro, Gabriella Hache \u2013 Relaciones Publicas para el Caribe y en representaci\u00f3n de la Fundaci\u00f3n Citi, resalt\u00f3:&nbsp;\u201cHoy nos encontramos impulsando y motivando a nuestra juventud para continuar en su ruta de aprendizaje y crecimiento y as\u00ed hacerles frente a los desaf\u00edos de un escenario laboral en constante transformaci\u00f3n. A trav\u00e9s de los DIA Labs, buscamos proveerle las oportunidades que los fortalezcan y generen las condiciones necesarias para mejorar sus vidas y las de sus comunidades.\u201d&nbsp;&nbsp; Asimismo, el Ing. Rafael Lorenzo, presidente de ADASEC, afirm\u00f3 el impacto que est\u00e1s iniciativas tienen en la vida de los participantes:&nbsp;\u201cEs para ADASEC Rep\u00fablica Dominicana una gran satisfacci\u00f3n ser parte de los sue\u00f1os de los j\u00f3venes que inician su viaje de emprendimiento a trav\u00e9s de los Laboratorios DIA de Innovaci\u00f3n y emprendimiento de The&nbsp;Trust&nbsp;for the&nbsp;Americas&nbsp;y el apoyo de Citi Foundation. Es un antes y un despu\u00e9s para la vida de todos los participantes, ya que han adquirido un nivel de conocimiento invaluable, que les servir\u00e1 para toda su vida. Los proyectos seleccionados dar\u00e1n testimonio de este aprendizaje y contribuir\u00e1n a mejorar el entorno socio econ\u00f3mico de sus comunidades.\u201d&nbsp; Como parte de un ecosistema \u00fanico que fomenta la innovaci\u00f3n y el emprendimiento, los&nbsp;DIA Labs en Rep\u00fablica Dominicana&nbsp;brindan oportunidades de desarrollo a j\u00f3venes de las comunidades de Ban\u00ed, La Vega y Bonao. A trav\u00e9s de acceso a tecnolog\u00eda, espacios colaborativos, entrenamiento y fondos semillas concursables, la juventud obtiene las herramientas para desarrollar sus ideas de negocios o impulsar proyectos sociales orientados a resolver desaf\u00edos locales.&nbsp; En este sentido, Rodrigo Iriani, Gerente Senior del Programa DIA de The Trust for the Americas, le asegur\u00f3&nbsp;a los jovenes que&nbsp;\u201clas competencias Pitch organizadas por el Programa DIA, son una celebraci\u00f3n del esfuerzo y el compromiso de la juventud en ser parte de la soluci\u00f3n con respecto a los desaf\u00edos locales. Continuar adquiriendo habilidades y aprovechando estas oportunidades marcar\u00e1n la diferencia para el desarrollo individual y colectivo.\u201d&nbsp; La&nbsp;Competencia Pitch de Proyectos Innovadores&nbsp;de los&nbsp;DIA Labs en Rep\u00fablica Dominicana, son s\u00f3lo el primer paso en su andadura empresarial, que busca mejorar la calidad de vida de los participantes, retribuir a la comunidad y marcar la diferencia en la vida de su gente.&nbsp;&nbsp;&nbsp;&nbsp; ***&nbsp;&nbsp;&nbsp; Sobre The Trust for the Americas:&nbsp;&nbsp; The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;&nbsp; \u202fFacebook:&nbsp;The Trust for the Americas&nbsp; | Twitter:&nbsp;@Trust4Americas&nbsp;&nbsp; Sobre el Programa Programa Democratizando la Innovaci\u00f3n en las Am\u00e9ricas (DIA):&nbsp;&nbsp; DIA es una iniciativa regional que promueve el fortalecimiento de los procesos democr\u00e1ticos en la regi\u00f3n y el empoderamiento de nuevas generaciones a trav\u00e9s del acceso a capacitaci\u00f3n en tecnolog\u00eda, curr\u00edcula especializada, espacios de colaboraci\u00f3n, mentor\u00edas y apoyos financieros para el desarrollo de emprendimientos sociales y econ\u00f3micos.&nbsp; Sobre Citi:&nbsp; Citi, el banco l\u00edder global, tiene aproximadamente 200 millones de cuentas de clientes y realiza negocios en m\u00e1s de 160 pa\u00edses y jurisdicciones. Citi ofrece a personas, corporaciones, gobiernos e instituciones una amplia gama de productos y servicios financieros, incluyendo servicios bancarios y de cr\u00e9dito al consumidor, servicios bancarios corporativos y de inversi\u00f3n, corretaje de valores, servicios de transacci\u00f3n y administraci\u00f3n patrimonial. Informaci\u00f3n adicional:&nbsp;www.citigroup.com&nbsp;| Twitter: @Citi | YouTube:&nbsp;www.youtube.com\/citi&nbsp;| Blog:&nbsp;http:\/\/blog.citigroup.com&nbsp;| Facebook:&nbsp;www.facebook.com\/citi&nbsp;| LinkedIn:&nbsp;www.linkedin.com\/company\/citi&nbsp;&nbsp; Sobre la Fundaci\u00f3n Citi:&nbsp; La Fundaci\u00f3n Citi trabaja para promover el progreso econ\u00f3mico y mejorar la vida de las personas en comunidades de bajos ingresos en todo el mundo. Invertimos en esfuerzos que aumentan la inclusi\u00f3n financiera, catalizan oportunidades laborales para los j\u00f3venes y reinventan enfoques para construir comunidades econ\u00f3micamente din\u00e1micas. El enfoque \u201cM\u00e1s que Filantrop\u00eda\u201d de la Fundaci\u00f3n Citi despliega la enorme especializaci\u00f3n de Citi y su gente para cumplir nuestra misi\u00f3n e impulsar el liderazgo de ideas y la innovaci\u00f3n. Para ver m\u00e1s informaci\u00f3n, visite&nbsp;www.citifoundation.com&nbsp; Rep\u00fablica Dominicana<\/p>","protected":false},"author":37,"featured_media":7548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7547","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=7547"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7547\/revisions"}],"predecessor-version":[{"id":7549,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7547\/revisions\/7549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/7548"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=7547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=7547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=7547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}