{"id":7473,"date":"2023-12-07T14:46:06","date_gmt":"2023-12-07T14:46:06","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7473"},"modified":"2024-11-14T14:47:36","modified_gmt":"2024-11-14T14:47:36","slug":"the-trust-for-the-americas-y-la-oea-entregaron-el-premio-ciudadano-corporativo-de-las-americas-2023","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/the-trust-for-the-americas-y-la-oea-entregaron-el-premio-ciudadano-corporativo-de-las-americas-2023\/","title":{"rendered":"THE TRUST FOR THE AMERICAS Y LA OEA ENTREGARON EL PREMIO CIUDADANO CORPORATIVO DE LAS AM\u00c9RICAS 2023."},"content":{"rendered":"<p class=\"wp-block-paragraph\">2023\/12\/07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Washington, D.C., 6 de diciembre de 2023<\/strong>&nbsp;\u2014 En una cena celebrada este 4 de diciembre, en el Hall de las Am\u00e9ricas de la Organizaci\u00f3n de Estados Americanos (OEA), The Trust for the Americas y la OEA entregaron el prestigioso Premio Ciudadano Corporativo de las Am\u00e9ricas (CCA). La ceremonia cont\u00f3 con la participaci\u00f3n de 90 distinguidos invitados, entre embajadores, dignatarios y representantes del gobierno de Estados Unidos y empresas de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las palabras inaugurales estuvieron a cargo de Enrique Garc\u00eda, Presidente del Directorio de The Trust for the Americas, quien dio la bienvenida a los presentes. Posteriormente, Alex Figueroa, Director de Operaciones (COO) del Trust for the Americas, ofreci\u00f3 un emocionante discurso recordando el impacto significativo de la organizaci\u00f3n, que en este a\u00f1o benefici\u00f3 a m\u00e1s de 5 millones de personas. Los asistentes tuvieron la oportunidad de conocer de primera mano un video de caso de \u00e9xito del Trust for the Americas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un di\u00e1logo estilo &#8220;fireside chat,&#8221; Linda Eddleman, CEO del Trust for the Americas, y el Secretario General de la OEA, Luis Almagro, abordaron la realidad actual de la regi\u00f3n y destacaron el papel fundamental del sector privado en la construcci\u00f3n de un futuro mejor para toda la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los galardonados de la noche fueron Wakami, representada por su COO, Diego Villa, quien recibi\u00f3 una Menci\u00f3n Especial por su destacada labor. Wakami se ha destacado por crear cadenas de valor que conectan a comunidades rurales, especialmente a mujeres, con mercados nacionales e internacionales. La organizaci\u00f3n, certificada como B Corporation, ha demostrado un compromiso excepcional con la autosuficiencia y la propiedad de los productores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n, el Secretario General de la OEA present\u00f3 al ganador del premio CCA Award de este a\u00f1o. Al referirse a lo dif\u00edcil de la decisi\u00f3n de elegir al ganador de este a\u00f1o, destac\u00f3 las propuestas y el trabajo de los otros 3 finalistas y pidi\u00f3 para sus representantes, un aplauso de la sala. Ellos son Grupo Financiero Ficohsa, Grupo Pantale\u00f3n y Grupo Mariposa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Premios CCA Award de este a\u00f1o fue para la empresa hondure\u00f1a Elcatex, representada por su CEO, Jes\u00fas Canahuati. La empresa ha demostrado un compromiso sobresaliente con un modelo de negocio impulsado por un prop\u00f3sito, destac\u00e1ndose en \u00e1reas como el crecimiento empresarial con un prop\u00f3sito, la gesti\u00f3n del talento, el compromiso con las generaciones futuras y la participaci\u00f3n comunitaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre este galard\u00f3n el Sr Canahuati coment\u00f3: \u201cEn Grupo Elcatex, orientamos todas nuestras iniciativas y esfuerzos hacia las personas. Nos enorgullece profundamente nuestro compromiso con el empoderamiento y la inclusi\u00f3n de las mujeres. Trabajamos de manera constante e incansable para proteger e integrar a los grupos con menos oportunidades en nuestra sociedad, centr\u00e1ndonos especialmente en la promoci\u00f3n de causas que respaldan el desarrollo de las mujeres.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La entrega de estos premios reconoce el esfuerzo continuo y el impacto positivo que estas empresas han generado en sus comunidades y m\u00e1s all\u00e1, demostrando que el sector privado desempe\u00f1a un papel crucial en el desarrollo sostenible de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acerca del Trust for the Americas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 29 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;<a href=\"http:\/\/www.trustfortheamericas.org\/\">www.trustfortheamericas.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Acerca de Elcatex<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La trayectoria del Grupo Elcatex es de una constante evoluci\u00f3n y crecimiento construyendo un exitoso conglomerado de empresas, que se ha destacado por su visi\u00f3n innovadora y su compromiso con la excelencia en todas las operaciones. Durante m\u00e1s de 30 a\u00f1os se ha centrado en la creaci\u00f3n de un ecosistema vertical \u00fanico, donde convergen cuatro divisiones fundamentales: Manufactura y Textil, Innovaci\u00f3n, Energ\u00eda y Bienes Ra\u00edces, colaborando de manera sin\u00e9rgica para contribuir al progreso sostenible de m\u00e1s de 14,000 colaboradores, sus familias, las comunidades y la regi\u00f3n. Grupo Elcatex: Lideramos, Cuidamos, Hacemos la Diferencia.&nbsp;<a href=\"http:\/\/www.elcatex.com\/\">www.elcatex.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\"> Estados Unidos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>2023\/12\/07 Washington, D.C., 6 de diciembre de 2023&nbsp;\u2014 En una cena celebrada este 4 de diciembre, en el Hall de las Am\u00e9ricas de la Organizaci\u00f3n de Estados Americanos (OEA), The Trust for the Americas y la OEA entregaron el prestigioso Premio Ciudadano Corporativo de las Am\u00e9ricas (CCA). La ceremonia cont\u00f3 con la participaci\u00f3n de 90 distinguidos invitados, entre embajadores, dignatarios y representantes del gobierno de Estados Unidos y empresas de la regi\u00f3n. Las palabras inaugurales estuvieron a cargo de Enrique Garc\u00eda, Presidente del Directorio de The Trust for the Americas, quien dio la bienvenida a los presentes. Posteriormente, Alex Figueroa, Director de Operaciones (COO) del Trust for the Americas, ofreci\u00f3 un emocionante discurso recordando el impacto significativo de la organizaci\u00f3n, que en este a\u00f1o benefici\u00f3 a m\u00e1s de 5 millones de personas. Los asistentes tuvieron la oportunidad de conocer de primera mano un video de caso de \u00e9xito del Trust for the Americas. En un di\u00e1logo estilo &#8220;fireside chat,&#8221; Linda Eddleman, CEO del Trust for the Americas, y el Secretario General de la OEA, Luis Almagro, abordaron la realidad actual de la regi\u00f3n y destacaron el papel fundamental del sector privado en la construcci\u00f3n de un futuro mejor para toda la regi\u00f3n. Los galardonados de la noche fueron Wakami, representada por su COO, Diego Villa, quien recibi\u00f3 una Menci\u00f3n Especial por su destacada labor. Wakami se ha destacado por crear cadenas de valor que conectan a comunidades rurales, especialmente a mujeres, con mercados nacionales e internacionales. La organizaci\u00f3n, certificada como B Corporation, ha demostrado un compromiso excepcional con la autosuficiencia y la propiedad de los productores. A continuaci\u00f3n, el Secretario General de la OEA present\u00f3 al ganador del premio CCA Award de este a\u00f1o. Al referirse a lo dif\u00edcil de la decisi\u00f3n de elegir al ganador de este a\u00f1o, destac\u00f3 las propuestas y el trabajo de los otros 3 finalistas y pidi\u00f3 para sus representantes, un aplauso de la sala. Ellos son Grupo Financiero Ficohsa, Grupo Pantale\u00f3n y Grupo Mariposa. El Premios CCA Award de este a\u00f1o fue para la empresa hondure\u00f1a Elcatex, representada por su CEO, Jes\u00fas Canahuati. La empresa ha demostrado un compromiso sobresaliente con un modelo de negocio impulsado por un prop\u00f3sito, destac\u00e1ndose en \u00e1reas como el crecimiento empresarial con un prop\u00f3sito, la gesti\u00f3n del talento, el compromiso con las generaciones futuras y la participaci\u00f3n comunitaria. Sobre este galard\u00f3n el Sr Canahuati coment\u00f3: \u201cEn Grupo Elcatex, orientamos todas nuestras iniciativas y esfuerzos hacia las personas. Nos enorgullece profundamente nuestro compromiso con el empoderamiento y la inclusi\u00f3n de las mujeres. Trabajamos de manera constante e incansable para proteger e integrar a los grupos con menos oportunidades en nuestra sociedad, centr\u00e1ndonos especialmente en la promoci\u00f3n de causas que respaldan el desarrollo de las mujeres.\u201d La entrega de estos premios reconoce el esfuerzo continuo y el impacto positivo que estas empresas han generado en sus comunidades y m\u00e1s all\u00e1, demostrando que el sector privado desempe\u00f1a un papel crucial en el desarrollo sostenible de la regi\u00f3n. Acerca del Trust for the Americas The Trust for the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida en 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 29 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno. Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo de nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar los desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.&nbsp;www.trustfortheamericas.org Acerca de Elcatex La trayectoria del Grupo Elcatex es de una constante evoluci\u00f3n y crecimiento construyendo un exitoso conglomerado de empresas, que se ha destacado por su visi\u00f3n innovadora y su compromiso con la excelencia en todas las operaciones. Durante m\u00e1s de 30 a\u00f1os se ha centrado en la creaci\u00f3n de un ecosistema vertical \u00fanico, donde convergen cuatro divisiones fundamentales: Manufactura y Textil, Innovaci\u00f3n, Energ\u00eda y Bienes Ra\u00edces, colaborando de manera sin\u00e9rgica para contribuir al progreso sostenible de m\u00e1s de 14,000 colaboradores, sus familias, las comunidades y la regi\u00f3n. Grupo Elcatex: Lideramos, Cuidamos, Hacemos la Diferencia.&nbsp;www.elcatex.com Estados Unidos<\/p>","protected":false},"author":37,"featured_media":7474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=7473"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7473\/revisions"}],"predecessor-version":[{"id":7475,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7473\/revisions\/7475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/7474"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=7473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=7473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=7473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}