{"id":7378,"date":"2023-09-28T10:31:00","date_gmt":"2023-09-28T10:31:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7378"},"modified":"2024-11-13T22:34:40","modified_gmt":"2024-11-13T22:34:40","slug":"la-3ra-edicion-de-la-semana-de-la-inclusion-trust-inteligencia-artificial-para-todos-llega-en-octubre-de-2023","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/la-3ra-edicion-de-la-semana-de-la-inclusion-trust-inteligencia-artificial-para-todos-llega-en-octubre-de-2023\/","title":{"rendered":"La 3ra edici\u00f3n de la Semana de la Inclusi\u00f3n Trust Inteligencia Artificial para Todos, llega en octubre de 2023"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li>Un evento de cuatro d\u00edas que profundizar\u00e1 en la aplicaci\u00f3n de la Inteligencia Artificial en entornos educativos, as\u00ed como su impacto en la accesibilidad y representatividad.\u00a0\u00a0<\/li>\n\n\n\n<li>Participar\u00e1n expertos de Argentina, Chile, Colombia, Estados Unidos y M\u00e9xico que discutir\u00e1n c\u00f3mo la IA est\u00e1 transformando la forma en que aprendemos y trabajamos.\u00a0<\/li>\n\n\n\n<li>Esta valiosa conversaci\u00f3n es la oportunidad de adentrarse en el mundo de la Inteligencia Artificial para promover la inclusi\u00f3n y equidad en la regi\u00f3n.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Washington DC, 27 de septiembre de 2023 &#8211; The Trust for the Americas, mediante el Programa de Oportunidades Econ\u00f3micas a trav\u00e9s de la Tecnolog\u00eda en las Am\u00e9ricas (POETA), se complace en anunciar la celebraci\u00f3n de la tercera edici\u00f3n de la Semana de la Inclusi\u00f3n Trust. Bajo el lema &#8220;Inteligencia Artificial para Todos: Desbloqueando la Tecnolog\u00eda y el Conocimiento&#8221;, este evento reunir\u00e1 a expertos y entusiastas de la tecnolog\u00eda para explorar el impacto y el potencial de la Inteligencia Artificial (IA) en el empoderamiento de docentes, empleados y emprendedores a trav\u00e9s de un uso productivo y \u00e9tico.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante cuatro d\u00edas, los participantes tendr\u00e1n la oportunidad de adentrarse en el fascinante mundo de la Inteligencia Artificial, desde su aplicaci\u00f3n en entornos educativos hasta su influencia en la accesibilidad y representatividad. Esta edici\u00f3n promete ofrecer una visi\u00f3n \u00fanica sobre c\u00f3mo la tecnolog\u00eda puede allanar el camino hacia una regi\u00f3n m\u00e1s inclusiva y equitativa.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pierina Nepote, Gerente Senior del Programa POETA, comparte \u201cEs con mucha ilusi\u00f3n que el Equipo POETA celebra, por tercera ocasi\u00f3n, la Semana de la Inclusi\u00f3n Trust. En esta ocasi\u00f3n, nos emociona reunir a socios locales POETA, expertos y entusiastas de la tecnolog\u00eda para conversar sobre el enorme potencial que la IA tiene para potenciar la labor y facilitar el d\u00eda a d\u00eda de estudiantes, docentes, empleados y emprendedores\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la gu\u00eda de Jorge Cella, Director de Microsoft Filantrop\u00edas en Am\u00e9ricas, se mostrar\u00e1 c\u00f3mo la Inteligencia Artificial puede optimizar el rendimiento en el trabajo, a trav\u00e9s de la sesi\u00f3n \u201cInteligencia Artificial para la Productividad\u201d.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, Lisseth Falcon de CDI, Chile; Gelber Mor\u00e1n de ParqueSoft, Colombia y Luis Monreal de UTSC, M\u00e9xico, representantes de socios locales implementadores del Proyecto POETA DigiSpark, abordar\u00e1n el tema \u201cIntegrando la IA en Contenidos para la Educaci\u00f3n y Empleabilidad\u201d mediante un conversatorio que promete insights valiosos sobre el futuro de la educaci\u00f3n y la empleabilidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, participar\u00e1 Leonardo Ortiz, Vicepresidente de Desarrollo &amp; Alianzas Internacionales en Code.org, que liderar\u00e1 el tema \u201cInteligencia Artificial para la Ense\u00f1anza y el Aprendizaje\u201d, donde se hablar\u00e1 de c\u00f3mo la Inteligencia Artificial est\u00e1 revolucionando el trabajo de docentes y el aprendizaje en sus estudiantes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cierre de la semana de la inclusi\u00f3n est\u00e1 a cargo de Andr\u00e9s Rengifo, Director de Asuntos Corporativos, Externos y Legales en Microsoft, quien hablar\u00e1 del \u201cUso Responsable de la IA e Inclusi\u00f3n\u201d, donde se profundizar\u00e1 sobre la utilizaci\u00f3n de la Inteligencia Artificial para promover la equidad e inclusi\u00f3n.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esperamos contar con tu valiosa presencia en este evento que sin duda ser\u00e1 enriquecedor y lleno de aprendizajes.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"15\" src=\"https:\/\/www.trustfortheamericas.org\/static\/webpage_app\/insumos\/projects\/icon-map-marker.svg\">Mexico<\/p>","protected":false},"excerpt":{"rendered":"<p>Washington DC, 27 de septiembre de 2023 &#8211; The Trust for the Americas, mediante el Programa de Oportunidades Econ\u00f3micas a trav\u00e9s de la Tecnolog\u00eda en las Am\u00e9ricas (POETA), se complace en anunciar la celebraci\u00f3n de la tercera edici\u00f3n de la Semana de la Inclusi\u00f3n Trust. Bajo el lema &#8220;Inteligencia Artificial para Todos: Desbloqueando la Tecnolog\u00eda y el Conocimiento&#8221;, este evento reunir\u00e1 a expertos y entusiastas de la tecnolog\u00eda para explorar el impacto y el potencial de la Inteligencia Artificial (IA) en el empoderamiento de docentes, empleados y emprendedores a trav\u00e9s de un uso productivo y \u00e9tico.&nbsp; Durante cuatro d\u00edas, los participantes tendr\u00e1n la oportunidad de adentrarse en el fascinante mundo de la Inteligencia Artificial, desde su aplicaci\u00f3n en entornos educativos hasta su influencia en la accesibilidad y representatividad. Esta edici\u00f3n promete ofrecer una visi\u00f3n \u00fanica sobre c\u00f3mo la tecnolog\u00eda puede allanar el camino hacia una regi\u00f3n m\u00e1s inclusiva y equitativa.&nbsp; Pierina Nepote, Gerente Senior del Programa POETA, comparte \u201cEs con mucha ilusi\u00f3n que el Equipo POETA celebra, por tercera ocasi\u00f3n, la Semana de la Inclusi\u00f3n Trust. En esta ocasi\u00f3n, nos emociona reunir a socios locales POETA, expertos y entusiastas de la tecnolog\u00eda para conversar sobre el enorme potencial que la IA tiene para potenciar la labor y facilitar el d\u00eda a d\u00eda de estudiantes, docentes, empleados y emprendedores\u201d.&nbsp; Con la gu\u00eda de Jorge Cella, Director de Microsoft Filantrop\u00edas en Am\u00e9ricas, se mostrar\u00e1 c\u00f3mo la Inteligencia Artificial puede optimizar el rendimiento en el trabajo, a trav\u00e9s de la sesi\u00f3n \u201cInteligencia Artificial para la Productividad\u201d.&nbsp;&nbsp; Adem\u00e1s, Lisseth Falcon de CDI, Chile; Gelber Mor\u00e1n de ParqueSoft, Colombia y Luis Monreal de UTSC, M\u00e9xico, representantes de socios locales implementadores del Proyecto POETA DigiSpark, abordar\u00e1n el tema \u201cIntegrando la IA en Contenidos para la Educaci\u00f3n y Empleabilidad\u201d mediante un conversatorio que promete insights valiosos sobre el futuro de la educaci\u00f3n y la empleabilidad.&nbsp; Tambi\u00e9n, participar\u00e1 Leonardo Ortiz, Vicepresidente de Desarrollo &amp; Alianzas Internacionales en Code.org, que liderar\u00e1 el tema \u201cInteligencia Artificial para la Ense\u00f1anza y el Aprendizaje\u201d, donde se hablar\u00e1 de c\u00f3mo la Inteligencia Artificial est\u00e1 revolucionando el trabajo de docentes y el aprendizaje en sus estudiantes.&nbsp; El cierre de la semana de la inclusi\u00f3n est\u00e1 a cargo de Andr\u00e9s Rengifo, Director de Asuntos Corporativos, Externos y Legales en Microsoft, quien hablar\u00e1 del \u201cUso Responsable de la IA e Inclusi\u00f3n\u201d, donde se profundizar\u00e1 sobre la utilizaci\u00f3n de la Inteligencia Artificial para promover la equidad e inclusi\u00f3n.&nbsp;&nbsp; Esperamos contar con tu valiosa presencia en este evento que sin duda ser\u00e1 enriquecedor y lleno de aprendizajes.&nbsp;&nbsp; Mexico<\/p>","protected":false},"author":38,"featured_media":7379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=7378"}],"version-history":[{"count":2,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7378\/revisions"}],"predecessor-version":[{"id":7381,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7378\/revisions\/7381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/7379"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=7378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=7378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=7378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}