{"id":7297,"date":"2024-07-01T15:00:00","date_gmt":"2024-07-01T15:00:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=7297"},"modified":"2024-11-13T21:17:20","modified_gmt":"2024-11-13T21:17:20","slug":"fundacion-citi-otorga-fondos-a-jovenes-dominicanos-para-impulsar-sus-proyectos-de-emprendimiento","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/fundacion-citi-otorga-fondos-a-jovenes-dominicanos-para-impulsar-sus-proyectos-de-emprendimiento\/","title":{"rendered":"Fundaci\u00f3n Citi otorga fondos a j\u00f3venes dominicanos para impulsar sus proyectos de emprendimiento"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Santo Domingo, Rep\u00fablica Dominicana. 28 de junio, 2024.-<\/strong>&nbsp;The Trust for the Americas, en colaboraci\u00f3n con su socio local ADASEC Dominicana y con el apoyo de la Fundaci\u00f3n Citi, celebr\u00f3 la Competencia Pitch de Proyectos Innovadores de los DIA Labs RD. En este evento, un grupo de j\u00f3venes present\u00f3 sus proyectos ante un jurado, compitiendo por la oportunidad de ganar fondos semilla para fortalecer e impulsar sus emprendimientos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los DIA Lab RD tienen como objetivo proporcionar a los j\u00f3venes acceso a tecnolog\u00eda, formaci\u00f3n en curr\u00edculos de innovaci\u00f3n y emprendimiento, y espacios de mentor\u00eda. Esto les ayuda a desarrollar las habilidades necesarias para el mercado laboral y la creaci\u00f3n de sus propios negocios. Los j\u00f3venes participantes, que desarrollaron sus propuestas de emprendimiento durante semanas de capacitaci\u00f3n y pr\u00e1ctica, compitieron en grupo o de manera individual. Los jueces evaluaron exhaustivamente los planes de negocios y el potencial de los proyectos presentados, seleccionando a los equipos ganadores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cLos DIA Labs RD han demostrado ser una plataforma invaluable para que los j\u00f3venes puedan transformar sus ideas en realidades que beneficien a sus comunidades y a s\u00ed mismos. Agradecemos a todos los j\u00f3venes que participaron con tanto entusiasmo y dedicaci\u00f3n. Juntos, continuaremos fomentando un futuro prometedor para la juventud del Caribe.,\u201d<\/em>&nbsp;coment\u00f3 Maximo Vidal, Gerente General de Citi Republica Dominicana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los proyectos ganadores de esta convocatoria fueron:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>DataGovRD:<\/strong>\u00a0Una iniciativa innovadora que tiene como misi\u00f3n fortalecer la transparencia y la accesibilidad de los datos p\u00fablicos en Rep\u00fablica Dominicana.\u00a0<\/li>\n\n\n\n<li><strong>AnalityRD:<\/strong>\u00a0Ofrece servicios de auditor\u00eda cibern\u00e9tica de alta calidad para mejorar la seguridad inform\u00e1tica en empresas de diversos sectores en el pa\u00eds.\u00a0<\/li>\n\n\n\n<li><strong>Desperdicio Cero:<\/strong>\u00a0Una aplicaci\u00f3n para que las empresas, a trav\u00e9s de sus programas de RSE, donen alimentos sobrantes, y sus voluntarios los distribuyan a los m\u00e1s necesitados.\u00a0<\/li>\n\n\n\n<li><strong>Organic:\u00a0<\/strong>Otra aplicaci\u00f3n con la que las compa\u00f1\u00edas pueden donar alimentos sobrantes.\u00a0<\/li>\n\n\n\n<li><strong>Reverdecer Organic:<\/strong>\u00a0Un modelo de negocio de cosm\u00e9tica artesanal que elabora productos con ingredientes naturales.\u00a0<\/li>\n\n\n\n<li><strong>Explorer Math:<\/strong>\u00a0Una propuesta de tutor\u00edas accesibles tanto en l\u00ednea como presenciales, que utiliza tecnolog\u00eda de punta para crear un entorno de aprendizaje interactivo y atractivo.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A nivel regional, los DIA Labs ha impactado a m\u00e1s de 8 313 personas en Jamaica, Trinidad y Tobago y la Rep\u00fablica Dominicana. Desde su inicio, el proyecto ha establecido seis laboratorios de innovaci\u00f3n, fomentando el desarrollo de proyectos empresariales y tecnol\u00f3gicos entre los j\u00f3venes, y otorgando financiamiento inicial a varios emprendimientos innovadores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>***&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:\u202f&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno.Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.\u202fThe Trust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3).\u202f\u202f\u202f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre Citi:\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Citi, el banco l\u00edder global, tiene aproximadamente 200 millones de cuentas de clientes y realiza negocios en m\u00e1s de 160 pa\u00edses y jurisdicciones. Citi ofrece a personas, corporaciones, gobiernos e instituciones una amplia gama de productos y servicios financieros, incluyendo servicios bancarios y de cr\u00e9dito al consumidor, servicios bancarios corporativos y de inversi\u00f3n, corretaje de valores, servicios de transacci\u00f3n y administraci\u00f3n patrimonial. Informaci\u00f3n adicional: www.citigroup.com | Twitter: @Citi | YouTube: www.youtube.com\/citi | Blog: http:\/\/blog.citigroup.com | Facebook: www.facebook.com\/citi | LinkedIn:&nbsp;<a href=\"http:\/\/www.linkedin.com\/company\/citi\" rel=\"noreferrer noopener\" target=\"_blank\">www.linkedin.com\/company\/citi<\/a>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre la Fundaci\u00f3n Citi:&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fundaci\u00f3n Citi trabaja para promover el progreso econ\u00f3mico y mejorar la vida de las personas en comunidades de bajos ingresos en todo el mundo. Invertimos en esfuerzos que aumentan la inclusi\u00f3n financiera, catalizan oportunidades laborales para los j\u00f3venes y reinventan enfoques para construir comunidades econ\u00f3micamente din\u00e1micas. El enfoque \u201cM\u00e1s que Filantrop\u00eda\u201d de la Fundaci\u00f3n Citi despliega la enorme especializaci\u00f3n de Citi y su gente para cumplir nuestra misi\u00f3n e impulsar el liderazgo de ideas y la innovaci\u00f3n. Para ver m\u00e1s informaci\u00f3n, visite www.citifoundation.com&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Republica Dominicana<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Santo Domingo, Rep\u00fablica Dominicana. 28 de junio, 2024.-&nbsp;The Trust for the Americas, en colaboraci\u00f3n con su socio local ADASEC Dominicana y con el apoyo de la Fundaci\u00f3n Citi, celebr\u00f3 la Competencia Pitch de Proyectos Innovadores de los DIA Labs RD. En este evento, un grupo de j\u00f3venes present\u00f3 sus proyectos ante un jurado, compitiendo por la oportunidad de ganar fondos semilla para fortalecer e impulsar sus emprendimientos.&nbsp; Los DIA Lab RD tienen como objetivo proporcionar a los j\u00f3venes acceso a tecnolog\u00eda, formaci\u00f3n en curr\u00edculos de innovaci\u00f3n y emprendimiento, y espacios de mentor\u00eda. Esto les ayuda a desarrollar las habilidades necesarias para el mercado laboral y la creaci\u00f3n de sus propios negocios. Los j\u00f3venes participantes, que desarrollaron sus propuestas de emprendimiento durante semanas de capacitaci\u00f3n y pr\u00e1ctica, compitieron en grupo o de manera individual. Los jueces evaluaron exhaustivamente los planes de negocios y el potencial de los proyectos presentados, seleccionando a los equipos ganadores.&nbsp; \u201cLos DIA Labs RD han demostrado ser una plataforma invaluable para que los j\u00f3venes puedan transformar sus ideas en realidades que beneficien a sus comunidades y a s\u00ed mismos. Agradecemos a todos los j\u00f3venes que participaron con tanto entusiasmo y dedicaci\u00f3n. Juntos, continuaremos fomentando un futuro prometedor para la juventud del Caribe.,\u201d&nbsp;coment\u00f3 Maximo Vidal, Gerente General de Citi Republica Dominicana.&nbsp; Los proyectos ganadores de esta convocatoria fueron:&nbsp; A nivel regional, los DIA Labs ha impactado a m\u00e1s de 8 313 personas en Jamaica, Trinidad y Tobago y la Rep\u00fablica Dominicana. Desde su inicio, el proyecto ha establecido seis laboratorios de innovaci\u00f3n, fomentando el desarrollo de proyectos empresariales y tecnol\u00f3gicos entre los j\u00f3venes, y otorgando financiamiento inicial a varios emprendimientos innovadores.&nbsp; ***&nbsp; Sobre The Trust for the Americas:\u202f&nbsp; The Trust\u202ffor the Americas es una entidad sin fines de lucro afiliada a la Organizaci\u00f3n de los Estados Americanos (OEA). Establecida\u202fen 1997 para promover alianzas p\u00fablico-privadas, The Trust ha implementado proyectos en 24 pa\u00edses y ha trabajado con m\u00e1s de 1,000 organizaciones en la regi\u00f3n. Nuestras iniciativas buscan promover oportunidades educativas y econ\u00f3micas, as\u00ed como la responsabilidad y transparencia del gobierno.Nuestra alianza \u00fanica con la OEA nos permite tener acceso a los tomadores de decisiones dentro de la regi\u00f3n. Esta asociaci\u00f3n fundamental es la base a trav\u00e9s de la cual creamos redes s\u00f3lidas en todos los estados miembros y el sector privado. A trav\u00e9s del desarrollo\u202fde nuestra regi\u00f3n, The Trust contin\u00faa contribuyendo a superar\u202flos desaf\u00edos a trav\u00e9s de alianzas estrat\u00e9gicas que promueven la cooperaci\u00f3n para resultados sostenibles.\u202fThe Trust for the Americas es una organizaci\u00f3n sin fines de lucro 501 (c) (3).\u202f\u202f\u202f&nbsp; Sobre Citi:\u00a0 Citi, el banco l\u00edder global, tiene aproximadamente 200 millones de cuentas de clientes y realiza negocios en m\u00e1s de 160 pa\u00edses y jurisdicciones. Citi ofrece a personas, corporaciones, gobiernos e instituciones una amplia gama de productos y servicios financieros, incluyendo servicios bancarios y de cr\u00e9dito al consumidor, servicios bancarios corporativos y de inversi\u00f3n, corretaje de valores, servicios de transacci\u00f3n y administraci\u00f3n patrimonial. Informaci\u00f3n adicional: www.citigroup.com | Twitter: @Citi | YouTube: www.youtube.com\/citi | Blog: http:\/\/blog.citigroup.com | Facebook: www.facebook.com\/citi | LinkedIn:&nbsp;www.linkedin.com\/company\/citi&nbsp; Sobre la Fundaci\u00f3n Citi:&nbsp; La Fundaci\u00f3n Citi trabaja para promover el progreso econ\u00f3mico y mejorar la vida de las personas en comunidades de bajos ingresos en todo el mundo. Invertimos en esfuerzos que aumentan la inclusi\u00f3n financiera, catalizan oportunidades laborales para los j\u00f3venes y reinventan enfoques para construir comunidades econ\u00f3micamente din\u00e1micas. El enfoque \u201cM\u00e1s que Filantrop\u00eda\u201d de la Fundaci\u00f3n Citi despliega la enorme especializaci\u00f3n de Citi y su gente para cumplir nuestra misi\u00f3n e impulsar el liderazgo de ideas y la innovaci\u00f3n. Para ver m\u00e1s informaci\u00f3n, visite www.citifoundation.com&nbsp; Rep\u00fablica Dominicana<\/p>","protected":false},"author":38,"featured_media":7298,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[145],"tags":[],"class_list":["post-7297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-press-releases"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=7297"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7297\/revisions"}],"predecessor-version":[{"id":7300,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/7297\/revisions\/7300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/7298"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=7297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=7297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=7297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}