{"id":555,"date":"2019-08-14T17:39:24","date_gmt":"2019-08-14T21:39:24","guid":{"rendered":"http:\/\/40.117.174.162\/instituto-idear-lanca-mostra-tecnologica-de-projetos\/"},"modified":"2019-08-14T17:39:24","modified_gmt":"2019-08-14T21:39:24","slug":"instituto-idear-lanca-mostra-tecnologica-de-projetos","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/instituto-idear-lanca-mostra-tecnologica-de-projetos\/","title":{"rendered":"Instituto Idear lan\u00e7a Mostra Tecnol\u00f3gica de Projetos"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O Instituto para o Desenvolvimento Tecnol\u00f3gico e Social \u2013 IDEAR realiza no pr\u00f3ximo dia 15 de agosto, a Mostra Tecnol\u00f3gica de Projetos que tem por objetivo reunir e apresentar \u00e0 comunidade local e convidados, os projetos tecnol\u00f3gicos desenvolvidos pelos jovens participantes do Projeto POETA YouthSpark, no segmento de Desenvolvimento de Aplicativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fruto da parceria entre IDEAR, The Trust for the Americas &#8211; organiza\u00e7\u00e3o afiliada \u00e0 Organiza\u00e7\u00e3o dos Estados Americanos (OEA) e Microsoft Filantropia, o <strong>Projeto POETA YouthSpark<\/strong> \u00e9 uma iniciativa que busca capacitar jovens em situa\u00e7\u00e3o de vulnerabilidade social na Am\u00e9rica Latina e no Caribe, por meio do uso e apropria\u00e7\u00e3o de tecnologias, visando facilitar oportunidades de educa\u00e7\u00e3o, empreendedorismo e emprego atrav\u00e9s de uma forma\u00e7\u00e3o integral em Alfabetiza\u00e7\u00e3o Digital e Ci\u00eancias da Computa\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Mostra Tecnol\u00f3gica de Projetos acontecer\u00e1 no Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Cear\u00e1, Campus Maracana\u00fa, a partir das 14 horas (hor\u00e1rio local) e contar\u00e1 com a presen\u00e7a dos participantes do primeiro semestre, al\u00e9m de representantes dos parceiros, patrocinadores e da Prefeitura Municipal de Maracana\u00fa, Instituto Federal (IFCE) e do Instituto Idear.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O evento, proposto como um marco de alto impacto no \u00e2mbito do projeto POETA YouthSpark, contar\u00e1 com apresenta\u00e7\u00f5es culturais, depoimentos dos participantes, homenagens e a solenidade de certifica\u00e7\u00e3o dos cerca de 130 jovens participantes do projeto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O grande objetivo da Mostra \u00e9 possibilitar aos participantes interagir\ncom a comunidade, expor suas conquistas e projetos e com isso potencializar o\nprotagonismo e a constru\u00e7\u00e3o de uma sociedade mais inclusiva e tecnol\u00f3gica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8212;<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"alignleft\" size-large is-resized\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SERVI\u00c7O<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I Mostra Tecnol\u00f3gica de Projetos \u2013 Projeto POETA YouthSpark<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Data: Dia 15 de agosto de 2019<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Local: Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia, Campus\nMaracana\u00fa (Av. Parque Central &#8211; Distrito Industrial, Maracana\u00fa \u2013 CE)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hor\u00e1rio 14 horas<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre a The Trust for the Americas:&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A The Trust for the Americas \u00e9 uma entidade sem fins lucrativos afiliada\n\u00e0 Organiza\u00e7\u00e3o dos Estados Americanos (OEA). Estabelecida em 1997 para promover\nparcerias p\u00fablico-privadas, a The Trust implementou projetos em 24 pa\u00edses e\ntrabalhou com mais de 1.000 organiza\u00e7\u00f5es na regi\u00e3o. Nossas iniciativas buscam\npromover oportunidades educacionais e econ\u00f4micas, bem como a responsabilidade e\ntranspar\u00eancia do governo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nossa alian\u00e7a \u00fanica com a OEA nos permite ter acesso a tomadores de\ndecis\u00e3o na regi\u00e3o. Esta parceria fundamental \u00e9 a base atrav\u00e9s da qual criamos\nredes s\u00f3lidas em todos os estados membros e o setor privado. Por meio do\ndesenvolvimento da nossa regi\u00e3o, A The Trust continua a enfrentar os desafios\natrav\u00e9s de parcerias estrat\u00e9gicas que promovem a coopera\u00e7\u00e3o para resultados\nsustent\u00e1veis.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Instituto para o Desenvolvimento Tecnol\u00f3gico e Social \u2013 IDEAR realiza no pr\u00f3ximo dia 15 de agosto, a Mostra Tecnol\u00f3gica de Projetos que tem por objetivo reunir e apresentar \u00e0 comunidade local e convidados, os projetos tecnol\u00f3gicos desenvolvidos pelos jovens participantes do Projeto POETA YouthSpark, no segmento de Desenvolvimento de Aplicativos. Fruto da parceria entre IDEAR, The Trust for the Americas &#8211; organiza\u00e7\u00e3o afiliada \u00e0 Organiza\u00e7\u00e3o dos Estados Americanos (OEA) e Microsoft Filantropia, o Projeto POETA YouthSpark \u00e9 uma iniciativa que busca capacitar jovens em situa\u00e7\u00e3o de vulnerabilidade social na Am\u00e9rica Latina e no Caribe, por meio do uso e apropria\u00e7\u00e3o de tecnologias, visando facilitar oportunidades de educa\u00e7\u00e3o, empreendedorismo e emprego atrav\u00e9s de uma forma\u00e7\u00e3o integral em Alfabetiza\u00e7\u00e3o Digital e Ci\u00eancias da Computa\u00e7\u00e3o. A Mostra Tecnol\u00f3gica de Projetos acontecer\u00e1 no Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia do Cear\u00e1, Campus Maracana\u00fa, a partir das 14 horas (hor\u00e1rio local) e contar\u00e1 com a presen\u00e7a dos participantes do primeiro semestre, al\u00e9m de representantes dos parceiros, patrocinadores e da Prefeitura Municipal de Maracana\u00fa, Instituto Federal (IFCE) e do Instituto Idear. O evento, proposto como um marco de alto impacto no \u00e2mbito do projeto POETA YouthSpark, contar\u00e1 com apresenta\u00e7\u00f5es culturais, depoimentos dos participantes, homenagens e a solenidade de certifica\u00e7\u00e3o dos cerca de 130 jovens participantes do projeto. O grande objetivo da Mostra \u00e9 possibilitar aos participantes interagir com a comunidade, expor suas conquistas e projetos e com isso potencializar o protagonismo e a constru\u00e7\u00e3o de uma sociedade mais inclusiva e tecnol\u00f3gica. &#8212; SERVI\u00c7O I Mostra Tecnol\u00f3gica de Projetos \u2013 Projeto POETA YouthSpark Data: Dia 15 de agosto de 2019 Local: Instituto Federal de Educa\u00e7\u00e3o, Ci\u00eancia e Tecnologia, Campus Maracana\u00fa (Av. Parque Central &#8211; Distrito Industrial, Maracana\u00fa \u2013 CE) Hor\u00e1rio 14 horas Sobre a The Trust for the Americas:&nbsp; A The Trust for the Americas \u00e9 uma entidade sem fins lucrativos afiliada \u00e0 Organiza\u00e7\u00e3o dos Estados Americanos (OEA). Estabelecida em 1997 para promover parcerias p\u00fablico-privadas, a The Trust implementou projetos em 24 pa\u00edses e trabalhou com mais de 1.000 organiza\u00e7\u00f5es na regi\u00e3o. Nossas iniciativas buscam promover oportunidades educacionais e econ\u00f4micas, bem como a responsabilidade e transpar\u00eancia do governo. Nossa alian\u00e7a \u00fanica com a OEA nos permite ter acesso a tomadores de decis\u00e3o na regi\u00e3o. Esta parceria fundamental \u00e9 a base atrav\u00e9s da qual criamos redes s\u00f3lidas em todos os estados membros e o setor privado. Por meio do desenvolvimento da nossa regi\u00e3o, A The Trust continua a enfrentar os desafios atrav\u00e9s de parcerias estrat\u00e9gicas que promovem a coopera\u00e7\u00e3o para resultados sustent\u00e1veis.<\/p>","protected":false},"author":6,"featured_media":556,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=555"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/555\/revisions"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}