{"id":537,"date":"2019-08-07T15:12:38","date_gmt":"2019-08-07T19:12:38","guid":{"rendered":"http:\/\/40.117.174.162\/fundacion-eva-de-camou-y-the-trust-for-the-americas-capacitaron-a-mujeres-jovenes-en-el-estado-de-mexico\/"},"modified":"2019-08-07T15:12:38","modified_gmt":"2019-08-07T19:12:38","slug":"fundacion-eva-de-camou-y-the-trust-for-the-americas-capacitaron-a-mujeres-jovenes-en-el-estado-de-mexico","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/fundacion-eva-de-camou-y-the-trust-for-the-americas-capacitaron-a-mujeres-jovenes-en-el-estado-de-mexico\/","title":{"rendered":"Fundaci\u00f3n Eva de Camou y The Trust for the Americas capacitaron a mujeres j\u00f3venes en el Estado de M\u00e9xico"},"content":{"rendered":"<p class=\"wp-block-paragraph\">The Trust for the Americas, a trav\u00e9s del Proyecto VIVE y con\napoyo de la Fundaci\u00f3n Eva de Camou, capacit\u00f3 a m\u00e1s de 350 mujeres de &nbsp;17 y 18 a\u00f1os de edad, inscritas en la Villa de\nlas Ni\u00f1as de Chalco, en el Estado de M\u00e9xico. La capacitaci\u00f3n incluy\u00f3 modulos en\ntemas de ventas, promotor\u00eda, mercadeo y atenci\u00f3n al cliente. Con esta\ncapacitaci\u00f3n se incrementar\u00e1n los conocimientos y las herramientas con las que\ncuentan las mujeres para empoderarlas y mejorar sus oportunidades econ\u00f3micas.<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large is-resized\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Marisela Melgar, Directora Ejecutiva de Fundaci\u00f3n Eva de\nCamou, al respecto del prorgama coment\u00f3: \u201cEn la villa de las ni\u00f1as desarrollan\nun plan de vida y si desean continuar sus estudios, las apoyamos con becas. Hay\nalgunas que deciden regresar a sus casas, en ese caso procuramos que sean\nagentes de cambio y que logren desarrollar sus propios emprendimientos.\u201d<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large is-resized\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente la Villa de las ni\u00f1as cuenta con m\u00e1s\nde tres mil alumnas provenientes de todo el pa\u00eds, divididas entre adolescentes\nde secundaria y mujeres j\u00f3venes que cursan el bachillerato tecnol\u00f3gico, del\ncual egresar\u00e1n en carreras t\u00e9cnicas tales como industria del vestido, asistente\nejecutivo, contabilidad, inform\u00e1tica y trabajo social. <\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large is-resized\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para lograr esta capacitaci\u00f3n simult\u00e1nea, contamos con el apoyo de Pro Mujer, Proacceso y ManpowerGroup, aliados estrat\u00e9gicos en la implementaci\u00f3n del Proyecto VIVE, adem\u00e1s de contar con el apoyo de las vinculadoras de las sedes de Guadalajara, San Luis Potos\u00ed y Xalapa, y la facilitadora de Ciudad de M\u00e9xico.<\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" size-large\\\"><img src=\"\\\"https:><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\n\nEl Proyecto VIVE es implementado por The Trust for the Americas gracias al apoyo de Walmart Foundation, actualmente tiene sedes en 14 estados de la Rep\u00fablica Mexicana, sumando cada d\u00eda. Entre 2016 y 2018 capacit\u00f3 a m\u00e1s de 51 mil personas a nivel nacional. Del total de personas capacitadas, m\u00e1s de 38 mil son mujeres (40% de las cuales son jefas de familia). Asimismo, cerca de 7 mil personas fueron vinculadas a oportunidades econ\u00f3micas (86% mujeres, 60% fueron vinculadas a un trabajo de tiempo completo y el 21% se auto-emplearon o iniciaron proyectos de emprendimiento).\n\n<\/p>","protected":false},"excerpt":{"rendered":"<p>The Trust for the Americas, a trav\u00e9s del Proyecto VIVE y con apoyo de la Fundaci\u00f3n Eva de Camou, capacit\u00f3 a m\u00e1s de 350 mujeres de &nbsp;17 y 18 a\u00f1os de edad, inscritas en la Villa de las Ni\u00f1as de Chalco, en el Estado de M\u00e9xico. La capacitaci\u00f3n incluy\u00f3 modulos en temas de ventas, promotor\u00eda, mercadeo y atenci\u00f3n al cliente. Con esta capacitaci\u00f3n se incrementar\u00e1n los conocimientos y las herramientas con las que cuentan las mujeres para empoderarlas y mejorar sus oportunidades econ\u00f3micas. Marisela Melgar, Directora Ejecutiva de Fundaci\u00f3n Eva de Camou, al respecto del prorgama coment\u00f3: \u201cEn la villa de las ni\u00f1as desarrollan un plan de vida y si desean continuar sus estudios, las apoyamos con becas. Hay algunas que deciden regresar a sus casas, en ese caso procuramos que sean agentes de cambio y que logren desarrollar sus propios emprendimientos.\u201d Actualmente la Villa de las ni\u00f1as cuenta con m\u00e1s de tres mil alumnas provenientes de todo el pa\u00eds, divididas entre adolescentes de secundaria y mujeres j\u00f3venes que cursan el bachillerato tecnol\u00f3gico, del cual egresar\u00e1n en carreras t\u00e9cnicas tales como industria del vestido, asistente ejecutivo, contabilidad, inform\u00e1tica y trabajo social. Para lograr esta capacitaci\u00f3n simult\u00e1nea, contamos con el apoyo de Pro Mujer, Proacceso y ManpowerGroup, aliados estrat\u00e9gicos en la implementaci\u00f3n del Proyecto VIVE, adem\u00e1s de contar con el apoyo de las vinculadoras de las sedes de Guadalajara, San Luis Potos\u00ed y Xalapa, y la facilitadora de Ciudad de M\u00e9xico. El Proyecto VIVE es implementado por The Trust for the Americas gracias al apoyo de Walmart Foundation, actualmente tiene sedes en 14 estados de la Rep\u00fablica Mexicana, sumando cada d\u00eda. Entre 2016 y 2018 capacit\u00f3 a m\u00e1s de 51 mil personas a nivel nacional. Del total de personas capacitadas, m\u00e1s de 38 mil son mujeres (40% de las cuales son jefas de familia). Asimismo, cerca de 7 mil personas fueron vinculadas a oportunidades econ\u00f3micas (86% mujeres, 60% fueron vinculadas a un trabajo de tiempo completo y el 21% se auto-emplearon o iniciaron proyectos de emprendimiento).<\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-537","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=537"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/537\/revisions"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}