{"id":444,"date":"2019-05-21T17:59:03","date_gmt":"2019-05-21T21:59:03","guid":{"rendered":"http:\/\/40.117.174.162\/the-trust-for-the-americas-y-la-organizacion-de-los-estados-americanos-oea-capacitan-a-jovenes-talentos-para-su-preparacion-para-el-mundo-laboral\/"},"modified":"2019-05-21T17:59:03","modified_gmt":"2019-05-21T21:59:03","slug":"the-trust-for-the-americas-y-la-organizacion-de-los-estados-americanos-oea-capacitan-a-jovenes-talentos-para-su-preparacion-para-el-mundo-laboral","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/the-trust-for-the-americas-y-la-organizacion-de-los-estados-americanos-oea-capacitan-a-jovenes-talentos-para-su-preparacion-para-el-mundo-laboral\/","title":{"rendered":"The Trust for the Americas y la Organizaci\u00f3n de los Estados Americanos- OEA, capacitan a j\u00f3venes talentos para su preparaci\u00f3n para el mundo laboral."},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Washington, D.C., <\/strong>21 de mayo de 2019 \u2014 En el marco del programa \\&#8221;Creaci\u00f3n de una Trayectoria Profesional en Seguridad Digital\\&#8221;, coordinado conjuntamente por el Programa de Ciberseguridad de la Organizaci\u00f3n de los Estados Americanos (OEA) y The Trust for the Americas, se anunci\u00f3 hoy que el programa capacit\u00f3 un promedio de 40 j\u00f3venes por pa\u00eds, Colombia, Per\u00fa, Brasil, Rep\u00fablica Dominicana, y Costa Rica. <\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\\\"\"><img src=\"\\\"https:><figcaption>Grupo de j\u00f3venes capacitados en Bogot\u00e1 Colombia. <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El programa incluy\u00f3 entre otras, la capacitaci\u00f3n en habilidades de liderazgo y comunicaci\u00f3n as\u00ed como en competencias para facilitar el ingreso de los j\u00f3venes al mundo laboral. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa incluye una capacitaci\u00f3n de 16 horas de duraci\u00f3n, llevada a cabo por capacitadoras de The Trust for the Americas, quienes viajan a los pa\u00edses para coordinar la tarea con los j\u00f3venes. El programa incluye actividades mediante las cuales los asistentes analizan, debaten y deciden de manera responsable sus objetivos e intereses para acceder a su primer empleo o mejorar el actual. <\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\\\"\"><img src=\"\\\"https:><figcaption>Grupo de j\u00f3venes capacitados en Lima, Per\u00fa. <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Los m\u00f3dulos de la capacitaci\u00f3n, est\u00e1n enfocados en resaltar y evaluar las motivaciones, intereses, expectativas, conocimientos y habilidades de los participantes. Asimismo, cada grupo de j\u00f3venes en los diferentes pa\u00edses crean una red de contactos a trav\u00e9s de LinkedIn que les permite contar con una red de apoyo a futuro en su carrera profesional.<\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\\\"\"><img src=\"\\\"https:><figcaption>Grupo de j\u00f3venes capacitados en Rep\u00fablica Dominicana. <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre el programa, Maria Liliana Mor<strong>,<\/strong> Directora de Programas de The Trust for the Americas, coment\u00f3:\u00a0\u201cDesde The Trust for the Americas estamos muy orgullosos de continuar con una edici\u00f3n m\u00e1s de este proyecto puesto que vemos reflejado el compromiso de estos j\u00f3venes para avanzar en sus carreras y preparaci\u00f3n para el mundo laboral. Todo lo anterior, es posible gracias al potencial de las asociaciones p\u00fablico &#8211; privadas para generar nuevas oportunidades para los j\u00f3venes de Am\u00e9rica Latina.\u201d<\/p>\n\n\n\n<figure class=\"\\\"wp-block-image\\\"\"><img src=\"\\\"https:><figcaption>J\u00f3venes de Bogot\u00e1, Colombia. <\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Esta tercera edici\u00f3n del programa, financiada por Citi Foundation, capacitar\u00e1 en seguridad digital y preparaci\u00f3n para el mundo laboral a un total de 200 j\u00f3venes con edades comprendidas entre los 17 y 25 a\u00f1os. El proyecto cuenta con el apoyo del Ministerio de Ciencia, Tecnolog\u00eda y Telecomunicaciones y del Instituto Nacional de Ciberseguridad- INCIBE quienes proporcionan la plataforma digital para la capacitaci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los mejores 20 estudiantes del programa en cada pa\u00eds, tendr\u00e1n acceso a una\nincubadora de emprendimiento que tendr\u00e1 lugar en Le\u00f3n, Espa\u00f1a, como pre\u00e1mbulo\ndel Summer Bootcamp al que tambi\u00e9n podr\u00e1n asistir con gastos pagados. Adem\u00e1s,\notros 20 estudiantes, recibir\u00e1n una pasant\u00eda en el sector privado en sus\nrespectivos pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sobre The Trust for the Americas:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Trust for the Americas\nes una Organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados\nAmericanos (OEA) cuya misi\u00f3n es promover alianzas para la inclusi\u00f3n econ\u00f3mica y\nsocial en las Am\u00e9ricas. Establecida en 1997, The Trust fue creado para la\nparticipaci\u00f3n del sector p\u00fablico, el sector privado y las iniciativas de la\nsociedad civil en el desarrollo social y econ\u00f3mico en Am\u00e9rica Latina y el\nCaribe. Las iniciativas de la organizaci\u00f3n mejoran el acceso de las comunidades\na oportunidades econ\u00f3micas, mejor seguridad ciudadana y oportunidades para la\nexpresi\u00f3n democr\u00e1tica y la gobernabilidad.&nbsp; The Trust for the Americas\nofrece a las organizaciones locales asociadas, instrumentos de capacitaci\u00f3n,\nservicios, productos y asistencia t\u00e9cnica para servir mejor a las comunidades\nvulnerables de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Visite:&nbsp;<a href=\"\/en\/\"http:>www.thetrustfortheamericas.org<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook:&nbsp;<a href=\"\/en\/\"https:>The Trust for the Americas<\/a>&nbsp;\nTwitter:&nbsp;&nbsp;&nbsp;<a href=\"\/en\/\"https:>@Trust4Americas<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Washington, D.C., 21 de mayo de 2019 \u2014 En el marco del programa \\&#8221;Creaci\u00f3n de una Trayectoria Profesional en Seguridad Digital\\&#8221;, coordinado conjuntamente por el Programa de Ciberseguridad de la Organizaci\u00f3n de los Estados Americanos (OEA) y The Trust for the Americas, se anunci\u00f3 hoy que el programa capacit\u00f3 un promedio de 40 j\u00f3venes por pa\u00eds, Colombia, Per\u00fa, Brasil, Rep\u00fablica Dominicana, y Costa Rica. El programa incluy\u00f3 entre otras, la capacitaci\u00f3n en habilidades de liderazgo y comunicaci\u00f3n as\u00ed como en competencias para facilitar el ingreso de los j\u00f3venes al mundo laboral. El programa incluye una capacitaci\u00f3n de 16 horas de duraci\u00f3n, llevada a cabo por capacitadoras de The Trust for the Americas, quienes viajan a los pa\u00edses para coordinar la tarea con los j\u00f3venes. El programa incluye actividades mediante las cuales los asistentes analizan, debaten y deciden de manera responsable sus objetivos e intereses para acceder a su primer empleo o mejorar el actual. Los m\u00f3dulos de la capacitaci\u00f3n, est\u00e1n enfocados en resaltar y evaluar las motivaciones, intereses, expectativas, conocimientos y habilidades de los participantes. Asimismo, cada grupo de j\u00f3venes en los diferentes pa\u00edses crean una red de contactos a trav\u00e9s de LinkedIn que les permite contar con una red de apoyo a futuro en su carrera profesional. Sobre el programa, Maria Liliana Mor, Directora de Programas de The Trust for the Americas, coment\u00f3:\u00a0\u201cDesde The Trust for the Americas estamos muy orgullosos de continuar con una edici\u00f3n m\u00e1s de este proyecto puesto que vemos reflejado el compromiso de estos j\u00f3venes para avanzar en sus carreras y preparaci\u00f3n para el mundo laboral. Todo lo anterior, es posible gracias al potencial de las asociaciones p\u00fablico &#8211; privadas para generar nuevas oportunidades para los j\u00f3venes de Am\u00e9rica Latina.\u201d Esta tercera edici\u00f3n del programa, financiada por Citi Foundation, capacitar\u00e1 en seguridad digital y preparaci\u00f3n para el mundo laboral a un total de 200 j\u00f3venes con edades comprendidas entre los 17 y 25 a\u00f1os. El proyecto cuenta con el apoyo del Ministerio de Ciencia, Tecnolog\u00eda y Telecomunicaciones y del Instituto Nacional de Ciberseguridad- INCIBE quienes proporcionan la plataforma digital para la capacitaci\u00f3n. Los mejores 20 estudiantes del programa en cada pa\u00eds, tendr\u00e1n acceso a una incubadora de emprendimiento que tendr\u00e1 lugar en Le\u00f3n, Espa\u00f1a, como pre\u00e1mbulo del Summer Bootcamp al que tambi\u00e9n podr\u00e1n asistir con gastos pagados. Adem\u00e1s, otros 20 estudiantes, recibir\u00e1n una pasant\u00eda en el sector privado en sus respectivos pa\u00edses. Sobre The Trust for the Americas: The Trust for the Americas es una Organizaci\u00f3n sin fines de lucro afiliada a la Organizaci\u00f3n de Estados Americanos (OEA) cuya misi\u00f3n es promover alianzas para la inclusi\u00f3n econ\u00f3mica y social en las Am\u00e9ricas. Establecida en 1997, The Trust fue creado para la participaci\u00f3n del sector p\u00fablico, el sector privado y las iniciativas de la sociedad civil en el desarrollo social y econ\u00f3mico en Am\u00e9rica Latina y el Caribe. Las iniciativas de la organizaci\u00f3n mejoran el acceso de las comunidades a oportunidades econ\u00f3micas, mejor seguridad ciudadana y oportunidades para la expresi\u00f3n democr\u00e1tica y la gobernabilidad.&nbsp; The Trust for the Americas ofrece a las organizaciones locales asociadas, instrumentos de capacitaci\u00f3n, servicios, productos y asistencia t\u00e9cnica para servir mejor a las comunidades vulnerables de la regi\u00f3n. Visite:&nbsp;www.thetrustfortheamericas.org Facebook:&nbsp;The Trust for the Americas&nbsp; Twitter:&nbsp;&nbsp;&nbsp;@Trust4Americas<\/p>","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-444","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/444\/revisions"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}