{"id":348,"date":"2019-04-09T17:36:25","date_gmt":"2019-04-09T21:36:25","guid":{"rendered":"http:\/\/40.117.174.162\/rendichicas-se-suma-al-empoderamiento-de-mujeres-tijuanenses-a-traves-de-proyecto-vive-2\/"},"modified":"2019-04-09T17:36:25","modified_gmt":"2019-04-09T21:36:25","slug":"rendichicas-se-suma-al-empoderamiento-de-mujeres-tijuanenses-a-traves-de-proyecto-vive-2","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/rendichicas-se-suma-al-empoderamiento-de-mujeres-tijuanenses-a-traves-de-proyecto-vive-2\/","title":{"rendered":"Rendichicas se suma al empoderamiento de mujeres tijuanenses a trav\u00e9s de Proyecto VIVE"},"content":{"rendered":"<p class=\"wp-block-paragraph\" style=\"\\\"text-align:justify;\\\"\"><strong>Tijuana, Baja California, 8 de abril de 2019.<\/strong> La empresa gasolinera Rendichicas se sum\u00f3 a la iniciativa de The Trust for the Americas llamada Proyecto VIVE: ven, insp\u00edrate y vende, para capacitar a 30 mujeres en los temas de atenci\u00f3n al cliente y prevenci\u00f3n de violencia hacia las ni\u00f1as y las mujeres.<\/p>\n\n\n\n<ul class=\"\\&quot;wp-block-gallery wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\" aligncenter columns-1 is-cropped\\\"><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"\\\"text-align:justify;\\\"\">Sara Gonz\u00e1lez, vinculadora del\nProyecto VIVE en Tijuana, coment\u00f3 que \u201cla empresa emplea a mujeres que fungen\ncomo despachadoras de gasolina, pero el objetivo es impulsarlas a trav\u00e9s de la\ncapacitaci\u00f3n para que puedan tener un crecimiento dentro y fuera de la empresa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"\\\"text-align:justify;\\\"\">A trav\u00e9s de la vinculaci\u00f3n que\nrealiza Sara Gonz\u00e1lez, la empresa abri\u00f3 sus puertas para que 30 mujeres que ya\nlaboran ah\u00ed, pudieran adquirir herramientas para mejorar sus estrategias de\natenci\u00f3n al cliente, adem\u00e1s de conocer m\u00e1s sobre los tipos de violencia, c\u00f3mo\nidentificarla y qu\u00e9 hacer en caso de vivirla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"\/en\/\"https:>Descarga el manual aqu\u00ed <\/a><\/p>\n\n\n\n<ul class=\"\\&quot;wp-block-gallery wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\" columns-1 is-cropped\\\"><li class=\"\\\"blocks-gallery-item\\\"\"><figure><img src=\"\\\"https:><\/figure><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"\\\"text-align:justify;\\\"\">\u201cInicialmente, est\u00e1 alianza es\npara beneficiar a las mujeres de Tijuana, pero esperamos que se sumen las\nsucursales de Mexicali, Baja California; Hermosillo y Obreg\u00f3n, Sonora y\nChihuahua, Chihuahua\u201d, dijo la vinculadora. <\/p>\n\n\n\n<div class=\"\\\"wp-block-image\\\"\"><figure class=\"\\\"aligncenter\" is-resized\\\"><img src=\"\\\"https:><figcaption> <br>Alejandra Aguayo, beneficiaria del Proyecto VIVE <\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"\\\"text-align:justify;\\\"\">Alejandra Aguayo, beneficiaria\ndel Proyecto VIVE, mencion\u00f3 que \u201cyo batallaba mucho para sonre\u00edr al cliente,\nera algo que no se me daba. El primer d\u00eda del curso nos pusieron un ejercicio\npara que reconoci\u00e9ramos como se ve\u00edan las personas cuando no sonr\u00eden y me quede\npensando que as\u00ed me veo yo, por esa raz\u00f3n cambie mi actitud. Ahora me va mejor\nen la venta de litros (de gasolina) y por ende en la parte econ\u00f3mica. \u00a1Me gust\u00f3\nmucho la capacitaci\u00f3n!\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"\\\"text-align:justify;\\\"\">El Proyecto\nVIVE es implementado por The Trust for the Americas gracias al apoyo de Walmart\nFoundation, actualmente tiene sedes en 14 estados de la Rep\u00fablica Mexicana,\nsumando cada d\u00eda. Entre 2016 y 2018 capacit\u00f3 a m\u00e1s de 51\nmil personas a nivel nacional. Del total de personas capacitadas, m\u00e1s de 38 mil\nson mujeres (40% de las cuales son jefas de familia). Asimismo, cerca de 7 mil\npersonas fueron vinculadas a oportunidades econ\u00f3micas (86% mujeres, 60% fueron\nvinculadas a un trabajo de tiempo completo y el 21% se auto-emplearon o\niniciaron proyectos de emprendimiento).<\/p>","protected":false},"excerpt":{"rendered":"<p>Tijuana, Baja California, 8 de abril de 2019. La empresa gasolinera Rendichicas se sum\u00f3 a la iniciativa de The Trust for the Americas llamada Proyecto VIVE: ven, insp\u00edrate y vende, para capacitar a 30 mujeres en los temas de atenci\u00f3n al cliente y prevenci\u00f3n de violencia hacia las ni\u00f1as y las mujeres. Sara Gonz\u00e1lez, vinculadora del Proyecto VIVE en Tijuana, coment\u00f3 que \u201cla empresa emplea a mujeres que fungen como despachadoras de gasolina, pero el objetivo es impulsarlas a trav\u00e9s de la capacitaci\u00f3n para que puedan tener un crecimiento dentro y fuera de la empresa\u201d. A trav\u00e9s de la vinculaci\u00f3n que realiza Sara Gonz\u00e1lez, la empresa abri\u00f3 sus puertas para que 30 mujeres que ya laboran ah\u00ed, pudieran adquirir herramientas para mejorar sus estrategias de atenci\u00f3n al cliente, adem\u00e1s de conocer m\u00e1s sobre los tipos de violencia, c\u00f3mo identificarla y qu\u00e9 hacer en caso de vivirla. Descarga el manual aqu\u00ed \u201cInicialmente, est\u00e1 alianza es para beneficiar a las mujeres de Tijuana, pero esperamos que se sumen las sucursales de Mexicali, Baja California; Hermosillo y Obreg\u00f3n, Sonora y Chihuahua, Chihuahua\u201d, dijo la vinculadora. Alejandra Aguayo, beneficiaria del Proyecto VIVE, mencion\u00f3 que \u201cyo batallaba mucho para sonre\u00edr al cliente, era algo que no se me daba. El primer d\u00eda del curso nos pusieron un ejercicio para que reconoci\u00e9ramos como se ve\u00edan las personas cuando no sonr\u00eden y me quede pensando que as\u00ed me veo yo, por esa raz\u00f3n cambie mi actitud. Ahora me va mejor en la venta de litros (de gasolina) y por ende en la parte econ\u00f3mica. \u00a1Me gust\u00f3 mucho la capacitaci\u00f3n!\u201d. El Proyecto VIVE es implementado por The Trust for the Americas gracias al apoyo de Walmart Foundation, actualmente tiene sedes en 14 estados de la Rep\u00fablica Mexicana, sumando cada d\u00eda. Entre 2016 y 2018 capacit\u00f3 a m\u00e1s de 51 mil personas a nivel nacional. Del total de personas capacitadas, m\u00e1s de 38 mil son mujeres (40% de las cuales son jefas de familia). Asimismo, cerca de 7 mil personas fueron vinculadas a oportunidades econ\u00f3micas (86% mujeres, 60% fueron vinculadas a un trabajo de tiempo completo y el 21% se auto-emplearon o iniciaron proyectos de emprendimiento).<\/p>","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-348","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=348"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/348\/revisions"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}