{"id":2292,"date":"2022-09-26T17:26:24","date_gmt":"2022-09-26T21:26:24","guid":{"rendered":"http:\/\/40.117.174.162\/el-ideaton-virtual-de-innovacion-y-emprendimiento-en-republica-dominicana\/"},"modified":"2022-09-26T17:26:24","modified_gmt":"2022-09-26T21:26:24","slug":"el-ideaton-virtual-de-innovacion-y-emprendimiento-en-republica-dominicana","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/el-ideaton-virtual-de-innovacion-y-emprendimiento-en-republica-dominicana\/","title":{"rendered":"El Ideat\u00f3n virtual de innovaci\u00f3n y emprendimiento en Rep\u00fablica Dominicana\u00a0\u00a0"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Del 6 al 16 de septiembre, celebramos el <strong>Ideat\u00f3n virtual de innovaci\u00f3n y emprendimiento en Rep\u00fablica Dominicana<\/strong> (RD), junto con nuestro socio local ADASEC, y con el apoyo de Citi Foundation, en el marco del programa <strong>DIA <\/strong>de The Trust for the Americas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante casi dos semanas, 200 j\u00f3venes de las comunidades de Ban\u00ed, Bonao y La Vega, recibieron mentor\u00eda y acompa\u00f1amiento por parte del m\u00e1s alto nivel de expertos locales e internacionales. En este encuentro, los participantes pudieron expandir sus conocimientos en:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"\\\"1\\\"\">\n<li><strong>Innovaci\u00f3n como estrategia para los emprendimientos de alto impacto<\/strong> al buscar<strong> <\/strong>dar respuesta a las necesidades del pa\u00eds, trazando los lineamientos estrat\u00e9gicos para obtener emprendimientos de alto impacto que generen valor a trav\u00e9s de la innovaci\u00f3n.&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"\\\"2\\\"\">\n<li><strong>Desarrollar emprendimientos de subsistencia<\/strong>,<strong> <\/strong>debido al alto \u00edndice de pobreza de RD, se fomentaron modelos de negocios inclusivos y rentables a trav\u00e9s de la generaci\u00f3n de oportunidades para las comunidades m\u00e1s vulnerables.&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"\\\"3\\\"\">\n<li><strong>Educaci\u00f3n y<s>\u202f<\/s> cultura para el emprendimiento<\/strong> al explorar<strong> <\/strong>estrategias educativas en t\u00e9rminos de emprendimiento que se desarrollan en el pa\u00eds y los nuevos enfoques que se est\u00e1n implementando.&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"\\\"4\\\"\">\n<li><strong>El Gobierno,<s>\u202f<\/s> la innovaci\u00f3n y el emprendimiento social<\/strong> para resaltar las estrategias que se deben implementar para lograr un modelo propio de desarrollo socialmente sostenible.&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"\\\"5\\\"\">\n<li><strong>Emprendimientos de base tecnol\u00f3gica y el uso de las TIC.<\/strong> Se dieron pautas de acci\u00f3n desde la \u00f3ptica p\u00fablica y privada sobre los mecanismos que permiten dinamizar los emprendimientos de base tecnol\u00f3gica a trav\u00e9s del uso adecuado de las TIC.&nbsp;<\/li>\n<\/ol>\n\n\n\n<ol class=\"wp-block-list\" start=\"\\\"6\\\"\">\n<li><strong>Comunidades de impacto <\/strong>con el fin de<strong> <\/strong>identificar estrategias que permiten a las comunidades de RD acceder al estatus de ciudades emprendedoras.&nbsp;<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Tomando en cuenta los conocimientos adquiridos en el Ideat\u00f3n virtual y las capacitaciones previas en habilidades para la era digital y el futuro del trabajo, los participantes de los <strong>DIA Labs RD<\/strong> presentar\u00e1n sus emprendimientos en la <strong>Competencia Pitch de Proyectos Innovadores<\/strong>, que, se llevar\u00e1 a cabo el 27 de septiembre. Despu\u00e9s de una rigurosa evaluaci\u00f3n por parte de un jurado multidisciplinario, los mejores proyectos recibir\u00e1n fondo semilla para seguir fortaleciendo sus ideas e impactos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas actividades se realizan en el marco de los <a rel=\"\\\"noreferrer\" noopener\\\" href=\"\/en\/\"https:><strong>Laboratorios de Innovaci\u00f3n DIA en Rep\u00fablica Dominicana<\/strong><\/a>, que tiene como objetivo fomentar y promover la innovaci\u00f3n y el emprendimiento en la juventud dominicana para inspirarla en la identificaci\u00f3n de soluciones a las problem\u00e1ticas de sus comunidades.&nbsp;&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Del 6 al 16 de septiembre, celebramos el Ideat\u00f3n virtual de innovaci\u00f3n y emprendimiento en Rep\u00fablica Dominicana (RD), junto con nuestro socio local ADASEC, y con el apoyo de Citi Foundation, en el marco del programa DIA de The Trust for the Americas. Durante casi dos semanas, 200 j\u00f3venes de las comunidades de Ban\u00ed, Bonao y La Vega, recibieron mentor\u00eda y acompa\u00f1amiento por parte del m\u00e1s alto nivel de expertos locales e internacionales. En este encuentro, los participantes pudieron expandir sus conocimientos en:&nbsp; Tomando en cuenta los conocimientos adquiridos en el Ideat\u00f3n virtual y las capacitaciones previas en habilidades para la era digital y el futuro del trabajo, los participantes de los DIA Labs RD presentar\u00e1n sus emprendimientos en la Competencia Pitch de Proyectos Innovadores, que, se llevar\u00e1 a cabo el 27 de septiembre. Despu\u00e9s de una rigurosa evaluaci\u00f3n por parte de un jurado multidisciplinario, los mejores proyectos recibir\u00e1n fondo semilla para seguir fortaleciendo sus ideas e impactos.&nbsp; Estas actividades se realizan en el marco de los Laboratorios de Innovaci\u00f3n DIA en Rep\u00fablica Dominicana, que tiene como objetivo fomentar y promover la innovaci\u00f3n y el emprendimiento en la juventud dominicana para inspirarla en la identificaci\u00f3n de soluciones a las problem\u00e1ticas de sus comunidades.&nbsp;&nbsp;<\/p>","protected":false},"author":32,"featured_media":2295,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[56,57,72,73],"class_list":["post-2292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-emprendimiento","tag-innovacion","tag-proyectos","tag-republica-dominicana"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/2292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=2292"}],"version-history":[{"count":0,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/2292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/2295"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=2292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=2292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=2292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}