{"id":1918,"date":"2021-10-26T12:54:13","date_gmt":"2021-10-26T16:54:13","guid":{"rendered":"http:\/\/40.117.174.162\/acordes-da-vida-un-proyecto-musical-que-fomenta-la-inclusion\/"},"modified":"2025-06-04T00:02:40","modified_gmt":"2025-06-04T00:02:40","slug":"acordes-da-vida-un-proyecto-musical-que-fomenta-la-inclusion","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/acordes-da-vida-un-proyecto-musical-que-fomenta-la-inclusion\/","title":{"rendered":"Acordes Da Vida &#8211;\u00a0Un proyecto musical que fomenta la inclusi\u00f3n\u00a0"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Una de las campa\u00f1as de movilizaci\u00f3n social de m\u00e1s larga duraci\u00f3n en Brasil,&nbsp;Crian\u00e7a&nbsp;Esperan\u00e7a, ha estado creando oportunidades de desarrollo para ni\u00f1os y j\u00f3venes en todo el pa\u00eds durante 36 a\u00f1os. Reconocido por la ONU como modelo internacional,&nbsp;Crian\u00e7a&nbsp;Esperan\u00e7a&nbsp;es uno de los programas&nbsp;sociales m\u00e1s visibles y reconocidos del pa\u00eds, as\u00ed como una poderosa herramienta de comunicaci\u00f3n para discutir temas importantes de la agenda social brasile\u00f1a.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de su campa\u00f1a anual de movilizaci\u00f3n, recolecta recursos que se invierten en proyectos sociales desarrollados por organizaciones de la sociedad civil en las cinco regiones de Brasil. Con la participaci\u00f3n de ciudadanos y grandes empresas, el programa ha apoyado m\u00e1s de 5.000 proyectos, que beneficiaron a m\u00e1s de 4 millones de ni\u00f1os y j\u00f3venes en situaci\u00f3n de vulnerabilidad en todo el pa\u00eds.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos los fondos recaudados se depositan directamente en una cuenta de la Unesco &#8211; Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura, responsable de la selecci\u00f3n de proyectos, a trav\u00e9s de un aviso p\u00fablico, as\u00ed como del monitoreo y seguimiento t\u00e9cnico y financiero a las organizaciones apoyadas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 2021,&nbsp;Crian\u00e7a&nbsp;Esperan\u00e7a&nbsp;celebr\u00f3 la educaci\u00f3n como un agente de transformaci\u00f3n social, en un escenario en el que la pandemia agrav\u00f3 las tasas de abandono escolar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de participar en el riguroso proceso de selecci\u00f3n de proyectos, OSJC \u2013 Obras&nbsp;Sociais&nbsp;Jer\u00f4nimo&nbsp;Candinho, organizaci\u00f3n que forma parte de la Franquicia Social POETA desde 2013 e implementa el proyecto POETA&nbsp;DigiSpark, con sede en la ciudad de&nbsp;Sobradinho, Distrito Federal, fue seleccionada con su proyecto Acordes da Vida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto Acordes da Vida participa en&nbsp;el programa&nbsp;Crian\u00e7a&nbsp;Esperan\u00e7a&nbsp;desde 2018 y ofrece talleres de m\u00fasica extraescolares, como Guitarra, Teclado, Viol\u00edn, Flauta, Coro y Percusi\u00f3n, adem\u00e1s de actividades recreativas, talleres de reciclaje, apoyo pedag\u00f3gico y psicosocial. Dirigido al p\u00fablico de 4 a 18 a\u00f1os, en 2021&nbsp;tiene como objetivo atender a 70 ni\u00f1os y adolescentes de forma directa y a 280 personas de forma indirecta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Obras&nbsp;Sociais&nbsp;Jer\u00f4nimo&nbsp;Candinho&nbsp;es una organizaci\u00f3n social&nbsp;orientada&nbsp;a promover la inclusi\u00f3n y mejorar la calidad de vida de ni\u00f1os y j\u00f3venes en situaciones de vulnerabilidad y exclusi\u00f3n social.&nbsp;Promueve la educaci\u00f3n escolar regular a trav\u00e9s del&nbsp;Col\u00e9gio&nbsp;Allan&nbsp;Kardec, ofreciendo educaci\u00f3n gratuita&nbsp;en todos los niveles, con el objetivo de rescatar los valores humanos y la autoestima de ni\u00f1os, j\u00f3venes y adolescentes,&nbsp;actividades diferenciadas, brindando un respiro a la convivencia con abandono, maltrato, negligencia y riesgos.&nbsp;Tambi\u00e9n ofrece&nbsp;talleres&nbsp;extracurriculares&nbsp;de&nbsp;educaci\u00f3n ambiental,&nbsp;artesan\u00eda y m\u00fasica, as\u00ed como clases de ciudadan\u00eda y actividades recreativas.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"636\" height=\"476\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2021\/10\/image.png\" alt=\"\" class=\"wp-image-12092\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/10\/image.png 636w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/10\/image-300x225.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/10\/image-16x12.png 16w\" sizes=\"(max-width: 636px) 100vw, 636px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Conhe\u00e7a aqui o Projeto Acordes da Vida e o momento que\u00a0organiza\u00e7\u00e3o Obras Sociais Jer\u00f4nimo Candinho recebeu a not\u00edcia de que havia sido contemplada com a edi\u00e7\u00e3o 2021\/2022\u00a0da Campanha Crian\u00e7a Esperan\u00e7a:\u00a0<a href=\"https:\/\/globoplay.globo.com\/v\/9752550\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/globoplay.globo.com\/v\/9752550\/<\/a>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Una de las campa\u00f1as de movilizaci\u00f3n social de m\u00e1s larga duraci\u00f3n en Brasil,&nbsp;Crian\u00e7a&nbsp;Esperan\u00e7a, ha estado creando oportunidades de desarrollo para ni\u00f1os y j\u00f3venes en todo el pa\u00eds durante 36 a\u00f1os. Reconocido por la ONU como modelo internacional,&nbsp;Crian\u00e7a&nbsp;Esperan\u00e7a&nbsp;es uno de los programas&nbsp;sociales m\u00e1s visibles y reconocidos del pa\u00eds, as\u00ed como una poderosa herramienta de comunicaci\u00f3n para discutir temas importantes de la agenda social brasile\u00f1a.&nbsp; A trav\u00e9s de su campa\u00f1a anual de movilizaci\u00f3n, recolecta recursos que se invierten en proyectos sociales desarrollados por organizaciones de la sociedad civil en las cinco regiones de Brasil. Con la participaci\u00f3n de ciudadanos y grandes empresas, el programa ha apoyado m\u00e1s de 5.000 proyectos, que beneficiaron a m\u00e1s de 4 millones de ni\u00f1os y j\u00f3venes en situaci\u00f3n de vulnerabilidad en todo el pa\u00eds.\u00a0 Todos los fondos recaudados se depositan directamente en una cuenta de la Unesco &#8211; Organizaci\u00f3n de las Naciones Unidas para la Educaci\u00f3n, la Ciencia y la Cultura, responsable de la selecci\u00f3n de proyectos, a trav\u00e9s de un aviso p\u00fablico, as\u00ed como del monitoreo y seguimiento t\u00e9cnico y financiero a las organizaciones apoyadas.&nbsp; En 2021,&nbsp;Crian\u00e7a&nbsp;Esperan\u00e7a&nbsp;celebr\u00f3 la educaci\u00f3n como un agente de transformaci\u00f3n social, en un escenario en el que la pandemia agrav\u00f3 las tasas de abandono escolar.&nbsp; Luego de participar en el riguroso proceso de selecci\u00f3n de proyectos, OSJC \u2013 Obras&nbsp;Sociais&nbsp;Jer\u00f4nimo&nbsp;Candinho, organizaci\u00f3n que forma parte de la Franquicia Social POETA desde 2013 e implementa el proyecto POETA&nbsp;DigiSpark, con sede en la ciudad de&nbsp;Sobradinho, Distrito Federal, fue seleccionada con su proyecto Acordes da Vida.&nbsp; El proyecto Acordes da Vida participa en&nbsp;el programa&nbsp;Crian\u00e7a&nbsp;Esperan\u00e7a&nbsp;desde 2018 y ofrece talleres de m\u00fasica extraescolares, como Guitarra, Teclado, Viol\u00edn, Flauta, Coro y Percusi\u00f3n, adem\u00e1s de actividades recreativas, talleres de reciclaje, apoyo pedag\u00f3gico y psicosocial. Dirigido al p\u00fablico de 4 a 18 a\u00f1os, en 2021&nbsp;tiene como objetivo atender a 70 ni\u00f1os y adolescentes de forma directa y a 280 personas de forma indirecta.&nbsp; Obras&nbsp;Sociais&nbsp;Jer\u00f4nimo&nbsp;Candinho&nbsp;es una organizaci\u00f3n social&nbsp;orientada&nbsp;a promover la inclusi\u00f3n y mejorar la calidad de vida de ni\u00f1os y j\u00f3venes en situaciones de vulnerabilidad y exclusi\u00f3n social.&nbsp;Promueve la educaci\u00f3n escolar regular a trav\u00e9s del&nbsp;Col\u00e9gio&nbsp;Allan&nbsp;Kardec, ofreciendo educaci\u00f3n gratuita&nbsp;en todos los niveles, con el objetivo de rescatar los valores humanos y la autoestima de ni\u00f1os, j\u00f3venes y adolescentes,&nbsp;actividades diferenciadas, brindando un respiro a la convivencia con abandono, maltrato, negligencia y riesgos.&nbsp;Tambi\u00e9n ofrece&nbsp;talleres&nbsp;extracurriculares&nbsp;de&nbsp;educaci\u00f3n ambiental,&nbsp;artesan\u00eda y m\u00fasica, as\u00ed como clases de ciudadan\u00eda y actividades recreativas.&nbsp; Conhe\u00e7a aqui o Projeto Acordes da Vida e o momento que\u00a0organiza\u00e7\u00e3o Obras Sociais Jer\u00f4nimo Candinho recebeu a not\u00edcia de que havia sido contemplada com a edi\u00e7\u00e3o 2021\/2022\u00a0da Campanha Crian\u00e7a Esperan\u00e7a:\u00a0https:\/\/globoplay.globo.com\/v\/9752550\/\u00a0<\/p>","protected":false},"author":4,"featured_media":12094,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/1918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=1918"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/1918\/revisions"}],"predecessor-version":[{"id":12095,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/1918\/revisions\/12095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/12094"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=1918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=1918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=1918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}