{"id":1782,"date":"2021-08-02T09:27:51","date_gmt":"2021-08-02T13:27:51","guid":{"rendered":"http:\/\/40.117.174.162\/the-trust-for-the-americas-y-parquesoft-narino-contribuyen-a-disminuir-la-brecha-digital-en-colombia\/"},"modified":"2025-06-04T00:10:31","modified_gmt":"2025-06-04T00:10:31","slug":"the-trust-for-the-americas-y-parquesoft-narino-contribuyen-a-disminuir-la-brecha-digital-en-colombia","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/the-trust-for-the-americas-y-parquesoft-narino-contribuyen-a-disminuir-la-brecha-digital-en-colombia\/","title":{"rendered":"The Trust for the Americas y ParqueSoft Nari\u00f1o contribuyen a disminuir la brecha digital en Colombia"},"content":{"rendered":"<p class=\"wp-block-paragraph\"> Texto por ParqueSoft Nari\u00f1o <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Julio es un mes especial, puesto que se celebra 12 a\u00f1os de alianza entre The Trust for the Americas y ParqueSoft Nari\u00f1o, quienes de manera sin\u00e9rgica han trabajado a trav\u00e9s del Programa de Oportunidades Econ\u00f3micas a trav\u00e9s de la Tecnolog\u00eda en las Americas &#8211; (POETA) haciendo realidad en el sur occidente colombiano m\u00e1s de once versiones, en las que la apropiaci\u00f3n social de la tecnolog\u00eda ha sido motor de nuevas oportunidades, para mejorar la calidad de vida de cada uno de los participantes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"721\" src=\"http:\/\/40.117.174.162\/wp-content\/uploads\/2021\/08\/image-2.png\" alt=\"\" class=\"wp-image-12104\" srcset=\"https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/08\/image-2.png 720w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/08\/image-2-300x300.png 300w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/08\/image-2-150x150.png 150w, https:\/\/trust-oea.org\/wp-content\/uploads\/2021\/08\/image-2-12x12.png 12w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cosechando a trav\u00e9s de las TIC<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del a\u00f1o 2009 al 2016 a trav\u00e9s de POETA Accesible, el objetivo fue incrementar las oportunidades de empleo para personas en situaci\u00f3n de discapacidad y cuidadores, en Latinoam\u00e9rica, para el caso del sur occidente colombiano, llegamos a 1258 matr\u00edculas entre la capital y la frontera de Nari\u00f1o con Ecuador. Caracol televisi\u00f3n en el a\u00f1o 2016 resalt\u00f3 la iniciativa a nivel nacional narrando las historias de Don Laureano, y Alonso de los R\u00edos, desde la ciudad sorpresa de Colombia <a href=\"\/en\/\"http:>http:\/\/bit.ly\/POETAenPasto<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">POETA en su versi\u00f3n YouthSpark, se enfoc\u00f3 en ser la Chispa Digital del a\u00f1o 2014 al 2019, trabajando especialmente con j\u00f3venes, en temas de inter\u00e9s mundial, como lo es la alfabetizaci\u00f3n, emprendimiento y nuevos conocimientos TIC para educadores, teniendo claro un enfoque de g\u00e9nero, permiti\u00e9ndonos motivar la participaci\u00f3n de la mujer en las ciencias de la computaci\u00f3n, prepar\u00e1ndolas para llegar al mercado laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La emergencia sanitaria nos llev\u00f3 a la nube (internet)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el mes de marzo de 2020 el programa se reinvent\u00f3 r\u00e1pidamente para brindar acompa\u00f1amiento a las poblaciones m\u00e1s afectadas por la pandemia. Llevando todas las capacitaciones, y convocatorias al escenario 100% digital, propiciando la transformaci\u00f3n digital para que los emprendedores, y empresarios se apropiaran de la tecnolog\u00eda, para facilitar el trabajo remoto, seguir llegando a sus clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para esta versi\u00f3n especial se trabaj\u00f3 de la mano de tutores en casa, para que los adultos mayores aprendieran sobre alfabetizaci\u00f3n digital, permiti\u00e9ndoles ganar mayor autonom\u00eda digital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el a\u00f1o en curso (2021) POETA DigiSpark sigue siendo motivador de esperanza, al trabajar con madres y padres de familia quienes ten\u00edan la necesidad de convertirse en unos super gu\u00edas digitales para sus hijos, tambi\u00e9n j\u00f3venes y adultos quienes est\u00e1n en la b\u00fasqueda de empleo, donde las habilidades digitales les contribuye para abordar su marca personal, y gestionar su oportunidad laboral, desde la generaci\u00f3n de contenido.<\/p>","protected":false},"excerpt":{"rendered":"<p>Texto por ParqueSoft Nari\u00f1o Julio es un mes especial, puesto que se celebra 12 a\u00f1os de alianza entre The Trust for the Americas y ParqueSoft Nari\u00f1o, quienes de manera sin\u00e9rgica han trabajado a trav\u00e9s del Programa de Oportunidades Econ\u00f3micas a trav\u00e9s de la Tecnolog\u00eda en las Americas &#8211; (POETA) haciendo realidad en el sur occidente colombiano m\u00e1s de once versiones, en las que la apropiaci\u00f3n social de la tecnolog\u00eda ha sido motor de nuevas oportunidades, para mejorar la calidad de vida de cada uno de los participantes. Cosechando a trav\u00e9s de las TIC Del a\u00f1o 2009 al 2016 a trav\u00e9s de POETA Accesible, el objetivo fue incrementar las oportunidades de empleo para personas en situaci\u00f3n de discapacidad y cuidadores, en Latinoam\u00e9rica, para el caso del sur occidente colombiano, llegamos a 1258 matr\u00edculas entre la capital y la frontera de Nari\u00f1o con Ecuador. Caracol televisi\u00f3n en el a\u00f1o 2016 resalt\u00f3 la iniciativa a nivel nacional narrando las historias de Don Laureano, y Alonso de los R\u00edos, desde la ciudad sorpresa de Colombia http:\/\/bit.ly\/POETAenPasto POETA en su versi\u00f3n YouthSpark, se enfoc\u00f3 en ser la Chispa Digital del a\u00f1o 2014 al 2019, trabajando especialmente con j\u00f3venes, en temas de inter\u00e9s mundial, como lo es la alfabetizaci\u00f3n, emprendimiento y nuevos conocimientos TIC para educadores, teniendo claro un enfoque de g\u00e9nero, permiti\u00e9ndonos motivar la participaci\u00f3n de la mujer en las ciencias de la computaci\u00f3n, prepar\u00e1ndolas para llegar al mercado laboral. La emergencia sanitaria nos llev\u00f3 a la nube (internet) Desde el mes de marzo de 2020 el programa se reinvent\u00f3 r\u00e1pidamente para brindar acompa\u00f1amiento a las poblaciones m\u00e1s afectadas por la pandemia. Llevando todas las capacitaciones, y convocatorias al escenario 100% digital, propiciando la transformaci\u00f3n digital para que los emprendedores, y empresarios se apropiaran de la tecnolog\u00eda, para facilitar el trabajo remoto, seguir llegando a sus clientes. Para esta versi\u00f3n especial se trabaj\u00f3 de la mano de tutores en casa, para que los adultos mayores aprendieran sobre alfabetizaci\u00f3n digital, permiti\u00e9ndoles ganar mayor autonom\u00eda digital. Para el a\u00f1o en curso (2021) POETA DigiSpark sigue siendo motivador de esperanza, al trabajar con madres y padres de familia quienes ten\u00edan la necesidad de convertirse en unos super gu\u00edas digitales para sus hijos, tambi\u00e9n j\u00f3venes y adultos quienes est\u00e1n en la b\u00fasqueda de empleo, donde las habilidades digitales les contribuye para abordar su marca personal, y gestionar su oportunidad laboral, desde la generaci\u00f3n de contenido.<\/p>","protected":false},"author":4,"featured_media":12106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/1782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=1782"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/1782\/revisions"}],"predecessor-version":[{"id":12107,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/1782\/revisions\/12107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/12106"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=1782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=1782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=1782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}