{"id":1555,"date":"2020-10-06T12:16:46","date_gmt":"2020-10-06T16:16:46","guid":{"rendered":"http:\/\/40.117.174.162\/la-educacion-del-futuro-te-necesita-a-ti\/"},"modified":"2025-06-04T00:44:30","modified_gmt":"2025-06-04T00:44:30","slug":"la-educacion-del-futuro-te-necesita-a-ti","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/la-educacion-del-futuro-te-necesita-a-ti\/","title":{"rendered":"La educaci\u00f3n del futuro te necesita a ti"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><em>Los cambios acelerados que&nbsp;traen consigo los avances tecnol\u00f3gicos, as\u00ed como el contexto&nbsp;de m\u00faltiples transformaciones en el&nbsp;\u00e1rea social, econ\u00f3mica y pol\u00edtica,&nbsp;sugieren&nbsp;un reenfoque de la educaci\u00f3n.<\/em>&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada vez m\u00e1s, los trabajos\u00a0dentro de compa\u00f1\u00edas y en los gobiernos, tienen un claro norte digital. Los lineamientos de confinamiento y distanciamiento social establecidos por los gobiernos alrededor del mundo, han impulsado a su vez el auge del teletrabajo, que en muchos gremios lleg\u00f3 para quedarse.\u00a0Sin embargo,&nbsp;las escuelas primarias y secundarias siguen presentando deudas con la digitalizaci\u00f3n&nbsp;y su uso efectivo.&nbsp;Como&nbsp;se\u00f1ala la exministra de Educaci\u00f3n guatemalteca, Mar\u00eda del Carmen Ace\u00f1a en&nbsp;<a href=\"https:\/\/forbescentroamerica.com\/2020\/04\/20\/coronavirus-falta-de-acceso-a-internet-amenaza-suenos-de-ninos-en-zonas-rurales\/\" target=\"_blank\" rel=\"noreferrer noopener\">Forbes Centroam\u00e9rica<\/a>,&nbsp;\u201ces primordial que la cartera educativa redistribuya sus recursos econ\u00f3micos en favor de las nuevas tecnolog\u00edas, para evitar que los inconvenientes causen deserci\u00f3n de ni\u00f1os y j\u00f3venes de escasos recursos\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan&nbsp;<a href=\"http:\/\/www3.weforum.org\/docs\/WEF_Schools_of_the_Future_Report_2019.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Schools of The Future Report (2019<\/em><\/a>), realizado por el&nbsp;World&nbsp;Economic&nbsp;Forum, existen 8 cualidades cr\u00edticas que permiten distinguir&nbsp;una&nbsp;educaci\u00f3n de alta calidad para la Cuarta Revoluci\u00f3n Industrial. Una de ellas&nbsp;es la Educaci\u00f3n Tecnol\u00f3gica, es decir, \u201cla inclusi\u00f3n de contenidos que se basen en desarrollar habilidades digitales,&nbsp;como&nbsp;programaci\u00f3n, responsabilidad digital y el uso de tecnolog\u00edas\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto con el fin de equiparar las estrategias educativas a otros procesos que las juventudes viven \u2013y vivir\u00e1n-&nbsp;de manera inevitable&nbsp;al crecer&nbsp;en la sociedad actual, por ejemplo:&nbsp;los nuevos modelos de teletrabajo, el reemplazo de personas por robots o m\u00e1quinas para realizar distintas tareas,&nbsp;y&nbsp;la capacidad de analizar&nbsp;las problem\u00e1ticas en su&nbsp;entorno a trav\u00e9s del pensamiento l\u00f3gico-matem\u00e1tico, sin&nbsp;dejar&nbsp;por fuera la inteligencia social y emocional.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mismo documento, adem\u00e1s, se\u00f1ala la importancia de potenciar las alianzas p\u00fablico-privadas para lograrlo, tomando en cuenta a empresas tecnol\u00f3gicas, institutos y ministerios de educaci\u00f3n, as\u00ed como los mismos profesionales en docencia.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el objetivo de incentivar este tipo de pr\u00e1cticas,&nbsp;EIDOS se encargar\u00e1 de impartir,&nbsp;el martes 6 de octubre, una capacitaci\u00f3n&nbsp;gratuita&nbsp;orientada a docentes.&nbsp;En este taller se explicar\u00e1n fundamentos b\u00e1sicos de&nbsp;las&nbsp;ciencias de la computaci\u00f3n, inteligencia artificial&nbsp;y&nbsp;aprendizaje autom\u00e1tico por medio de una actividad de La Hora del C\u00f3digo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gracias a oportunidades como esta, docentes de diferentes pa\u00edses hispanohablantes podr\u00e1n prepararse para el reto que implica la ense\u00f1anza durante y despu\u00e9s&nbsp;del CoVid-19, que sin duda requerir\u00e1 el trabajo integral, din\u00e1mico&nbsp;y unificado.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1La\u00a0ense\u00f1anza\u00a0del futuro empieza contigo!\u00a0<br>Ingresa al taller a trav\u00e9s del siguiente\u00a0enlace\u00a0<a href=\"https:\/\/linktr.ee\/eidosglobal?fbclid=IwAR3nWRKVDQQuAd6_z94_-LJ4Ps_g35buMJv_dBEaGLI65-b2NKsmrfmof4M\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/linktr.ee\/eidosglobal\u00a0<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Los cambios acelerados que&nbsp;traen consigo los avances tecnol\u00f3gicos, as\u00ed como el contexto&nbsp;de m\u00faltiples transformaciones en el&nbsp;\u00e1rea social, econ\u00f3mica y pol\u00edtica,&nbsp;sugieren&nbsp;un reenfoque de la educaci\u00f3n.&nbsp;&nbsp; Cada vez m\u00e1s, los trabajos\u00a0dentro de compa\u00f1\u00edas y en los gobiernos, tienen un claro norte digital. Los lineamientos de confinamiento y distanciamiento social establecidos por los gobiernos alrededor del mundo, han impulsado a su vez el auge del teletrabajo, que en muchos gremios lleg\u00f3 para quedarse.\u00a0Sin embargo,&nbsp;las escuelas primarias y secundarias siguen presentando deudas con la digitalizaci\u00f3n&nbsp;y su uso efectivo.&nbsp;Como&nbsp;se\u00f1ala la exministra de Educaci\u00f3n guatemalteca, Mar\u00eda del Carmen Ace\u00f1a en&nbsp;Forbes Centroam\u00e9rica,&nbsp;\u201ces primordial que la cartera educativa redistribuya sus recursos econ\u00f3micos en favor de las nuevas tecnolog\u00edas, para evitar que los inconvenientes causen deserci\u00f3n de ni\u00f1os y j\u00f3venes de escasos recursos\u201d.&nbsp; Seg\u00fan&nbsp;Schools of The Future Report (2019), realizado por el&nbsp;World&nbsp;Economic&nbsp;Forum, existen 8 cualidades cr\u00edticas que permiten distinguir&nbsp;una&nbsp;educaci\u00f3n de alta calidad para la Cuarta Revoluci\u00f3n Industrial. Una de ellas&nbsp;es la Educaci\u00f3n Tecnol\u00f3gica, es decir, \u201cla inclusi\u00f3n de contenidos que se basen en desarrollar habilidades digitales,&nbsp;como&nbsp;programaci\u00f3n, responsabilidad digital y el uso de tecnolog\u00edas\u201d.&nbsp; Esto con el fin de equiparar las estrategias educativas a otros procesos que las juventudes viven \u2013y vivir\u00e1n-&nbsp;de manera inevitable&nbsp;al crecer&nbsp;en la sociedad actual, por ejemplo:&nbsp;los nuevos modelos de teletrabajo, el reemplazo de personas por robots o m\u00e1quinas para realizar distintas tareas,&nbsp;y&nbsp;la capacidad de analizar&nbsp;las problem\u00e1ticas en su&nbsp;entorno a trav\u00e9s del pensamiento l\u00f3gico-matem\u00e1tico, sin&nbsp;dejar&nbsp;por fuera la inteligencia social y emocional.&nbsp;&nbsp; El mismo documento, adem\u00e1s, se\u00f1ala la importancia de potenciar las alianzas p\u00fablico-privadas para lograrlo, tomando en cuenta a empresas tecnol\u00f3gicas, institutos y ministerios de educaci\u00f3n, as\u00ed como los mismos profesionales en docencia.&nbsp; Con el objetivo de incentivar este tipo de pr\u00e1cticas,&nbsp;EIDOS se encargar\u00e1 de impartir,&nbsp;el martes 6 de octubre, una capacitaci\u00f3n&nbsp;gratuita&nbsp;orientada a docentes.&nbsp;En este taller se explicar\u00e1n fundamentos b\u00e1sicos de&nbsp;las&nbsp;ciencias de la computaci\u00f3n, inteligencia artificial&nbsp;y&nbsp;aprendizaje autom\u00e1tico por medio de una actividad de La Hora del C\u00f3digo.&nbsp; Gracias a oportunidades como esta, docentes de diferentes pa\u00edses hispanohablantes podr\u00e1n prepararse para el reto que implica la ense\u00f1anza durante y despu\u00e9s&nbsp;del CoVid-19, que sin duda requerir\u00e1 el trabajo integral, din\u00e1mico&nbsp;y unificado.&nbsp;&nbsp; \u00a1La\u00a0ense\u00f1anza\u00a0del futuro empieza contigo!\u00a0Ingresa al taller a trav\u00e9s del siguiente\u00a0enlace\u00a0https:\/\/linktr.ee\/eidosglobal\u00a0<\/p>","protected":false},"author":23,"featured_media":12128,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1555","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/1555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=1555"}],"version-history":[{"count":1,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/1555\/revisions"}],"predecessor-version":[{"id":12130,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/1555\/revisions\/12130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/12128"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=1555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=1555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=1555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}