{"id":11818,"date":"2025-05-30T20:38:00","date_gmt":"2025-05-30T20:38:00","guid":{"rendered":"http:\/\/40.117.174.162\/?p=11818"},"modified":"2025-07-14T22:30:31","modified_gmt":"2025-07-14T22:30:31","slug":"impulsando-el-desarrollo-de-juventudes-en-tecnologia-e-innovacion-nuestra-participacion-en-la-plenaria-del-colaborativo-goyn-cdmx","status":"publish","type":"post","link":"https:\/\/trust-oea.org\/en\/impulsando-el-desarrollo-de-juventudes-en-tecnologia-e-innovacion-nuestra-participacion-en-la-plenaria-del-colaborativo-goyn-cdmx\/","title":{"rendered":"Impulsando el desarrollo de juventudes en tecnolog\u00eda e innovaci\u00f3n: nuestra participaci\u00f3n en la plenaria del colaborativo GOYN CDMX\u00a0"},"content":{"rendered":"<p class=\"wp-block-paragraph\">El pasado 12 de mayo tuvimos la oportunidad de participar en la&nbsp;<strong>plenaria del colaborativo GOYN Ciudad de M\u00e9xico<\/strong>, un espacio fundamental para compartir, reflexionar y construir estrategias en favor de las y los j\u00f3venes oportunidad.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta jornada fue organizada por la Red GOYN CDMX y reuni\u00f3 a diversos actores comprometidos con el impulso de juventudes en temas como educaci\u00f3n, empleo, emprendimiento y territorio.\u00a0Durante el encuentro,&nbsp;<strong>Emilia Ram\u00edrez, directora de la Red GOYN<\/strong>, present\u00f3 un recuento de los logros alcanzados en el \u00faltimo a\u00f1o, incluyendo el n\u00famero de j\u00f3venes impactadxs, los avances en las rutas estrat\u00e9gicas y las valiosas alianzas generadas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue un momento clave para reconocer el trabajo colectivo y reafirmar el compromiso hacia una transformaci\u00f3n sostenible e inclusiva.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como representantes de&nbsp;<strong>The Trust for the Americas<\/strong>, nos sentimos honrados de haber estado presentes a trav\u00e9s de&nbsp;<strong>Karen Castro, Coordinadora Nacional de Proyectos en M\u00e9xico<\/strong>, quien pudo conocer de primera mano las iniciativas que se est\u00e1n llevando a cabo desde la Red y compartir los avances de nuestra reciente&nbsp;<strong>alianza con GOYN CDMX<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde esta colaboraci\u00f3n, hemos trabajado conjuntamente para&nbsp;<strong>capacitar y empoderar a miembros de la Red GOYN mediante talleres, webinarios, acceso a cursos y otras iniciativas orientadas al desarrollo tecnol\u00f3gico, educacional y profesional<\/strong>, con un enfoque especial en&nbsp;<strong>temas de inteligencia artificial<\/strong>. Hasta la fecha, gracias a esta alianza colaborativa,&nbsp;<strong>hemos capacitado a 40 l\u00edderes organizacionales<\/strong>, generando nuevas oportunidades de formaci\u00f3n y crecimiento para las juventudes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La plenaria se llev\u00f3 a cabo en el nuevo&nbsp;<strong>Hub de CLAP, ubicado en Tacubaya<\/strong>, un espacio lleno de energ\u00eda colaborativa, por lo que extendemos un especial agradecimiento a su equipo por el c\u00e1lido recibimiento.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde The Trust for the Americas reiteramos nuestro compromiso con el impulso de juventudes y la creaci\u00f3n de alianzas significativas que potencien sus capacidades y oportunidades. Seguimos aprendiendo y construyendo juntos.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>El pasado 12 de mayo tuvimos la oportunidad de participar en la&nbsp;plenaria del colaborativo GOYN Ciudad de M\u00e9xico, un espacio fundamental para compartir, reflexionar y construir estrategias en favor de las y los j\u00f3venes oportunidad.&nbsp;&nbsp; Esta jornada fue organizada por la Red GOYN CDMX y reuni\u00f3 a diversos actores comprometidos con el impulso de juventudes en temas como educaci\u00f3n, empleo, emprendimiento y territorio.\u00a0Durante el encuentro,&nbsp;Emilia Ram\u00edrez, directora de la Red GOYN, present\u00f3 un recuento de los logros alcanzados en el \u00faltimo a\u00f1o, incluyendo el n\u00famero de j\u00f3venes impactadxs, los avances en las rutas estrat\u00e9gicas y las valiosas alianzas generadas.&nbsp;&nbsp; Fue un momento clave para reconocer el trabajo colectivo y reafirmar el compromiso hacia una transformaci\u00f3n sostenible e inclusiva.&nbsp; Como representantes de&nbsp;The Trust for the Americas, nos sentimos honrados de haber estado presentes a trav\u00e9s de&nbsp;Karen Castro, Coordinadora Nacional de Proyectos en M\u00e9xico, quien pudo conocer de primera mano las iniciativas que se est\u00e1n llevando a cabo desde la Red y compartir los avances de nuestra reciente&nbsp;alianza con GOYN CDMX.&nbsp; Desde esta colaboraci\u00f3n, hemos trabajado conjuntamente para&nbsp;capacitar y empoderar a miembros de la Red GOYN mediante talleres, webinarios, acceso a cursos y otras iniciativas orientadas al desarrollo tecnol\u00f3gico, educacional y profesional, con un enfoque especial en&nbsp;temas de inteligencia artificial. Hasta la fecha, gracias a esta alianza colaborativa,&nbsp;hemos capacitado a 40 l\u00edderes organizacionales, generando nuevas oportunidades de formaci\u00f3n y crecimiento para las juventudes.&nbsp; La plenaria se llev\u00f3 a cabo en el nuevo&nbsp;Hub de CLAP, ubicado en Tacubaya, un espacio lleno de energ\u00eda colaborativa, por lo que extendemos un especial agradecimiento a su equipo por el c\u00e1lido recibimiento.&nbsp;&nbsp; Desde The Trust for the Americas reiteramos nuestro compromiso con el impulso de juventudes y la creaci\u00f3n de alianzas significativas que potencien sus capacidades y oportunidades. Seguimos aprendiendo y construyendo juntos.&nbsp;<\/p>","protected":false},"author":40,"featured_media":12744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-11818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/11818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/comments?post=11818"}],"version-history":[{"count":2,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/11818\/revisions"}],"predecessor-version":[{"id":12745,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/posts\/11818\/revisions\/12745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media\/12744"}],"wp:attachment":[{"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/media?parent=11818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/categories?post=11818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trust-oea.org\/en\/wp-json\/wp\/v2\/tags?post=11818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}